{"id":5294,"date":"2012-11-15T00:00:00","date_gmt":"2012-11-14T23:00:00","guid":{"rendered":""},"modified":"2016-02-04T15:08:26","modified_gmt":"2016-02-04T14:08:26","slug":"il-freno-dellafrica-nelluomo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/","title":{"rendered":"Il freno dell&#8217;Africa &egrave; nell&#8217;uomo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30287\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg\" alt=\"Islam_Africa\" width=\"250\" height=\"166\" \/><\/a>Italia Oggi<\/strong> 8 novembre 2012<\/div>\n<p style=\"text-align: justify;\"><em>Gheddo: l&#8217;Islam non \u00e8 ancora entrato nel mondo moderno. Non conosce eguaglianza e perdono La inchiodano ignoranza, corruzione, stregonerie e militari<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Luigi Chiarello <\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">\u00abNon sono l&#8217;accaparramento di terre e le rapine di diamanti\u00bb a rubare il futuro agli africani. Piuttosto, \u00abanalfabetismo, corruzione, animismo e arroganza della casta militare\u00bb sono le vere cause che inchiodano l&#8217;Africa Nera. Il cui sviluppo \u00e8 incastrato sotto il tallone dei Marabut, gli stregoni, ed \u00e8 stretto al giogo di \u00abgoverni mafiosi\u00bb.<\/div>\n<p style=\"text-align: justify;\">Cos\u00ec, i crimini pi\u00f9 evidenti ai nostri occhi, quelli pi\u00f9 enfatizzati dai media del primo mondo, sono in realt\u00e0 fattori residuali. Tanto che perfino il discuterne ha il retrogusto del lusso.\u00a0 Il solenne ceffone verbale che Piero Gheddo riserva all&#8217;intervistatore \u00e8 di quelli che bruciano.<\/p>\n<p style=\"text-align: justify;\">La sensazione \u00e8 di far domande disconnesse dalla realt\u00e0. Di guardare al dito e non alla luna, per rimozione inconscia. Come se il tentativo di leggere i problemi dell&#8217;Africa con le lenti della politica e dell&#8217;economia, senza toccar con mano le miserie quotidiane, finisse per smascherare una cecit\u00e0 culturale verso il Continente nero. Cos\u00ec vicino e sconosciuto.<\/p>\n<p style=\"text-align: justify;\">Gheddo conosce bene l&#8217;Africa. Anzi, le Afriche. Il missionario del Pime, nei suoi 83 anni di vita, le ha girate in lungo e in largo, descrivendole in due volumi interessanti: \u00abMeno male che Cristo c&#8217;\u00e8\u00bb (edizioni Lindau, Torino) e \u00abLa sfida dell&#8217;Islam all&#8217;Occidente\u00bb (edizioni San Paolo).<\/p>\n<p style=\"text-align: justify;\">E proprio sull&#8217;Islam Gheddo non fa sconti: \u00abLa verit\u00e0 \u00e8 che non \u00e8 ancora entrato nel mondo moderno. Non conosce uguaglianza tra gli uomini e perdono\u00bb. Eppure una speranza c&#8217;\u00e8. Ed \u00e8 nelle primavere arabe: \u00abHanno affermato il valore della persona, della democrazia, dello sviluppo umano e tecnico, delle giustizie sociali, dei diritti delle donne\u00bb, dice. \u00abI giovani\u00bb che hanno acceso le rivolte \u00abvolevano proprio questo\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Domanda. Perch\u00e9 il continente nero sta soffrendo la globalizzazione?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Risposta. Se fosse pi\u00f9 evoluto, nel senso dell&#8217;educazione del proprio popolo, potrebbe utilizzare bene la globalizzazione, come hanno fatto i paesi asiatici. Guardi a India e Bangladesh: sono molto pi\u00f9 avanti nello sviluppo, perch\u00e9 hanno popoli pi\u00f9 preparati. Infatti, per partecipare in modo positivo alla globalizzazione bisogna avere un certo livello di conoscenze e di produttivit\u00e0 per l&#8217;esportazione. Invece, buona parte dei paesi africani hanno il 40-50% della popolazione analfabeta e un altro 10-15% di \u00abanalfabeti di ritorno\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Quali gli esempi virtuosi, in grado di cogliere chance dalla globalizzazione?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Ghana, Benin, Costa d&#8217;Avorio, Camerun, Senegal, Kenya, Angola, Botswana, Congo-Brazzaville. Poi ci sono il Sudafrica e la Namibia, che per\u00f2 fanno storia a s\u00e9, sono un altro mondo. In quei paesi l&#8217;apartheid divideva neri e bianchi, ma i bianchi hanno educato i neri. Anche se in scuole separate. La separazione \u00e8 stata un crimine orrendo, ma i neri sono abbastanza scolarizzati e si \u00e8 formata una classe media e dirigente nera, che ora guida il paese senza aver cacciato i bianchi.<\/p>\n<p style=\"text-align: justify;\"><strong>D. E i paesi messi peggio?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Quelli che hanno dittature o regimi paternalisti corrotti e conservatori. Quelli in cui i partiti comunisti hanno avuto un ruolo dominante e sono ancora al potere (tipo Eritrea, Zimbabwe, Etiopia, in parte anche Mozambico).<\/p>\n<p style=\"text-align: justify;\"><strong>D. Quali sono le principali cause che bloccano lo sviluppo dell&#8217;Africa nera?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. L&#8217;ostacolo principale \u00e8 nella mancanza di educazione del popolo. Non \u00e8 solo questione di analfabetismo, ma anche di assenza di capacit\u00e0 tecniche e di spirito imprenditoriale. Il Camerun, che pure ha un tasso di sviluppo abbastanza buono, importa ancora tutto il manifatturiero dall&#8217;Europa, persino le lampadine e le biciclette. In sostanza, la globalizzazione vive attraverso la pace, la libert\u00e0 e il commercio e diventa un fenomeno positivo solo se i popoli sono preparati a produrre per l&#8217;esportazione.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Oggi l&#8217;allarme \u00e8 nello shopping di terre africane fatto da Pechino. Il cosiddetto land grabbing o accaparramento di terra.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Lo fanno i cinesi, ma anche i coreani, i Paesi arabi del Golfo e l&#8217;India. Sono campagne di acquisti condotte da paesi che non hanno sufficiente produzione di grano e di cereali per la propria domanda interna. Questi paesi tolgono agli africani le terre migliori. E questo svela il secondo ostacolo allo sviluppo in Africa: la corruzione.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Land grabbing sinonimo di corruzione?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Si, perch\u00e9 i paesi pi\u00f9 ricchi pagano le terre africane, comprandole dai governi. I soldi, per\u00f2 e in genere, non vanno al popolo, ma alle mafie che pullulano nei governi africani. Corruzione e mancanza di democrazia bloccano lo sviluppo. In molti paesi africani non c&#8217;\u00e8 alcun controllo del popolo sugli esecutivi. E chi va al governo pensa a se stesso, alla sua famiglia, alla sua etnia e non tanto nel senso dello sviluppo, ma nel senso del lusso, delle molte propriet\u00e0 e dei capitali all&#8217;estero. Quante volte ho visto in Africa ponti o strade in costruzione con finanziamenti dell&#8217;Unione europea, che non sono mai finiti. I soldi arrivano, ma spariscono prima di giungere a destinazione.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Pare succeda anche da noi<\/strong><\/p>\n<p style=\"text-align: justify;\">R. C&#8217;\u00e8 un abisso. In Italia ci sono casi gravi. Ma se lei va a prendere un documento in comune non le chiedono la mancia. Nei paesi africani, invece, \u00e8 cosa comune. La corruzione \u00e8 a ogni livello, basso o alto che sia. La verit\u00e0 \u00e8 che, al contrario di quanto si legge in Europa, n\u00e9 il land grabbing n\u00e9 le rapine di diamanti sono il vero problema del mancato sviluppo dell&#8217;Africa nera. Sono certo crimini da condannare, ma non sono determinanti per il mancato sviluppo. La radice del sottosviluppo africano \u00e8 nell&#8217;uomo, nel popolo di non educati e non liberi. Gli africani sono giovani, svegli, intelligenti, con enormi potenzialit\u00e0 di sviluppo, ma non sono educati. Quando vengono a studiare in Europa e vivono in libert\u00e0, ben nutriti e curati, spesso sono i migliori studenti, i migliori medici.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Quindi?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. La verit\u00e0 \u00e8 che l&#8217;Africa si sviluppa poco soprattutto per quattro cause. Come ho detto, primo l&#8217;analfabetismo, secondo la corruzione, terzo l&#8217;animismo, quarto i militari, che sono la casta con le armi in mano.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Perch\u00e9 l&#8217;animismo?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Perch\u00e9 non educa l&#8217;uomo ad avere coscienza della realt\u00e0. La professoressa Silvia Recchi, che insegna all&#8217;Universit\u00e0 di Yaound\u00e8 da 14 anni, mi diceva due anni fa in Camerun: \u00abLa cultura magica rifiuta l&#8217;analisi dei problemi, rifiuta la razionalit\u00e0. La vita africana \u00e8 tutta dominata dagli spiriti, dal malocchio, dalle forze misteriose della natura o dello stregone. La malattia non \u00e8 causata da cause fisiche ma vien dal malocchio e dal tab\u00f9 che abbiamo violato. Abbiamo giovani che si sono laureati in Europa e che nel loro profondo ragionano ancora come nel mondo antico, specie nei momenti di difficolt\u00e0, nelle decisioni fondamentali della vita\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Mi spieghi meglio?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Un esempio lo racconta padre Carlo Scapin del Pime, in Camerun da 44 anni: \u00abNella loro cultura ancestrale, c&#8217;\u00e8 Dio creatore che sta sopra tutti. Ma Dio non si interessa degli uomini, \u00e8 lontano, invisibile e inconoscibile. La vita e l&#8217;agire degli uomini sono governati dagli spiriti buoni e cattivi. \u00c8 difficile dire chi sono e dove sono questi spiriti; un po&#8217; sono quelli dei morti e degli antenati e un po&#8217; sono forze spirituali misteriose, che per\u00f2 agiscono sugli uomini. Non molto tempo fa, un nostro cristiano, che \u00e8 generoso e aiuta in parrocchia, al mattino ha trovato davanti alla sua porta un uovo rotto, che \u00e8 segno di morte. Disperazione della famiglia, perch\u00e9 pensano che questa \u00e8 una minaccia di morte\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Addirittura?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Scapin la racconta cos\u00ec: \u00abVado a dare una benedizione a quella casa con i paramenti sacri pi\u00f9 solenni, l&#8217;acqua santa, l&#8217;incenso, il mio crocifisso di missionario, il libretto delle benedizioni in latino. Erano in molti ad aspettarmi, seduti anche per terra, parenti e vicini di casa. Ho fatto una cerimonia solenne e lunga, con canti, letture in ewondo, benedizioni in latino; poi ho benedetto con l&#8217;acqua santa e incensato tutta la casa, ho imposto le mani a tutti i membri della famiglia. Infine ho fatto il mio discorsetto dicendo loro: non abbiate paura, con le mie benedizioni Ges\u00f9 Cristo \u00e8 entrato nella vostra casa e nessuno pu\u00f2 pi\u00f9 mandarlo via, se voi pregate con fede. Se avete altri segni negativi, chiamatemi\u00bb.<\/p>\n<p style=\"text-align: justify;\">E tutto per un uovo! Se la cosa fosse andata avanti, quella povera gente, che pure sono fedeli a Cristo e alla Chiesa, sarebbe vissuta nel terrore. I casi di questo genere sono molti e spesso non vengono subito alla Chiesa, ma vanno dal marabut (stregone, ndr) che queste cose le capisce pi\u00f9 del prete. Il quale fa i suoi segni misteriosi e d\u00e0 il responso: accusa il tale o il tal altro di voler male a quella famiglia e incominciano i sospetti, le gelosie, le vendette, una famiglia o due sono distrutte o squassate.<\/p>\n<p style=\"text-align: justify;\"><strong>D. \u00c8 una realt\u00e0 che non conosciamo.<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Perch\u00e9 non se ne parla mai. Un popolo non pu\u00f2 svilupparsi senza aver abolito le superstizioni e l&#8217;irrazionalit\u00e0. L&#8217;uomo africano finisce per vivere una doppia vita: una vita nel mondo moderno e una vita, personale e familiare, in cui resta prigioniero di incubi e malocchio.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Lei dice che gli africani producono poco. Perch\u00e8?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Io vengo da Vercelli dove si produce riso. Produciamo 80 quintali di riso l&#8217;ettaro. Nell&#8217;agricoltura tradizionale africana si producono pi\u00f9 o meno 5-6 quintali di riso all&#8217;ettaro. Non perch\u00e9 gli africani non lavorano, ma perch\u00e9 non hanno strumenti di livellamento del terreno, non hanno sementi selezionate n\u00e9 l&#8217;acqua assicurata ecc. Non \u00e8 solo questione di conoscenze tecniche: c&#8217;\u00e8 un deficit di mentalit\u00e0. La cultura produce sviluppo. Le vacche italiane producono 25-30 litri di latte al giorno. Le vacche africane non producono latte, eccetto uno o due litri al giorno quando hanno il vitellino. Potrebbero produrre, come si vede nelle fattorie-scuola delle missioni, ma non hanno l&#8217;erba come le nostre, non hanno i mangimi, non hanno i veterinari ecc.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Vede una via d&#8217;uscita per l&#8217;Africa nera?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Non sono affatto pessimista, perch\u00e9 un certo progresso di mentalit\u00e0 e di coscienza c&#8217;\u00e8 gi\u00e0 stato e sta crescendo nei giovani. La grande rivoluzione del Cristianesimo nell&#8217;Africa nera \u00e8 che Ges\u00f9 Cristo, Figlio di Dio fatto uomo, libera gli africani dalle loro tradizioni sugli spiriti cattivi. Dio \u00e8 Padre buono e misericordioso, che ama tutti gli uomini. Ges\u00f9 ha portato la \u00abRivoluzione dell&#8217;amore\u00bb e le missioni cristiane (cattoliche e protestanti) sono impegnate ad aiutare con l&#8217;educazione e l&#8217;assistenza sanitaria lo sviluppo dei popoli, con risultati molto positivi.<\/p>\n<p style=\"text-align: justify;\"><strong>D. In centro Africa, per\u00f2, ci sono anche altre situazioni. I Janjaweed in Darfour-Sudan, i\u00a0 Boko Aram in Nigeria, gli al-Shabab in Somalia. Gli jihadisti in Mauritania e Mali. Al Qaeda nel Maghreb. Tutto il centro Africa \u00e8 attraversato da una ondata di integralismo.<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Il discorso \u00e8 lungo, non riducibile a una battuta. Ma la verit\u00e0 \u00e8 che l&#8217;Islam non \u00e8 ancora entrato nel mondo moderno. Per come \u00e8 praticata oggi la religione islamica non aiuta i popoli a svilupparsi. L&#8217;Islam deve confrontarsi con la democrazia, i diritti dell&#8217;uomo e della donna, il rispetto della libert\u00e0 di ogni uomo e la condanna dell&#8217;uso della violenza per risolvere i conflitti e per imporre la fede religiosa.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Perch\u00e9?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Perch\u00e9 l&#8217;Islam \u00e8 rimasto al Vecchio Testamento. Pur venendo dopo Cristo non conosce il concetto di perdono e di uguaglianza di tutti gli uomini. Non ha accettato Cristo come Figlio di Dio, lo considera un profeta come gli altri.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Chi finanzia la crescita del wahabismo integralista?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. I paesi pi\u00f9 integralisti, cio\u00e8 l&#8217;Arabia Saudita e paesi del golfo.<\/p>\n<p style=\"text-align: justify;\"><strong>D. C&#8217;\u00e8 una regia salafita che parte da quei paesi, per destabilizzare il centro Africa e attaccare i cristiani?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. L&#8217;Islam integralista e i salafiti jihadisti vorrebbero tornare all&#8217;epoca dei califfi, successori di Maometto, vorrebbero ristabilire il califfato, in cui il califfo era al contempo capo religioso, capo politico e capo militare degli islamici. \u00c8 questo l&#8217;Islam delle origini. Ma la persecuzione dei cristiani non avviene in tutto il mondo islamico. Laddove, invece, ci sono capi che sposano questa ideologia salafita succedono disastri. La persecuzione c&#8217;\u00e8 solo in quei paesi in cui \u00e8 entrata Al Qaeda, depositaria di una ideologia integralista che non si sconfigge con la guerra ma con il dialogo, la carit\u00e0, il perdono e la testimonianza della vita cristiana.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Le cosiddette primavere arabe sono una primavera o un inverno?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Una primavera, senza ombra di dubbio!<\/p>\n<p style=\"text-align: justify;\"><strong>D. Ma ha innescato una raffica di vittorie elettorali dei partiti integralisti, alle elezioni.<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Le primavere arabe hanno la loro origine nei giovani, negli intellettuali, nelle persone evolute e nella classe media del mondo islamico, che vorrebbero cambiare la situazione dei loro paesi: pi\u00f9 libert\u00e0, pi\u00f9 democrazia, pi\u00f9 sviluppo, anche economico.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Non sembra ci riescano&#8230;<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Eh\u2026 non sono mica finite, sa! Mi ascolti! Le primavere arabe sono state una benedizione per i paesi islamici. O lo diventeranno a lunga scadenza.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Perch\u00e9?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Perch\u00e9 hanno affermato il valore della persona, della democrazia, dello sviluppo umano e tecnico, delle giustizie sociali, dei diritti delle donne. I giovani che le hanno accese volevano proprio questo. E, per questo, hanno liberato i loro paesi dai dittatori. Questo \u00e8 un fatto estremamente positivo per il mondo islamico, perch\u00e9 rivela un desiderio di evoluzione dell&#8217;Islam.<\/p>\n<p style=\"text-align: justify;\"><strong>D. Ha anche portato alla vittoria movimenti islamisti e sdoganato movimenti salafiti<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Si, le primavere arabe hanno suscitato la reazione dell&#8217;integralismo. Ma, nel lungo periodo, non so dire entro quanto tempo, anche i popoli islamici cambieranno. E si evolveranno. Tempo al tempo: tutto \u00e8 iniziato negli ultimi due anni. Si tratta di un movimento che costa molte sofferenze specialmente ai cristiani, che sboccher\u00e0 in risultati positivi per tutti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italia Oggi 8 novembre 2012 Gheddo: l&#8217;Islam non \u00e8 ancora entrato nel mondo moderno. Non conosce eguaglianza e perdono La inchiodano ignoranza, corruzione, stregonerie e militari di Luigi Chiarello<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,16,108],"tags":[2393,161],"class_list":["post-5294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-islam","category-paesi-e-continenti","tag-africa","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il freno dell&#039;Africa &egrave; nell&#039;uomo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il freno dell&#039;Africa &egrave; nell&#039;uomo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-14T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-04T14:08:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il freno dell&#8217;Africa &egrave; nell&#8217;uomo\",\"datePublished\":\"2012-11-14T23:00:00+00:00\",\"dateModified\":\"2016-02-04T14:08:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/\"},\"wordCount\":2270,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Islam_Africa.jpg\",\"keywords\":[\"Africa\",\"islam\"],\"articleSection\":[\"Africa\",\"Islam\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/\",\"name\":\"Il freno dell'Africa &egrave; nell'uomo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Islam_Africa.jpg\",\"datePublished\":\"2012-11-14T23:00:00+00:00\",\"dateModified\":\"2016-02-04T14:08:26+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Islam_Africa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Islam_Africa.jpg\",\"width\":276,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-freno-dellafrica-nelluomo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il freno dell&#8217;Africa &egrave; nell&#8217;uomo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il freno dell'Africa &egrave; nell'uomo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/","og_locale":"it_IT","og_type":"article","og_title":"Il freno dell'Africa &egrave; nell'uomo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-11-14T23:00:00+00:00","article_modified_time":"2016-02-04T14:08:26+00:00","og_image":[{"width":276,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il freno dell&#8217;Africa &egrave; nell&#8217;uomo","datePublished":"2012-11-14T23:00:00+00:00","dateModified":"2016-02-04T14:08:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/"},"wordCount":2270,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg","keywords":["Africa","islam"],"articleSection":["Africa","Islam","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/","name":"Il freno dell'Africa &egrave; nell'uomo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg","datePublished":"2012-11-14T23:00:00+00:00","dateModified":"2016-02-04T14:08:26+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/11\/Islam_Africa.jpg","width":276,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-freno-dellafrica-nelluomo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il freno dell&#8217;Africa &egrave; nell&#8217;uomo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5294"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5294\/revisions"}],"predecessor-version":[{"id":30288,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5294\/revisions\/30288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30287"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}