{"id":52922,"date":"2021-11-11T00:00:12","date_gmt":"2021-11-10T23:00:12","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=52922"},"modified":"2024-10-15T09:37:28","modified_gmt":"2024-10-15T07:37:28","slug":"lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/","title":{"rendered":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/ilpensierostorico.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-52923 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg\" alt=\"\" width=\"186\" height=\"271\" \/>Ilpensierostorico.com<\/a><\/strong><\/span> <span style=\"color: #000000;\">3 Novembre 2021\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <\/span><strong><span style=\"color: #000000;\">Danilo Breschi<\/span> <\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abI cattolici tirano a s\u00e9 il cielo, vogliono farlo scendere; gli ortodossi, cercano una via, una scala per salirvi\u00bb. Cos\u00ec, con queste parole, un giovane pope dette molto da riflettere ad Armando Torno, recatosi a San Pietroburgo sulla tracce lasciate da Dostoevskij, a cominciare da quell\u2019ultima casa che oramai sa pi\u00f9 di posticcio e turistico nel suo arredamento interno, eppure qualcosa di autentico ancora conserva, un\u2019atmosfera.<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Quella che sapientemente l\u2019Autore \u00e8 riuscito a restituirci in questo testo che nasce come raccolta e cucitura delle introduzioni che negli anni ha scritto ad alcune opere di Dostoevskij per la collana \u201cIl pensiero occidentale\u201d della Bompiani, diretta all\u2019epoca da Giovanni Reale. Fu proprio questi a spronare Torno a curare alcuni testi dostoevskiani e possiamo dire che mai scelta fu pi\u00f9 azzeccata.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22774 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/04\/Fedor_Dostoevskij-237x300.jpg\" alt=\"\" width=\"237\" height=\"300\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/04\/Fedor_Dostoevskij-237x300.jpg 237w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/04\/Fedor_Dostoevskij.jpg 305w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/>Sfogliando il volume, a cui \u00e8 stata aggiunta una premessa \u00aba mo\u2019 di giustifica\u00bb, si ha modo di cogliere quanto Dostoevskij sia uno scrittore di idee, sostanzialmente un filosofo. Ha ragione Torno nello scrivere, in vari passaggi, quanto segue:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Dostoevskij non \u00e8 autore facile. [&#8230;] la sua opera sfugge da ogni teorizzazione. Anzi, \u00e8 lui stesso che fa perdere le tracce alle idee che mette in gioco, perch\u00e9 l\u2019unica che sembra lo interessi veramente \u00e8 quella di Dio. Le azioni umane non sembrano intelligibili senza di Lui. [&#8230;] denuda impietosamente la coscienza dei suoi eroi lacerandola, crea senza requie \u00a0uno spasmodico crescendo utilizzando i conflitti dei pensieri. I personaggi non li lascia tranquilli e si direbbe che in ogni pagina stiano lottando con la propria mente. [&#8230;] Di certo la sua fede non \u00e8 qualcosa di definito, di sicuro cui aggrapparsi. \u00c8 dubbio, ricerca esasperata, che talvolta si trasforma in tormento (pp. 12-13). <\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43515 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massone_inquisitore_Dostoevskij.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>Soprattutto, per Dostoevskij \u00abi contrasti aiutano a pensare, a dubitare, a comprendere che la vita umana e la societ\u00e0 avranno sempre zone oscure e inesplorabili\u00bb (p. 15). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Detto ci\u00f2, quel che emerge con forza dalla lettura delle pagine che Torno ha dedicato all\u2019opera del grande scrittore russo \u00e8 che ci troviamo di fronte ad un artista che pensa religiosamente. Pi\u00f9 precisamente: un pensatore cristiano. Inutile girarci troppo intorno.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se lo leggi per quel che egli stesso dice, per la mole di appunti preparatori, note di diario, taccuini di lavoro, lettere private, viene fuori sempre e comunque, ineluttabile, l\u2019intelligenza mobile, viva, dunque tormentata e pungente, di un uomo convertitosi al cristianesimo ortodosso russo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Scrive Torno: \u00abci spinge nei grandi romanzi disperatamente verso Dio\u00bb e \u00abci fa capire, insomma, che la morte di Dio non \u00e8 un annuncio filosofico, n\u00e9 un incidente teologico-clinico, ma \u00e8 semplicemente contenuta nella moltiplicazione delle nostre azioni\u00bb (p. 54).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33437 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Idiot_Dostoevskij.jpg\" alt=\"\" width=\"259\" height=\"194\" \/>E dov\u2019\u00e8 il problema? Si chiederanno in molti. \u00c8 da circa un secolo che quel funerale \u00e8 stato celebrato in Europa, nei campi di battaglia della prima guerra mondiale, in quelli di concentramento e sterminio della seconda. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Eppure la vita \u00e8 andata avanti, si \u00e8 rigenerata, nuove generazioni si sono susseguite l\u2019una dopo l\u2019altra.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Non si capisce proprio perch\u00e9 dovremmo leggere ancora un simile scrittore, che ci pone domande spinose, che ritiene essenziale interrogarci sull\u2019eterno, anzitutto sull\u2019esistenza di Dio. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I pi\u00f9 oggi si dilettano con u Dostoevskij relegato al rango di autore di letteratura poliziesca, ritrattista di personaggi foschi, maledetti, noir e dark Tengono la forma e omettono la sostanza delle sue trame e dei personaggi che ora le intrecciano, le aggrovigliano fino quasi all\u2019asfissia del lettore, ora invece le dipanano, per lampi le dischiudono ad una comprensione superiore, che eleva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-52924 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/chiesa_ortodossa_russia.jpg\" alt=\"\" width=\"364\" height=\"240\" \/>Anzi, a scioglierle \u00e8 sovente un evento esterno, che magari agisce nel foro interiore di quegli stessi personaggi, ma che ha altrove la propria scaturigine. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tutto questo rende Dostoevskij uno scrittore unico, qualcuno che oggi circola sotto mentite spoglie, mantenendo la capacit\u00e0 di scuotere il lettore che, ignaro, gli si avvicina cercando qualche brivido e un impercettibile corrugarsi della fronte spacciato per pensiero. Se cadi nella trappola, non c\u2019\u00e8 scampo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo perch\u00e9, come annota Torno commentando l\u2019interpretazione che Nikolaj Berdjaev dette del pensiero dostoevskiano, l\u2019autore di <em>Delitto e castigo<\/em> e dell\u2019 <em>Idiota <\/em>, dei <em>Demon<\/em>i \u00a0e dei <em>Fratelli Karamazov <\/em>\u00abnon \u00e8 un mistico legato a concezioni antiche, immerso in dimensioni ormai perdute, ma un autentico psicologo della fede dell\u2019uomo\u00bb (p. 124). Ovvero:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>al centro della sua meditazione teologica e della sua esegesi biblica, c\u2019\u00e8 quasi la possibilit\u00e0 di constatare il fallimento storico della redenzione, o meglio la delusione della speranza messianica. La fede sembra sperare l\u2019impossibile, eppure \u00e8 irrinunciabile; finisce per essere un tragico ossimoro: tutto ci\u00f2 che l\u2019uomo possiede \u00e8 una sorta di speranza disperata, spes contra spem . E questo aspetto Dostoevskij lo porta a una radicalit\u00e0 estrema, a una travolgente incandescenza. In questa sua odissea fatta di fede e di disperazione c\u2019\u00e8 l\u2019uomo contemporaneo dinanzi alle grandi domande, alle quali \u00e8 sempre pi\u00f9 difficile rispondere (pp.124-125).<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47605 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Fedor_-Dostojevsky.jpg\" alt=\"\" width=\"185\" height=\"272\" \/>Proprio per questa crescente difficolt\u00e0, questa dilagante afasia rispetto alla dimensione trascendente dell\u2019esistenza umana, che, per definizione, \u00e8 qualcosa che sbalza fuori da qualcos\u2019altro (cosa?), urge pi\u00f9 che mai leggere l\u2019opera di Dostoevskij.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma come? Lo scrittore che si aggira e si agita in lungo e largo per i sottosuoli della nostra pi\u00f9 terrigna umanit\u00e0 sarebbe colui che pi\u00f9 ti innalza ai cieli del divino? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ebbene s\u00ec, Dostoevskij scava nelle viscere della terra per sbucare nel centro esatto del nostro destino di esseri umani. Ed \u00e8 qualcosa che eccede dall\u2019orbe terracqueo e va persino oltre l\u2019atmosfera. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 questione di chiamare in causa ci\u00f2 che fa essere tutto questo. Dostoevskij ci sveglia e ci catapulta nello spazio siderale. Dostoevskij, il nostro caro fratello che ci ricorda che siamo fatti anche di pulviscolo stellare.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">____________________<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A. Torno, <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.mondadoristore.it\/Fedor-Dostoevskij-Nostro-Armando-Torno\/eai978889298109\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>F\u00ebdor Dostoevskij. Nostro fratello<\/em> <\/a><\/span>\u00a0Edizioni Ares, Milano 2021, pp. 144, \u20ac 14,00.<\/span><\/p>\n<p>___________________________________<\/p>\n<p><strong>Leggi anche:<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fedor-michajlovic-dostoevskij\/\" target=\"_blank\" rel=\"noopener\">Fedor Michajlovic Dostoevskij<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ilpensierostorico.com 3 Novembre 2021\u00a0 di Danilo Breschi \u00abI cattolici tirano a s\u00e9 il cielo, vogliono farlo scendere; gli ortodossi, cercano una via, una scala per salirvi\u00bb. Cos\u00ec, con queste parole, un giovane pope dette molto da riflettere ad Armando Torno, recatosi a San Pietroburgo sulla tracce lasciate da Dostoevskij, a cominciare da quell\u2019ultima casa che &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":52923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,18],"tags":[1966,265,283],"class_list":["post-52922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri","category-personaggi","tag-fedor-dostoevskij","tag-libri-2","tag-personaggi-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-10T23:00:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T07:37:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"186\" \/>\n\t<meta property=\"og:image:height\" content=\"271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare\",\"datePublished\":\"2021-11-10T23:00:12+00:00\",\"dateModified\":\"2024-10-15T07:37:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/\"},\"wordCount\":950,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Torno_cover.jpg\",\"keywords\":[\"Fedor Dostoevskij\",\"libri\",\"personaggi\"],\"articleSection\":[\"Libri\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/\",\"name\":\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Torno_cover.jpg\",\"datePublished\":\"2021-11-10T23:00:12+00:00\",\"dateModified\":\"2024-10-15T07:37:28+00:00\",\"description\":\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Torno_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Torno_cover.jpg\",\"width\":186,\"height\":271},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica","description":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/","og_locale":"it_IT","og_type":"article","og_title":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica","og_description":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2021-11-10T23:00:12+00:00","article_modified_time":"2024-10-15T07:37:28+00:00","og_image":[{"width":186,"height":271,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare","datePublished":"2021-11-10T23:00:12+00:00","dateModified":"2024-10-15T07:37:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/"},"wordCount":950,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg","keywords":["Fedor Dostoevskij","libri","personaggi"],"articleSection":["Libri","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/","name":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg","datePublished":"2021-11-10T23:00:12+00:00","dateModified":"2024-10-15T07:37:28+00:00","description":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare. Un libro su un autore di idee, sostanzialmente un filosofo.","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Torno_cover.jpg","width":186,"height":271},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-scrittore-grazie-a-cui-ascendi-dostoevskij-fratello-stellare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Lo scrittore grazie a cui ascendi: \u00a0Dostoevskij, fratello stellare"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=52922"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52922\/revisions"}],"predecessor-version":[{"id":61466,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52922\/revisions\/61466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/52923"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=52922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=52922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=52922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}