{"id":52454,"date":"2021-09-16T00:00:53","date_gmt":"2021-09-15T22:00:53","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=52454"},"modified":"2025-07-17T14:53:47","modified_gmt":"2025-07-17T12:53:47","slug":"dallambientalismo-tradizionale-allecologismo-rivoluzionario","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/","title":{"rendered":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/atfp.it\/\">Tradizione<span style=\"color: #000000;\"> Famiglia Propriet\u00e0<\/span><\/a><\/strong><span style=\"color: #000000;\"> Giugno 2021<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\"><strong>&nbsp;<\/strong><em>Da pochi mesi \u00e8 uscito un libretto di Guido Vignelli che confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale: \u00abDa Dio al Buio. L\u2019ecologismo come religone del nuovo ordine mondiale\u00bb (Il Maniero del Mirto, Roma 2020), Cogliamo l&#8217;occasione della \u201cGiornata della<\/em><em> terra\u201d per parlare con l\u2019autore di questo argomento di grande attualit\u00e0 <\/em><\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione-1024x576.jpg\" alt=\"\" class=\"wp-image-52462\" style=\"width:432px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><\/span><wp-block data-block=\"core\/more\"><\/wp-block><span style=\"color: #000000;\"><strong>Lei stabilisce una differenza tra il vecchio ambientalismo e il nuove ecologismo; di cosa si tratta? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">Il vecchie ambientalismo era una difesa della natura e delle attivit\u00e0 umane primarie (agricoltura, allevamento preso, artigianato) dalla invadenza della urbanizzazione e della industrializzazione col conseguente degrado ambientale provocato dall&#8217;inquinamento Il nuove ecologismo invece non mira a tutelare la \u201ccasa comune&#8221; dei viventi mediante un&#8217;armonica e gerarchica convivenza tra l&#8217;uomo e la na-tura, ma mira ad emarginare l&#8217;uomo dalla natura, negandogli ogni diritto non solo di governo ma anche d&#8217;intervento.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">L&#8217;ecologismo radicale mira non tantoa salvare la natura dall&#8217;uomo, quanto ad asservire l\u2019uomo alla natura, a degradare la vita umana al livello istintuale, selvatico, animalesco. Si trat5ta di una rivoluzione antropologica che tenta di abbattere l\u2019ultima diseguaglianza &nbsp;rimasta nella gerarchia del creato: la signoria dell\u2019uomo sugli altrui esseri viventi<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>Cos&#8217;\u00e8 questa ecologia di cui tanto si parla? E\u2019 una scienza, una filosofia, una religione? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">L\u2019odierna ecologia si presenta&nbsp; come scienza dell\u2019ambiente naturale e dei rapporti tra il mondo, le sue parti e i viventi che l\u2019abitano, specialmente l\u2019uomo. Ma i presupposti scientifici degli ecologisti servono solo a dare un\u2019apparenza di oggettivit\u00e0 e indiscutibilit\u00e0 alle loro posizioni e scelte operative, approfittandosi del fatto che, dopo la crisi delle ideologie, la gente attribuisce ancora una sorta di infallibilit\u00e0 a oracoli scientifici che per\u00f2 poi si rivelano sbagliati.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">In realt\u00e0, l&#8217;ecologismo \u00e8 una cosmologia alla rovescia che sovverte la tradizionale concezione dell&#8217;uomo come signore o custode del creato, trasformandola in servo della natura&#8221;. Partendo dal presupposto che tutto \u00e8 connesso l&#8217;ecologismo diuisce l&#8217;umana dignit\u00e0 nel calderone dell&#8217;ambiente (sia umano che naturale), per cui individuo, famiglia e societ\u00e0 sono solo manifestazioni del mondo animale, vegetale e minerale.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">Ecco perch\u00e9 i capi dell&#8217;ecologismo radicale si comportano come guru di una religione cosmica che venera l&#8217;idolo della Madre Terra (Gaia Gea o Pacha Mama). In questo modo, si tenta di ricuperare le origini gnostiche (ossia irrazionali) della Rivoluzione anticristiana, presentandosi come fautori di una pseudo-religione dedita al culto della Natura.<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>Quando nasce questo ecologismo anti-umano?<\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">fine degli anni 1960. le moderne promesse di pace, sicurezza ricchezza si erano rivelate deludenti e la giovent\u00f9 contestatrice reag\u00ec passando da un eccesso di civilt\u00e0 a un eccesso di barbarie. Alcuni movimenti rivoluzionari nati dal &#8217;68 rovesciarono la loro prospettiva progressista e tecnologica in una prospettiva regressista e tribale, passando dal marxismo all&#8217;ecologismo, dall&#8217;antropo-centrismo al cosmo-centrismo. Avendo fallito nel tentativo di costruire una nuova civilt\u00e0, oggi quei movimenti ripiegano nel \u201cdecostruire&#8221; la residua civilt\u00e0 cristiana al fine di sostituirla con un&#8217;anti-civilt\u00e0 tribale, come il prof. Plinio Corr\u00eaa de Oliveira aveva denunciato fin dal 1977<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>E\u2019 credibile l&#8217;ecologia in salsa cattolica oggi propostaci? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">Sull&#8217;onda della nuova &#8220;teologia della liberazione&#8221; latino-americana, oggi la Gerarchia ecclesiastica tenta di adattarsi alla moda culturale inventando una &#8220;ecologia integrale&#8221;, ossia una ideologia capace di conciliare primitivismo e pauperismo col mantenimento delle conquiste sociali della civilt\u00e0 del benessere. Gli stessi documenti di papa Francesco (Laudato si&#8217; e Fratelli tutti) oscillano ambiguamente tra il &#8220;rosso della prospettiva socialista e il verde&#8221; di quella ecologista; ma questa posizione equilibrista non convince nella teoria e non funziona nella pratica.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">In realt\u00e0, la sicurezza sociale e la protezione sindacale finora garantite ai lavoratori furono preparate proprio da quella Cristianit\u00e0 oggi rifiutata dalla Gerarchia ecclesiastica come &#8220;integrista&#8221;. La soluzione sta nell&#8217;opporsi alla idolatria ecologista riaffermando Dio come creatore, legislatore e provvidente, e il conseguente concetto di ordine naturale creato, al fine di ricuperare la prospettiva del vero ambientalismo, inteso come restaurazione sia della natura secondo il progetto divino, sia della sovvertita societ\u00e0 umana secondo il diritto cristiano e la dottrina sociale della Chiesa<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>C&#8217;\u00e8 un nesso tra l&#8217;ecologismo, il cosiddetto &#8220;Great Reset&#8221; e la pandemia oggi dilagante? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">La rivoluzione ecologista fu occultamente prevista fin dall&#8217;inizio del XX secolo dalla setta para-massonica nota come Sinarchia, poi fu apertamente programmata da convegni dell&#8217;ONU e dell&#8217;Unesco; infine \u00e8 stata progettata da influenti circoli culturali, politici ed economici globalisti per bocca di guru intellettuali come Edgar Morin, Michel Serres, Henry Atlan, e per opera di economisti come Jacques Attali George Soros Klaus Schwab Oggi quella rivoluzione ufficialmente riproposta sotto la forma del Gran Reset (\u201cgrande azzeramento&#8221;) promosso dal World Economic Forum di Davos.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">Le recenti vicende confermano l&#8217;abilit\u00e0 de capi rivoluzionari nell&#8217;approfittarsi delle vantaggiose occasioni offerte da avvenimenti devastanti (crisi conomiche, carestie. Epidemie, guerre) che spingono l&#8217;opinione pubblica impaurita a reclamare interventi totalitari. Ad esempio Klaus Schwab ha ammesso che la crisi sanitaria mondiale prodotta dal virus cinese costituisce una decisiva occasione per sistemare le cose intervista ad Euronews. 19-11-2020)<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\">\u201c<strong>Niente sar\u00e0 pi\u00f9 come prima&#8221;; &#8220;la crisi far\u00e0 nascere un mondo nuovo&#8221;: &#8220;cambiare le abitudini della vita quotidiana&#8221;: &#8220;rivedere i tempi e i modi della nostra vita&#8221;: &#8220;rinunciare alla vita comoda e sicura&#8221;. Questi slogan ecologisti sono stati rilanciati dalla propaganda sanitaria del Governo italiano. C\u2019\u00e8 un legame tra i due fenomeni? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"color: #000000;\">La pandemia cinese costituisce una occasione storica per i promotori della rivoluzione ecologista ma anche una occasione per rilanciare una nuova internazionale socialista che abbatta il regime capitalistico e il sistema borghese. Lo ha ammesso lo stesso ministro della Sanit\u00e0 (Speranza). La politica statale degli ultimi due anni costituisce una sorta di sperimentazione sociale tentata dal Governo.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">Dapprima, quello che ho chiamato \u201ccirco mediatico-sanitario\u201d ha terrorizzato la cittadinanza sulle possibili conseguenze della epidemia. Poi il Governo ha avviato una politica di emergenza che ha imposto un dispotismo statalista terapeutico (come lo ha chiamato il giornalista Aldo Maria Valli), che ha sospeso molti diritti civili (anche costituzionali) impedendo la circolazione di persone, idee e merci. In questo modo, la produzione e il commercio privati sono stati messi in crisi, consegnando l&#8217;economia in potere del settore pubblico o delle multinazionali. L&#8217;imminente crollo sociale permetter\u00e0 forse al globalismo di ridurre alla impotenza quella classe media e quegli ambienti conservatori capaci di opporsi alla &#8220;svolta ecologica&#8221;.<\/span><\/p>\n\n\n\n<p><span style=\"font-size: inherit; color: #000000;\">Le vittime di questo esperimento sociale saranno la famiglia, la scuola, la libera comunicazione, la classe borghese, la piccola e media impresa, l&#8217;economia privata, il turismo: ossia. guarda caso, proprio i fattori accusati dal- l&#8217;ecologismo di causare il degrado ambientale. Cosi facendo, pero, il popolo avr\u00e0 venduto l&#8217;anima nella illusione di salvare il corpo <\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong style=\"font-size: inherit;\">Pu\u00f2 illustrarci i possibili sviluppi dell&#8217;attuale crisi previsti alla fine del suo libro? <\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"font-size: inherit; color: #000000;\">Siamo a un bivio decisivo tra due possibili sviluppi: o la setta ecologista riuscit\u00e0 a sottomettere completamente quel che resta della libera societ\u00e0 civile, prima che questa possa reagire alla offensiva globalista, oppure la societ\u00e0 civile riuscir\u00e0 a sconfiggere questa offensiva, prima che la setta ecologista possa ridurla alla miseria e al silenzio. Le recenti reazioni popolari alla offensiva ecologista espresse dalla classe media conservatrice e produttiva fanno sperare che la societ\u00e0 civile non sia disposta ad arrendersi senza combattere. <\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong style=\"font-size: inherit;\">In origine, l&#8217;ecologia non era forse un argomento sollevato dal mondo tradizionale contro le devastazioni prodotte dalla modernit\u00e0 progressista e tecnocratica?<\/strong><\/span><\/h4>\n\n\n\n<p><span style=\"font-size: inherit; color: #000000;\">Effettivamente, fin dall&#8217;inizio del secolo XIX, la difesa dell&#8217;ambiente (specialmente rurale) fu un argomento tipico della cultura e della politica cristiana tradizionale. Purtroppo per\u00f2, dalla esplosione del sessantottismo in poi, questa bandiera della Destra fu sequestrata e fatta propria dalla Sinistra, nella illusione di opporre alla borghesia trionfante un&#8217;alternativa sociale che fosse non idilliaca e bucolica ma selvatica e tribale. <\/span><\/p>\n\n\n\n<p><span style=\"font-size: inherit; color: #000000;\">Fin dagli anni Settanta, il prof. Plinio Corr\u00eaa de Oliveira not\u00f2 questa incapacit\u00e0 degli ambienti tradizionali di opporre al modello del progressismo tecnocratico quello di una societ\u00e0 in sintonia con la natura, incapacit\u00e0 dovuta anche a un certo timore di sembrare retrogradi e utopisti. Tuttavia, oggi questa offensiva ecologista pu\u00f2 dare occasione alle forze tradizionali di ricuperare il tema del sano ambientalismo; \u00e8 ci\u00f2 che speriamo e per cui lottiamo.<\/span><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradizione Famiglia Propriet\u00e0 Giugno 2021 &nbsp;Da pochi mesi \u00e8 uscito un libretto di Guido Vignelli che confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale: \u00abDa Dio al Buio. L\u2019ecologismo come religone del nuovo ordine mondiale\u00bb (Il Maniero del Mirto, Roma 2020), Cogliamo l&#8217;occasione della \u201cGiornata della terra\u201d per parlare con l\u2019autore di questo argomento di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":52462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,54],"tags":[1708,386,237],"class_list":["post-52454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","category-rivoluzione-e-controrivoluzione","tag-ecologismo","tag-rivoluzione","tag-totalitarismo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T22:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T12:53:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario\",\"datePublished\":\"2021-09-15T22:00:53+00:00\",\"dateModified\":\"2025-07-17T12:53:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/\"},\"wordCount\":1372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"keywords\":[\"ecologismo\",\"Rivoluzione\",\"totalitarismo\"],\"articleSection\":[\"Ambientalismo\",\"Rivoluzione e controrivoluzione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/\",\"name\":\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"datePublished\":\"2021-09-15T22:00:53+00:00\",\"dateModified\":\"2025-07-17T12:53:47+00:00\",\"description\":\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica","description":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/","og_locale":"it_IT","og_type":"article","og_title":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica","og_description":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2021-09-15T22:00:53+00:00","article_modified_time":"2025-07-17T12:53:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario","datePublished":"2021-09-15T22:00:53+00:00","dateModified":"2025-07-17T12:53:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/"},"wordCount":1372,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","keywords":["ecologismo","Rivoluzione","totalitarismo"],"articleSection":["Ambientalismo","Rivoluzione e controrivoluzione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/","name":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","datePublished":"2021-09-15T22:00:53+00:00","dateModified":"2025-07-17T12:53:47+00:00","description":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario. Un libro confuta l\u2019ideologia e il progetto politico dell\u2019ecologismo radicale","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dallambientalismo-tradizionale-allecologismo-rivoluzionario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Dall\u2019ambientalismo tradizionale all\u2019ecologismo rivoluzionario"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=52454"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52454\/revisions"}],"predecessor-version":[{"id":63375,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/52454\/revisions\/63375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/52462"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=52454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=52454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=52454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}