{"id":5207,"date":"2012-09-27T00:00:00","date_gmt":"2012-09-26T22:00:00","guid":{"rendered":""},"modified":"2015-05-08T17:42:59","modified_gmt":"2015-05-08T15:42:59","slug":"un-fiore-nella-desolazione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/","title":{"rendered":"Un fiore nella desolazione"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-24348\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png\" alt=\"Takashi Nagai\" width=\"151\" height=\"200\" \/><\/a>L\u2019Osservatore Romano<\/strong> n.14, marted\u00ec 5 aprile 2011<\/div>\n<p style=\"text-align: center;\"><em>II Giappone di fronte alle prove antiche e nuove<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Ferdinando Cancelli<\/strong><\/p>\n<p style=\"text-align: justify;\">Un padre si aggira per le rovine fumanti di Nagasaki. Vicina a lui, in lacrime, la sua piccola figlia trova un fiore spuntato in quella desolazione: \u00abNon piangere, vedi bene che il buon Dio non ci ha completamente abbandonati\u00bb le dice il papa. A raccogliere delicatamente e a riferire queste parole del dottor Takashi Nagai \u00e8 padre Christian de Cherg\u00e9, priore di Notre Dame de l&#8217;Atlas a Tibhirine, nell&#8217;omelia per l&#8217;Immacolata del 1993.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">Pur riferendo un solo dettaglio della tragica e coraggiosa vita di un giapponese della prima met\u00e0 del secolo scorso, il monaco dischiude uno spiraglio che ci aiuta a ricordare la figura di un cattolico giapponese e a comprendere meglio la compostezza di un popolo duramente provato allora come oggi.<\/p>\n<p style=\"text-align: justify;\">Takashi, il cui nome significa \u00abnobilt\u00e0\u00bb, nacque nel 1908 vicino a Hiroshima da una nobile famiglia che lo alleva nel solco della tradizione shintoista. Approdato come il padre agli studi medici, trover\u00e0 alla facolt\u00e0 di medicina dell&#8217;universit\u00e0 di Nagasaki un clima materialista e riduzionista. Sar\u00e0 per\u00f2 il confronto con la morte della madre, discendente da un&#8217;antica famiglia di samurai, a imprimere alla sua vita un orientamento nuovo.<\/p>\n<p style=\"text-align: justify;\">Ricordando infatti quei momenti trascorsi il 29 marzo 1930 seduto accanto al suo letto, scriver\u00e0: \u00abAttraverso quell&#8217;ultimo penetrante sguardo mia madre demol\u00ec il quadro ideologico che io mi ero costruito. Questa donna, che mi aveva messo al mondo e allevato, questa donna che non si era mai concessa un momento di riposo nel suo amore per me, negli ultimi istanti della sua vita mi parl\u00f2 molto chiaramente. Il suo sguardo mi diceva che lo spirito umano continua a vivere dopo la morte. Tutto questo veniva come un&#8217;intuizione, un&#8217;intuizione che aveva il sapore della verit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il Signore, ancora solo sull&#8217;uscio, busser\u00e0 pi\u00f9 forte e lo far\u00e0 mettendo nelle mani di Takashi i Pensieri di Blaise Pascal: \u00abCosa dovr\u00e0 mai essere questa fede cattolica \u2014 si chiede il giovane \u2014 perch\u00e9 il sapiente Pascal abbia potuto accettarla senza rinnegare la sua scienza?\u00bb. Il suo cuore \u00e8 ormai abitato e lo porter\u00e0 a scegliere una famiglia cattolica per alloggiare durante i suoi studi: Sadakichi Moriyama e la sua sposa sono discendenti di una casata giapponese che ha saputo, durante lunghe persecuzioni, conservare accesa la fiamma della fede cattolica<\/p>\n<p style=\"text-align: justify;\">Sar\u00e0 la loro giovane figlia Maria Midori a invitare, la sera del 24 dicembre 1932, il giovane Takashi alla messa di mezzanotte: \u00abHo sentito Qualcuno vicino a me che non conoscevo ancora\u00bb scriver\u00e0 qualche anno pi\u00f9 tardi nel libro Una luce su Nagasaki il giovane ormai divenuto medico riferendosi a quella celebrazione. Battezzato il 9 giugno 1934 con il nome di Paolo in onore di san Paolo Miki, Takashi sposa nello stesso anno Maria Midori dalla quale avr\u00e0 quattro figli: \u00e8 ormai sordo dall&#8217;orecchio destro per le conseguenze di una severa otite e dovr\u00e0 rinunciare alla medicina clinica per l&#8217;impossibilit\u00e0 di servirsi dello stetoscopio.<\/p>\n<p style=\"text-align: justify;\">Il Signore infatti stava preparando per lui un avvenire diverso: si dedicher\u00e0, supportato costantemente dalla moglie, alla radiologia, branca della medicina che muoveva ancora i primi passi esponendo i suoi pionieri al pericolo costante delle radiazioni ionizzanti.<\/p>\n<p style=\"text-align: justify;\">Influenzato anche dagli incontri con padre Massimiliano Kolbe \u2014 che tra il 1931 e il 1936 risiedeva in un sobborgo di Nagasaki ove aveva fondato un convento \u2014 Takashi diverr\u00e0 un vero apostolo della carit\u00e0 per i suoi malati: \u00abL&#8217;opera di un medico \u00e8 di soffrire e di rallegrarsi con i suoi pazienti, di ingegnarsi a diminuire le loro sofferenze come se fossero le proprie\u00bb. Da allora quest&#8217;uomo, che nei momenti di sconforto trover\u00e0 nel rosario e nella Madonna la forza per andare avanti, percorrer\u00e0 la strada della sofferenza e del servizio che lo porter\u00e0 pi\u00f9 vicino a Ges\u00f9 e ai fratelli.<\/p>\n<p style=\"text-align: justify;\">Quando il 9 agosto del 1945 una seconda bomba atomica viene sganciata sul Giappone, a essere colpita \u00e8 proprio la citt\u00e0 di Nagasaki, in particolare il quartiere nord di Urakami: il dottor Nagai, gi\u00e0 dal giugno di quello stesso anno consapevole di essere malato di leucemia, alle 11.02 si trova al lavoro nel proprio servizio di radiologia situato a 700 metri dal punto di esplosione e viene seriamente ferito.<\/p>\n<p style=\"text-align: justify;\">Solo l\u201911 agosto, dopo essersi dedicato con tutte le forze alla cura dei feriti, riuscir\u00e0 a ritrovare le macerie della propria casa e i pochi resti carbonizzati della moglie, allora trentasettenne, Maria Midori. Accanto \u2014 scriver\u00e0 \u2014 giaceva una corona del rosario.<\/p>\n<p style=\"text-align: justify;\">Takashi, giunto in punto di morte, si ristabilir\u00e0 dopo aver pregato intensamente padre Kolbe e vorr\u00e0 essere tra i primi a riabitare quel quartiere di Urakami devastato dalla bomba atomica: far\u00e0 ricostruire, con i materiali ricavati dalla propria casa distrutta, una piccola baracca dalla superficie pari a quella di due tatami e la chiamer\u00e0 Nyokodo (che significa \u00abcome te stesso\u00bb, dal precetto evangelico \u00abama il prossimo tuo come te stesso\u00bb). Vi abiter\u00e0 con i due figli sopravvissuti Makoto e Kayano e con altri parenti.<\/p>\n<p style=\"text-align: justify;\">Comincer\u00e0 a dedicarsi ai moltissimi orfani di Nagasaki (per i quali fonder\u00e0 anche una biblioteca) e a scrivere libri: tra questi, Le campane di Nagasaki che, insieme all&#8217;opera del figlio Makoto, \/\/ sorr\u00ecso delle campane di Nagasaki, \u00e8 forse l&#8217;opera che pi\u00f9 ha contribuito a diffonderne il messaggio di pace.<\/p>\n<p style=\"text-align: justify;\">Il dottor Nagai morir\u00e0 nel 1951, il primo maggio, mese dedicato a Maria. La folla che segue il suo funerale, nella cattedrale di Urakami, alla fine della cerimonia si mette in marcia per il cimitero distante un chilometro: i primi vi giungeranno quando molti non saranno ancora riusciti a uscire dalla cattedrale.<\/p>\n<p style=\"text-align: justify;\">Ancora oggi nel quartiere \u00e8 possibile passeggiare sotto alcuni dei mille ciliegi da lui piantati per far rifiorire la terra devastata, dove il suo Nyokodo \u00e8 diventato il Nagasaki City Nagai Takashi Memorial Museum diretto dal nipote Tokusaburo Nagai.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Osservatore Romano n.14, marted\u00ec 5 aprile 2011 II Giappone di fronte alle prove antiche e nuove di Ferdinando Cancelli Un padre si aggira per le rovine fumanti di Nagasaki. Vicina a lui, in lacrime, la sua piccola figlia trova un fiore spuntato in quella desolazione: \u00abNon piangere, vedi bene che il buon Dio non ci &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,18],"tags":[548,2094],"class_list":["post-5207","post","type-post","status-publish","format-standard","hentry","category-chiesa","category-personaggi","tag-giappone","tag-nagai-takashi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un fiore nella desolazione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un fiore nella desolazione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-08T15:42:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Un fiore nella desolazione\",\"datePublished\":\"2012-09-26T22:00:00+00:00\",\"dateModified\":\"2015-05-08T15:42:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/\"},\"wordCount\":961,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Takashi-Nagai.png\",\"keywords\":[\"Giappone\",\"Nagai Takashi\"],\"articleSection\":[\"Chiesa\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/\",\"name\":\"Un fiore nella desolazione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Takashi-Nagai.png\",\"datePublished\":\"2012-09-26T22:00:00+00:00\",\"dateModified\":\"2015-05-08T15:42:59+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Takashi-Nagai.png\",\"contentUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Takashi-Nagai.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-fiore-nella-desolazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un fiore nella desolazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un fiore nella desolazione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/","og_locale":"it_IT","og_type":"article","og_title":"Un fiore nella desolazione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-09-26T22:00:00+00:00","article_modified_time":"2015-05-08T15:42:59+00:00","og_image":[{"url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png","type":"","width":"","height":""}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Un fiore nella desolazione","datePublished":"2012-09-26T22:00:00+00:00","dateModified":"2015-05-08T15:42:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/"},"wordCount":961,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png","keywords":["Giappone","Nagai Takashi"],"articleSection":["Chiesa","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/","name":"Un fiore nella desolazione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png","datePublished":"2012-09-26T22:00:00+00:00","dateModified":"2015-05-08T15:42:59+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#primaryimage","url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png","contentUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Takashi-Nagai.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-fiore-nella-desolazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Un fiore nella desolazione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5207"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5207\/revisions"}],"predecessor-version":[{"id":24349,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5207\/revisions\/24349"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}