{"id":5206,"date":"2012-09-20T00:00:00","date_gmt":"2012-09-19T22:00:00","guid":{"rendered":""},"modified":"2015-09-04T11:35:43","modified_gmt":"2015-09-04T09:35:43","slug":"la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/","title":{"rendered":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26760\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg\" alt=\"kyenge\" width=\"250\" height=\"187\" \/><\/a>Radici cristiane<\/strong> n.77 settembre 2012<\/div>\n<p style=\"text-align: justify;\"><em>Una riflessione sulla delicata questione della volont\u00e0 di cambiamento del concetto stesso di cittadinanza statale, fra ordine morale e tendenze al caos mondialista.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Luca Galantini<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Lo scenario politico internazionale contemporaneo sembra essere dominato dal tramonto degli Stati sovrani. In realt\u00e0 nell&#8217;universo contemporaneo \u2014 pur perdendo quote di sovranit\u00e0 \u2014 gli Stati non scompaiono. L&#8217;ordinamento giuridico globale &#8211; la celebre societ\u00e0 aperta vaticinata da Hayek e Kelsen \u2014 risulta a oggi una organizzazione centrifuga, senza centro, e somiglia a un aggregato caotico, molto frammentato, asimmetrico, come bene osserva Zygmun Baumann: un regime permanente di confusione di poteri e funzioni un tempo esclusiva dello Stato.<\/div>\n<p style=\"text-align: justify;\">Se si considera come sia rovinosamente fallita a oggi l&#8217;aspettativa della societ\u00e0 politica globalizzata, secondo i paradigmi troppo spesso retorici dei diritti umani, del multi-culturalismo e della democrazia, viene spontaneo porsi la domanda se questa logica di una &#8220;cooperazione senza sovranit\u00e0&#8221;, di una societ\u00e0 politica reticolare e priva del modello dello Stato sia in grado di governare il processo di globalizzazione che.\u2014 ricordiamolo bene &#8211; \u00e8 processo prima ancora che integrativo, disintegrativo.<\/p>\n<p style=\"text-align: justify;\">Se le cose stanno in questi termini &#8211; ed \u00e8 ragionevolmente difficile negarlo &#8211; \u00e8 pi\u00f9 che comprensibile la necessit\u00e0 doverosa di acribia nell\u2019affrontare il delicatissimo tema giuridico-istituzionale della riforma dello status di cittadinanza, che in tempi recenti \u00e8 stato poste in discussione da autorevoli rappresentanti della politica italiana, dal Presidente Napolitano al Ministro per la Cooperazione Riccardi. Alcune brevi osservazioni.<\/p>\n<p style=\"text-align: justify;\"><strong>Ridefinire il concetto di cittadinanza?<\/strong><\/p>\n<p style=\"text-align: justify;\">La cittadinanza \u00e8 uno status, non un mero diritto, cio\u00e8 non \u00e8 una semplice facolt\u00e0 di cui pu\u00f2 disporre il singolo individuo. Infatti con l&#8217;acquisto della cittadinanza la persona entra a far parte del &#8220;popolo&#8221; italiano, come afferma uno dei pi\u00f9 celebri costituzionalisti italiani, Paolo Barile, ed \u00e8 chiamata a precisi doveri nei confronti della Stato, tra cui la fedelt\u00e0 ai valori della Repubblica (art. 53) e il concorso alla spesa pubblica (art. 54).<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 significa che la giurisprudenza stessa dei padri della Costituzione repubblicana richiede, ai fini della qualificazione della cittadinanza, una complessit\u00e0 di valori identitari, etici, culturali e linguistici &#8211; in altri termini pre-politici \u2014 che non sono viceversa oggetto di considerazione con riferimento a un semplice diritto privato.<\/p>\n<p style=\"text-align: justify;\">La cittadinanza va ben oltre un mero fondamentale diritto privato come pu\u00f2 essere la propriet\u00e0, in quanto \u00e8 la base, il pilastro metagiuridico, quindi anche culttarale e filosofico, che giustifica il concetto stesso di Stato e popolo. Prova ne sia che la dottrina del diritto costituzionale considera cittadini anche le persone\u00a0 giuridiche e le associazioni che hanno la &#8220;nazionalit\u00e0&#8221; italiana, ovvero i corpi intermedi della societ\u00e0 italiana. Questo punto apre un&#8217;altra finestra, in quanto introduce il concetto di nazione, che \u00e8 sociologico, a base identitaria, linguistica, culturale.<\/p>\n<p style=\"text-align: justify;\">Queste brevi riflessioni per rammentare che i diritti sono sempre riconducibili a un popolo &#8211; cio\u00e8 ad una societ\u00e0 civile omogeneamente e storicamente organizzata &#8211; e questo a un territorio (elementi fondamentali, assieme alla sovranit\u00e0, dello Stato, secondo il diritto costituzionale).<\/p>\n<p style=\"text-align: justify;\">Dunque ogni ipotesi di ridefinizione di cittadinanza non si risolve semplicisticamente con l&#8217;abbreviazione del periodo di permanenza sul territorio del cittadino extracomnitario, ovvero con la introduzione dello <em>jus soli <\/em>in luogo dello <em>jus sanguinis <\/em>a favore dei figli di cittadini extracomunitari nati in territorio italiano (si tratta di istituti che hanno pari dignit\u00e0 razionale), ma richiede una ben altra congegnata riflessione costituzionale e ben altra proposta culturale che sappia considerare adeguatamente i valori comuni identitari di nazione, popolo, lingua e religione come elementi di virtuosa e armoniosi di crescita del bene comune nel quadro policentrico di un universo politico in profonda incerta mutazione.<\/p>\n<p style=\"text-align: justify;\"><strong>Cittadinanza e stato nazionale<\/strong><\/p>\n<p style=\"text-align: justify;\">Alcuni tra i principali studiosi di relazioni nazionali e societ\u00e0 politiche, da R. Robertson a Susan Strange, sostenitori della teoria del declino della sovranit\u00e0 degli Stati nazionali successivamente al crollo del totalitarismo comunista e della formazione di una &#8220;societ\u00e0 globale&#8221;, transanzionale e immune da connotazioni territoriali, si sono ricreduti in quest&#8217;avvio di millennio, riconoscendo la profonda valenza delle identit\u00e0 culturali e territoriali come fattori di stabilit\u00e0 e inclusione sociale.<\/p>\n<p style=\"text-align: justify;\">Lo stesso Premio Nobel Amartya Sen si \u00e8 espresso in tal senso, paventando i tremendi rischi di una societ\u00e0 &#8220;liquida&#8221; priva di riferimenti identitari e in balia del velleitario <em>melting pot <\/em>multietnico, multireligioso e multiculturale. La stessa UE nega l&#8217;acquisto della cittadinanza del Paese di residenza ai cittadini di Paesi membri dell&#8217;Unione stessa, anche se presenti da anni, ma si rimette alla legislazione dei singoli Stati di appartenenza. Il concetto stesso di cittadinanza europea risulta ad oggi un <em>wishful tinking <\/em>che gli Stati membri si guardano bene dal tradurre in pratica.<\/p>\n<p style=\"text-align: justify;\">Infine. Il diritto di voto stesso si lega non tanto alla permanenza sul territorio straniero, quanto alla partecipazione alla costruzione della <em>respublica <\/em>e della <em>communis opinio<\/em> di una societ\u00e0 civile. In caso contrario infatti risulta strumentale e non favorisce l&#8217;integrazione matura tra persone provenienti da radicali differenti esperienze di societ\u00e0 civile.<\/p>\n<p style=\"text-align: justify;\">La stessa U\u00c8 infatti distingue tra cittadinanza europea e cittadinanza del singolo Stato di appartenenza, privilegiando la seconda rispetto alla prima in materia di diritto di voto politico e amministrativo. A maggior ragione non vi \u00e8 logica nel fatto che cittadini extra UE possano vantare status o diritti come il voto che presuppongo non solo la fiscalit\u00e0, ma anche la cittadinanza.<\/p>\n<p style=\"text-align: justify;\">Si rammenter\u00e0 certamente il monito del filosofo Thoreau, che legittimava il cittadino a non pagare le tasse ove le stesse fossero utilizzate dallo Stato per progetti e opere immorali.<\/p>\n<p style=\"text-align: justify;\">Non vi \u00e8 dubbio che lo Stato nazionale come abbiamo imparato a conoscerlo nel XX secolo &#8211; basato sui concetti di popolo, territorio e sovranit\u00e0 &#8211; present\u00ec un&#8217;immagine problematica con pi\u00f9 ombre che luci, ma appare poco lungimirante portarlo sul banco degli accusati in nome della sua inadeguatezza a far fronte alle sfide della globalizzazione: infatti qualunque organizzazione politico-giuridica tollera un certo grado di eterogeneit\u00e0 e conflittualit\u00e0 sociale a condizione che il pluralismo si mantenga entro colturali determinati e condivisi.<\/p>\n<p style=\"text-align: justify;\">Il bene comune esige la &#8220;polifonia&#8221; bdei valori, come rammentano Joseph Ratzinger e Jurgen Habermas nel loro colloquio alla Katholische Akademie di Monaco, e non il caos istituzionalizzato.<\/p>\n<p style=\"text-align: justify;\">______________________________<\/p>\n<p style=\"text-align: justify;\"><strong>leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=2207\" target=\"_blank\">Multiculturalismo e cittadinanza breve<br \/>\n<\/a><br \/>\n<a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=4945\" target=\"_blank\">Giusnaturalismo e identit\u00e0 dei popoli<\/a><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=4945\" target=\"_blank\"><br \/>\n<\/a><br \/>\n<\/strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=4832\" target=\"_blank\">Italiani si nasce, cittadini si diventa<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radici cristiane n.77 settembre 2012 Una riflessione sulla delicata questione della volont\u00e0 di cambiamento del concetto stesso di cittadinanza statale, fra ordine morale e tendenze al caos mondialista. di Luca Galantini<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":26760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[241],"class_list":["post-5206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immigrazione","tag-cittadinanza","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-19T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-04T09:35:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La concessione della cittadinanza. Tra riforma dello Stato e bene comune\",\"datePublished\":\"2012-09-19T22:00:00+00:00\",\"dateModified\":\"2015-09-04T09:35:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/\"},\"wordCount\":1033,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/kyenge.jpg\",\"keywords\":[\"cittadinanza\"],\"articleSection\":[\"Immigrazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/\",\"name\":\"La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/kyenge.jpg\",\"datePublished\":\"2012-09-19T22:00:00+00:00\",\"dateModified\":\"2015-09-04T09:35:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/kyenge.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/kyenge.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La concessione della cittadinanza. Tra riforma dello Stato e bene comune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/","og_locale":"it_IT","og_type":"article","og_title":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-09-19T22:00:00+00:00","article_modified_time":"2015-09-04T09:35:43+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune","datePublished":"2012-09-19T22:00:00+00:00","dateModified":"2015-09-04T09:35:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/"},"wordCount":1033,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg","keywords":["cittadinanza"],"articleSection":["Immigrazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/","name":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg","datePublished":"2012-09-19T22:00:00+00:00","dateModified":"2015-09-04T09:35:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/kyenge.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-concessione-della-cittadinanza-tra-riforma-dello-stato-e-bene-comune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La concessione della cittadinanza. Tra riforma dello Stato e bene comune"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5206"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5206\/revisions"}],"predecessor-version":[{"id":26761,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5206\/revisions\/26761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26760"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}