{"id":5200,"date":"2012-09-20T00:00:00","date_gmt":"2012-09-19T22:00:00","guid":{"rendered":""},"modified":"2016-03-16T09:36:39","modified_gmt":"2016-03-16T08:36:39","slug":"attraverso-le-tenebre","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/","title":{"rendered":"Attraverso le tenebre"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-31820\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg\" alt=\"Defanti_cover\" width=\"131\" height=\"200\" \/>L\u2019Osservatore Romano<\/strong> n.34-35, marted\u00ec 28 agosto 2012<\/div>\n<p style=\"text-align: center;\"><em>Limiti e pregi di una nuova storia dell&#8217;eugenetica<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Lucetta Scaraffia<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">In Italia il celebre neurologo e studioso di bioetica Carlo Alberto Defanti ha scritto un libro sull&#8217;eugenetica (<em>Eugenetica: un tab\u00f9 contemporaneo. Storia di un&#8217;idea controversa, <\/em>Torino, Codice edizioni, 2012, pagine XV + 309, euro 23) con il coraggioso intento di fare chiarezza su un dubbio che serpeggia nella nostra societ\u00e0 e di cui spesso cerchiamo di sbarazzarci senza successo, e cio\u00e8 \u00abse gli orrori della cosiddetta eutanasia nazista e poi quelli della Shoah siano stati o no una delle possibili derive dell&#8217;eugenetica\u00bb.<\/div>\n<p style=\"text-align: justify;\">E quindi se dobbiamo, di conseguenza, sottoporre a critica severa i comportamenti biopolitici, oggi in atto, che possono essere ricondotti per certi versi all&#8217;eugenetica, come l&#8217;aborto cosiddetto terapeutico o la selezione embrionale degli embrioni pi\u00f9 sani.<\/p>\n<p style=\"text-align: justify;\">Lo studioso giustamente pensa che per rispondere a questa domanda sia necessario tornare all&#8217;Ottocento, alla nascita dell&#8217;eugenetica nell&#8217;Inghilterra darwiniana e alla rapida diffusione di questa nuova scienza nei Paesi occidentali, fino a includere la Germania nazista. Non \u00e8 la prima volta che Defanti coglie un aspetto importante della riflessione bioetica: quello della necessit\u00e0 della riflessione storica per comprendere meglio alcune questioni, come l&#8217;eutanasia.<\/p>\n<p style=\"text-align: justify;\">E bisogna ammettere che affronta questa ricostruzione del passato con una preparazione e un rigore che quasi mai i suoi colleghi dimostrano quando si accingono, come per divertimento, a cimentarsi con la storia.<\/p>\n<p style=\"text-align: justify;\">Ricostruire la storia dell&#8217;eugenetica non \u00e8 certo impresa facile, nonostante negli ultimi decenni siano usciti tanti studi sul tema, perch\u00e9 si \u00e8 trattato di una sorta di moda scientifica, che poi in molti casi \u00e8 diventata pratica politica. A sua volta questa si \u00e8 diffusa con straordinario successo in tutti i Paesi occidentali, creando uno strato di esperti, in genere anche abili divulgatori, che per la prima volta hanno coinvolto l&#8217;opinione pubblica nelle loro proposte di miglioramento del genere umano.<\/p>\n<p style=\"text-align: justify;\">Uno strato numeroso e osannato, ma poi velocemente dimenticato e nascosto dopo la seconda guerra mondiale, cio\u00e8 dopo che l&#8217;eugenetica \u00e8 diventata sinonimo di nazismo. Troppi protagonisti, quindi, e in parte dimenticati. Invece non era cos\u00ec, e su questo punto lo studioso ha ragione.<\/p>\n<p style=\"text-align: justify;\">L&#8217;eugenetica \u00e8 nata e si \u00e8 diffusa al di fuori della Germania nazista, prima dell&#8217;avvento al potere di Hitler, e per molti versi ha continuato a essere messa in pratica anche in seguito, ma con modalit\u00e0 meno crudeli e soprattutto meno efficaci di quelle tedesche. Egli arriva quindi a concludere che \u00abla messa in opera di pratiche aberranti vada messa in conto non a un&#8217;irresistibile pulsione propria del biopotere, ma semplicemente al venir meno dell&#8217;ordinamento liberaldemocratico e all&#8217;avvento di un regime totalitario\u00bb.<\/p>\n<p style=\"text-align: justify;\">In sostanza Defanti, nel ricostruire ampi stralci del pensiero degli eugenisti, vuole separarlo dalla realizzazione nazista e in questo modo salvarlo, non considerando cos\u00ec negativamente, almeno in rapporto alla ricerca scientifica del tempo, gli eugenisti stessi. Fino al punto di rileggere perfino il breve opuscolo di Karl Binding e Alfred Hoche intitolato\u00a0<em>Il<\/em> <em>permesso di sopprimere le vite non degne di vivere<\/em> \u2014 sul quale i nazisti hanno fondato la loro, giustificazione dell&#8217;operazione T4 di eliminazione dei malati mentali \u2014 come un libro non pericoloso, ma in certa misura accettabile. Tanto che ne fornisce una traduzione in italiano, perch\u00e9 ogni lettore se ne faccia un&#8217;idea personale.<\/p>\n<p style=\"text-align: justify;\">Ora, senza dubbio n\u00e9 il giurista Binding n\u00e9 lo psichiatra Hoche avevano simpatie naziste, n\u00e9 Hoche, che sopravvisse pi\u00f9 a lungo, ebbe mai rapporti con il regime, ma l&#8217;affinit\u00e0 che i nazisti rinvennero con le loro teorie forse andrebbe analizzata pi\u00f9 seriamente. Soprattutto per questa nuova definizione \u2014 \u00abvite indegne di essere vissute\u00bb \u2014 che tanto successo ha avuto e che in fondo giustifica ancora oggi l&#8217;eliminazione di feti portatori di handicap.<\/p>\n<p style=\"text-align: justify;\">L&#8217;esame che ne fa Defanti \u00e8 per\u00f2 pi\u00f9 superficiale, anche se considera accettabile il concetto solo se la definizione \u00e8 riconosciuta come soggettiva, cio\u00e8 se il candidato all&#8217;eutanasia \u00e8 consenziente. La buona volont\u00e0 del medico scrittore e il suo pur lungo lavoro di scavo dell&#8217;eugenetica non sono tuttavia approfonditi a sufficienza: la sua bibliografia presenta vaste lacune, soprattutto per quanto riguarda l&#8217;applicazione delle idee eugenetiche in Paesi come gli Stati Uniti, la Svizzera e nelle democrazie scandinave.<\/p>\n<p style=\"text-align: justify;\">Se Defanti avesse letto i libri di Colla e Dotti sulle pratiche eugenetiche svedesi, ad esempio, avrebbe visto come anche la socialdemocrazia pu\u00f2 esercitare un biopotere opprimente e lesivo della libert\u00e0 personale sui deboli, soprattutto sulle donne sole e povere: sono loro infatti, e non i malati, ad avere costituito oltre l&#8217;80 per cento delle vittime della politica di sterilizzazione e di aborto eugenetico.<\/p>\n<p style=\"text-align: justify;\">E si sarebbe accorto che la motivazione economica \u2014 cio\u00e8 la lamentela sul costo dell&#8217;assistenza ai malati, che lo stesso studioso respinge con forza come motivazione accettabile nel saggio di Hoche, qualificandola come \u00absorprendente\u00bb \u2014 costituisca la prima e pi\u00f9 diffusa ragione delle pratiche eugenetiche messe in opera da diversi Governi democratici.<\/p>\n<p style=\"text-align: justify;\">Uno sguardo pi\u00f9 largo e approfondito su questo tema porta insomma a una conclusione: la certezza dell&#8217;autore che in regimi politici democratici non corriamo pericoli di eugenetica di tipo nazista \u00e8 smentita dalla storia, cos\u00ec come sono smentite altre sue osservazioni, basate sul ristretto campione di eugenisti che prende in esame.<\/p>\n<p style=\"text-align: justify;\">Ma, mentre non risulta per nulla convincente la conclusione del libro, che vorrebbe dissipare i timori che aleggiano intorno a un uso eugenetico della scienza oggi, rimane molto interessante e condivisibile l&#8217;idea di Defanti che per giudicare il presente dobbiamo ripercorrere il passato, e in particolare fare i conti con il fantasma dell\u2019eugenetica nazista.<\/p>\n<p style=\"text-align: justify;\">Come infatti ha scritto Roberto Esposito a proposito del nazismo \u00abper rovesciarlo davvero \u2013 per rigettarlo nell\u2019inferno da cui \u00e8 uscito \u2013 bisogna attraversare consapevolmente quelle tenebre, rispondere naturalmente in maniera opposta, a quanto allora fu fatto, alle domande che da essa si levano\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Osservatore Romano n.34-35, marted\u00ec 28 agosto 2012 Limiti e pregi di una nuova storia dell&#8217;eugenetica di Lucetta Scaraffia<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,117],"tags":[382],"class_list":["post-5200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","category-eugenetica","tag-eugenetica-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attraverso le tenebre - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attraverso le tenebre - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-19T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-16T08:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"182\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Attraverso le tenebre\",\"datePublished\":\"2012-09-19T22:00:00+00:00\",\"dateModified\":\"2016-03-16T08:36:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/\"},\"wordCount\":967,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Defanti_cover.jpg\",\"keywords\":[\"eugenetica\"],\"articleSection\":[\"Bioetica\",\"Eugenetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/\",\"name\":\"Attraverso le tenebre - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Defanti_cover.jpg\",\"datePublished\":\"2012-09-19T22:00:00+00:00\",\"dateModified\":\"2016-03-16T08:36:39+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Defanti_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/Defanti_cover.jpg\",\"width\":182,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attraverso-le-tenebre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attraverso le tenebre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attraverso le tenebre - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/","og_locale":"it_IT","og_type":"article","og_title":"Attraverso le tenebre - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-09-19T22:00:00+00:00","article_modified_time":"2016-03-16T08:36:39+00:00","og_image":[{"width":182,"height":277,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Attraverso le tenebre","datePublished":"2012-09-19T22:00:00+00:00","dateModified":"2016-03-16T08:36:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/"},"wordCount":967,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg","keywords":["eugenetica"],"articleSection":["Bioetica","Eugenetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/","name":"Attraverso le tenebre - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg","datePublished":"2012-09-19T22:00:00+00:00","dateModified":"2016-03-16T08:36:39+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/Defanti_cover.jpg","width":182,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attraverso-le-tenebre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Attraverso le tenebre"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5200"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5200\/revisions"}],"predecessor-version":[{"id":31821,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5200\/revisions\/31821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31820"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}