{"id":505,"date":"2005-05-18T00:00:00","date_gmt":"2005-05-17T22:00:00","guid":{"rendered":""},"modified":"2016-01-23T12:48:44","modified_gmt":"2016-01-23T11:48:44","slug":"guardini-e-laborto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/","title":{"rendered":"Guardini e l&#8217;aborto"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29690 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg\" alt=\"aborto\" width=\"206\" height=\"245\" \/><\/a>Corriere della Sera<\/strong> 8 maggio 2005<\/div>\n<p style=\"text-align: justify;\"><em>Il problemi dell\u2019uso dell\u2019embrione, che a noi sembrano sorti con le tecniche di procreazione assistita, agli occhi di Guardini erano gi\u00e0 tutti presenti al momento della legislazione tedesca sull\u2019aborto, e s\u2019intrecciano con la consapevolezza storica del recentissimo passato nazista, il quale impedisce di vedere che \u201cogni violazione della persona, specialmente quando s\u2019effettua sotto l\u2019egida della legge, prepara lo Stato totalitario\u201d.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Lucetta Scaraffia<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Sembra scritto per l\u2019acceso dibattito che sta precedendo il referendum sulla legge 40 questo piccolo ma intenso saggio del filosofo e teologo tedesco Romano Guardini (<em>Il diritto alla vita prima della nascita<\/em>, Morcelliana) scritto nel 1947 \u2013 quando fu presentata al parlamento tedesco la legge sull\u2019interruzione volontaria di gravidanza \u2013 e pubblicato nel 1949.<\/div>\n<p style=\"text-align: justify;\">Stupisce per lo sguardo acuto, per la capacit\u00e0 di trattare temi complessi come la dignit\u00e0 dell\u2019uomo e i modi in cui la vita dev\u2019essere salvaguardata, per la pacata lucidit\u00e0 e la chiarezza che i contendenti di oggi di rado sanno raggiungere. Stupisce anche perch\u00e9 difende la sua posizione senza mai ricorrere ad argomenti religiosi.<\/p>\n<p style=\"text-align: justify;\">I problemi dell\u2019uso dell\u2019embrione, che a noi sembrano sorti con le tecniche di procreazione esistita, agli occhi di Guardini erano gi\u00e0 tutti presenti al momento della legislazione tedesca sull\u2019aborto, e s\u2019intrecciano con la consapevolezza storica del recentissimo passato nazista, il quale impedisce di vedere che \u201cogni violazione della persona, specialmente quando s\u2019effettua sotto l\u2019egida della legge, prepara lo Stato totalitario\u201d.<\/p>\n<p style=\"text-align: justify;\">Il ragionamento del filosofo inizia smontando l\u2019obiezione che l\u2019aborto sia una questione di competenza degli esperti \u2013 giuristi, medici, sociologi \u2013 mentre \u00e8 problema che \u201criguarda l\u2019intero rapporto del singolo con la societ\u00e0, investendo il carattere fondamentale dell\u2019esistenza umana\u201d.<\/p>\n<p style=\"text-align: justify;\">E prosegue contrapponendo la moderna \u201cconcezione dell\u2019uomo quale unico responsabile e padrone della propria esistenza\u201d con \u201cil senso prima vivissimo della fondamentale intangibilit\u00e0 della vita umana\u201d. Nel valutare questi due diversi modi di giudicare Guardini considera centrale il ruolo del nazismo, responsabile di avere stabilito l\u2019eliminazione dei disabili, a cui sarebbe seguita quella dei malati inguaribili e dei vecchi, di quanti cio\u00e8 non erano pi\u00f9 \u201cutili\u201d alla societ\u00e0, ma costituivano un peso, un danno: \u201cse si comincia a considerare il danno come una ragion sufficiente per violare la vita umana, non si pu\u00f2 pi\u00f9 tener fermo nessun limite in maniera convincente\u201d.<\/p>\n<p style=\"text-align: justify;\">Il filosofo \u00e8 infatti fortemente convinto che \u201cil rispetto dell\u2019uomo in quanto persona \u00e8 una delle esigenze che non ammettono discussione: ne dipendono la dignit\u00e0, ma anche il benessere e alla fine la durata dell\u2019umanit\u00e0. Se questa esigenza viene messa in forse, si cade nella barbarie\u201d.<\/p>\n<p style=\"text-align: justify;\">Guardini risponde, con anticipo, alla pretesa delle donne di essere padrone assolute del proprio corpo, e quindi anche del figlio che vi \u00e8 racchiuso: \u201cla donna non ha il diritto di disporre del proprio corpo, non \u00e8 padrona della vita in divenire, ma questa le \u00e8 affidata; in sostanza non ha su di essa maggiori diritti di quanto ne abbia un qualsiasi essere umano su un altro essere umano\u201d.<\/p>\n<p style=\"text-align: justify;\">Anche su questo ritorna il parallelo con il nazismo: \u201cl\u2019affermazione che il figlio nel grembo della madre sia semplicemente una parte del corpo di lei, equivale a quella che l\u2019uomo sia nello Stato una semplice parte del tutto\u201d e quindi \u201cquesta opinione deve egualmente concedere allo Stato il diritto di disporre degli uomini che ne fanno parte\u201d.<\/p>\n<p style=\"text-align: justify;\">Un intero capitolo \u00e8 dedicato alla questione dell\u2019embrione, se cio\u00e8 questo possa essere considerato un essere umano fin dal primo momento del suo sviluppo. Guardini risponde che l\u2019organismo si manifesta in forma sia sincronica che diacronica, secondo gli stadi in cui \u00e8 passato o deve ancora passare l\u2019essere umano. E che entrambe le forme, quella strutturale e quella del divenire, \u201csi coappartengono, vale a dire rappresentano entrambe appunto l\u2019organismo, la prima nello spazio, l\u2019altra nel tempo.<\/p>\n<p style=\"text-align: justify;\">In entrambi i casi si tratta di una unit\u00e0 indivisibile\u201d perch\u00e9 l\u2019uomo \u201c\u00e8 la totalit\u00e0 della sua esistenza, che non \u00e8 soltanto natura, ma anche storia, che non possiede soltanto uno sviluppo, ma anche un destino\u201d. Se si rifiuta questa realt\u00e0, se si considera l\u2019essere umano non un carattere essenziale, ma qualcosa che \u00e8 dato in grado superiore o inferiore, si finisce fatalmente con il costruire una graduatoria, applicabile non solo alla fase embrionale, ma a tutte le parti del complesso vitale.<\/p>\n<p style=\"text-align: justify;\">La distanza dall\u2019<em>optimum<\/em> si pu\u00f2 dunque manifestare sia nella decadenza della vecchiaia sia nelle menomazioni e nelle malattie, cosicch\u00e9 \u201cquanto pi\u00f9 un individuo \u00e8 malato, debole, sventurato, tanto meno pu\u00f2 pretendere al carattere di vero essere umano\u201d.<\/p>\n<p style=\"text-align: justify;\">In perfetta analogia con il concetto, originariamente nazista,\u00a0 di \u201cvita non degna di essere vissuta\u201d. La difesa della vita in Guardini coincide con la difesa dell\u2019umanit\u00e0 dalla barbarie, appena sperimentata nella dittatura hitleriana, e il suo lucido ragionare mette in guardia da ripetere gli stessi errori, perch\u00e9 \u201cle azioni sbagliate, anche se appaiono utili, alla fine conducono alla rovina\u201d. Confutando chi sostiene che l\u2019aborto, la selezione degli embrioni e il loro uso a fini di ricerca sono libere decisioni individuali e non coercizione dello Stato, come al tempo del nazismo. La sostanza, sostiene Guardini, \u00e8 la stessa e uguale il pericolo di barbarie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corriere della Sera 8 maggio 2005 Il problemi dell\u2019uso dell\u2019embrione, che a noi sembrano sorti con le tecniche di procreazione assistita, agli occhi di Guardini erano gi\u00e0 tutti presenti al momento della legislazione tedesca sull\u2019aborto, e s\u2019intrecciano con la consapevolezza storica del recentissimo passato nazista, il quale impedisce di vedere che \u201cogni violazione della persona, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29690,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guardini e l&#039;aborto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guardini e l&#039;aborto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-17T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-23T11:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"206\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Guardini e l&#8217;aborto\",\"datePublished\":\"2005-05-17T22:00:00+00:00\",\"dateModified\":\"2016-01-23T11:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/\"},\"wordCount\":865,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/aborto.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/\",\"name\":\"Guardini e l'aborto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/aborto.jpg\",\"datePublished\":\"2005-05-17T22:00:00+00:00\",\"dateModified\":\"2016-01-23T11:48:44+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/aborto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/aborto.jpg\",\"width\":206,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guardini-e-laborto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guardini e l&#8217;aborto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guardini e l'aborto - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/","og_locale":"it_IT","og_type":"article","og_title":"Guardini e l'aborto - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-17T22:00:00+00:00","article_modified_time":"2016-01-23T11:48:44+00:00","og_image":[{"width":206,"height":245,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Guardini e l&#8217;aborto","datePublished":"2005-05-17T22:00:00+00:00","dateModified":"2016-01-23T11:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/"},"wordCount":865,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/","name":"Guardini e l'aborto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg","datePublished":"2005-05-17T22:00:00+00:00","dateModified":"2016-01-23T11:48:44+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg","width":206,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guardini-e-laborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Guardini e l&#8217;aborto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=505"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/505\/revisions"}],"predecessor-version":[{"id":29691,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/505\/revisions\/29691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29690"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}