{"id":497,"date":"2005-05-14T00:00:00","date_gmt":"2005-05-13T22:00:00","guid":{"rendered":""},"modified":"2016-07-14T12:34:18","modified_gmt":"2016-07-14T10:34:18","slug":"il-graduale-abbandono-della-vita-domestica","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/","title":{"rendered":"Il graduale abbandono della vita domestica"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36015\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg\" alt=\"focolare_domestico\" width=\"250\" height=\"183\" \/>Tratto da: <strong><em>La Chiesa viva<\/em><\/strong>, Ed.Paoline, 1963, pp.43-54<\/div>\n<p style=\"text-align: justify;\"><em>La verit\u00e0 \u00e8 che nessuno ha il diritto di distruggere nessuna istituzione sociale sinch\u00e9 abbia visto che si tratta per davvero di una istituzione storica. Quando egli sapr\u00e0 come \u00e8 sorta e a quali scopi si voleva servisse, sar\u00e0 anche in grado di dire se si trattava di scopi cattivi o di scopi diventati cattivi in seguito, o di scopi che in tal modo non si possono pi\u00f9 utilmente servire<\/em><\/p>\n<p style=\"text-align: center;\">di<strong> G.K.Chesterton<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Parlando dell\u2019opera di riforma delle cose, ben diversa da quella che tende a deformarle, non si deve trascurare un principio chiaro e semplice, che probabilmente verr\u00e0 accusato di essere paradossale. Esister\u00e0 in un dato caso una certa istituzione o una legge; diremo per amore di semplicit\u00e0 che esiste una barriera o un cancello che sbarrano la via. Il riformatore ultramoderno andr\u00e0 avanti per la sua via esclamando allegramente: \u00abNon vedo a che cosa possa servire, quindi \u00e8 cosa da distruggere&#8221;. A che il riformatore intelligente far\u00e0 bene ribattere: &#8220;Se non vedi a che cosa possa servire, non per questo ti permetter\u00f2 di distruggerla. Vattene, e ripensaci, e quando potrai ritornare a dirmi che sei riuscito a vederne l\u2019utilit\u00e0 ti potr\u00f2 permettere di operarne la distruzione\u00bb.<\/div>\n<p style=\"text-align: justify;\">Questo paradosso riposa sul pi\u00f9 elementare buon senso. La barriera o il cancello non sono cresciuti spontaneamente sul posto, non li ha costruiti durante il sonno qualche sonnambulo. E\u2019 molto poco probabile che siano stati eretti da mentecatti fuggiti dal manicomio e capitati chiss\u00e0 come a passare di l\u00e0. Alcuni debbono avere avuto qualche ragione di pensare che per altri sarebbero state cose buone. E finch\u00e9 non scopriremo quale fosse questa ragione non saremo davvero in grado di giudicarla ragionevole o no.<\/p>\n<p style=\"text-align: justify;\">Se le cose erette da esseri umani quanto lo siamo noi ci appaiono del tutto misteriose e affatto prive di significato, \u00e8 del tutto probabile che si abbia trascurato il lato d\u2019insieme della questione. Esistono riformatori che superano tale difficolt\u00e0 coll\u2019ammettere che tutti i loro antenati fossero degli sciocchi. Se il caso fosse davvero questo, non potremmo che dedurre l\u2019ereditariet\u00e0 di tale malattia. Ma la verit\u00e0 \u00e8 che nessuno ha il diritto di distruggere nessuna istituzione sociale sinch\u00e9 abbia visto che si tratta per davvero di una istituzione storica.<\/p>\n<p style=\"text-align: justify;\">Quando egli sapr\u00e0 come \u00e8 sorta e a quali scopi si voleva servisse, sar\u00e0 anche in grado di dire se si trattava di scopi cattivi o di scopi diventati cattivi in seguito, o di scopi che in tal modo non si possono pi\u00f9 utilmente servire. Ma se si limiter\u00e0 a fissare la cosa quasi fosse una mostruosit\u00e0 priva di significato, sorta chiss\u00e0 come a intralciargli il cammino, \u00e8 lui e non il tradizionalista ad essere affetto da allucinazioni.<\/p>\n<p style=\"text-align: justify;\">Potremmo giungere sino a dire che egli vede le cose come se si trovasse in preda a un incubo. Il principio si applica a mille casi, a quelli insignificanti quanto alle vere istituzioni, alle convenzioni cos\u00ec come alle convinzioni.<\/p>\n<p style=\"text-align: justify;\">Era esattamente una persona come Giovanna d\u2019Arco, la quale sapeva bene perch\u00e9 le donne indossano le gonne, che aveva tutte le giustificazioni per non indossarle; era esattamente una persona come san Francesco, il quale aveva provato grande simpatia per i banchetti e l\u2019angolo del focolare, ad avere pi\u00f9 d\u2019ogni altro il diritto di farsi mendicante sulle vie maestre. E quando, nella grande corrente di emancipazione della societ\u00e0 moderna, la Duchessa dice di non vedere perch\u00e9 non dovrebbe giocare a saltamontone, o il Decano dichiara di non notare nessuna solida ragione canonica che gli impedisca di stare ritto sulla testa, potremo rispondere loro con paziente benevolenza: \u00abVi invitiamo a differire queste operazioni sin quando, dopo mature riflessioni, abbiate compreso quale principio o pregiudizio intendete violare. E allora giocate a saltamontone e state ritti a gambe all\u2019aria, e che il Signore vi benedica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Fra le tradizioni che si stanno attaccando, non con intelligenza ma del tutto stupidamente, si trova la fondamentale creazione umana definita il focolare domestico o la Casa. \u00c8 tipico degli uomini l\u2019attaccarla, non perch\u00e9 riescono a portare gli sguardi di l\u00e0 di essa, ma perch\u00e9 non riescono a vederla affatto.<\/p>\n<p style=\"text-align: justify;\">Vi sferrano contro i loro colpi alla cieca, assolutamente a Casaccio, approfittando di ogni occasione; molti sarebbero lietissimi di abbatterla senza neppure fermarsi a chiedersi perch\u00e9 mai sia stata dunque edificata. \u00c8 vero che soltanto pochi vorrebbero confessare tale scopo a parole, il che prova soltanto quanto siano ciechi e balordi. Ma si sono lasciati trascinare dalla corrente che li sospinge con graduale distacco lontano dalla vita domestica, da un processo quindi a volte soltanto accidentale e privo affatto di una teoria ben definita.<\/p>\n<p style=\"text-align: justify;\">Ma bench\u00e9 accidentale, non \u00e8 per questo un fenomeno meno anarchico, e tanto pi\u00f9 anarchico per non essere tale a parole. Esso sembra fondarsi in larga misura sull\u2019irritazione personale, un\u2019irritazione che varia da individuo a individuo.<\/p>\n<p style=\"text-align: justify;\">Ci si dir\u00e0 soltanto che in questo o quel caso un dato temperamento si sentiva tormentare da un certo ambiente, ma nessuno ha mai saputo spiegare come abbia avuto inizio il male, senza dire poi che non si \u00e8 mai potuto spiegare se il male sia stato per davvero evitato. Ci si dir\u00e0 che in questa o quella famiglia la Nonnina diceva un mucchio di sciocchezze e Dio sa quanto vero sia; o che \u00e8 estremamente difficile stringere intime relazioni intellettuali con lo zio Gregorio senza dirgli che \u00e8 uno sciocco mentre questa \u00e8 la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ma nessuno considera con seriet\u00e0 il rimedio e neppure la malattia; e non si considera neppure se la dissoluzione individualistica sia un rimedio per davvero. Gran parte della cosa ebbe inizio con Ibsen che fu drammaturgo potente ma filosofo estremamente debole. Credo che la Nora di Casa di Bambola dovesse infatti essere nell\u2019intenzione dell\u2019autore una persona illogica ma senza dubbio la sua pi\u00f9 illogica azione fu l\u2019ultima. Si lamentava di non essere ancora adatta a badare ai bambini e poi, certo allo scopo di studiarli pi\u00f9 da vicino, prese la decisione di allontanarsi da loro il pi\u00f9 possibile.<\/p>\n<p style=\"text-align: justify;\">Abbiamo una prova semplice e tipica di questa abitudine che si ha di trascurare il pensiero scientifico e il significato delle regole sociali, abitudine che ci ha lasciato soltanto un gran sudiciume di eccezioni. In tutti i romanzi e i giornali dei nostri giorni ho letto centinaia e migliaia di volte certe frasi intorno al giusto diritto dei giovani alla libert\u00e0, intorno all\u2019ingiustizia del controllo da parte degli anziani, intorno al concetto che tutti gli spiriti debbono essere liberi e tutti i cittadini eguali, intorno all\u2019assurdit\u00e0 dell\u2019autorit\u00e0 e all\u2019indegnit\u00e0 dell\u2019obbedienza.<\/p>\n<p style=\"text-align: justify;\">Per il momento non intendo discutere direttamente tali proposizioni. Ma ci\u00f2 che mi colpisce come un\u2019enormit\u00e0 priva di senso \u00e8 che neppure uno fra queste miriadi di romanzieri e di giornalisti neanche sogna di passare a formulare in maniera ovvia la questione successiva. Sembra che non pensino neppure a chiedersi che ne \u00e8 dell\u2019obbligo reciproco. Se fin dal principio il figlio \u00e8 libero di trascurare i genitori, perch\u00e9 i genitori non saranno pure liberi sin dal principio di trascurare i figli?<\/p>\n<p style=\"text-align: justify;\">Se il signor Jones padre e il signor Jones figlio non sono che due cittadini liberi ed eguali perch\u00e9 uno dei due dovrebbe sfruttare l\u2019altro durante i suoi primi quindici anni di vita? Perch\u00e9 si dovrebbe esigere che il signor Jones anziano nutra, vesta e dia ospitalit\u00e0 di tasca sua a un\u2019altra persona affatto priva di ogni obbligo verso di lui?<\/p>\n<p style=\"text-align: justify;\">Se non \u00e8 possibile chiedere alla creatura giovane e brillante di tollerare sua nonna che s\u2019\u00e8 fatta noiosa, perch\u00e9 la nonna e la madre dovrebbero tollerare la creatura giovane e brillante nel periodo della vita in cui essa non era affatto brillante? Perch\u00e9 esse hanno preso faticosa cura di lei nel tempo in cui il suo contributo alla conversazione era ben di rado epigrammatico e non spesso intelligibile?<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 Jones padre dovrebbe offrire gratis cibo e bevande a una persona come Jones figlio cos\u00ec poco simpatica nelle fasi immature della sua esistenza? Perch\u00e9 non dovrebbe poter gettare il bambino dalla finestra o per lo meno scacciare il ragazzo dalla porta? \u00c8 ovvio che si tratta di una vera relazione che potr\u00e0 essere di eguaglianza ma che non \u00e8 davvero di somiglianza.<\/p>\n<p style=\"text-align: justify;\">So che taluni riformatori sociali cercano di superare la difficolt\u00e0 per mezzo di qualche vago concetto intorno allo Stato, ad un\u2019astrazione che si definisce l\u2019Istruzione pubblica con cui si eliminerebbero le funzioni dei genitori. Ma come altri concetti, che possiede la gente scientificamente solida, si tratta di un\u2019illusione stramba sul genere di quelle suscitate dai colpi di sole. Essa si fonda su quella strana e nuovissima superstizione che \u00e8 l\u2019idea delle infinite risorse dell\u2019organizzazione.<\/p>\n<p style=\"text-align: justify;\">\u00c8 come se i funzionari crescessero come l\u2019erba o si potessero allevare come i conigli. Si suppone di poter avere masse senza fine di persone salariate e di salari da rimettere loro; e che esse siano destinate a compiere tutto ci\u00f2 che gli esseri umani fanno naturalmente per loro stessi, compresa la cura dei figli. Ma non si pu\u00f2 continuare a vivere all\u2019infinito lavando la biancheria sudicia di bambini altrui. Non si pu\u00f2 fornire un precettore per ogni nuovo cittadino; chi sarebbe poi in grado di istruire i precettori? Gli uomini non si possono educare a macchina, e se anche sar\u00e0 possibile avere il muratore o lo spazzino meccanico non si avr\u00e0 mai per\u00f2 il maestro o la governante costruiti meccanicamente.<\/p>\n<p style=\"text-align: justify;\">L\u2019effetto reale di questa teoria \u00e8 che una persona oppressa dal lavoro dovr\u00e0 badare a cento bambini invece che una persona in buona salute badi a un numero di bambini normale. In via ordinaria quest\u2019ultima persona si sente spinta da una forza normale che non le costa nulla e che non esige alcun salario dalla forza dell\u2019affetto naturale verso i propri piccoli che esiste anche tra gli animali inferiori.<\/p>\n<p style=\"text-align: justify;\">Tagliando via questa forza naturale e sostituendovi una burocrazia retribuita si agirebbe come lo sciocco il quale paga degli uomini a girare per lui la ruota del mulino per la ragione che si rifiuta di usare il vento o l\u2019acqua che possiede senza spesa. Si agirebbe come il pazzo che annacqua diligentemente il giardino con l\u2019annaffiatoio tenendo aperto l\u2019ombrello per riparare la terra dalla pioggia.<\/p>\n<p style=\"text-align: justify;\">E necessario ritornare con la mente a queste verit\u00e0 lapalissiane perch\u00e9 soltanto in questo modo potremo scorgere vagamente la ragione dell\u2019esistenza della famiglia, quella appunto che ho incominciato a chiedermi all\u2019inizio di questo saggio. Ai nostri padri esse erano tutte verit\u00e0 familiari, poich\u00e9 essi credevano nei legami della parentela cos\u00ec come nei legami della logica<\/p>\n<p style=\"text-align: justify;\">Oggi la nostra logica consiste pi\u00f9 che altro nel perdere di vista i legami, e le nostre famiglie sono composte in gran parte di membri assenti. Ma tuttavia \u00e8 questa l\u2019estremit\u00e0 giusta da cui si deve incominciare ogni inchiesta del genere: non si deve partire dalla coda o dal mozzicone di sigaretta di qualche disordine privato avvenuto perch\u00e9 Dick \u00e8 scontento e Susanna se ne \u00e8 andata per conto suo. Se Dick e Susanna non vedono lo scopo a cui serve la famiglia e desiderano distruggerla, ripeter\u00f2 quanto ho detto da principio: se non vedono a che cosa possa servire farebbero meglio a conservarla. Non hanno nessun diritto neppure di pensare a distruggerla, sin che ne abbiano veduta almeno l\u2019utilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ma serve anche ad altre cose oltre al fatto ovvio che essa significa un lavoro sociale necessario, eseguito per amore l\u00e0 dove non lo si potrebbe compiere per denaro, e (si oserebbe quasi dire) che dovrebbe essere logicamente ripagato di eguale amore, dato che in moneta non \u00e8 possibile ripagarlo.<\/p>\n<p style=\"text-align: justify;\">L\u2019attuale sistema sociale che ai nostri giorni e nella nostra cultura industriale vien fatto segno a violente ingiurie ed \u00e8 intessuto di problemi penosi, \u00e8 tuttavia normale. Si tratta dell\u2019idea che la comunit\u00e0 \u00e8 formata da un certo numero di piccoli regni nei quali, compatibilmente al buon senso della comunit\u00e0, l\u2019uomo e la donna diventano il re e la regina sinch\u00e9 coloro che sono a loro soggetti crescono per fondare a loro volta regni simili e per esercitarvi un\u2019identica autorit\u00e0. \u00c8 la struttura sociale dell\u2019umanit\u00e0 la quale \u00e8 di gran lunga pi\u00f9 antica di ogni cronaca e pi\u00f9 universale di tutte le sue religioni, e ogni tentativo che tenda ad alterarla non \u00e8 che una somma di vane parole e di buffonate.<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019altro vantaggio che deriva dal piccolo gruppo non viene ora tanto dimenticato quanto invece non compreso. Anche qui si nota una straordinaria illusione diffusa in tutta la letteratura e nel giornalismo dei nostri giorni. Illusioni del genere esistono oggi in grado tale che in pratica si pu\u00f2 giungere a dire che quando una cosa viene detta e ripetuta per vera un migliaio di volte \u00e8 quasi certo che sia assolutamente falsa.<\/p>\n<p style=\"text-align: justify;\">Qui ne potremo citare specialmente una. Si pu\u00f2 certo dir qualcosa contro la vita domestica e in favore della tendenza generale del vivere in albergo, al circolo, in collegio, in alloggi comuni e cos\u00ec via; o in favore di una vita sociale organizzata sul piano dei grandi sistemi commerciali del nostro tempo. Ma la cosa davvero straordinaria \u00e8 che spesso si dice come questa evasione dalla casa porta verso una maggiore libert\u00e0, ch\u00e9 il mutamento viene infatti offerto in favore della libert\u00e0.<\/p>\n<p style=\"text-align: justify;\">Per chiunque sia capace di pensare \u00e8 chiaro che si tratta esattamente del contrario. Essendo umana, la suddivisione domestica della societ\u00e0 non \u00e8 perfetta. Non potr\u00e0 realizzare una libert\u00e0 completa che \u00e8 cosa alquanto difficile a farsi e anche soltanto a definirsi. Ma \u00e8 semplice questione aritmetica il fatto che essa dia a un grandissimo numero di persone il controllo supremo di qualcosa e la possibilit\u00e0 di foggiare questa cosa stessa a piacer loro in misura molto maggiore di quanto facciano le vaste organizzazioni che governano dal di fuori la societ\u00e0, sia con sistemi legali, commerciali, o soltanto sociali.<\/p>\n<p style=\"text-align: justify;\">Anche se si trattasse soltanto di voler prendere in considerazione i genitori \u00e8 chiaro che il numero di genitori che esistono \u00e8 superiore a quello dei poliziotti, degli uomini politici, dei direttori di grandi aziende, e di proprietari d\u2019alberghi. Come fra poco accenner\u00f2, la questione si pu\u00f2 in maniera indiretta applicare tanto ai figli che ai genitori. Ma il punto centrale \u00e8 che il mondo esterno alla famiglia si trova ora sottoposto ad una rigida disciplina e ad una altrettanto rigida routine, e che soltanto entro la casa vi \u00e8 posto per la libert\u00e0 personale.<\/p>\n<p style=\"text-align: justify;\">Chiunque varca la soglia per uscire nella via \u00e8 costretto a mettersi in colonna con tutti coloro che vanno nella medesima direzione e in misura non piccola \u00e8 addirittura costretto anche a indossare la stessa uniforme. Gli affari, specialmente i pi\u00f9 vasti, sono oggi organizzati come l\u2019esercito. Qualcuno direbbe che si tratta di una specie di militarismo moderato senza spargimento di sangue, mentre io lo chiamerei un militarismo privo anche delle virt\u00f9 militari.<\/p>\n<p style=\"text-align: justify;\">\u00c8 tuttavia evidente che i cento impiegati di una banca o le cento cameriere di un grande caff\u00e8 sono pi\u00f9 irregimentati e governati da regole fisse dei medesimi individui quando essi siano ritornati a casa o nella camera ammobigliata adorna con le vedute preferite e profumate dal fumo delle sigarette economiche preferite.<\/p>\n<p style=\"text-align: justify;\">Ma, per quanto ovvio nel campo del commercio, questo non \u00e8 meno vero se detto del campo sociale. In pratica il perseguimento del piacere non \u00e8 che frutto della moda, e il seguire la moda non \u00e8 che una convenzione, una convenzione che appare nuova. Il jazz, le gite, i grandi ricevimenti e i trattenimenti negli alberghi non tendono a soddisfare il gusto veramente indipendente pi\u00f9 di quanto facessero le mode del passato.<\/p>\n<p style=\"text-align: justify;\">Se una fanciulla ricca desidera fare tutto ci\u00f2 che fanno le altre fanciulle ricche si divertir\u00e0 un mondo semplicemente perch\u00e9 tanto la giovent\u00f9 che la societ\u00e0 son divertenti. Essa godr\u00e0 di essere moderna esattamente come sua nonna vissuta nell\u2019epoca vittoriana godeva di essere vittoriana. E questo ben a ragione; ma si tratta di godimento convenzionale, non di un godimento libero. \u00c8 cosa sanissima che i giovani di ogni tempo, in una certa ragionevole misura, si raggruppino copiandosi l\u2019un l\u2019altro con entusiasmo, ma non esiste in questo nulla di specialmente fresco e neppure nulla di specialmente libero.<\/p>\n<p style=\"text-align: justify;\">La ragazza a cui piace avere i capelli corti e usare il trucco e indossare abiti corti trover\u00e0 che il mondo \u00e8 organizzato apposta per lei e tutta felice si metter\u00e0 in marcia seguendo il corteo. Ma la ragazza a cui per caso piacesse avere i capelli lunghi sino ai piedi, adornarsi di acconciature antiquate, portare vesti con lo strascico e (orrore di tutti gli orrori) mostrare il volto al naturale sar\u00e0 bene si attenga al consiglio di soddisfare questi desideri entro i confini della sua abitazione.<\/p>\n<p style=\"text-align: justify;\">Se la Duchessa sceglie di esercitarsi nel saltamontone, essa non dovr\u00e0 mettersi di punto in bianco a saltare come una ranocchia da un capo all\u2019altro del salone da ballo dell\u2019Hotel di Babilonia affollato dalle cinquanta migliori coppie le quali stanno eseguendo a beneficio della societ\u00e0 le danze di ultima creazione. La Duchessa trover\u00e0 pi\u00f9 semplice esercitarsi nel salto innanzi alla ammirata presenza delle amiche pi\u00f9 intime nell\u2019antico vestibolo rivestito di quercia del Castello di Fitzdragon.<\/p>\n<p style=\"text-align: justify;\">Se il Decano della Cattedrale vuole stare ritto sulla testa lo far\u00e0 con maggiore comodit\u00e0 e grazia nella calma atmosfera della sua residenza piuttosto che interrompendo il programma di qualche trattenimento sociale organizzato a scopo benefico.<\/p>\n<p style=\"text-align: justify;\">Se la routine impersonale esiste nelle cose commerciali e anche in quelle sociali va da s\u00e9 che esista e debba esistere sempre anche nelle cose politiche e legali. Per esempio, le punizioni inflitte dallo Stato debbono di necessit\u00e0 essere delle generalizzazioni. \u00c8 soltanto la punizione applicata entro le pareti domestiche che potr\u00e0 venire adattata ai singoli casi poich\u00e9 \u00e8 soltanto qui che il giudice pu\u00f2 essere a conoscenza della natura dell\u2019individuo.<\/p>\n<p style=\"text-align: justify;\">Se Tommy prende il ditale d\u2019argento dal cestino di lavoro, sua madre potr\u00e0 agire a seconda che sappia se egli l\u2019ha fatto per gioco o per dispetto o per vederlo o per mettere nei pasticci qualcuno. Ma se Tomkins prende un ditale d\u2019argento in un negozio, la legge non potr\u00e0 se non punirlo secondo le regole applicabili a tutti i taccheggiatori e a tutti i ladri di oggetti d\u2019argento. \u00c8 soltanto la disciplina domestica che \u00e8 in grado di dimostrare comprensione, e specialmente umorismo.<\/p>\n<p style=\"text-align: justify;\">Non dico che la famiglia faccia questo in ogni singolo caso, ma affermo che lo Stato non potrebbe mai tentare di farlo. Cos\u00ec che, anche soltanto a voler considerare i genitori come principi indipendenti e i figli come semplici sudditi, la libert\u00e0 relativa della famiglia pu\u00f2 operare e spesso opera davvero in favore di questi soggetti. Ma sintanto che i figli sono giovani dovranno sempre andare soggetti a qualcuno. La questione sar\u00e0 di decidere se si dovranno lasciare naturalmente ai loro sovrani naturali come in antico si diceva, i quali normalmente provano verso di loro sentimenti che nessun altro \u00e8 in grado di provare e cio\u00e8 degli affetti naturali. Mi sembra chiaro che tale sistema distributivo dia la maggiore misura di libert\u00e0 al maggior numero di persone.<\/p>\n<p style=\"text-align: justify;\">La mia protesta contro la corrente contraria alla vita domestica \u00e8 che essa manca di intelligenza. La gente non sa quello che fa poich\u00e9 non conosce l\u00e0 cosa che sta disfacendo. Esiste un gran numero di manifestazioni moderne, dalla maggiore alla minima, e vanno dal divorzio alla scampagnata. Ma non si tratta che di evasioni, e specialmente di maniera con cui trattare evasivamente la questione principale.<\/p>\n<p style=\"text-align: justify;\">La gente dovrebbe decidere filosoficamente se desidera o no l\u2019ordine sociale tradizionale e se esiste un\u2019altra soluzione particolarmente desiderabile. In realt\u00e0 si tratta la questione pubblica semplicemente come un imbroglio e un groviglio di confusioni private. Anche volendo comportarsi in maniera antidomestica si \u00e8 troppo domestici in questa maniera di porre in discussione la vita domestica. Ogni famiglia non fa che prendere in considerazione il proprio caso e il risultato \u00e8 semplicemente meschino o negativo.<\/p>\n<p style=\"text-align: justify;\">Ogni caso forma l\u2019eccezione a una regola che non esiste. Specie nella sua condizione moderna la famiglia mostra la necessit\u00e0 di una notevole correzione e ricostruzione, e questo andrebbe detto oggi anche di altre moltissime cose. Ma la casa deve venire preservata, distrutta o ricostruita; non le si deve permettere di cadere in pezzi un mattone dopo l\u2019altro, per la ragione che nessuno possiede abbastanza senso storico intorno al modo di mettere i mattoni. Gli architetti della restaurazione dovrebbero, per esempio, ricostruire la casa con porte pi\u00f9 ampie e facilmente apribili per facilitare la pratica delle antiche virt\u00f9 ospitali.<\/p>\n<p style=\"text-align: justify;\">In altre parole, la propriet\u00e0 privata dovrebbe venire distribuita con sufficiente eguaglianza cos\u00ec da permettere un certo margine per i rapporti festosi. Ma l\u2019ospitalit\u00e0 della casa rimarr\u00e0 sempre diversa da quella dell\u2019albergo; sar\u00e0 diversa per il fatto di essere pi\u00f9 personale, pi\u00f9 indipendente e pi\u00f9 interessante di quella. \u00c8 perfettamente giusto che i giovani Brown e i giovani Robinson s\u2019incontrino e ballino e facciano gli stupidi secondo gli intendimenti del loro Creatore.<\/p>\n<p style=\"text-align: justify;\">Ma esister\u00e0 sempre una certa differenza tra i Brown nell\u2019atto di offrire un ricevimento ai Robinson e i Robinson che offrono un ricevimento ai Brown. Sar\u00e0 una diversit\u00e0 che andr\u00e0 a favore della variet\u00e0 della personalit\u00e0 e delle facolt\u00e0 mentali dell\u2019uomo, in altre parole, della vita, della libert\u00e0 e del raggiungimento della felicit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tratto da: La Chiesa viva, Ed.Paoline, 1963, pp.43-54 La verit\u00e0 \u00e8 che nessuno ha il diritto di distruggere nessuna istituzione sociale sinch\u00e9 abbia visto che si tratta per davvero di una istituzione storica. Quando egli sapr\u00e0 come \u00e8 sorta e a quali scopi si voleva servisse, sar\u00e0 anche in grado di dire se si trattava &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36015,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[156],"class_list":["post-497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","tag-famiglia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-13T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-14T10:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"262\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il graduale abbandono della vita domestica\",\"datePublished\":\"2005-05-13T22:00:00+00:00\",\"dateModified\":\"2016-07-14T10:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/\"},\"wordCount\":3542,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/focolare_domestico.jpg\",\"keywords\":[\"famiglia\"],\"articleSection\":[\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/\",\"name\":\"Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/focolare_domestico.jpg\",\"datePublished\":\"2005-05-13T22:00:00+00:00\",\"dateModified\":\"2016-07-14T10:34:18+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/focolare_domestico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/focolare_domestico.jpg\",\"width\":262,\"height\":192},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-graduale-abbandono-della-vita-domestica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il graduale abbandono della vita domestica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/","og_locale":"it_IT","og_type":"article","og_title":"Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-13T22:00:00+00:00","article_modified_time":"2016-07-14T10:34:18+00:00","og_image":[{"width":262,"height":192,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il graduale abbandono della vita domestica","datePublished":"2005-05-13T22:00:00+00:00","dateModified":"2016-07-14T10:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/"},"wordCount":3542,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg","keywords":["famiglia"],"articleSection":["Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/","name":"Il graduale abbandono della vita domestica - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg","datePublished":"2005-05-13T22:00:00+00:00","dateModified":"2016-07-14T10:34:18+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/focolare_domestico.jpg","width":262,"height":192},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-graduale-abbandono-della-vita-domestica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il graduale abbandono della vita domestica"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"predecessor-version":[{"id":36016,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/497\/revisions\/36016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36015"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}