{"id":4923,"date":"2012-03-08T00:00:00","date_gmt":"2012-03-07T23:00:00","guid":{"rendered":""},"modified":"2015-04-21T17:30:33","modified_gmt":"2015-04-21T15:30:33","slug":"non-per-giudicare-ma-per-salvare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/","title":{"rendered":"\u201cNon per giudicare ma per salvare\u201d"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-23535\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg\" alt=\"confessionale\" width=\"250\" height=\"178\" \/><\/a>Ag Zenit<\/strong> (Zenit.org) 11 luglio 2011<\/div>\n<p style=\"text-align: center;\"><em>Intervista a don Andrea Mardegan sulla confessione<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Antonio Gaspari<\/strong><\/p>\n<p style=\"text-align: justify;\">ROMA _ In un passaggio del Vangelo secondo Giovanni, Ges\u00f9 disse a Nicodemo: \u201cDio, non ha mandato il Figlio nel mondo per condannare il mondo, ma perch\u00e9 il mondo sia salvato per mezzo di lui\u201d (Gv 3,16-18).<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">E per salvare gli umani che cadono per la loro fragilit\u00e0, la Chiesa ha il sacramento della confessione. Un sacramento la cui pratica \u00e8 centrale per l\u2019opera di conversione, e che sta tornando al centro dell\u2019attenzione di fedeli e teologi.<\/p>\n<p style=\"text-align: justify;\">A questo proposito don Andrea Mardegan, cappellano del collegio universitario Torriana di Milano, ha pubblicato per le edizioni Paoline il libro &#8220;Il sacramento della gioia&#8221; in cui presenta brani evangelici che hanno un legame immediato con i temi della conversione, della richiesta di perdono, della confessione e della riconciliazione.<\/p>\n<p style=\"text-align: justify;\">Con questo libro l\u2019autore cerca di rispondere alla <em>Verbum Domini<\/em> di Benedetto XVI, secondo cui: \u201cAffinch\u00e9 si approfondisca la forza riconciliatrice della Parola di Dio si raccomanda che il singolo penitente si prepari alla confessione meditando un brano adatto della Sacra Scrittura\u201d.<\/p>\n<p style=\"text-align: justify;\">Il volume si articola in sette parti che dovrebbero rappresentare le linee guida per affrontare la confessione ed arrivare alla comunione con un senso di felicit\u00e0, di gioia, di beatitudine e di benedizione.<\/p>\n<p style=\"text-align: justify;\">ZENIT ha intervistato don Andrea Mardegan.<\/p>\n<p style=\"text-align: justify;\"><strong>Un diffuso pregiudizio considera la confessione una sorta di tribunale che seleziona e punisce i peccatori, mentre per un cristiano la confessione \u00e8 la forma pi\u00f9 alta di carit\u00e0 che il Signore gli abbia dato. Pu\u00f2 spiegare il rapporto tra confessione e carit\u00e0 e perch\u00e8 ha intitolato il suo libro \u201cil sacramento della gioia?\u201d.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span>: Uno dei motivi per cui ho scritto questo libro \u00e8 per far eco alla verit\u00e0 che il Vangelo ci svela, che Ges\u00f9 \u00e8 venuto per perdonare i peccatori, per salvare ci\u00f2 che era perduto. Anche oggi non aspetta altro: Lui \u00e8 il Salvatore. Per incontrarlo per\u00f2 dobbiamo accogliere la verit\u00e0 che siamo peccatori e andare verso di Lui come il figlio giovane della parabola che Lui stesso ci ha narrato, che torna dal Padre e da Lui riceve il bacio, l\u2019abbraccio: il perdono ricevuto; la veste nuova, una festa con la musica e le danze: il frutto di gioia che d\u00e0 la riconciliazione con Dio, non solo per il peccatore perdonato, ma per tutta la sua famiglia, che \u00e8 la Chiesa. Ci\u00f2 che accade nella confessione \u00e8 una manifestazione altissima di carit\u00e0. L\u00ec si riversa nell\u2019anima tutta la carit\u00e0 di Dio, che nella sua sovrabbondanza di bene annega il male che \u00e8 il peccato.<\/p>\n<p style=\"text-align: justify;\">Lo stesso peccatore (ciascuno di noi), manifesta nel suo chiedere perdono l\u2019amore che ha per Dio (chiedere perdono \u00e8 sempre un atto d\u2019amore), la fiducia totale in Lui, l\u2019abbandono tra le sue braccia. C\u2019\u00e8 anche l\u2019amore del peccatore per la Chiesa e la fiducia nel sacerdozio, che \u00e8 dono di Dio, e il confessore da parte sua manifesta tutto l\u2019amore materno della Chiesa per i peccatori, e il suo amore fraterno da sacerdote che sostiene, incoraggia, consiglia e non ci lascia soli.<\/p>\n<p style=\"text-align: justify;\">\u00c8 segno di un amore fraterno che nella Chiesa ha tante altre manifestazioni, ma nella confessione raggiunge un culmine. Ho intitolato il libro \u201cIl sacramento della gioia\u201d perch\u00e9 il Vangelo mette in evidenza la gioia della conversione, e perch\u00e9 \u00e8 esperienza comune che la confessione ben fatta porti una gioia profonda, i confessori lo sanno e i santi lo dicono. Ricordo in particolare espressioni del Beato Giovanni Paolo II e di San Josemar\u00eda Escriv\u00e1 che nelle sue catechesi sulla confessione amava usare quest\u2019espressione e altre simili.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 confessarsi?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span>: Per incontrarsi con Cristo, per ascoltare la sua voce che ci dice: \u201cneanch\u2019io ti condanno, sii perdonato dal tuo peccato, va e non peccare pi\u00f9\u201d, per ricevere il suo aiuto, la sua grazia santificante che ci rende santi, la sua grazia sacramentale che \u00e8 un aiuto specifico per proseguire il cammino, per essere rafforzati da Dio nella lotta di quel momento della nostra vita. Per avere il consiglio e la preghiera del confessore. Per arrivare a conoscersi davvero. Per non essere soli nel cammino.<\/p>\n<p style=\"text-align: justify;\">Per godere della purezza d\u2019animo del Battesimo, per poter aiutare gli altri. Per confrontare il nostro pensiero con il pensiero della Chiesa, il pensiero di Cristo, in questioni che ci toccano nell\u2019intimo e che a volte non possiamo o non vogliamo rivelare ad altri. Per non lasciarci sviare da tentazioni, o da idee sbagliate, da comportamenti che ci portano fuori strada. Per essere sicuri di una totale riservatezza. Per sentire una parola di vita eterna.<\/p>\n<p style=\"text-align: justify;\"><strong>E che cosa significa prepararsi alla confessione?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span>: Dipende dalla situazione di ciascuno, ma direi che ci\u00f2 che il Papa suggerisce nella <em>Verbum Domini<\/em>, cio\u00e8 prepararsi alla confessione meditando il Vangelo, che \u00e8 quello che il mio libro si propone di aiutare il lettore a fare, \u00e8 un consiglio che aiuta a prepararsi nella preghiera, a recuperare la visione giusta di fede nella presenza di Cristo nel suo sacramento, il suo essere presente nel suo ministro: \u00e8 Lui e solo Lui che pu\u00f2 dire io ti perdono, nel suo nome il confessore pu\u00f2 pronunciare le parole dell\u2019assoluzione.<\/p>\n<p style=\"text-align: justify;\">Prepararsi meditando il Vangelo pu\u00f2 significare \u201critornare in s\u00e9\u201d come il figliol prodigo e accettare la rivelazione sul nostro essere peccatori; e accorgerci, guidati dallo Spirito Santo, dalla parola di Dio e dall\u2019insegnamento della Chiesa: in questa e in quest\u2019altra azione, pensiero, parola, ho peccato.<\/p>\n<p style=\"text-align: justify;\">Prepararsi pu\u00f2 significare: fare il proposito di non peccar pi\u00f9 con l\u2019aiuto di Dio e della grazia del sacramento, anche quando siamo consapevoli che da soli non ce la faremmo mai. Comunque alcuni di questi passi possono avvenire anche all\u2019interno del dialogo del sacramento. Meglio arrivare alla confessione con la preparazione essenziale, che rimandarla: \u00e8 la grazia di Dio che ci sana, non il nostro sforzo, e un buon confessore deve saper aiutare opportunamente.<\/p>\n<p style=\"text-align: justify;\"><strong>In che senso l\u2019uomo pecca?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span><strong>: <\/strong>Nella situazione attuale, dopo il peccato originale, l\u2019uomo ha difficolt\u00e0 a vedere Dio, a facilit\u00e0 a non capire Dio, a dimenticarsi di Dio rendendosi Dio a se stesso. Oppure ha grande facilit\u00e0 a considerare fine assoluto della sua vita, Amore infinito che motiva tutte le azioni, non Dio, ma una creatura di Dio, una persona amata, o un obbiettivo temporale, un lavoro, un potere, delle ricchezze, un piacere. Tutte cose create da Dio, che possono nell\u2019ordine del suo Amore avere una finalit\u00e0 positiva e anche santa.<\/p>\n<p style=\"text-align: justify;\">L\u2019uomo nel peccare sbaglia obbiettivo, o sbaglia ordine, tralascia un aspetto essenziale per il bene, disobbedisce a Dio, decide in proprio cosa \u00e8 bene e cosa \u00e8 male. Molto spesso tutto ci\u00f2 avviene per debolezza, per fragilit\u00e0, altre volte invece ci pu\u00f2 essere malizia, una volont\u00e0 radicata nel male.<\/p>\n<p style=\"text-align: justify;\">Come insegnano i primi capitoli della Genesi, non manca in questo processo l\u2019azione del tentatore, del nemico del genere umano, dell\u2019accusatore dei nostri fratelli, del divisore. L\u2019esperienza umana e della Chiesa insegna anche che da un peccato , se non purificato, ne pu\u00f2 sorgere un altro e altri peggiori, in una catena negativa. Ma la forza del perdono di Cristo che meditiamo nelle scene del Vangelo, \u00e8 sempre pi\u00f9 grande del peccato.<\/p>\n<p style=\"text-align: justify;\"><strong>Chi \u00e8 autorizzato a perdonare i peccati?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span>: Coloro a cui Ges\u00f9 ha trasmesso questo potere dopo la sua risurrezione: gli apostoli e i loro successori: il Papa e i Vescovi, e i sacerdoti loro collaboratori che hanno ricevuto da loro il sacramento dell\u2019ordine sacro e la facolt\u00e0 di ascoltare confessioni. Ma l\u2019interesse di Cristo e della Chiesa per il perdono dei peccati \u00e8 tale, che se una persona fosse in punto di morte e non avesse altra possibilit\u00e0, anche un sacerdote sospeso dal ministero, o che avesse lasciato il sacerdozio, pu\u00f2 darle l\u2019assoluzione dei peccati.<\/p>\n<p style=\"text-align: justify;\"><strong>Un anziano confessore mi ha spiegato che il Signore si intristisce per le nostre cadute, ma \u00e8 interessato soprattutto a vedere le opere di bene di cui siamo capaci. Non basta infatti essere virtuosi se poi non si fanno opere buone. E\u2019 corretto questo punto di vista?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan:<\/span> Sicuramente l\u2019anziano confessore le ha detto cose sagge che anch\u2019io ascolto per imparare. Quanto il Signore soffre per i nostri peccati: basta guardarlo sulla Croce. Giovanni Paolo II nell\u2019Enciclica <em>Dominum et Vivificantem<\/em> parla del dolore di Dio dopo il peccato dei progenitori. Quello fu il primo dolore che entr\u00f2 nella storia della salvezza. Non il dolore dell\u2019uomo.<\/p>\n<p style=\"text-align: justify;\">Dal punto di vista della pastorale \u00e8 giusto sottolineare tutto ci\u00f2 che pu\u00f2 incoraggiare il cristiano a essere o diventare penitente, a imparare a chiedere perdono. Pu\u00f2 essere la considerazione della Passione di Cristo con la quale lo Spirito Santo ci spiega la gravit\u00e0 del peccato, o pu\u00f2 essere la forza della Risurrezione, della vita nuova che Dio ci dona con il suo perdono.<\/p>\n<p style=\"text-align: justify;\">Egli fa nuove tutte le cose. E Ges\u00f9 \u00e8 contento di ritrovarci, di perdonarci, di incontrarci personalmente e di rivestirci di s\u00e9: come fu contento di far scendere Zaccheo dal sicomoro, o come fu contento delle lacrime della peccatrice che gli lavavano i piedi.<\/p>\n<p style=\"text-align: justify;\">Per ci\u00f2 che riguarda le opere buone: se non si fanno opere buone, non si \u00e8 virtuosi, infatti la virt\u00f9 \u00e8 proprio la capacit\u00e0 di operare il bene. \u00c8 vero che non pu\u00f2 bastare al Signore una presunta impeccabilit\u00e0 che non sia unita alla carit\u00e0 e alla operosit\u00e0 nel bene, anche perch\u00e9 se non c\u2019\u00e8 carit\u00e0 veniamo meno al pi\u00f9 importante dei comandamenti di Ges\u00f9, che racchiude tutti gli altri. Lo diceva gi\u00e0 la lettera di san Giacomo, la fede senza le opere \u00e8 morta.<\/p>\n<p style=\"text-align: justify;\">E&#8217; l\u2019atteggiamento di Ges\u00f9 \u201cconfessore\u201d, se cos\u00ec si pu\u00f2 dire, che ho cercato di approfondire nel mio libro, meditando su vari episodi evangelici, \u00e8 sempre orientato al bene che pu\u00f2 operare chi \u00e8 guarito dal peccato. Basti pensare alla Samaritana che corre ad annunciare a tutti che ha incontrato il Messia,O a Zaccheo che restituisce il quadruplo e cambia vita, al paralitico che torna dai suoi glorificando Dio, a Pietro che piange ma poi conferma i suoi fratelli.<\/p>\n<p style=\"text-align: justify;\"><strong>Come si fa l\u2019esame di coscienza e perch\u00e8 \u00e8 cos\u00ec importante?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Don Mardegan<\/span>: Ho proposto varie domande di esame di coscienza nell\u2019ultimo capitolo del libro. Ho notato che c\u2019\u00e8 molto interesse tra i lettori per questo aiuto. Non \u00e8 possibile dare ricette generali, diverso \u00e8 l\u2019esame giornaliero, normalmente breve e denso di amore di Dio, da quello che si fa prima della confessione, come diverso \u00e8 se la confessione \u00e8 frequente o se \u00e8 trascorso molto tempo dalla precedente. \u00c8 Ges\u00f9 che incita spesso alla vigilanza, e Papa Benedetto lo ha ricordato varie volte, anche di recente, parlando alla Penitenzieria Apostolica.<\/p>\n<p style=\"text-align: justify;\">Tendiamo a minimizzare, a dimenticare, o a esagerare ci\u00f2 che facciamo. Dobbiamo chiederci in coscienza, davanti a Dio e alla sua parola, che cosa nella nostra condotta \u00e8 andato contro di Lui e anche se stiamo compiendo ci\u00f2 che Dio ci fa capire che vuole da noi, se adempiamo i suoi comandamenti, i doveri della nostra condizione di vita, ci\u00f2 che le circostanze e le persone che incontriamo ci chiedono volta per volta.<\/p>\n<p style=\"text-align: justify;\">Per aiutare in questo compito i lettori ho preparato delle domande seguendo i dieci comandamenti. Li ho introdotti con testi di beatitudini bibliche, perch\u00e9 ci ricordino, quando ci esaminiamo in coscienza, che vivere i comandamenti \u00e8 strada per la felicit\u00e0 promessaci dal Signore.<\/p>\n<p style=\"text-align: justify;\">\u00c8 importante esaminarci chiedendo luci allo Spirito Santo per non essere come colui che non nota la trave nel proprio occhio e vuole togliere la pagliuzza in quello del fratello, per non essere una guida cieca che conduce altri ciechi al precipizio, per non costruire l\u2019edificio della vita cristiana sulla sabbia, per non lasciare che nel nostro campo interiore abbondi la zizzania seminata nottetempo dal nemico, perch\u00e9 il seme della parola di Dio cada nella terra buona del nostro cuore preparato: via gli sterpi e i sassi, via gli uccelli che ce lo vogliono rubare.<\/p>\n<p style=\"text-align: justify;\">E, in positivo, per essere colui che costruisce la casa sulla roccia, che segue Ges\u00f9 ovunque egli vada, che diventa suo discepolo e va ad annunziare il suo Vangelo nelle circostanze della vita quotidiana, che dona la sua vita per amore e risponde alla sua vocazione. La Madonna che non ha peccato, ma che custodisce e medita ogni cosa della vita di Ges\u00f9 e della nostra nel suo cuore, ci pu\u00f2 aiutare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag Zenit (Zenit.org) 11 luglio 2011 Intervista a don Andrea Mardegan sulla confessione di Antonio Gaspari ROMA _ In un passaggio del Vangelo secondo Giovanni, Ges\u00f9 disse a Nicodemo: \u201cDio, non ha mandato il Figlio nel mondo per condannare il mondo, ma perch\u00e9 il mondo sia salvato per mezzo di lui\u201d (Gv 3,16-18).<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":23535,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,42],"tags":[1940],"class_list":["post-4923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-dottrina-e-morale","tag-confessione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-07T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-21T15:30:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"266\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"\u201cNon per giudicare ma per salvare\u201d\",\"datePublished\":\"2012-03-07T23:00:00+00:00\",\"dateModified\":\"2015-04-21T15:30:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/\"},\"wordCount\":2055,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/confessionale.jpg\",\"keywords\":[\"confessione\"],\"articleSection\":[\"Chiesa\",\"Dottrina e morale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/\",\"name\":\"\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/confessionale.jpg\",\"datePublished\":\"2012-03-07T23:00:00+00:00\",\"dateModified\":\"2015-04-21T15:30:33+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/confessionale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/confessionale.jpg\",\"width\":266,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/non-per-giudicare-ma-per-salvare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNon per giudicare ma per salvare\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-03-07T23:00:00+00:00","article_modified_time":"2015-04-21T15:30:33+00:00","og_image":[{"width":266,"height":189,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"\u201cNon per giudicare ma per salvare\u201d","datePublished":"2012-03-07T23:00:00+00:00","dateModified":"2015-04-21T15:30:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/"},"wordCount":2055,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg","keywords":["confessione"],"articleSection":["Chiesa","Dottrina e morale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/","name":"\u201cNon per giudicare ma per salvare\u201d - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg","datePublished":"2012-03-07T23:00:00+00:00","dateModified":"2015-04-21T15:30:33+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/confessionale.jpg","width":266,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/non-per-giudicare-ma-per-salvare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"\u201cNon per giudicare ma per salvare\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4923"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4923\/revisions"}],"predecessor-version":[{"id":23536,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4923\/revisions\/23536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/23535"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}