{"id":4914,"date":"2012-02-24T12:00:14","date_gmt":"2012-02-24T11:00:14","guid":{"rendered":""},"modified":"2015-11-13T13:04:33","modified_gmt":"2015-11-13T12:04:33","slug":"il-divorzio-in-un-anno-s-bipartisan-alla-camera","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/","title":{"rendered":"Il divorzio in un anno . S&igrave; bipartisan alla Camera"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27734\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg\" alt=\"divorzio\" width=\"250\" height=\"168\" \/><\/a>Il Corriere della Sera<\/strong> 24 febbraio 2012<\/div>\n<p style=\"text-align: center;\"><strong>M.Antonietta Calabr\u00f2 <\/strong><\/p>\n<p style=\"text-align: justify;\">ROMA &#8211; Divorzio in un anno, in due anni se ci sono figli minori. Il primo \u00abs\u00ec\u00bb al cosiddetto \u00abdivorzio breve\u00bb \u00e8 arrivato grazie a un&#8217;intesa bipartisan, in particolare di Pdl e Pd, nella commissione giustizia della Camera. Il testo \u00e8 costituito da due soli articoli, ed era stato messo in \u00ablavorazione\u00bb in commissione il 18 gennaio scorso (dopo che nel 2003 un analogo tentativo di introdurre il divorzio breve era fallito).<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Il primo articolo del testo abbassa appunto di due terzi il tempo di \u00abattesa\u00bb tra separazione e divorzio. Il secondo prevede che in ogni caso la comunione tra marito e moglie si sciolga nel momento in cui il magistrato, in sede di udienza, li autorizzi a vivere separati.<\/div>\n<p style=\"text-align: justify;\">Sono stati respinti tutti gli emendamenti presentati su fronti opposti da Lega e Radicali: dal Carroccio erano arrivate proposte del tutto soppressive delle modifiche. I radicali volevano invece introdurre il divorzio \u00ablampo\u00bb, senza nessun tempo di separazione. La scorsa settimana la commissione aveva anche respinto un emendamento della centrista Paola Binetti che chiedeva di mantenere il termine di tre anni in caso di coppia con figli piccoli e di abbassarlo a due anni per chi ha figli maggiorenni o \u00e8 senza prole.\u00a0 Sar\u00e0 la capogruppo di Montecitorio (insieme al presidente Gianfranco Fini) a dover decidere quando il provvedimento arriver\u00e0 in Aula.<\/p>\n<p style=\"text-align: justify;\"><strong>La proposta di legge approvata dalla commissione \u00ab\u00e8 semplicemente una norma di civilt\u00e0\u00bb<\/strong> ha commentato il relatore Maurizio Paniz, del Pdl. Per il capogruppo del Pd in commissione, Donatella Ferranti, \u00e8 stato trovato \u00abun giusto equilibrio\u00bb, le \u00abnuove norme sono attese dagli italiani\u00bb e quindi per questo andrebbero \u00abcalendarizzate presto in Aula\u00bb. \u00abFinalmente siamo passati dal processo breve al divorzio breve\u00bb ha detto il pd Roberto Giachetti, alludendo al ruolo di Paniz, uno degli avvocati di Berlusconi.<\/p>\n<p style=\"text-align: justify;\"><strong>Secondo le statistiche dell&#8217;Istat, riferite al 2009, pi\u00f9 di un matrimonio su 4 finisce male. <\/strong>In media si divorzia dopo 18 anni di matrimonio. Ci si dice addio a ogni et\u00e0. Poco dopo il matrimonio (18,5%) ma anche dopo 25 anni di unione e sopportazione (16,2%). E se in media ci si separa quando lei raggiunge i 41 anni (21,2% del totale dei casi) e lui i 45 (21,2%), sono in forte aumento gli addii tra i coniugi over 60. Nella classifica tra Nord e Sud, le separazioni sono al minimo nel Sud.<\/p>\n<p style=\"text-align: justify;\">\u00abSe anche il divorzio breve passasse a Montecitorio, al Senato cercheremo di riuscire a non farlo approvare&#8230;\u00bb, ha annunciato il capogruppo pdl a Palazzo Madama, Maurizio Gasparri, nel corso del convegno su \u00abCattolici e bipolarismo\u00bb organizzato dalla Fondazione Magna Carta. Per Gasparri \u00abproprio il disegno di legge sul divorzio breve dimostra \u00abche per difendere i valori cattolici \u00e8 meglio il bipolarismo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Corriere della Sera 24 febbraio 2012 M.Antonietta Calabr\u00f2 ROMA &#8211; Divorzio in un anno, in due anni se ci sono figli minori. Il primo \u00abs\u00ec\u00bb al cosiddetto \u00abdivorzio breve\u00bb \u00e8 arrivato grazie a un&#8217;intesa bipartisan, in particolare di Pdl e Pd, nella commissione giustizia della Camera. Il testo \u00e8 costituito da due soli articoli, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,20],"tags":[315],"class_list":["post-4914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","category-politica-nazionale","tag-divorzio","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-24T11:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-13T12:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il divorzio in un anno . S&igrave; bipartisan alla Camera\",\"datePublished\":\"2012-02-24T11:00:14+00:00\",\"dateModified\":\"2015-11-13T12:04:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/\"},\"wordCount\":453,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/divorzio.jpg\",\"keywords\":[\"divorzio\"],\"articleSection\":[\"Famiglia\",\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/\",\"name\":\"Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/divorzio.jpg\",\"datePublished\":\"2012-02-24T11:00:14+00:00\",\"dateModified\":\"2015-11-13T12:04:33+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/divorzio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/divorzio.jpg\",\"width\":273,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il divorzio in un anno . S&igrave; bipartisan alla Camera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/","og_locale":"it_IT","og_type":"article","og_title":"Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-02-24T11:00:14+00:00","article_modified_time":"2015-11-13T12:04:33+00:00","og_image":[{"width":273,"height":184,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il divorzio in un anno . S&igrave; bipartisan alla Camera","datePublished":"2012-02-24T11:00:14+00:00","dateModified":"2015-11-13T12:04:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/"},"wordCount":453,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg","keywords":["divorzio"],"articleSection":["Famiglia","Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/","name":"Il divorzio in un anno . S&igrave; bipartisan alla Camera - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg","datePublished":"2012-02-24T11:00:14+00:00","dateModified":"2015-11-13T12:04:33+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/divorzio.jpg","width":273,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-divorzio-in-un-anno-s-bipartisan-alla-camera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il divorzio in un anno . S&igrave; bipartisan alla Camera"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4914"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4914\/revisions"}],"predecessor-version":[{"id":27735,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4914\/revisions\/27735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27734"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}