{"id":4913,"date":"2012-02-24T08:13:10","date_gmt":"2012-02-24T07:13:10","guid":{"rendered":""},"modified":"2016-07-07T16:43:10","modified_gmt":"2016-07-07T14:43:10","slug":"i-tecnici-dellomofobia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/","title":{"rendered":"I tecnici dell&#8217;omofobia"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35852\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png\" alt=\"Unar\" width=\"199\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png 224w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar-150x150.png 150w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/>Dal sito <strong>Culturacattolica.it<\/strong> 19 febbraio 2012<\/div>\n<p style=\"text-align: center;\">di <strong>Gianfranco Amato<\/strong><\/p>\n<p style=\"text-align: justify;\">Sembrava che il Governo Monti si dovesse qualificare come un mero esecutivo tecnico incaricato di affrontare le emergenze economiche del nostro Paese, privo di qualunque connotazione politica e soprattutto ben attento a non sfiorare il delicatissimo campo dei cosiddetti temi sensibili. Sembra invece che cos\u00ec non sia.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Lo dimostra la recente Conferenza dal titolo \u201cContrasto della discriminazione basata sull\u2019orientamento sessuale e sull\u2019identit\u00e0 di genere\u201d, organizzata dall\u2019UNAR, l\u2019Ufficio Nazionale Antidiscriminazioni Razziali, tenuta lo scorso 16 febbraio 2012 presso la prestigiosa Sala Polifunzionale della Presidenza del Consiglio dei Ministri, quella di Via Santa Maria.<\/div>\n<p style=\"text-align: justify;\">Ad aprire i lavori, alle 9.30, ci ha pensato Elsa Fornero, Ministro del Lavoro, delle Politiche Sociali e delle Pari Opportunit\u00e0, seguita subito dopo dal Capo Dipartimento Pari Opportunit\u00e0, Patrizia De Rose, che ha introdotto i lavori. Sono quindi intervenuti il Sen. Pietro Marcenaro, Presidente Commissione Diritti Umani del Senato, Massimiliano Monnanni, Direttore dell\u2019UNAR, Ralf-Ren\u00e9 Weingaertner, Direttore del <em>Directorate of Human Rights and Antidiscrimination <\/em>del Consiglio d\u2019Europa, Diego Brasioli, Presidente del Comitato interministeriale diritti umani del Ministero Affari Esteri, un rappresentante dell\u2019OSCAD (Osservatorio per la Sicurezza contro gli Atti Discriminatori), e Filomena Fotia, per conto del Ministero dell\u2019Istruzione, Universit\u00e0 e Ricerca.<\/p>\n<p style=\"text-align: justify;\">Alle 10.45 \u00e8 stato presentato il Progetto LGBT del Consiglio d\u2019Europa e la Raccomandazione CM\/Rec (2010) 5 del Comitato dei Ministri agli Stati membri sulle misure volte a combattere la discriminazione fondata sull\u2019orientamento sessuale o sull\u2019identit\u00e0 di genere (quella raccomandazione, tanto per intenderci, che spesso \u00e8 invocata per pretendere, tra l\u2019altro, anche il riconoscimento del matrimonio tra persone dello stesso sesso).<\/p>\n<p style=\"text-align: justify;\">A presentare il progetto ci hanno pensato Annachiara Cerri, Capo Unit\u00e0 LGBT del Consiglio d\u2019Europa, Dag Robin Simonsen, Responsabile di progetto Unit\u00e0 LGBT del Consiglio d\u2019Europa e Dennis Van Der Veur, esperto di politiche LGBT del Consiglio d\u2019Europa.<\/p>\n<p style=\"text-align: justify;\">Alle 11.30 una seconda sessione della Conferenza \u00e8 stata dedicata alla presentazione delle attivit\u00e0 UNAR nel settore LGBT, a cura di Paolo Patan\u00e8, Presidente Arcigay, Rita De Santis, Presidente Agedo, Porpora Marcasciano, Presidente Movimento Identit\u00e0 Transessuale, Antonio Rotelli, Presidente Rete Lenford e Ivan Scalfarotto, Presidente PARKS.<\/p>\n<p style=\"text-align: justify;\">Alle 12.15 si \u00e8 aperto il dibattito sulla \u00abcondizione delle persone LGBT in Italia e le sfide per il futuro\u00bb, introdotto da Massimiliano Monnanni, nel quale sono intervenuti molti rappresentati della colorita e vasta galassia associativa dell\u2019universo omosessuale: Agedo, ALI, Arcigay, Arcilesbica, ATN, Azione Trans, Certi Diritti, Circolo Mario Mieli, Circolo Maurice Lgbtq, Circolo Pink, Consultorio Transgenere, Crisalide Pangender, Di\u2019 Gay Project, Donne Trans di Puglia, Egma, Equality, Famiglie Arcobaleno, Gaylib, Gaynet, Gay Help Line, I-Ken, Ireos, Libellula, Linfa. MIT, Milk, Parks, Princesa, Queer Lab, Rete Lenford, Sportello Ala Trans, Trans Genere.<\/p>\n<p style=\"text-align: justify;\">Il messaggio pi\u00f9 grave e inquietante che \u00e8 stato lanciato da quella iniziativa, sponsorizzata ad altissimo livello istituzionale governativo, sta nel subdolo tentativo di assimilare l\u2019orientamento sessuale alla razza. Far passare come razzismo forme di discriminazione basate sull\u2019orientamento sessuale.<\/p>\n<p style=\"text-align: justify;\">La \u201ctendenza sessuale\u201d, in realt\u00e0, non pu\u00f2 costituire una qualit\u00e0 paragonabile alla razza, all\u2019origine etnica, ecc. rispetto alla non-discriminazione, perch\u00e9 diversamente da queste, essa appartiene oggettivamente alla sfera etico-morale. E vi sono ambiti nei quali non pu\u00f2 considerarsi ingiusta discriminazione il fatto di tener conto della tendenza sessuale: per esempio nella collocazione di bambini per adozione o affido.<\/p>\n<p style=\"text-align: justify;\">Il <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.vatican.va\/roman_curia\/congregations\/cfaith\/documents\/rc_con_cfaith_doc_19920724_homosexual-persons_it.html\" target=\"_blank\">Magistero della Chiesa Cattolica<\/a><\/span> sul punto \u00e8 chiarissimo, come attesta un documento della Congregazione per la Dottrina della Fede, che merita di essere testualmente riportato in alcuni suoi passi:<\/p>\n<p style=\"text-align: justify;\">12. Le persone omosessuali, in quanto persone umane, hanno gli stessi diritti di tutte le altre persone, incluso il diritto di non essere trattate in una maniera che offende la loro dignit\u00e0 personale. Fra gli altri diritti, tutte le persone hanno il diritto al lavoro, all\u2019abitazione, ecc. Nondimeno questi diritti non sono assoluti. Essi possono essere legittimamente limitati a motivo di un comportamento esterno obiettivamente disordinato. Ci\u00f2 \u00e8 talvolta non solo lecito ma obbligatorio, e inoltre si imporr\u00e0 non solo nel caso di comportamento colpevole ma anche nel caso di azioni di persone fisicamente o mentalmente malate. Cos\u00ec \u00e8 accettato che lo stato possa restringere l\u2019esercizio di diritti, per esempio, nel caso di persone contagiose o mentalmente malate, allo scopo di proteggere il bene comune.<\/p>\n<p style=\"text-align: justify;\">13. Includere la \u201ctendenza omosessuale\u201d fra le considerazioni sulla base delle quali \u00e8 illegale discriminare pu\u00f2 facilmente portare a ritenere l\u2019omosessualit\u00e0 quale fonte positiva di diritti umani, ad esempio, in riferimento alla cosiddetta \u201c<em>affirmative action<\/em>\u201d o trattamento preferenziale nelle pratiche di assunzione. Ci\u00f2 \u00e8 tanto pi\u00f9 deleterio dal momento che non vi \u00e8 un diritto all\u2019omosessualit\u00e0, che pertanto non dovrebbe costituire la base per rivendicazioni giudiziali. Il passaggio dal riconoscimento dell\u2019omosessualit\u00e0 come fattore in base al quale \u00e8 illegale discriminare pu\u00f2 portare facilmente, se non automaticamente, alla protezione legislativa e alla promozione dell\u2019omosessualit\u00e0. L\u2019omosessualit\u00e0 di una persona sarebbe invocata in opposizione a una asserita discriminazione e cos\u00ec l\u2019esercizio dei diritti sarebbe difeso precisamente attraverso l\u2019affermazione della condizione omosessuale invece che nei termini di una violazione di diritti umani fondamentali.<\/p>\n<p style=\"text-align: justify;\">14. La \u201ctendenza sessuale\u201d di una persona non \u00e8 paragonabile alla razza, al sesso, all\u2019et\u00e0, ecc. anche per un\u2019altra ragione che merita attenzione, oltre quella sopramenzionata. La tendenza sessuale di un individuo non \u00e8 in genere nota ad altri a meno che egli identifichi pubblicamente se stesso come avente questa tendenza o almeno qualche comportamento esterno lo manifesti. Di regola, la maggioranza delle persone a tendenza omosessuale che cercano di condurre una vita casta non rende pubblica la sua tendenza sessuale. Di conseguenza il problema della discriminazione in termini di impiego, alloggio, ecc. normalmente non si pone.<\/p>\n<p style=\"text-align: justify;\">Le persone omosessuali che dichiarano la loro omosessualit\u00e0 sono in genere proprio quelle che ritengono il comportamento o lo stile di vita omosessuale essere \u201cindifferente o addirittura buono\u201d , e quindi degno di approvazione pubblica. \u00c8 all\u2019interno di questo gruppo di persone che si possono trovare pi\u00f9 facilmente coloro che cercano di manipolare la Chiesa conquistandosi il sostegno, spesso in buona fede, dei suoi pastori, nello sforzo volto a cambiare le norme della legislazione civile, coloro che usano la tattica di affermare con toni di protesta che qualsiasi critica o riserva nei confronti delle persone omosessuali (\u2026) \u00e8 semplicemente una forma di ingiusta discriminazione. Inoltre, vi \u00e8 il pericolo che una legislazione che faccia dell\u2019omosessualit\u00e0 una base per avere dei diritti possa di fatto incoraggiare una persona con tendenza omosessuale a dichiarare la sua omosessualit\u00e0 o addirittura a cercare un partner allo scopo di sfruttare le disposizioni della legge.<\/p>\n<p style=\"text-align: justify;\">Parole chiarissime.<\/p>\n<p style=\"text-align: justify;\">Ebbene, io rivendico il mio sacrosanto diritto \u2013 senza per questo essere tacciato di razzismo \u2013 di sostenere che l\u2019omosessualit\u00e0 rappresenta una \u00abgrave depravazione\u00bb (<em>Gn <\/em>19,1-29; <em>Rm <\/em>1,24-27; <em>1 Cor <\/em>6,9-10; <em>1 Tm <\/em>1,10.), che i suoi atti \u00absono intrinsecamente disordinati\u00bb (Sacra Congregazione per la Dottrina della Fede, Dich. <em>Persona humana)<\/em>, e \u00abcontrari alla legge naturale\u00bb, poich\u00e9 \u00abprecludono all\u2019atto sessuale il dono della vita e non costituiscono il frutto di una vera complementarit\u00e0 affettiva e sessuale\u00bb (art. 2357 del Catechismo della Chiesa Cattolica). Io rivendico il mio sacrosanto diritto di sostenere che non deve essere giuridicamente riconosciuto il matrimonio tra persone dello stesso sesso, e che non deve essere consentita la possibilit\u00e0 di adozione per le coppie omosessuali. Io rivendico il mio sacrosanto diritto di sostenere che l\u2019orientamento sessuale non pu\u00f2 essere riconosciuto come un diritto fondamentale dell\u2019uomo.<\/p>\n<p style=\"text-align: justify;\">E continuer\u00f2 a rivendicare il mio diritto, costituzionalmente garantito, di esprimere una mia opinione e di professare pubblicamente la mia fede religiosa, fino a quando un Governo Tecnico che ha commissariato la politica, il Parlamento ed i partiti, non imporr\u00e0 per legge la <em>political correctness<\/em> di Bruxelles e mi boller\u00e0 come razzista. Se ci\u00f2 accadr\u00e0, allora vorr\u00e0 dire che i tecnici avranno gettato la maschera, mostrando il loro vero volto. E facendoci cos\u00ec rimpiangere il volto di chi li ha preceduti. <em><em>Vive la politique!<\/em><\/em><\/p>\n<p style=\"text-align: center;\">__________________________<\/p>\n<p style=\"text-align: center;\"><strong>La Bussola quotidiana<\/strong> 20 febbraio 2012<\/p>\n<p style=\"text-align: center;\"><strong>I TECNICI DELLA LOBBY GAY<\/strong><\/p>\n<p style=\"text-align: center;\">di<strong> Riccardo Cascioli<\/strong><\/p>\n<p style=\"text-align: justify;\">Non ce ne vogliano i lettori se torniamo sull\u2019argomento <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=4890\" target=\"_blank\">a distanza di pochi giorni<\/a>, ma l\u2019attivismo del ministro Fornero per la promozione dei diritti gay \u00e8 un fenomeno che deve essere rilevato, tanto pi\u00f9 che viene ignorato dalla grande stampa nazionale.<\/p>\n<p style=\"text-align: justify;\">Dunque il 16 febbraio, il ministro del Welfare (con delega per le Pari Opportunit\u00e0) ha aperto il convegno organizzato dall\u2019UNAR (Ufficio Nazionale Antidiscriminazioni Razziali), operante presso la presidenza del Consiglio dei ministri, con tutta la galassia delle associazioni LGBT (Lesbo-Gay-Bisex-Transgender). Il convegno si \u00e8 tenuto nella Sala polifunzionale della Presidenza del Consiglio dei ministri con il titolo \u201dContrasto della discriminazione basata sull\u2019orientamento sessuale e sull\u2019identit\u00e0 di genere\u201d. Nell\u2019occasione l\u2019Italia ha firmato un programma del Consiglio d\u2019Europa per promuovere l\u2019agenda gay.<\/p>\n<p style=\"text-align: justify;\">Addirittura l\u2019Italia \u2013 come ha detto il direttore dell\u2019UNAR Massimiliano Monnanni &#8211; \u201c\u00e8 il primo Paese dell&#8217;Unione europea ad aderire al programma del Consiglio d\u2019Europa che, recependo la\u00a0 Raccomandazione adottata dal Comitato dei Ministri CM\/REC 5 del 2010, mira ad offrire assistenza tecnica e finanziaria agli Stati membri del Consiglio d&#8217;Europa nell\u2019implementazione di politiche di contrasto alla discriminazione nei confronti delle persone LGBT, avvalendosi, in ciascuno stato, di un network informale di focal point governativi&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il programma prevede interventi nel campo della scuola per \u201cprevenire e contrastare il bullismo omofobico e transfobico\u201d, la prevenzione e il contrasto della discriminazione nel mondo del lavoro, informazione e sensibilizzazione nei confronti delle forze dell\u2019ordine; e l\u2019intervento anche su quanto verr\u00e0 detto in proposito sui mass media (e su questo vigiler\u00e0 anche il sindacato dei giornalisti).<\/p>\n<p style=\"text-align: justify;\">La Fornero ha dato un grosso sostegno a questo programma, e ancora una volta ha sottolineato l\u2019importanza dell\u2019intervento nella scuola per combattere queste discriminazioni \u201cattraverso l&#8217;educazione e la formazione alle diversit\u00e0 che esistono tra le persone e che noi dobbiamo vivere come un fatto bello della vita&#8221;. Come si vede, per i ministri di questo governo non solo il posto fisso \u00e8 noioso, ma anche essere maschio o femmina tutta la vita.<\/p>\n<p style=\"text-align: justify;\">&#8220;Dobbiamo fare molto in questo Paese sotto il profilo della discriminazione \u2013 ha aggiunto la Fornero -, dobbiamo mettere in campo strumenti normativi-educativi fin dalla prima infanzia, sapendo che abbiamo poche risorse&#8221;.<\/p>\n<p style=\"text-align: justify;\">Poi si \u00e8 scusata se in questi mesi ha dato l\u2019impressione di dedicarsi troppo al tema del lavoro e delle pensioni perch\u00e9 per lei in realt\u00e0 non \u00e8 cos\u00ec: &#8220;l&#8217;impressione che si pu\u00f2 avere \u00e8 che la mia attenzione sia spostata su altri temi: per quanto riguarda il mio convincimento non \u00e8 cos\u00ec. Non \u00e8 un&#8217;adesione di maniera la mia, ma nasce da un profondo convincimento&#8221;.<\/p>\n<p style=\"text-align: justify;\">Parole che sono state ben accolte da Ralf-Rene&#8217; Weingaertner, direttore della sezione Diritti umani e Antidiscriminazione del Consiglio d&#8217;Europa, che ha parlato compiaciuto di \u201cnuova strategia dell\u2019Italia\u201d in materia ma ha poi sottolineato che devono anche mutare normativa e mentalit\u00e0. E\u2019 evidente dunque che mentre si parla \u2013 e si parler\u00e0 &#8211; tanto di riforma del mercato del lavoro tra mille contrasti, sul tema gay e transgender il ministro Fornero ha un\u2019autostrada davanti su cui sta procedendo a grande velocit\u00e0.<\/p>\n<p style=\"text-align: justify;\">A questo punto, possiamo immaginare cosa ci aspetta nei prossimi mesi: programmi scolastici obbligatori che insegnino come l\u2019omosessualit\u00e0 sia una delle tante opzioni possibili in materia di genere; tentativo di equiparare le unioni gay ai matrimoni eterosessuali; apertura alle adozioni da parte di gay e lesbiche; controllo sulle opinioni espresse sui mass media e via di questo passo.<\/p>\n<p style=\"text-align: justify;\">Ovviamente nessuno pensa di chiedere chiarimenti al governo in materia (visto che oltre alla Fornero \u00e8 direttamente implicata la Presidenza del Consiglio dei ministri): n\u00e9 una voce si \u00e8 alzata dall\u2019interno dell\u2019esecutivo, n\u00e9 abbiamo letto note di agenzie e giornali legati alla Conferenza episcopale, malgrado la preparazione in vista dell\u2019Incontro mondiale delle famiglie dovrebbe rendere pi\u00f9 attenti e sensibili a questi argomenti. Ma c\u2019\u00e8 da capirli: in questi giorni sono tutti troppo impegnati a difendersi dai pericolosissimi attacchi di Adriano Celentano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal sito Culturacattolica.it 19 febbraio 2012 di Gianfranco Amato Sembrava che il Governo Monti si dovesse qualificare come un mero esecutivo tecnico incaricato di affrontare le emergenze economiche del nostro Paese, privo di qualunque connotazione politica e soprattutto ben attento a non sfiorare il delicatissimo campo dei cosiddetti temi sensibili. Sembra invece che cos\u00ec non &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35852,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[916,341],"class_list":["post-4913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-omosessualit","tag-ideologia-gay","tag-omofobia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I tecnici dell&#039;omofobia - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I tecnici dell&#039;omofobia - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-24T07:13:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-07T14:43:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"224\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I tecnici dell&#8217;omofobia\",\"datePublished\":\"2012-02-24T07:13:10+00:00\",\"dateModified\":\"2016-07-07T14:43:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/\"},\"wordCount\":1962,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/Unar.png\",\"keywords\":[\"ideologia gay\",\"omofobia\"],\"articleSection\":[\"Omosessualit&agrave;\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/\",\"name\":\"I tecnici dell'omofobia - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/Unar.png\",\"datePublished\":\"2012-02-24T07:13:10+00:00\",\"dateModified\":\"2016-07-07T14:43:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/Unar.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/Unar.png\",\"width\":224,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-tecnici-dellomofobia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I tecnici dell&#8217;omofobia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I tecnici dell'omofobia - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/","og_locale":"it_IT","og_type":"article","og_title":"I tecnici dell'omofobia - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-02-24T07:13:10+00:00","article_modified_time":"2016-07-07T14:43:10+00:00","og_image":[{"width":224,"height":225,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I tecnici dell&#8217;omofobia","datePublished":"2012-02-24T07:13:10+00:00","dateModified":"2016-07-07T14:43:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/"},"wordCount":1962,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png","keywords":["ideologia gay","omofobia"],"articleSection":["Omosessualit&agrave;"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/","name":"I tecnici dell'omofobia - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png","datePublished":"2012-02-24T07:13:10+00:00","dateModified":"2016-07-07T14:43:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/Unar.png","width":224,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-tecnici-dellomofobia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I tecnici dell&#8217;omofobia"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4913"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4913\/revisions"}],"predecessor-version":[{"id":35853,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4913\/revisions\/35853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35852"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}