{"id":4909,"date":"2012-02-23T00:00:00","date_gmt":"2012-02-22T23:00:00","guid":{"rendered":""},"modified":"2016-06-06T11:34:52","modified_gmt":"2016-06-06T09:34:52","slug":"una-fede-indebolita-nei-palazzi-degli-intrighi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/","title":{"rendered":"Una Fede Indebolita nei Palazzi degli Intrighi"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34202\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg\" alt=\"vaticano\" width=\"250\" height=\"172\" \/>Corriere della Sera<\/strong> 13 febbraio 2012<\/div>\n<p style=\"text-align: center;\">di <strong>Vittorio Messori <\/strong><\/p>\n<p style=\"text-align: justify;\">Di questi tempi, seguire certe non edificanti cronache vaticane pu\u00f2 essere gustoso o rattristante, a seconda degli umori anticlericali o clericali. In realt\u00e0, non dovrebbe scomporsi pi\u00f9 di tanto il cattolico che non solo conosca la storia della sua Chiesa ma che non sia dimentico degli avvertimenti del Vangelo.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Questa Chiesa, cio\u00e8, \u00e8 un campo dove buon grano e velenosa zizzania cresceranno sempre insieme; \u00e8 una rete gettata a mare e nella quale convivranno sempre pesci buoni e cattivi. Parola di Ges\u00f9 stesso, che esorta a non scandalizzarsi per questo e a non tentare neppure di dividere il sano dal guasto, riservando a s\u00e9 questo compito nel giorno del Grande Giudizio.<\/div>\n<p style=\"text-align: justify;\">Esempio primo di questa situazione \u00e8 ovviamente il centro e il motore della \u00abmacchina\u00bb ecclesiale: la Curia vaticana, cio\u00e8, l&#8217; amministrazione centrale di quella che la Tradizione chiama \u00abla Chiesa militante\u00bb. Beh, quanto a questa, non fu un eretico o un mangiapreti, bens\u00ec una santa che Paolo VI volle proclamare \u00abdottore della Chiesa\u00bb, la compatrona d&#8217; Italia, Caterina da Siena, a constatare: \u00abLa corte del Padre Santo Nostro sembrami talora un nido d&#8217; angeli, tal altra un covo di vipere\u00bb.<\/p>\n<p style=\"text-align: justify;\">Bene e male, dunque, uniti nella stessa realt\u00e0, com&#8217; \u00e8 di ogni cosa umana: e la Chiesa \u00e8 anche una istituzione umana, \u00e8 un involucro storico (con i limiti che ne derivano) per contenere un Mistero metastorico. Ma a una valutazione morale faremo un cenno pi\u00f9 sotto.<\/p>\n<p style=\"text-align: justify;\">C&#8217; \u00e8, prima, un aspetto \u00aborganizzativo\u00bb da considerare. Va ricordato, infatti, che dal Vaticano odierno non giungono solo echi di \u00abscandali\u00bb per affari, sesso, potere. \u00c8 la macchina stessa dell&#8217; amministrazione che da anni ormai sembra incepparsi con inquietante frequenza; sono gli equivoci, le distrazioni, le gaffe diplomatiche, persino gli errori &#8211; magari in documenti solenni &#8211; in quel latino che \u00e8 ancora la sua lingua ufficiale, ma che \u00e8 conosciuto sempre meno e sempre peggio.<\/p>\n<p style=\"text-align: justify;\">D&#8217; accordo, la Curia, al pari della Chiesa stessa, <em>semper reformanda est<\/em> . Ma qui non sembra possibile una \u00abriorganizzazione aziendale\u00bb, perch\u00e9 sembrano mancare le forze fresche e di qualit\u00e0. Gli infiniti uffici vaticani sono retti, sin dai tempi della Controriforma, da personale ecclesiastico che giunge da tutte le diocesi e da tutti gli ordini religiosi del mondo. Ma \u00e8 un mondo, questo nostro, dove la maggioranza delle diocesi e delle congregazioni ha chiuso seminari e studentati per mancanza di frequentatori e il loro problema non \u00e8 certo quello di inviare a Roma, al servizio della Chiesa universale, i giovani pi\u00f9 promettenti. Questi giovani non ci sono e, se qualcuno c&#8217; \u00e8, \u00e8 difeso gelosamente da vescovi e dai superiori generali.<\/p>\n<p style=\"text-align: justify;\">Eppure, dopo quel Vaticano II che avrebbe dovuto snellire la struttura ecclesiale, l&#8217; Annuario pontificio ha quasi triplicato le sue pagine, l&#8217; espansione burocratica non ha avuto sosta. Aumentano funzioni, posti, responsabilit\u00e0, mentre vengono meno, anno dopo anno, le risorse umane. E i pochi rincalzi non sembrano in grado di portare quella schiacciante responsabilit\u00e0 che \u00e8 gestire in terra nientemeno che la volont\u00e0 del Cielo.<\/p>\n<p style=\"text-align: justify;\">Dunque, il realismo cattolico sembra imporre un drastico ridimensionamento della struttura di una Catholica che, di massa quale era, sta diventando o \u00e8 gi\u00e0 divenuta comunit\u00e0 di minoranza. Voler mantenere l&#8217; imponente apparato barocco quando le forze vengono a mancare (e le poche che ancora ci sono talvolta non sono adeguate) porta inevitabilmente agli sbandamenti e agli errori che si constatano nella gestione ecclesiale.<\/p>\n<p style=\"text-align: justify;\">Prendere, dunque, sul serio chi propone di ritornare al primo millennio, coll&#8217; affidare all&#8217; Unesco, come siti artistici e turistici, i palazzi sul colle Vaticano e tornare alla \u00abvera\u00bb cattedrale del vescovo di Roma, quella di san Giovanni in Laterano, con una struttura istituzionale al minimo? Non \u00e8 il caso di rifugiarsi in simili estremi, ma il problema esiste e dovr\u00e0 essere affrontato, pur lontani da ideologie \u00absessantottine\u00bb, di demagogia pauperista.<\/p>\n<p style=\"text-align: justify;\">Ma, dicevamo, sembra esserci anche un cedimento morale che non \u00e8 solo sessuale (questione pedofili, ma non solo, docet ) ma \u00e8 anche il ritorno, quasi come ai tempi rinascimentali, di palazzi vaticani ridotti a nodi di intrighi e di lotte per carriere, poteri, denaro, interessi ideologici e politici.<\/p>\n<p style=\"text-align: justify;\">Ebbene, qui, non c&#8217; \u00e8 riforma che tenga, qui non c&#8217; \u00e8 rimedio solo umano. Qui, ogni tecnica di riorganizzazione aziendale \u00e8 ridicolmente impotente e deve aprirsi allo \u00abscandalo\u00bb della preghiera. Parola di papa Benedetto XVI ma, per decenni, parola anche del cardinal Joseph Ratzinger.<\/p>\n<p style=\"text-align: justify;\">Se la Chiesa \u00e8 in crisi, ha sempre ripetuto, \u00e8 perch\u00e9 \u00e8 in crisi la fede degli uomini di Chiesa. Gerarchia non esclusa. Giunse a dirmi, una volta: \u00abAl punto in cui siamo, lo confesso: la fede , quella piena, quella che non esita, mi sembra essersi fatta cos\u00ec rara che, incontrandola , mi stupisce di pi\u00f9 che l&#8217; incredulit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Per questo \u00e8 tornato alle radici di tutto, con i suoi tre volumi sul Ges\u00f9 della storia, per questo ha voluto un organo apposito per la nuova evangelizzazione, per questo ha proclamato questo 2012 \u00abanno della fede\u00bb. L&#8217; <em>intendance suivra<\/em> , diceva Napoleone: prima la conquista, poi i funzionari dell&#8217; amministrazione.<\/p>\n<p style=\"text-align: justify;\">La Chiesa, papa Benedetto ne \u00e8 certo, ha da fare essa pure una conquista, anzi una riconquista: quella della fede nella storicit\u00e0 dei Vangeli, nel Dio che si \u00e8 incarnato in una donna, in un Ges\u00f9 che risorgendo ha mostrato di essere il Cristo. La Chiesa ha ormai pochi uomini e talvolta poco adeguati, come si dice?<\/p>\n<p style=\"text-align: justify;\">Ebbene, lo sfaldamento, per l&#8217; istituzione, sarebbe sicuro se chi \u00e8 ancora \u00abal lavoro nella vigna del Signore\u00bb (cos\u00ec ama dire il Papa) perdesse la prospettiva di impegnarsi non per un premio umano bens\u00ec divino. Se la fede vacilla o si spegne, se non \u00e8 pi\u00f9 la ragione quotidiana di vita, la pigrizia sorniona del burocrate \u00e8 in agguato, il vecchio monsignore come il giovane religioso sono pronti a trasformarsi in funzionari da ministero clericale e, come tali, soggetti a ogni tentazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corriere della Sera 13 febbraio 2012 di Vittorio Messori Di questi tempi, seguire certe non edificanti cronache vaticane pu\u00f2 essere gustoso o rattristante, a seconda degli umori anticlericali o clericali. In realt\u00e0, non dovrebbe scomporsi pi\u00f9 di tanto il cattolico che non solo conosca la storia della sua Chiesa ma che non sia dimentico degli &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[157],"class_list":["post-4909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-chiesa-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-22T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-06T09:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Una Fede Indebolita nei Palazzi degli Intrighi\",\"datePublished\":\"2012-02-22T23:00:00+00:00\",\"dateModified\":\"2016-06-06T09:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/\"},\"wordCount\":956,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/vaticano.jpg\",\"keywords\":[\"chiesa\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/\",\"name\":\"Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/vaticano.jpg\",\"datePublished\":\"2012-02-22T23:00:00+00:00\",\"dateModified\":\"2016-06-06T09:34:52+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/vaticano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/vaticano.jpg\",\"width\":270,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-fede-indebolita-nei-palazzi-degli-intrighi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una Fede Indebolita nei Palazzi degli Intrighi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/","og_locale":"it_IT","og_type":"article","og_title":"Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-02-22T23:00:00+00:00","article_modified_time":"2016-06-06T09:34:52+00:00","og_image":[{"width":270,"height":186,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Una Fede Indebolita nei Palazzi degli Intrighi","datePublished":"2012-02-22T23:00:00+00:00","dateModified":"2016-06-06T09:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/"},"wordCount":956,"commentCount":0,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg","keywords":["chiesa"],"articleSection":["Chiesa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/","name":"Una Fede Indebolita nei Palazzi degli Intrighi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg","datePublished":"2012-02-22T23:00:00+00:00","dateModified":"2016-06-06T09:34:52+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/vaticano.jpg","width":270,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-fede-indebolita-nei-palazzi-degli-intrighi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Una Fede Indebolita nei Palazzi degli Intrighi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4909"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4909\/revisions"}],"predecessor-version":[{"id":34203,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4909\/revisions\/34203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34202"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}