{"id":49011,"date":"2020-11-05T00:00:15","date_gmt":"2020-11-04T23:00:15","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=49011"},"modified":"2020-11-05T10:57:47","modified_gmt":"2020-11-05T09:57:47","slug":"ecco-perche-un-vero-cattolico-non-puo-che-votare-trump","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/","title":{"rendered":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/11\/Trump.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36726 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/11\/Trump.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/11\/Trump.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/11\/Trump-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>La Nuova Bussola<\/strong> <strong>quotidiana<\/strong> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">3 Novembre 2020 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>\u00a0<\/strong><em>A spiegare come mai un uomo che ama e vuole seguire la Chiesa deve sostenere il presid<\/em><em>ente repubblicano \u00e8 un libro di <\/em><em>Austin Ruse,<\/em><em> soprannumerario dell&#8217;Opus Dei: <\/em><em>Trump non ha mai violato una volta la dottrina sociale cattolica,<\/em> <em>nemmeno in tema di accoglien<\/em><em>za e di povert\u00e0, <\/em><em>oltre ad essersi battuto per i principi non negoziabili (vedi\u00a0l&#8217;aborto<\/em><em>) pi\u00f9 di ogni suo predecessore. <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Marco Respinti<\/strong><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Negli Stati Uniti d\u2019America li chiamano \u00abcafeteria Catholic\u00bb e sono un po\u2019 come i \u00absocial smoker\u00bb. Non ci credono sul serio, i secondi nel tabacco e i primi nella dottrina. Sono quelli che immancabilmente scroccano, giusto per stare in compagnia. Gli uni non distinguono una bionda dal trinciato, gli altri nemmeno, e pensano regolarmente con la testa <em>liberal<\/em> degli altri. <\/span><\/p>\n<div id=\"attachment_48145\" style=\"width: 201px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/08\/Joe_Biden.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48145\" class=\"wp-image-48145 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/08\/Joe_Biden.jpg\" alt=\"\" width=\"201\" height=\"251\" \/><\/a><p id=\"caption-attachment-48145\" class=\"wp-caption-text\">Joe Biden<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>I \u00abcattolici da bar\u00bb hanno una serie di chiodi fissi:<\/strong> uno, enorme, \u00e8 il presidente Donald J. Trump. Ritengono immorale appoggiarlo e immorale in modo speciale che un cattolico lo appoggi. Il punto per\u00f2 \u00e8 che non sanno nemmeno cosa sia, la morale: quella cosa che, essendo serissima, distingue, con precisione da orologiaio, le immoralit\u00e0 di un uomo che abbia pure la ventura di diventare presidente del Paese pi\u00f9 importante del mondo e gli atti di governo di un uomo soprattutto alla guida del Paese pi\u00f9 importante del mondo. Poi ci sono i cattolici veri, ovvero quelli che prendono la dottrina sul serio e non a cialde compostabili, tanti dei quali sono, per gli stessi motivi, nemici di Trump. \u00c8 per tutti questi cattolici in libera uscita che Austin Ruse, cattolico vero, ha scritto <em>The Catholic Case for Trump<\/em> (Regnery, Washington 2020). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Ruse \u00e8 il presidente del Center for Family and Human Rights<\/strong> (C-Fam), una Ong conservatrice che monitora e denuncia la cultura abortista e l\u2019ideologia <em>gender<\/em> nell\u2019ONU e in altri organismi internazionali. \u00c8 soprannumerario dell\u2019Opus Dei e nel settembre 2016 fu scelto da Trump per il<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.p2016.org\/trump\/trump092216pr.html\" target=\"_blank\" rel=\"noopener noreferrer\">proprio comitato cattolico d\u2019indirizzo<\/a><\/span>. <span style=\"color: #000000;\">Il suo \u00e8 uno di quei libri che benedici il Cielo per essere stato scritto. Ridotto all\u2019osso, \u00e8 l\u2019illustrazione documentata e ragionata dei motivi per cui, il 3 novembre, un cattolico deve votare Trump: non cio\u00e8 semplicemente pu\u00f2, ma <em>deve<\/em> farlo. Primo, perch\u00e9 il presidente Trump non mai ha violato la dottrina sociale cattolica. Secondo, perch\u00e9 il suo avversario, Joe Biden, \u00e8 incommensurabilmente peggio. Terzo, perch\u00e9 il suo avversario \u00e8 Joe Biden, punto. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Biden \u00e8 infatti cattolico.<\/strong> Cos\u00ec almeno dice l\u2019anagrafe. Trump no, dice sempre <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/Trump.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39478 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/Trump.jpg\" alt=\"\" width=\"277\" height=\"182\" \/><\/a>l\u2019anagrafe. Ogni posizione di Biden \u00e8 per\u00f2 incompatibile con il magistero della Chiesa, anzi contraddice il magistero in modo patente. Biden \u00e8 dunque estremamente imbarazzante per qualsiasi cattolico. Se Biden non fosse stato cattolico, per un cattolico Trump sarebbe stato comunque la scelta migliore, anzi obbligata, ma quanto meno non vi sarebbe stato scandalo. Questo al netto delle posizioni personali. Qualcuno punta infatti ancora il dito contro il Trump sciupafemmine. Ora, in primo luogo, da quando \u00e8 diventato presidente, quattro anni fa, Trump non ha dato adito ad alcuna diceria in questo ambito, ma soprattutto il fatto che Biden appaia su questo piano pi\u00f9 \u201cpulito\u201d non elimina il fatto, gravissimo, che le sue posizioni pubbliche siano, cattolicamente parlando, e appunto con scandalo, essendo lui cattolico, irrimediabilmente sciagurate. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Per elencare tutto bisognerebbe scriverci un libro,<\/strong> ma, appunto, lo ha gi\u00e0 fatto Ruse. Potr\u00e0 allora bastare qualche esempio. Partiamo da quelli consuetamente additati dagli avversari <em>liberal<\/em> di Trump e da certi cattolici: la povert\u00e0 e l\u2019ambiente. Ebbene, la ricetta economica di Trump, fatta anche di riduzioni fiscali, ha prodotto una crescita fermata soltanto dalla crisi del Covid-19. Questo ha prodotto ricchezza diffusa e calo drastico della disoccupazione, che ha raggiunto i minimi storici da un cinquantennio a prima del Covid-19. Come sottolinea Ruse, la disoccupazione \u00e8 scesa al minimo in specie per gli afro-americani, per i <em>latinos<\/em> e per le donne, le categorie pi\u00f9 svantaggiate, sul serio o nella retorica <em>liberal<\/em>. La lotta alla povert\u00e0 \u00e8 una richiesta della dottrina sociale cattolica e Trump ha risposto superbamente, a meno di non imputare stupidamente a lui la colpa della pandemia diffusasi dalla Cina. Del resto i dati dei giorni scorsi<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.foxbusiness.com\/economy\/gdp-numbers-trump-economy-andy-puzder\" target=\"_blank\" rel=\"noopener noreferrer\">indicano che l\u2019economia americana \u00e8 nuovamente in rialzo<\/a><\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quanto all\u2019ecologia, Trump sta cercando di non sacrificare<\/strong> i grandi risultati <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-46182 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente-300x150.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente-768x384.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente-1024x512.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/greta-thunberg_clima_ambiente.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>economici che hanno fatto bene ai poveri per la <em>woodoo science<\/em> totalmente imperniata a denunciare l\u2019uomo come il cancro della terra, laddove l\u2019uomo \u00e8 piuttosto l\u2019unica risorsa possibile per fronteggiare le crisi ambientali. E anche questo \u00e8 in linea con il magistero, tant\u2019\u00e8 che nemmeno orientamenti culturali differenti presenti fra uomini di Chiesa e persino presso il pontefice, per quanto diffusi accoratamente, sono mai diventati, giacch\u00e9 non possono farlo, questioni dottrinali. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Un terzo punto \u00e8 l\u2019immigrazione,<\/strong> ma qui la risposta \u00e8 facile. Gli Stati Uniti restano il primo Paese del mondo per numero di stranieri accolti e solo uno sguardo molto superficiale pu\u00f2 omettere di dire che lo sforzo dell\u2019Amministrazione Trump \u00e8 sempre stato quello di arginare l\u2019immigrazione clandestina e l\u2019illegalit\u00e0 che essa si porta dietro in tema di droga, violenza, magari terrorismo. Povert\u00e0, ambiente e immigrazione sono per\u00f2 priorit\u00e0 assolute soltanto per chi dimentica che prima ci sono princ\u00ecpi non negoziabili, quelli che non possono mai venire dopo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Sull\u2019aborto Trump ha infatti fatto pi\u00f9 di qualsiasi altro presidente <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/pro_life.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32176 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/pro_life.jpg\" alt=\"\" width=\"304\" height=\"228\" \/><\/a>americano<\/strong>, laddove Biden difende l\u2019aborto come un diritto. Trump ha cio\u00e8 ripetuto le politiche benemerite dei suoi predecessori che si sono spesi per la vita umana nascente (su tutte l\u2019implementazione della cosiddetta \u00abMexico City Policy\u00bb, che nega i fondi dei contribuenti americani per il sostengo dell\u2019aborto all\u2019estero), ma le ha anche potenziate, ampliandone la portata, aumentandone il peso e cercando di renderle il pi\u00f9 possibile strutturali firmando leggi ed emettendo ordini esecutivi senza precedenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>C\u2019\u00e8 una cosa che i<\/strong> <em><strong>liberal<\/strong><\/em> <strong>e i cattolici da salotto o capatosta<\/strong> non capiranno mai, e Ruse la dice cattolicamente benissimo. Che Trump sia sinceramente antiabortista o no, la sua politica \u00e8 stata pi\u00f9 antiabortista di quella dei suoi predecessori antiabortisti. Aggiunto che probabilmente Trump, da ondivago sul tema che era, \u00e8 assai probabilmente diventato antiabortista convinto, tutto sta nel suo essere anzitutto un uomo di affari. Nel 2016 strinse un patto con i <em>pro-lifer<\/em> e, eletto presidente, ha mantenuto il patto. \u00c8 da <em>businessman<\/em>, \u00e8 da persona retta ed \u00e8 da cattolico. Sicuramente non \u00e8 da uomo politico, specie ormai in via di estinzione riconoscibile per la memoria corta. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Fa del resto testo la questione<\/strong> <em><strong>gender<\/strong><\/em><strong>.<\/strong> Ruse riconosce senza problemi che <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/trans_gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-48315 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/trans_gender.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>questo \u00e8 il territorio per Trump pi\u00f9 sdrucciolevole, eppure in pubblico ha sempre tenuto la barra dritta: niente <em>trans<\/em> nell\u2019esercito, difesa di quella libert\u00e0 religiosa che negli Stati Uniti \u00e8 lo scudo principale per fermare le imposizioni <em>gender<\/em> e fiera opposizione all\u2019\u00abEqual Act\u00bb, che invece Biden ha promesso di firmare il primo giorno di presidenza qualora venisse eletto, avendolo il Congresso a maggioranza Democratica approvato nel 2019. L\u2019\u00abEqual Act\u00bb imporrebbe a un\u2019impresa qualsiasi di assumere anche personale di orientamento opposto a quello del titolare. Per esempio una organizzazione <em>pro life<\/em> sarebbe tenuta a mettere a libro paga anche un attivista per l\u2019aborto. Basterebbe anche solo questo, dice Ruse, a fare di Trump il candidato migliore possibile. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Si aggiunga poi il minor numero di guerre possibili,<\/strong> con il minor spreco di vite umane immaginabile, come insegna la dottrina sociale della Chiesa, che Trump ha condotto e condurr\u00e0, e il fatto che solo lui \u00e8 riuscito a concludere la pace tra Israele e diversi Paesi arabi. Quanto alla Corte Suprema, punto qualificante decisivo di ogni presidente americano, il libro di Ruse \u00e8 uscito prima che Amy Coney Barrett venisse eletta al massimo tribunale del Paese, e qui le medaglie di Trump da politiche si fanno istituzionali. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Il libro di Ruse ha per\u00f2 un difetto.<\/strong> Il titolo. Trump \u00e8 il candidato migliore per qualunque persona abbia a cuore davvero un mondo (visto il ruolo che gli Stati Uniti hanno in esso) un tantino migliore che se venisse eletto Biden pi\u00f9 qualche migliaio di vite umane salvate. Era una speranza quattro anni fa, quando il problema era Hillary Clinton, \u00e8 una certezza da libro di storia oggi alla vigilia di elezioni cruciali. Per questo il bel libro di Ruse \u00e8 un libro sul serio cattolico.<\/span><\/p>\n<p>_______________________<\/p>\n<p>[nota di <strong>Rassegna Stampa<\/strong>. le medesime considerazioni valgono anche per i &#8220;cattolici da bar&#8221; di casa nostra, che come negli Usa vanno a messa la domenica ma pensano come i radicalchic per il resto della settimana]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola quotidiana 3 Novembre 2020 \u00a0A spiegare come mai un uomo che ama e vuole seguire la Chiesa deve sostenere il presidente repubblicano \u00e8 un libro di Austin Ruse, soprannumerario dell&#8217;Opus Dei: Trump non ha mai violato una volta la dottrina sociale cattolica, nemmeno in tema di accoglienza e di povert\u00e0, oltre ad &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":49012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[2523,1298,2401],"class_list":["post-49011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stati-uniti","tag-donald-trump","tag-elezioni-presidenziali","tag-stati-uniti","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T23:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T09:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump\",\"datePublished\":\"2020-11-04T23:00:15+00:00\",\"dateModified\":\"2020-11-05T09:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/\"},\"wordCount\":1408,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Usa_elezioni.jpg\",\"keywords\":[\"Donald Trump\",\"elezioni presidenziali\",\"Stati Uniti\"],\"articleSection\":[\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/\",\"name\":\"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Usa_elezioni.jpg\",\"datePublished\":\"2020-11-04T23:00:15+00:00\",\"dateModified\":\"2020-11-05T09:57:47+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Usa_elezioni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Usa_elezioni.jpg\",\"width\":1300,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/","og_locale":"it_IT","og_type":"article","og_title":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-11-04T23:00:15+00:00","article_modified_time":"2020-11-05T09:57:47+00:00","og_image":[{"width":1300,"height":682,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump","datePublished":"2020-11-04T23:00:15+00:00","dateModified":"2020-11-05T09:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/"},"wordCount":1408,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg","keywords":["Donald Trump","elezioni presidenziali","Stati Uniti"],"articleSection":["Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/","name":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg","datePublished":"2020-11-04T23:00:15+00:00","dateModified":"2020-11-05T09:57:47+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_elezioni.jpg","width":1300,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ecco-perche-un-vero-cattolico-non-puo-che-votare-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Ecco perch\u00e9 un vero cattolico non pu\u00f2 che votare Trump"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/49011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=49011"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/49011\/revisions"}],"predecessor-version":[{"id":49016,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/49011\/revisions\/49016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/49012"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=49011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=49011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=49011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}