{"id":48960,"date":"2020-10-29T00:00:22","date_gmt":"2020-10-28T23:00:22","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=48960"},"modified":"2020-10-28T19:24:11","modified_gmt":"2020-10-28T18:24:11","slug":"il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/","title":{"rendered":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-48963 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia-1.jpg\" alt=\"\" width=\"262\" height=\"192\" \/><\/a>Atlantico <\/strong>28 Ottobre 2020, <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"> di <strong>Umberto Camillo Iacoviello<\/strong>, <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0Emanuele Fusi nasce a Barga (Lucca) nel 1978. Laureato in giurisprudenza intraprende la professione di avvocato presso il Foro di Lucca, specializzandosi in diritto penale e diritto tributario. \u00c8 autore di diversi romanzi e saggi, per <em>Passaggio al bosco<\/em> ha pubblicato il saggio\u00a0<em>\u201cWhite guilt, il razzismo contro i bianchi al tempo della societ\u00e0 multietnica\u201d<\/em>, e per la stessa casa editrice ha da poco pubblicato il saggio\u00a0<em>\u201cLa sinistra degli orchi\u201d<\/em>, in cui ricostruisce, a partire dagli \u201950, il tentativo di sdoganare la pedofilia. <\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UMBERTO CAMILLO IACOVIELLO:<\/strong> Lei nel suo libro parla del tentativo di sdoganare la pedofilia, al grande pubblico pu\u00f2 sembrare assurdo, ma c\u2019\u00e8 una parte del mondo accademico che da decenni cerca di infrangere questo tab\u00f9. Chi sono i pionieri della \u201cnormalizzazione della pedofilia\u201d?<\/span><\/p>\n<div id=\"attachment_26586\" style=\"width: 292px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/Alfred-Charles-Kinsey.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26586\" class=\"wp-image-26586\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/Alfred-Charles-Kinsey.jpg\" alt=\"\" width=\"292\" height=\"219\" \/><\/a><p id=\"caption-attachment-26586\" class=\"wp-caption-text\">Alfred Kinsey<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EMANUELE FUSI:<\/strong> Il discorso \u00e8 complesso. Diciamo che tutto parte storicamente dalla rivoluzione sessuale degli anni \u201950 e \u201960 negli Stati Uniti d\u2019America. Una figura importante, \u00e8 sicuramente Alfred Kinsey (1894-1956), inizialmente assistente professore di zoologia presso l\u2019universit\u00e0 dell\u2019Indiana. Nel 1938 viene invitato a coordinare un corso sul matrimonio chiamato <em>\u201cMarriage and Family\u201d<\/em> da un\u2019associazione studentesca femminile che si fa promotrice della proposta di inserire questo corso presso l\u2019Universit\u00e0 dell\u2019Indiana. Da qui inizia l\u2019interesse del professore per lo studio dei rapporti sessuali e inizia una raccolta di storie ed esperienze dai suoi stessi studenti. Kinsey comincia cos\u00ec una ricerca che lo porta ad ispezionare circa 18.000 casi. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Fu il primo a fare esperimenti su infanti e bambini, come \u00e8 documentato nel libro, e riteneva \u2013 con lo psicologo Jhon Money (1921-2006), il teorico del cosiddetto <em>\u201cgender\u201d<\/em> \u2013 che la sessualizzazione dei bambini e della intera societ\u00e0 avrebbe portato la stessa ad essere pi\u00f9 pacifica e tollerante. Per fare questo si dovevano quindi rompere i tab\u00f9 del passato. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In ambito accademico, sempre negli Stati Uniti, vi sono stati esponenti come il professore John De Cecco (1925-2017), professore di psicologia alla San Francisco State University, caporedattore del <em>Journal of Homosexuality<\/em> dal 1975 al 2009, e anche membro editoriale della rivista olandese pro-pedofilia <em>Paidika<\/em>. Nel 1977 elabor\u00f2 una proposta di legge sui diritti sessuali dei bambini chiamata <em>\u201cA Child\u2019s Sexual Bill of Rights\u201d<\/em>, secondo cui i bambini dovrebbero avere dei diritti sessuali e riproduttivi, essere in grado di esplorare a fondo la loro sessualit\u00e0 ed essere liberi di scegliere relazioni amorose e sessuali, inclusi genitori, fratelli e adulti responsabili. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UCI:<\/strong> Queste idee vennero accolte da diversi esponenti appartenenti ai movimenti di liberazione sessuale, ci fa qualche esempio? <\/span><\/p>\n<div id=\"attachment_48965\" style=\"width: 180px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Shulamith_Firestone.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48965\" class=\"wp-image-48965 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Shulamith_Firestone.jpg\" alt=\"\" width=\"180\" height=\"280\" \/><\/a><p id=\"caption-attachment-48965\" class=\"wp-caption-text\">Shulamith Firestone<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EF:<\/strong> Shulamith Firestone (1945-2012), canadese naturalizzata americana, esponente del <em>\u201cfemminismo lesbico\u201d<\/em> degli anni Settanta e inizio Ottanta, nel 1970 pubblica il testo <em>\u201cLa dialettica dei sessi\u201d<\/em>, in cui sostiene che le donne sono sottomesse agli uomini per motivi biologici e strutturali della societ\u00e0. Secondo la Firestone non basta liberarsi dal \u201cprivilegio maschile\u201d ma occorre anche eliminare del tutto la distinzione tra i sessi. Inoltre sosteneva che l\u2019incesto e il sesso con i bambini erano barriere che impedivano la vera emancipazione della donna dall\u2019uomo e che per abbattere il patriarcato si doveva quindi passare anche per la rottura di quelle restrizioni legali e morali: in tal modo, liberata la sessualit\u00e0 in maniera totale, il maschio avrebbe perso il suo potere sulla donna e in particolare sulla riproduzione, e la donna sarebbe stata l\u2019unica a decidere in tal senso, mettendo fine al concetto di famiglia patriarcale. <\/span><\/p>\n<div id=\"attachment_31062\" style=\"width: 225px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-31062\" class=\"wp-image-31062 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><p id=\"caption-attachment-31062\" class=\"wp-caption-text\">Mario Mieli<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In Italia, chi par\u00f2 esplicitamente della pedofilia come \u201cpratica liberatoria\u201d fu Mario Mieli (1952-1983), noto esponente del mondo LGBT, morto suicida nel 1983, le cui tesi sono esposte nel libro <em>\u201cElementi di critica omosessuale\u201d<\/em> del 1977, pubblicato da <em>Einaudi<\/em>. Noto \u00e8 il passaggio sulla pederastia: Noi checche rivoluzionarie sappiamo vedere nel bambino non tanto l\u2019Edipo, o il futuro Edipo, <em>bens\u00ec l\u2019essere umano potenzialmente libero<\/em>. Noi, s\u00ec, possiamo amare i bambini. Possiamo desiderarli eroticamente rispondendo alla loro voglia di Eros, possiamo cogliere a viso e a braccia aperte la sensualit\u00e0 inebriante che profondono, possiamo fare l\u2019amore con loro. Per questo la pederastia \u00e8 tanto duramente condannata: essa rivolge messaggi amorosi al bambino che la societ\u00e0 invece, tramite la famiglia, traumatizza, educastra, <em>nega<\/em>, calando sul suo erotismo la griglia edipica. La societ\u00e0 repressiva eterosessuale costringe il bambino al periodo di latenza; ma il periodo di latenza non \u00e8 che l\u2019introduzione mortifera all\u2019ergastolo di una \u201cvita\u201d latente. La pederastia, invece, \u201c\u00e8 una freccia di libidine scagliata verso il feto\u201d (Francesco Ascoli). <\/span><span style=\"color: #000000;\">C\u2019\u00e8 un elemento che accomuna queste persone: appartengono tutti, e proprio tutti, al mondo culturale della sinistra, del progressismo e del comunismo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UCI:<\/strong> Questo punto \u00e8 importante, cosa hanno preso questi esponenti dal marxismo? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EF:<\/strong> Dal marxismo hanno preso in particolare la dialettica dello scontro tra due entit\u00e0: che per\u00f2 questa volta non passa attraverso la sola lotta di classe tra proletari e detentori dei mezzi di produzione, ma tra minoranze organizzate sessuali, quali categoria di oppressi, contro il maschio eterosessuale e la societ\u00e0 patriarcale, che sarebbero gli oppressori da abbattere. <\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45657 size-medium alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione-300x219.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione-768x561.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione-1024x749.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/sesso_rivoluzione.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Infatti, nell\u2019ambito dell\u2019Anglosfera, pi\u00f9 che di marxismo <em>tout court<\/em>, si parla di marxismo culturale, ossia di neo marxismo riletto alla luce degli autori della Scuola di Francoforte, i quali non vedono nell\u2019operaio e nella classe lavoratrice il motore della storia \u2013 in quanto si andava adagiando e integrando nella societ\u00e0 borgese \u2013 ma negli oppressi e nelle categorie discriminate, la molla che avrebbe costruito il \u201cGrande Rifiuto\u201d alla societ\u00e0 autoritaria e del padre. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Si faccia presente che la \u201clobby pedofila\u201d nasce nei turbolenti anni \u201960 e \u201970, quando venivano messi in discussione i fondamenti della societ\u00e0 occidentale tradizionale retta sui valori cristiani, l\u2019economia di impresa e la propriet\u00e0 privata, la famiglia eterosessuale e la figura del padre quale capo famiglia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Inoltre, questi autori ritenevano che il capitalismo potesse essere abbattuto proprio eliminando la differenza tra i generi fin dalla tenera et\u00e0, in quanto \u00e8 grazie ad essa che il capitalismo \u2013 con i suoi meccanismi di sfruttamento \u2013 si rigenerava, strutturava e perpetuava, dando ai bambini una identit\u00e0 fin dalla nascita che poi sarebbe stata \u2013 a dir loro \u2013 funzionale alla prassi capitalista e ai suoi meccanismi di oppressione. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Da qui l\u2019idea della Shulamith Firestone che le donne avrebbero dovuto prendere il possesso sui mezzi di riproduzione biologica e non solo di produzione economica, in modo da togliere il potere al padre, ossia \u2013 dal loro punto di vista \u2013 all\u2019oppressore. Infine, direi anche il \u201cmessianismo\u201d, ossia che grazie alla totale liberazione sessuale del bambino, si sarebbe arrivati ad una societ\u00e0 tollerante, pacifica e senza pi\u00f9 oppressioni e violenze, fondata sul piacere e l\u2019amore, dato che sarebbero sparite le differenze tra i generi e i ruoli assegnati dal capitalismo fin dalla nascita. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UCI:<\/strong> Restando in tema, Marx ed Engels nel Manifesto del Partito Comunista hanno scritto che <em>\u201cle idee dominanti di un\u2019epoca, sono state in ogni momento, soltanto le idee della classe dominante\u201d<\/em>: se la sessualizzazione dei bambini viene promossa dai programmi scolastici (lei nel libro parla del caso croato) a <em>Netflix<\/em>, vuol dire che l\u2019ideologia dominante con i suoi apparati si sta muovendo per accelerare questo processo? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EF<\/strong>: Il limite di Marx \u00e8 l\u2019economicismo, ossia ridurre la narrazione storica ad un perenne conflitto tra classi economiche, quindi dobbiamo stare attenti ad interpretare <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/marx.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27263 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/marx.jpg\" alt=\"\" width=\"188\" height=\"268\" \/><\/a>tutto in chiave materialista e dialettica di classe. Tuttavia si pu\u00f2 senz\u2019altro dire che oggi il grande Capitale Finanziario, multinazionale e apolide, ha interesse ad un mondo senza radici ed identit\u00e0, di ogni genere: etniche, religiose, linguistiche culturali e anche sessuali. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Quindi senz\u2019altro lo scopo finale \u2013 ossia creare una massa omogenea di miliardi di individui senza differenze da dominare con il consumismo \u2013 include anche la sessualizzazione dei bambini, dato che cos\u00ec si aboliscono i limiti, i ruoli, le gerarchie e si toglie di mezzo anche l\u2019dea di religione (come diceva Dostoevskij ne <em>\u201cI Demoni\u201d<\/em>, \u201cse Dio non esiste, tutto \u00e8 permesso\u201d). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del resto viviamo nella fase storica del \u201ccapitalismo liquido\u201d, quello che Jacques Attali \u2013 filosofo, banchiere, tecnocrate francese \u2013 definisce \u201ccaliforniano\u201d, privo di identit\u00e0, globale e digitale. Tutto ci\u00f2 abolisce il limite di ogni genere, e quindi anche di fatto i tab\u00f9 culturali legati alla sessualit\u00e0. Non \u00e8 un mistero che lo stesso <em>TikTok<\/em> sia una piattaforma che notoriamente contribuisce alla sessualizzazione precoce. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UCI:<\/strong> Nel suo libro dedica un capitolo al Forteto e a Bibbiano, perch\u00e9 sono importanti questi due casi? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EF:<\/strong> Perch\u00e9 rappresentano due casi tipici di ingegneria sociale e culturale proprie del pensiero della sinistra, secondo cui i figli non sono dei genitori ma della collettivit\u00e0. Il <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/forteto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-26551 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/forteto-300x165.jpg\" alt=\"\" width=\"355\" height=\"195\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/forteto-300x165.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/forteto.jpg 302w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><\/a>Forteto si insinua nella scia del pensiero del \u201968 e del cattocomunismo, e che si basa sulla necessit\u00e0 di costruire una nuova societ\u00e0 pura e migliore, abbattendo quella precedente borghese, fondata sull\u2019ingiustizia, e si propone un nuovo modello: quello della \u201cfamiglia funzionale\u201d, ossia di una famiglia che non si fonda sul legame di sangue ma su presunti affetti sconnessi dalla realt\u00e0. In verit\u00e0 poi si dimostr\u00f2 con le inchieste giudiziarie e due commissioni di inchiesta regionali, che anche questa era a sua volta una \u201cfinzione\u201d che serviva solo per far finta che ci fossero delle famiglie all\u2019interno, affinch\u00e9 il Tribunale dei Minori mandasse i ragazzi nella struttura, quando invece i sessi erano rigorosamente separati e l\u2019omosessualit\u00e0 incentivata e incoraggiata dai fondatori. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/bibbiano_gay-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43530 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/bibbiano_gay-1.jpg\" alt=\"\" width=\"324\" height=\"243\" \/><\/a>Il fenomeno di Bibbiano si fonda invece sull\u2019idea che i figli non appartengano ai genitori ma allo Stato e alle istituzioni, contraddicendo il principio cardine della \u201csussidiariet\u00e0\u201d, e lo Stato pu\u00f2 farne ci\u00f2 che vuole, se considera i genitori non all\u2019altezza del compito educativo. Per\u00f2 chi decide quale sia il compito educativo giusto e migliore? La sinistra ovviamente, dal loro punto di vista. E cos\u00ec ci sono stati dei casi dove i figli sono stati tolti ai genitori in quanto considerati \u201comofobi\u201d e quindi non buoni per educarli al bene, ossia al pensiero progressista; e pertanto di tale educazione (in tal caso LGBT e omosessista) se ne deve occupare lo Stato anche se i genitori sono contrari a tale ideologia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo rappresenta un gravissimo precedente, perch\u00e9 un domani la sinistra potrebbe fare delle leggi (peraltro gi\u00e0 invocate da esponenti della sinistra su <em>Twitter<\/em>) che prevedono di togliere i figli ai genitori che \u201cnon rispettano la Costituzione\u201d, inteso \u2013 dal punto di vista LGBT e progressista \u2013 nel senso di \u201cnon rispettano il pensiero di sinistra\u201d, che poi vorrebbe dire appunto togliere i figli a quelli considerati \u201cfascisti\u201d, di destra, cattolici tradizionali conservatori, ecc. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo \u00e8 gi\u00e0 successo nei paesi socialisti, non dobbiamo credere che sia una idea strampalata e utopica, siamo di fronte a due casi di perfetta ingegneria sociale fondata sul pensiero marxista e progressista, e che porta alla necessaria conseguenza che la famiglia \u00e8 un istituto che pu\u00f2 essere abolito (come in Cambogia sotto Pol Pot) o trasformato in qualcosa di irriconoscibile, pur tenendone l\u2019etichetta formale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>UCI:<\/strong> La finestra di Overton potr\u00e0 essere applicata per sdoganare anche la pedofilia?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>EF:<\/strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/finestra_Overton.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48966 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/finestra_Overton-300x168.jpg\" alt=\"\" width=\"357\" height=\"200\" \/><\/a> Assolutamente s\u00ec. Ne parlo approfonditamente nel libro. Come \u00e8 noto, la finestra di Overton \u00e8 un modello di rappresentazione delle possibilit\u00e0 di cambiamenti nell\u2019opinione pubblica, descrivendo come delle idee, totalmente respinte al loro apparire, possano essere poi accettate pienamente dalla societ\u00e0, per diventare infine legge. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo Overton, qualsiasi idea, anche la pi\u00f9 incredibile, per potersi sviluppare nella societ\u00e0 ha una finestra di opportunit\u00e0. In questa finestra l\u2019idea pu\u00f2 essere ampiamente discussa, e si pu\u00f2 apertamente tentare di modificare la legge in suo favore. L\u2019apparire di questa idea, in quel che potremmo chiamare la \u201c<em>finestra di<\/em>\u00a0<em>Overton<\/em>\u201d, permette il passaggio dallo stadio di \u201c<em>impensabile<\/em>\u201d a quello di un pubblico dibattito, prima dalla sua adozione da parte della coscienza di massa e il suo inserimento nella legge. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Non si tratta di lavaggio del cervello puro e semplice, ma di tecniche pi\u00f9 sottili, efficaci e coerenti; si tratta di portare il dibattito fino al cuore della societ\u00e0, per fare s\u00ec che il cittadino comune si appropri di una certa idea e la faccia sua. All\u2019inizio \u00e8 talvolta sufficiente che un personaggio pubblico o politico la promuova in modo caricaturale ed estremo, e che poi il resto della classe pubblica e politica smentisca con grande foga. Ecco, l\u2019idea \u00e8 nata, e la danza dei furbetti pu\u00f2 cominciare. Il soggetto \u00e8 lanciato, e si pu\u00f2 discuterne per il bene di tutti e sgombrare il campo dagli equivoci. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/pedofilia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27416 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/pedofilia.jpg\" alt=\"\" width=\"279\" height=\"181\" \/><\/a>Secondo questa teoria, una finestra \u00e8 l\u2019intervallo di idee che possono essere accettate dalla societ\u00e0 in un determinato momento e che vengono apertamente manifestate dai politici senza che questi ultimi passino per estremisti. Le idee evolvono secondo i seguenti stadi: <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-inconcepibile (inaccettabile, vietato) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-radicale (vietato, ma con delle riserve) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-accettabile (l\u2019opinione pubblica sta cambiando) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-utile (ragionevole, razionale) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-popolare (socialmente accettabile) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-legalizzazione (nella politica dello Stato) <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Molte altre idee contemporanee sembravano assolutamente inconcepibili solo qualche decina di anni fa e sono poi diventate accettabili per la legge e agli occhi della societ\u00e0: aborto, immigrazione di massa, droghe \u201cleggere\u201d da liberalizzare, eutanasia, poliamore. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per andare sul concreto, per esempio, nell\u2019ottobre 2014, il giornale progressista <em>New York Times<\/em> pubblicava un editoriale chiarissimo: <em>\u201cPedofilia: un disordine, non un crimine\u201d<\/em>. Si ebbe quello che nel mondo giornalistico si chiama \u201c<em>New York Times Effect\u201d<\/em>, l\u2019eco tematico sul resto dei media: ecco <em>l\u2019Huffington Post<\/em>: <em>\u201cSono un pedofilo, ma non sono un mostro\u201d<\/em>, \u00e8 il titolo di un articolo del 2015. Occhiello: <em>\u201cIn una lettera online la confessione di un designer americano. \u2018Non tutti facciamo del male&#8217;\u201d<\/em>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Dopo aver letto tutte queste cose, il bravo cittadino democratico non pu\u00f2 aver dubbi: meglio pedofilo che assassino. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/pedofilia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7211 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/pedofilia.jpg\" alt=\"\" width=\"301\" height=\"213\" \/><\/a>Il dott. Klaus Michael Beier, medico, psicoterapeuta e sessuologo tedesco, ha rilasciato un\u2019intervista al <em>Times of India<\/em> nel marzo del 2017. \u201c<em>La pedofilia \u00e8 una realt\u00e0 e le societ\u00e0 sane devono imparare ad accettarla<\/em>\u201d, afferma il medico. Secondo Beier la perversione sessuale verso i bambini \u00e8 da considerarsi un \u201cdestino\u201d e non una scelta. Per questo, quindi, dovremmo accettarla. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il medico Klaus Beier, al quale si \u00e8 ispirata Mirjam Heine per la sua <em>Ted Talk<\/em> in cui ha dichiarato che \u201cla pedofilia \u00e8 un orientamento sessuale naturale\u201d, oltre a essere direttore del dipartimento di sessuologia del\u00a0<em>Charite<\/em>, dirige anche un discusso programma di prevenzione per pedofili sempre all\u2019interno dell\u2019ospedale universitario di Berlino. L\u2019iniziativa si chiama \u201c<em>Kein Tater Werden<\/em>\u201d, che tradotto dal tedesco significa <em>\u201cNon offendere\u201d<\/em>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019obiettivo del corso \u00e8 insegnare ai pedofili come controllare i loro impulsi sessuali nei confronti dei bambini. Al programma, lanciato 13 anni fa, partecipano potenziali criminali sessuali e anche coloro che hanno commesso reati sessuali ma sono riusciti a farla franca con la giustizia tedesca. <em>\u201cLa pedofilia non \u00e8 curabile\u201d<\/em>, aveva spiegato Beier al quotidiano inglese. <em>\u201cMa pu\u00f2 essere trattabile\u201d<\/em>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Netflix_cuties.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48967 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Netflix_cuties.jpg\" alt=\"\" width=\"318\" height=\"240\" \/><\/a>Secondo il medico, quindi, un pedofilo pu\u00f2 imparare a controllare i suoi impulsi. Il progetto si fonda infatti sul principio che l\u2019attrazione sessuale verso i bambini \u00e8 s\u00ec un problema medico ma, come ha affermato Beier, <em>\u201cnon \u00e8 un crimine\u201d<\/em> fino a quando non si abusa. Come si vede, piano piano si inizia a discutere della questione come \u201cpossibilit\u00e0\u201d anche se vista ancora in maniera negativa. Ma col tempo, piano piano, si passer\u00e0 alla fase successiva, ossia l\u2019accettabilit\u00e0, una volta che la fase della possibilit\u00e0 si sar\u00e0 radicata. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del resto, recentemente, il grande pubblico \u00e8 stato gi\u00e0 abituato con il film <em>\u201cCutes\u201d<\/em>, su <em>Netflix<\/em>, a movimenti sensuali, erotici e ammiccanti, di bambine di 10 anni, e <em>Netflix<\/em> non ha subito poi censure o processi, se non qualche disappunto da parte del mondo cattolico (a dir il vero, nemmeno tutto, per esempio <em>Avvenire<\/em> ha giustificato il film): il tutto \u00e8 passato come se fosse una cosa possibile. Come si vede, la legge del piano inclinato funziona anche in questo caso<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atlantico 28 Ottobre 2020, di Umberto Camillo Iacoviello, \u00a0Emanuele Fusi nasce a Barga (Lucca) nel 1978. Laureato in giurisprudenza intraprende la professione di avvocato presso il Foro di Lucca, specializzandosi in diritto penale e diritto tributario. \u00c8 autore di diversi romanzi e saggi, per Passaggio al bosco ha pubblicato il saggio\u00a0\u201cWhite guilt, il razzismo contro &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":48961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[304,454],"class_list":["post-48960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","tag-costume-2","tag-pedofilia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T23:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1433\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi\",\"datePublished\":\"2020-10-28T23:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/\"},\"wordCount\":2603,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pedofilia.jpg\",\"keywords\":[\"costume\",\"pedofilia\"],\"articleSection\":[\"Costume\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/\",\"name\":\"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pedofilia.jpg\",\"datePublished\":\"2020-10-28T23:00:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pedofilia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pedofilia.jpg\",\"width\":1433,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/","og_locale":"it_IT","og_type":"article","og_title":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-10-28T23:00:22+00:00","og_image":[{"width":1433,"height":630,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi","datePublished":"2020-10-28T23:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/"},"wordCount":2603,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg","keywords":["costume","pedofilia"],"articleSection":["Costume"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/","name":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg","datePublished":"2020-10-28T23:00:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/pedofilia.jpg","width":1433,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-tentativo-di-sdoganare-la-pedofilia-intervista-a-emanuele-fusi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il tentativo di sdoganare la pedofilia. Intervista a Emanuele Fusi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=48960"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48960\/revisions"}],"predecessor-version":[{"id":48968,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48960\/revisions\/48968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/48961"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=48960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=48960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=48960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}