{"id":4865,"date":"2012-01-05T00:00:00","date_gmt":"2012-01-04T23:00:00","guid":{"rendered":""},"modified":"2016-04-29T13:44:28","modified_gmt":"2016-04-29T11:44:28","slug":"ii-dna-contadino-degli-italiani","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/","title":{"rendered":"II Dna &laquo;contadino&raquo; degli italiani"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33793\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg\" alt=\"contadini\" width=\"250\" height=\"156\" \/>Studi cattolici<\/strong> n. 609 novembre 2011<\/div>\n<p style=\"text-align: center;\">di<strong> Ugo Finetti<\/strong><\/p>\n<p style=\"text-align: justify;\">Quando nell&#8217;autunno del 1978 venne proiettato con grande successo nelle sale cinematografiche italiane <em>L&#8217;albero degli zoccoli, <\/em>il film di Ermanno Olmi fu \u00abaccolto\u00bb, ricorda Sandro Fontana, \u00abcon la puzza sotto il naso dalla cultura dominante\u00bb, che \u00abveniva ancora una volta dimostrando quale abisso separasse il pensiero in quel tempo egemone dalla realt\u00e0 viva del Paese e come certa cultura cosiddetta progressiva operasse per rinnegare il codice genetico che da secoli caratterizzava il modo di essere e di pensare degli italiani\u00bb.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Si tratt\u00f2, infatti, di una polemica molto accesa e che lo stesso Olmi ha ancora ricordato proprio festeggiando gli ottant&#8217;anni nell&#8217;aprile scorso: \u00abMoravia disse che nel mio film solo il cavallo imbizzarrito esprimeva ribellione alle angherie del padrone\u00bb.<\/div>\n<p style=\"text-align: justify;\">\u00abOsservazioni da borghese di salotto\u00bb, commenta Olmi, ma che ebbero un coro di adesioni nella intellettualit\u00e0 dell&#8217;epoca. A stroncare il film di Olmi si distinse, per esempio, Beniamino Placido, nel rispecchiare il fastidio verso quella rievocazione del mondo contadino: \u00abPerch\u00e9 mai il buon contadino Batisti deve mutilare un albero sacrificandolo agli zoccoli del buon figliolino Minik, quando c&#8217;\u00e8 tanta legna nel cortile?\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abEgli non sapeva\u00bb, rileva Fontana, \u00abche il legno per gli zoccoli deve essere leggero e spugnoso, cio\u00e8 diverso da quello che viene usato per il fuoco: esso inoltre deve essere intagliato ancora verde e possedere il dono raro di essiccare senza subire crepe\u00bb. Questo \u00e8 uno degli episodi che troviamo raccontati da Sandro Fontana nel suo <em>Il Dna degli italiani <\/em>(Marsilio, pp.140, 14 euro) e che mette in luce come le cosiddette \u00abvirt\u00f9 del passato\u00bb che traggono origine dal mondo contadino non abbiano rappresentato un handicap, ma, al contrario, un punto di forza per il nostro Paese.<\/p>\n<p style=\"text-align: justify;\">Il saggio si articola, infatti, secondo una serie di capitoli in cui Fontana offre una sorta di \u00abscheda storico-antropologica\u00bb di questi elementi del Dna italiano secondo un suggestivo arco di riferimenti che va dai dati anagrafici ai dialetti. E cos\u00ec che viene illustrata nel corso degli sviluppi storici e sociali una galleria di ritratti italiani: la fame, il lavoro, il risparmio, la religione, l&#8217;amore, la famiglia, la lingua, il Paese.<\/p>\n<p style=\"text-align: justify;\"><strong>Luoghi comuni sull&#8217;Italia arretrata<\/strong><\/p>\n<p style=\"text-align: justify;\">Come emerge dalla rievocazione della polemica sul film di Olmi, il libro di Fontana si presenta come un intervento che contesta i principali luoghi comuni che si sono andati consolidando sull&#8217;onda soprattutto di una lettura classista circa l&#8217;identit\u00e0 italiana. \u00c8 l&#8217;impostazione secondo cui gli italiani dovrebbero essere considerati un popolo \u00abarretrato\u00bb rispetto al resto d&#8217;Europa perch\u00e9 non hanno conosciuto n\u00e9 la riforma protestante n\u00e9 la rivoluzione giacobina.<\/p>\n<p style=\"text-align: justify;\">Il perdurare di un mondo contadino-cattolico, secondo questa storiografia dominante, sarebbe alla base dei nostri vizi e mali, a cominciare dallo scarso senso del bene pubblico con una corruzione irrimediabile in quanto connaturata al suo Dna cattolico-contadino.<\/p>\n<p style=\"text-align: justify;\">In verit\u00e0 non solo da parte marxista nell&#8217;intellettualit\u00e0 italiana \u00e8 prevalsa la presa di distanza critica verso la \u00abmassa\u00bb degli italiani. Si pensa solitamente di poter definire identit\u00e0 nazionale, senso dello Stato, concetto di patria secondo la prospettiva delle \u00abminoranze virtuose\u00bb, guardando dall&#8217;alto di un&#8217;Italia parallela e alternativa, nei secoli arroccata su vette ghibellin-giacobine incontaminate.<\/p>\n<p style=\"text-align: justify;\">Ma a smentire questa impostazione \u00e8 il fatto che, soprattutto nei momenti pi\u00f9 critici della storia d&#8217;Italia, \u00e8 invece scendendo verso il basso nella scala sociale che si avverte in modo crescente un&#8217;identit\u00e0 nazionale troppo frettolosamente travisata e bollata da quella intellettualit\u00e0 come immobilismo, arretratezza, conservatorismo, avversione alla modernit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Proprio uno storico a lungo perseguitato dall&#8217;intellettualit\u00e0 che cantano le \u00abminoranze virtuose\u00bb, Renzo De Felice, ha osservato come di fronte alla catastrofe dell&#8217;8 settembre il senso dello Stato fu maggiormente presente tra i subalterni: \u00abSolo se si discende ai gradini ancora inferiori della scala gerarchica\u00bb, scrive De Felice, \u00ab\u00e8 possibile trovare un maggior numero di ufficiali che vissero il dramma dell&#8217;8 settembre senza mettersi sotto i piedi dignit\u00e0 nazionale, patriottismo, etica militare\u00bb.<\/p>\n<p style=\"text-align: justify;\">Sandro Fontana evidenzia, quindi, come proprio le radici \u00abcontadine\u00bb e \u00abcattoliche\u00bb siano state un punto di forza e di salvezza: un patrimonio di moralit\u00e0 che ha consentito di fronteggiare e superare numerose prove storiche.<\/p>\n<p style=\"text-align: justify;\">Il Dna che \u00e8 al centro del saggio di Fontana mette a fuoco un&#8217;identit\u00e0 nazionale che rispecchia e anima le ragioni per cui l&#8217;Italia \u00e8 riconosciuta come Patria nei momenti pi\u00f9 difficili e in un comune e radicato spirito di solidariet\u00e0 e di sacrificio. Quindi il Dna popolare si rivela come la base di una patriottismo spesso misconosciuto, ma decisivo.<\/p>\n<p style=\"text-align: justify;\">E Sandro Fontana sottolinea appunto come il senso di appartenenza a una comunit\u00e0 \u00abcontadina\u00bb sia stato alla base del patriottismo dei militari nelle situazioni pi\u00f9 drammatiche come la \u00abcampagna\u00bb in Russia degli Alpini, dove la divisione Tridentina riusc\u00ec a respingere gli attacchi nemici perch\u00e9\u00bb, rievoca Fontana, \u00abnelle lunghe gallerie scavate sulle rive del Don essi avevano ricostruito su scala ridotta, e quindi difeso con i denti, il &#8220;paese&#8221; (con le baite, la chiesa e l&#8217;osteria), e avevano saputo intraprendere quella epica ritirata travolgendo ogni ostacolo perch\u00e9 erano posseduti dal desiderio di &#8220;tornare alla baita&#8221;, cio\u00e8 di poter tornare a vivere nel proprio paese\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Significato morale del lavoro<\/strong><\/p>\n<p style=\"text-align: justify;\">In questo Dna &#8211; che \u00e8 identit\u00e0 e amor di patria &#8211; un ruolo fondamentale \u00e8 rappresentato dal lavoro: \u00abII lavoro\u00bb, scrive Fontana, \u00abaveva soprattutto un significato morale e lavorare voleva dire &#8220;cercare di avere la testa a posto&#8221;, riscuotere la stima e il rispetto dei compaesani, trovare moglie e, quindi, avviare una nuova famiglia\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00c8 una \u00abpatria\u00bb arretrata e immobile? Fontana, scrutando crisi ed evoluzioni nazionali, mette a fuoco due momenti decisivi: la deindustrializzazione degli anni &#8217;70 e la crisi finanziaria attuale. \u00c8 stato proprio nel momento della crisi della grande industria che il Dna nazionale, \u00abcontadino\u00bb, ha dato vita a un nuovo modello di sviluppo basato sui distretti industriali, cio\u00e8 &#8211; scrive Fontana &#8211; \u00absu una sorta di capitalismo popolare formato da una miriade di piccole e medie imprese specializzate in determinati settori merceologici\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abSi tratta \u2014 prosegue Fontana &#8211; di quel modello di sviluppo che ha consentito a un Paese come il nostro, povero di materie prime e di capitali e ricco solo di manodopera da impiegare e di bocche da sfamare, di conquistare, nel giro di pochi decenni, i primi posti nella gerarchia mondiale dei Paesi pi\u00f9 industrializzati\u00bb. \u00c8 l&#8217;esempio di quella risorsa \u00abstorico-patriottica\u00bb che era la manodopera italiana, a basso costo e di prim&#8217;ordine, abituata da secoli, come aveva scritto Carlo Cattaneo gi\u00e0 nel 1844, a tenere desti \u00abl&#8217;intendimento, la previdenza e la frugalit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00c8 cos\u00ec che, sottolinea Sandro Fontana, vi \u00e8 stata una sorta di \u00absalvezza\u00bb grazie a queste \u00abvirt\u00f9 del passato\u00bb anche di fronte alla crisi mondiale di questi ultimi anni. Come mai l&#8217;Italia di fronte a un&#8217;\u00abonda anomala\u00bb che ha investito la scena internazionale e in particolare quella europea e occidentale ha avuto una maggiore tenuta pur presentando, a cominciare dal debito pubblico, non poche fragilit\u00e0?<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 lo si deve proprio a quei fattori additati come negativi dai cantori delle \u00abminoranze virtuose\u00bb come il risparmio e la casa di propriet\u00e0. \u00abI lavoratori di un tempo\u00bb, osserva Fontana, \u00absi sono via via trasformati in veri e propri <em>rentiers, <\/em>quindi attenti pi\u00f9 del passato alla stabilit\u00e0 della moneta e della economia\u00bb. Il Dna indagato da Sandro Fontana diventa, quindi, la definizione dell&#8217;Italia come Patria che confligge con la cultura classista che ha inventato e coltivato in questi decenni il mito dell&#8217;Altra Italia, descrivendo una storia nazionale tutta \u00aboccasioni mancate\u00bb e minando cos\u00ec la stessa celebrazione del 150 dell&#8217;unit\u00e0 d&#8217;Italia.<\/p>\n<p style=\"text-align: justify;\">In partenza sembrava che il 150 potesse offrire la possibilit\u00e0 della messa in scena di un primato di sinistra \u2014 soprattutto postcomunista \u2014 e cio\u00e8 di una sontuosa mobilitazione istituzionale contro il Vaticano e quindi il Governo a componente \u00ableghista\u00bb. Ma proprio la partecipazione della Segreteria di Stato alla celebrazione romana del 20 settembre ha spento l&#8217;armeggiare incendiario anticattolico consegnando alla riflessione storica se il Risorgimento sia stato non solo \u00abguerra di indipendenza\u00bb, ma anche \u00abguerra civile\u00bb.<\/p>\n<p style=\"text-align: justify;\">A questo punto il \u00abpatriottismo\u00bb di certa sinistra ha ceduto ai riflessi condizionati della propria matrice classista (e internazionalista) ed \u00e8 fuoriuscito dalla celebrazione. \u00c8 cos\u00ec che nella sinistra italiana \u00e8 emerso in primo piano in questo 150 come protagonista lo storico Alberto Maria Banti con la sua tesi sulla \u00abcontinuit\u00e0 tra Risorgimento e fascismo\u00bb, che altro non \u00e8 stata se non la riproposizione sull&#8217;argomento delle tesi di Togliatti sostenute nel 1931 contro la prospettiva di un&#8217;intesa antifascista con liberalsocialisti e cattolici (\u00abLa tradizione del Risorgimento\u00bb, tuonava Togliatti su <em>Stato Operaio, <\/em>\u00abvive nel fascismo ed \u00e8 stata da esso sviluppata sino all&#8217;estremo. La rivoluzione antifascista non potr\u00e0 essere che una rivoluzione &#8220;contro il Risorgimento&#8221;. Le fantasie sul &#8220;secondo Risorgimento&#8221; sono fatte solo per nascondere questa realt\u00e0\u00bb).<\/p>\n<p style=\"text-align: justify;\">Il saggio di Fontana rappresenta un&#8217;argomentata contestazione di questa \u00abaccademia\u00bb che si atteggia a Super-Io nazionale discettando senza conoscenza \u00abumana\u00bb della realt\u00e0 italiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Studi cattolici n. 609 novembre 2011 di Ugo Finetti Quando nell&#8217;autunno del 1978 venne proiettato con grande successo nelle sale cinematografiche italiane L&#8217;albero degli zoccoli, il film di Ermanno Olmi fu \u00abaccolto\u00bb, ricorda Sandro Fontana, \u00abcon la puzza sotto il naso dalla cultura dominante\u00bb, che \u00abveniva ancora una volta dimostrando quale abisso separasse il pensiero &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[1996,1251],"class_list":["post-4865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","tag-anti-italiani","tag-italia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-04T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-29T11:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"284\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"II Dna &laquo;contadino&raquo; degli italiani\",\"datePublished\":\"2012-01-04T23:00:00+00:00\",\"dateModified\":\"2016-04-29T11:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/\"},\"wordCount\":1469,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/contadini.jpg\",\"keywords\":[\"anti-italiani\",\"Italia\"],\"articleSection\":[\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/\",\"name\":\"II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/contadini.jpg\",\"datePublished\":\"2012-01-04T23:00:00+00:00\",\"dateModified\":\"2016-04-29T11:44:28+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/contadini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/contadini.jpg\",\"width\":284,\"height\":177},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ii-dna-contadino-degli-italiani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Dna &laquo;contadino&raquo; degli italiani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/","og_locale":"it_IT","og_type":"article","og_title":"II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-01-04T23:00:00+00:00","article_modified_time":"2016-04-29T11:44:28+00:00","og_image":[{"width":284,"height":177,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"II Dna &laquo;contadino&raquo; degli italiani","datePublished":"2012-01-04T23:00:00+00:00","dateModified":"2016-04-29T11:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/"},"wordCount":1469,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg","keywords":["anti-italiani","Italia"],"articleSection":["Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/","name":"II Dna &laquo;contadino&raquo; degli italiani - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg","datePublished":"2012-01-04T23:00:00+00:00","dateModified":"2016-04-29T11:44:28+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/contadini.jpg","width":284,"height":177},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ii-dna-contadino-degli-italiani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"II Dna &laquo;contadino&raquo; degli italiani"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4865"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4865\/revisions"}],"predecessor-version":[{"id":33794,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4865\/revisions\/33794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33793"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}