{"id":4864,"date":"2012-01-05T00:00:00","date_gmt":"2012-01-04T23:00:00","guid":{"rendered":""},"modified":"2016-06-16T09:51:48","modified_gmt":"2016-06-16T07:51:48","slug":"la-buona-sociologia-e-i-cattolici-allitaliana","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/","title":{"rendered":"La buona sociologia e i cattolici &laquo;all&#8217;italiana&raquo;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34956\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg\" alt=\"Garelli_cover\" width=\"124\" height=\"200\" \/>La Bussola quotidiana <\/strong>19 dicembre 2011<\/div>\n<p style=\"text-align: center;\">di<strong> Massimo Introvigne<\/strong><\/p>\n<p style=\"text-align: justify;\">Un recentissimo sondaggio dell\u2019IPSOS mostra che i cattolici italiani, nonostante il governo tecnico, hanno ancora voglia di politica e sarebbero interessati a offerte politiche coerenti con i loro valori, di cui tuttavia riscontrano la mancanza, e che oltre il quaranta per cento degli italiani \u2013 cattolici o non \u2013 segue con interesse il dibattito sulla politica all\u2019interno dell\u2019associazionismo cattolico.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>Ma chi sono, quanti sono, dove sono i cattolici in Italia?\u00a0<\/strong>Risponde ora adeguatamente a questa domanda una ricchissima ricerca del sociologo torinese Franco Garelli, uscita dal Mulino con il titolo <em>Religione all\u2019italiana. L\u2019anima del paese messa a nudo<\/em>: un volume che verosimilmente definir\u00e0 il campo della sociologia delle religioni in Italia per parecchi anni a venire.<\/div>\n<p style=\"text-align: justify;\"><strong>Che cosa ha scoperto Garelli? Che l\u2019Italia ha un sua via alla modernit\u00e0<\/strong>, alla religione e alla secolarizzazione che non coincide esattamente con quella di alcun altro Paese occidentale. Uscendo dai dibattiti un po\u2019 stucchevoli su se vi sia o no una secolarizzazione, e se sia vero che all\u2019America devota si contrappone un\u2019Europa che sta abbandonando la religione, Garelli dopo un\u2019ampia indagine mostra, cifre alla mano, che gli italiani sono ancora cattolici ma lo sono, appunto, \u00aball\u2019italiana\u00bb.<\/p>\n<p style=\"text-align: justify;\">Con riferimento a una precedente indagine che lo stesso sociologo condusse, con altri, nel 1995, Garelli mostra che sono passati quindici anni ma le cose non sono molto cambiate. L\u201982,7% degli italiani continua a credere in Dio, anche se il 36,8% crede \u00abcon dubbi\u00bb. Il 32,5% prega almeno una volta al giorno.<\/p>\n<p style=\"text-align: justify;\">Il 26,5% dichiara di andare a Messa tutte le settimane \u2013 cifra che pu\u00f2 sembrare bassa, ma che \u00e8 ai vertici europei se si escludono Malta e la Polonia \u2013 e il 42,3% afferma di andarci almeno una volta al mese. Quasi l\u201980% degli italiani si considera cattolico. Il numero di atei e agnostici \u2013 nonostante una rumorosa promozione \u2013 non aumenta da vent\u2019anni. Crescono i fedeli di altre religioni, ma questo avviene in gran parte a causa dell\u2019immigrazione.<\/p>\n<p style=\"text-align: justify;\"><strong>Come tutte le ricerche importanti, quella di Garelli ha avuto molte recensioni,<\/strong> talora \u00abdi parte\u00bb, nel senso che c\u2019\u00e8 chi ha visto il bicchiere mezzo pieno e chi mezzo vuoto. Va sempre cos\u00ec per la sociologia: si pu\u00f2 sottolineare che gli italiani dichiarano di andare a Messa cinque volte pi\u00f9 dei francesi oppure, al contrario, che comunque quasi tre quarti dei nostri connazionali non rispettano il precetto domenicale. Tuttavia \u00e8 innegabile la maggiore tenuta della Chiesa Cattolica in Italia rispetto agli altri grandi Paesi europei.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma che cosa \u00abtiene\u00bb esattamente?<\/strong> Qui sta, specificamente, la via italiana al cattolicesimo di cui parla Garelli. Il sociologo nota come, quando parla di tenuta della Chiesa Cattolica in Italia con colleghi stranieri, viene spesso accolto con sorrisi di sufficienza. Com\u2019\u00e8 possibile, si chiedono all\u2019estero, che gli italiani siano ancora cattolici quando l\u2019Italia ha il triste primato mondiale della denatalit\u00e0? E la stessa ricerca di Garelli dimostra come \u2013 sia pure fra molte perplessit\u00e0 e dubbi, anche questi tipici del nostro Paese \u2013 una met\u00e0 abbondante degli italiani non si senta di escludere l\u2019aborto e l\u2019eutanasia sempre e comunque, anche se c\u2019\u00e8 ancora una maggioranza contraria al matrimonio e alle adozioni omosessuali.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma la contraddizione, in qualche modo, fa parte del carattere nazionale italiano.<\/strong> Pi\u00f9 del settanta per cento degli italiani non segue la Chiesa nei suoi insegnamenti in materia di morale sessuale, e anzi dichiara che si pu\u00f2 essere buoni cattolici anche senza conformarsi al Magistero sul punto. Ma nello stesso tempo oltre il settanta per cento dei nostri connazionali afferma che la Chiesa fa bene a mantenere fermo un insegnamento alto ed esigente sui temi dell\u2019aborto, dell\u2019eutanasia e della sessualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">In altre parole, mentre in altri Paesi \u00e8 forte una contestazione organizzata, anche intra-cattolica, del Magistero morale della Chiesa che ne chiede a gran voce il cambiamento, in Italia questo dissenso \u00e8 ridotto a piccole frange d\u2019intellettuali. La maggioranza degli italiani non si conforma alla dottrina morale della Chiesa, ma la sente con una sorta di nostalgia come annuncio di un mondo diverso e forse migliore. Non chiede che la Chiesa modifichi questo annuncio, per quanto non si senta capace di seguirlo, talora pi\u00f9 per debolezza che per vero dissenso.<\/p>\n<p style=\"text-align: justify;\"><strong>Il dichiararsi cattolici, nota Garelli, non \u00e8 una variabile significativa per la morale individuale,<\/strong> per il voto politico, e anche per comportamenti di morale sociale come l\u2019evasione fiscale o il non pagare il biglietto sull\u2019autobus. L\u2019ottanta per cento che si dichiara cattolico si comporta pi\u00f9 o meno come il venti per cento che \u00e8 ateo, agnostico o segue altre religioni. Garelli per\u00f2 sostiene che l\u2019espressione \u00abmondo cattolico\u00bb \u00e8 ormai obsoleta. \u00c8 un ombrello troppo grande, che copre realt\u00e0 molto diverse fra loro. All\u2019interno del cosiddetto mondo cattolico c\u2019\u00e8 una parte \u2013 circa il venti per cento degli italiani \u2013 che va regolarmente a Messa e in pi\u00f9 s\u2019interessa agli insegnamenti della Chiesa, anche se non li segue sempre e tutti.<\/p>\n<p style=\"text-align: justify;\">Un dieci per cento degli italiani fa parte di associazioni e movimenti cattolici \u2013 una percentuale altissima e unica al mondo \u2013 e un altro dieci per cento segue con qualche assiduit\u00e0 la vita parrocchiale. \u00c8 questo venti per cento che sul piano morale e del comportamento \u00e8 diverso dal resto degli italiani, e pi\u00f9 vicino alle indicazioni del Magistero anche se ad esse non perfettamente e sempre docile.<\/p>\n<p style=\"text-align: justify;\"><strong>Del resto, gli italiani dichiarano di sentirsi pi\u00f9 vicini al Papa<\/strong> \u2013 anche se pi\u00f9 al beato Giovanni Paolo II (1920-2005) che a Benedetto XVI \u2013 che ai loro vescovi, e pi\u00f9 ai vescovi che ai politici, anche \u00abcattolici\u00bb. E a grande maggioranza i nostri connazionali apprezzano molto l\u2019aiuto concreto che i preti, le parrocchie e il volontariato danno a chi ne ha veramente bisogno, per cui non contestano l\u2019otto per mille anche se \u2013 forse suggestionati da campagne recenti \u2013 vorrebbero pi\u00f9 severit\u00e0 nel far pagare l\u2019ICI alla Chiesa per gli edifici non strettamente di culto.<\/p>\n<p style=\"text-align: justify;\"><strong>Il testo di Garelli \u00e8 un\u2019opera di sociologia, non di pastorale o di apologetica.<\/strong> Tuttavia \u00e8 di grande interesse per i cattolici e per i pastori. Da una parte, indica che il cattolicesimo in Italia \u00e8 ancora vivo e vitale, assai pi\u00f9 di quanto non sia in altri Paesi mediterranei di antica tradizione cattolica come la Francia o la Spagna. Gli italiani restano affezionati alle loro radici cattoliche. Ma il rapporto con queste radici \u00e8 confuso. Se le radici non sono irradiate da un\u2019adeguata catechesi, rischiano d\u2019inaridire. \u00c8 questo il senso della \u00abnuova evangelizzazione\u00bb e ora dell\u2019Anno della Fede proclamato da Benedetto XVI. Una base c\u2019\u00e8, ma \u00e8 fragile. O su questa base si costruisce, o la vedremo a poco a poco sgretolarsi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bussola quotidiana 19 dicembre 2011 di Massimo Introvigne Un recentissimo sondaggio dell\u2019IPSOS mostra che i cattolici italiani, nonostante il governo tecnico, hanno ancora voglia di politica e sarebbero interessati a offerte politiche coerenti con i loro valori, di cui tuttavia riscontrano la mancanza, e che oltre il quaranta per cento degli italiani \u2013 cattolici &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34956,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1599,2005],"class_list":["post-4864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","tag-cattolici","tag-cattolici-e-politica","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La buona sociologia e i cattolici &laquo;all&#039;italiana&raquo; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La buona sociologia e i cattolici &laquo;all&#039;italiana&raquo; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-04T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-16T07:51:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"136\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La buona sociologia e i cattolici &laquo;all&#8217;italiana&raquo;\",\"datePublished\":\"2012-01-04T23:00:00+00:00\",\"dateModified\":\"2016-06-16T07:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/\"},\"wordCount\":1112,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/Garelli_cover.jpg\",\"keywords\":[\"cattolici\",\"cattolici e politica\"],\"articleSection\":[\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/\",\"name\":\"La buona sociologia e i cattolici &laquo;all'italiana&raquo; - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/Garelli_cover.jpg\",\"datePublished\":\"2012-01-04T23:00:00+00:00\",\"dateModified\":\"2016-06-16T07:51:48+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/Garelli_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/Garelli_cover.jpg\",\"width\":136,\"height\":220},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-sociologia-e-i-cattolici-allitaliana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La buona sociologia e i cattolici &laquo;all&#8217;italiana&raquo;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La buona sociologia e i cattolici &laquo;all'italiana&raquo; - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/","og_locale":"it_IT","og_type":"article","og_title":"La buona sociologia e i cattolici &laquo;all'italiana&raquo; - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-01-04T23:00:00+00:00","article_modified_time":"2016-06-16T07:51:48+00:00","og_image":[{"width":136,"height":220,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La buona sociologia e i cattolici &laquo;all&#8217;italiana&raquo;","datePublished":"2012-01-04T23:00:00+00:00","dateModified":"2016-06-16T07:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/"},"wordCount":1112,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg","keywords":["cattolici","cattolici e politica"],"articleSection":["Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/","name":"La buona sociologia e i cattolici &laquo;all'italiana&raquo; - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg","datePublished":"2012-01-04T23:00:00+00:00","dateModified":"2016-06-16T07:51:48+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Garelli_cover.jpg","width":136,"height":220},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-sociologia-e-i-cattolici-allitaliana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La buona sociologia e i cattolici &laquo;all&#8217;italiana&raquo;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4864"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4864\/revisions"}],"predecessor-version":[{"id":34957,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4864\/revisions\/34957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34956"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}