{"id":48364,"date":"2020-09-17T00:00:13","date_gmt":"2020-09-16T22:00:13","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=48364"},"modified":"2020-09-10T12:08:23","modified_gmt":"2020-09-10T10:08:23","slug":"paradisi-purgatori-e-inferni-fiscali","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/","title":{"rendered":"Paradisi, Purgatori e Inferni fiscali"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/03\/fisco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20601 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/03\/fisco.jpg\" alt=\"\" width=\"266\" height=\"190\" \/><\/a>Alleanza Cattolica<\/strong> Sabato, 25 luglio 2020 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Nel dibattito pubblico ritorna periodicamente il tema dei cosiddetti \u201cparadisi fiscali\u201d. Non certo per lodare una supposta benevolenza dell\u2019esattore quanto per stigmatizzare una presunta concorrenza sleale, un dumping fiscale e contributivo a danno degli altri paesi. Paesi che, evidentemente, si auto considerano come \u201cpurgatori\u201d, quando non veri e propri \u201cinferni\u201d fiscali.<\/em> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di<strong> Maurizio Milano<\/strong> <\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Si potrebbe liquidare la discussione con una semplice battuta: i \u201cparadisi fiscali\u201d, se esistono, devono la propria esistenza proprio agli \u201cinferni fiscali\u201d.<\/strong>\u00a0Se si vogliono davvero eliminare i \u201cparadisi\u201d fiscali occorre allora eliminare anche e innanzitutto gli \u201cinferni\u201d fiscali. Il problema non \u00e8 l\u2019esistenza di quelli che sarebbe pi\u00f9 corretto definire \u201c<em>tax haven<\/em>\u201d \u2013 ossia \u201crifugi fiscali\u201d \u2013 e non \u201c<em>tax heaven\u201d \u2013<\/em> \u201cparadisi fiscali\u201d: dei \u201cporti sicuri\u201d dove il capitale, altrove colpito da tassazioni sempre pi\u00f9 espropriatrici, cerca comprensibilmente rifugio. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/fisco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27722 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/fisco.jpg\" alt=\"\" width=\"249\" height=\"202\" \/><\/a>Il tema vero \u00e8 invece, rovesciando la prospettiva, l\u2019esistenza certa e documentabile dei tantissimi \u201cpurgatori\u201d fiscali \u2013 la quasi totalit\u00e0 dei sistemi fiscali moderni \u2013 e, soprattutto, dei veri e propri \u201cinferni\u201d fiscali, una classifica dove il nostro paese si piazza infelicemente tra i primi posti. Il vero e pericoloso \u201cfuorilegge\u201d, a ben vedere, non \u00e8 <em>Robin Hood<\/em> ma lo sceriffo di <em>Nottingham<\/em>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Con ci\u00f2 non si vogliono certamente sottacere o minimizzare i problemi reali di opacit\u00e0 di certe legislazioni fiscali<\/strong>, che ovviamente pongono legittimi problemi di evasione ed elusione fiscale, oltre che di <em>money laundering <\/em>di origine malavitosa. Tutto vero, e ovviamente da contrastare, purch\u00e9 la <em>black list <\/em>dei \u201cparadisi fiscali\u201d non serva strumentalmente a distogliere l\u2019attenzione dal problema principale: il fatto, cio\u00e8, che gli Stati moderni continuano da decenni ad allargare il proprio perimetro di intervento nella vita economica e sociale, comprimendo progressivamente \u2013 in accelerazione dopo ogni crisi, come sta avvenendo con l\u2019attuale epidemia Covid \u2013 gli spazi di libert\u00e0 e di sussidiariet\u00e0 propri delle famiglie e dei corpi intermedi. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/fisco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6809 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/fisco.jpg\" alt=\"\" width=\"211\" height=\"211\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/fisco.jpg 159w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/fisco-150x150.jpg 150w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/a>Livelli esorbitanti di spesa pubblica (in Italia circa il 50% del Pil) significano un\u2019intermediazione da parte dei pubblici poteri \u2013 e ultimamente della classe politica e delle burocrazie varie \u2013 di una fetta maggioritaria o comunque elevatissima della torta della ricchezza prodotta.<\/strong> Una \u201cconvergenza\u201d delle politiche fiscali tra i vari Stati toglierebbe al contribuente vessato ogni possibilit\u00e0 di \u201cevasione\u201d, da intendersi nel senso <em>tolkieniano<\/em> di legittima \u201cfuga del prigioniero\u201d dalle sbarre della prigione; gli Stati potrebbero cos\u00ec proseguire ancora pi\u00f9 indisturbati con le loro politiche vessatorie, con quell\u2019\u00abarte della tassazione\u00bb, come ebbe a scrivere cinicamente <em>Jean-Baptiste Colbert\u00a0<\/em>(1619-1683), ministro delle Finanze di Luigi XIV, che \u00abconsiste nello spennare l\u2019oca al fine di ottenere la quantit\u00e0 massima di piume con il minimo di starnazzo possibile\u00bb. Ma, si dir\u00e0, le entrate fiscali servono a sostenere la spesa pubblica, l\u2019erogazione di servizi essenziali ai cittadini. Vero? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/fisco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22716 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/fisco.jpg\" alt=\"\" width=\"249\" height=\"203\" \/><\/a>Vero, ma giova ricordare i principali effetti distorsivi della spesa pubblica quando questa va fuori controllo: un\u2019allocazione \u201cpolitica\u201d delle risorse, scarse, a vantaggio delle <em>lobbies <\/em>e del capitalismo clientelare<\/strong>, una distorsione della libera e leale concorrenza, una diminuzione della \u201ctorta della ricchezza\u201d a causa dell\u2019allocazione inefficiente delle risorse, una contrazione degli spazi di libert\u00e0 personale e familiare, un\u2019atrofizzazione della societ\u00e0 invasa dagli apparati pubblici, un\u2019imposizione fiscale \u2013 per tornare al punto dolente \u2013 vessatoria e iniqua, che scoraggia il lavoro e gli investimenti e fa fuggire, chi pu\u00f2, alla ricerca di lidi migliori. Un processo di avvitamento progressivo, come stiamo vivendo sulla nostra pelle da alcuni decenni, a svantaggio dei pi\u00f9, in specie di chi non gode delle \u201cridistribuzioni\u201d politiche della ricchezza accentrata dallo Stato. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>La societ\u00e0 viene cos\u00ec spaccata in due: da un lato, i beneficiari netti delle politiche redistributive, i \u201c<em>tax-consumers\u201d; <\/em>dall\u2019altro, quelli che pagano il conto, i \u201c<em>tax-payers\u201d,<\/em>\u00a0i contributori netti. <\/strong>Un fenomeno sempre pi\u00f9 evidente nel nostro paese, dove con la progressiva contrazione della base produttiva \u2013 sia per il declino demografico sia per la fuga dei capitali \u2013 il peso crescente dei costi sanitari, pensionistici ed assistenziali si scarica su una base sempre pi\u00f9 ridotta, e quindi sempre pi\u00f9 tartassata. Alla faccia del \u201cbene comune\u201d, la cui promozione \u00e8 il dovere primo dello Stato e la sua ultima ragion d\u2019essere. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/tasse_fisco_evasione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47360 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/tasse_fisco_evasione-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/tasse_fisco_evasione-300x171.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/tasse_fisco_evasione-768x438.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/tasse_fisco_evasione-1024x584.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>A tale proposito, l\u2019economista francese <em>Fr\u00e9d\u00e9ric Bastiat<\/em> (1801-1850), nell\u2019opera \u201cLa legge\u201d del 1850, di ispirazione giusnaturalista, parlava di \u201cspoliazione legale\u201d, denunciando la raccolta esosa di denaro effettuata dall\u2019autorit\u00e0 pubblica sulla collettivit\u00e0 dei saccheggiati, denaro poi dirottato a favore delle <em>\u00e9lites<\/em> politico-economiche che gestiscono la cosa pubblica, i <em>tax-consumers.<\/em> Parole forti, che purtroppo trovano corrispondenza nell\u2019iniquit\u00e0 dei sistemi fiscali moderni. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Lo <em>slogan <\/em>utilizzato dai fautori del leviatano fiscale per gettare fumo negli occhi \u00e8 sempre il medesimo: \u201c<em>pagare tutti per pagare meno<\/em>\u201d<\/strong>, con conseguente \u201ccaccia all\u2019evasore\u201d e spinta all\u2019invidia e alla delazione sociale; in realt\u00e0, la soluzione corretta sarebbe \u201c<em>pagare meno perch\u00e9 paghino tutti<\/em>\u201d<em>, <\/em>perch\u00e9 riducendo la pressione fiscale automaticamente diminuirebbe la tentazione e la convenienza economica dell\u2019evasione. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/fisco_adempimenti.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32423 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/fisco_adempimenti.jpg\" alt=\"\" width=\"307\" height=\"204\" \/><\/a>Se la rivolta fiscale non scatta \u00e8 solo perch\u00e9 i lavoratori dipendenti non hanno piena contezza dell\u2019enorme incidenza fiscale e contributiva sulla busta paga netta che ricevono; molte altre tasse poi sono assolutamente opache, pensiamo solo agli incentivi alle fonti rinnovabili e al canone Rai che tutti paghiamo, non sempre con consapevolezza, nella bolletta elettrica delle utenze domestiche residenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Oltre al tema dell\u2019iniquit\u00e0 si dovrebbe poi aggiungere anche quello dell\u2019estrema inefficienza ed inefficacia della ricchezza accentrata e gestita direttamente dalla classe politica.<\/strong> Pensiamo, a titolo di esempio, ai costi esorbitanti della scuola e della sanit\u00e0 in Italia, a cui corrispondono servizi assolutamente inadeguati alle esigenze e ai costi sostenuti. La \u201cqualit\u00e0\u201d, e non solo la \u201cquantit\u00e0\u201d della spesa pubblica, deve quindi essere posta sul banco degli imputati. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/tasse_basta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28039 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/tasse_basta.jpg\" alt=\"\" width=\"251\" height=\"201\" \/><\/a>Gi\u00e0, perch\u00e9 se \u00e8 comunque sbagliato un sistema di Stato assistenziale che drena gran parte della ricchezza privata ancorch\u00e9 poi elargisca servizi, in ipotesi, eccellenti \u2013 perch\u00e9 comunque liberticida e deresponsabilizzante \u2013 che dire di uno Stato esoso che poi fornisce servizi pubblici scadenti e aiuta solo gli \u201camici\u201d e gli \u201camici degli amici\u201d? <em>Cui prodest<\/em>? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>I \u201cparadisi fiscali\u201d possono attendere, preoccupiamoci invece di combattere gli \u201cinferni fiscali\u201d in cui viviamo, anzi \u201c<em>sopravviviamo<\/em>\u201d.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alleanza Cattolica Sabato, 25 luglio 2020 Nel dibattito pubblico ritorna periodicamente il tema dei cosiddetti \u201cparadisi fiscali\u201d. Non certo per lodare una supposta benevolenza dell\u2019esattore quanto per stigmatizzare una presunta concorrenza sleale, un dumping fiscale e contributivo a danno degli altri paesi. Paesi che, evidentemente, si auto considerano come \u201cpurgatori\u201d, quando non veri e propri &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":48369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[145,177],"class_list":["post-48364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisco","tag-fisco-2","tag-tasse","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T22:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Paradisi, Purgatori e Inferni fiscali\",\"datePublished\":\"2020-09-16T22:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/\"},\"wordCount\":1005,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/soldi_fisco_Economia.jpg\",\"keywords\":[\"fisco\",\"tasse\"],\"articleSection\":[\"Fisco\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/\",\"name\":\"Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/soldi_fisco_Economia.jpg\",\"datePublished\":\"2020-09-16T22:00:13+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/soldi_fisco_Economia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/soldi_fisco_Economia.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paradisi-purgatori-e-inferni-fiscali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paradisi, Purgatori e Inferni fiscali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/","og_locale":"it_IT","og_type":"article","og_title":"Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-09-16T22:00:13+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Paradisi, Purgatori e Inferni fiscali","datePublished":"2020-09-16T22:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/"},"wordCount":1005,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg","keywords":["fisco","tasse"],"articleSection":["Fisco"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/","name":"Paradisi, Purgatori e Inferni fiscali - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg","datePublished":"2020-09-16T22:00:13+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/09\/soldi_fisco_Economia.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paradisi-purgatori-e-inferni-fiscali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Paradisi, Purgatori e Inferni fiscali"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=48364"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48364\/revisions"}],"predecessor-version":[{"id":48370,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/48364\/revisions\/48370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/48369"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=48364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=48364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=48364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}