{"id":47965,"date":"2020-07-30T00:00:41","date_gmt":"2020-07-29T22:00:41","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=47965"},"modified":"2020-07-24T13:22:34","modified_gmt":"2020-07-24T11:22:34","slug":"la-vittima-leroe-del-nostro-tempo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/","title":{"rendered":"La vittima, l\u2019eroe del nostro tempo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/occidente_vittimismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47966 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/occidente_vittimismo-300x227.jpg\" alt=\"\" width=\"300\" height=\"227\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/occidente_vittimismo-300x227.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/occidente_vittimismo.jpg 456w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ricognizioni <\/strong>22 Luglio 2020<\/p>\n<p style=\"text-align: center;\">di <strong>Roberto Pecchioli <\/strong><\/p>\n<p style=\"text-align: justify;\"><em>\u201cLa vittima \u00e8 l\u2019eroe del nostro tempo. Essere vittime d\u00e0 prestigio, impone ascolto, promette e promuove riconoscimento, attiva un potente generatore di identit\u00e0, diritto, autostima. Immunizza da ogni critica, garantisce innocenza al di l\u00e0 di ogni ragionevole dubbio. Come potrebbe la vittima essere colpevole, e anzi responsabile di qualcosa? Non ha fatto, le \u00e8 stato fatto. Non agisce, patisce. Nella vittima si articolano mancanza e rivendicazione, debolezza e pretesa, desiderio di avere e desiderio di essere. Non siamo ci\u00f2 che facciamo, ma ci\u00f2 che abbiamo subito, ci\u00f2 che possiamo perdere, ci\u00f2 che ci hanno tolto\u201d.<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Cos\u00ec \u00e8 scritto nella quarta di copertina di un libro del 2014, <em>Critica della vittima<\/em>, dello scrittore e docente universitario Daniele Giglioli. Pur muovendo da una visione del mondo assai diversa da quella del professore bergamasco, ne siamo convinti anche noi. La volont\u00e0 d\u2019impotenza che ci domina ha bisogno di una figura simbolica alla quale intestare la sua azione dissolvente. Si tratta, in verit\u00e0, della maschera dietro la quale si nascondono vecchi carnefici.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/Giglioli_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47967 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/Giglioli_cover.jpg\" alt=\"\" width=\"188\" height=\"268\" \/><\/a>\u00c8 tempo di superare questo paradigma paralizzante e <em>\u201cridisegnare i tracciati di una prassi, di un\u2019azione del soggetto nel mondo: in credito di futuro, non di passato\u201d<\/em>. Al di l\u00e0 del linguaggio che svela il debito nei confronti della cultura marxista, la rivelazione di Giglioli \u00e8 una boccata di aria fresca e pulita da respirare a pieni polmoni.<\/p>\n<p style=\"text-align: justify;\">Dalla politica al costume, dalla storia alla letteratura, dal diritto alla psicologia, si diffonde la sintomatologia della vittima contemporanea: l\u2019eroe del nostro tempo, come il capitano Pe\u00e7orin del romanzo omonimo di Michail Lermontov, anti eroe di una generazione priva di cause a cui votarsi.<\/p>\n<p style=\"text-align: justify;\">Tra le manifestazioni pi\u00f9 vistose del neo-vittimismo, la celebrazione ossessiva della propria specifica memoria, il credo umanitario che mantiene \u201cinermi i disarmati\u201d e \u201clascia intatti gli arsenali dei forti\u201d, l\u2019imperativo del diritto al benessere che si rovescia in frustrazione e inadeguatezza.<\/p>\n<p style=\"text-align: justify;\">In ogni caso, la responsabilit\u00e0 del male \u00e8 altrove, fuori da noi, principalmente nel passato demonizzato. Che cosa significa quindi essere vittime e quali sono le implicazioni etiche del sentirsi tali? Qual \u00e8 il significato di parole come innocenza, diritto inalienabile o immunit\u00e0?<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/ingiustizia_vittimismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47968 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/ingiustizia_vittimismo-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>Si consolida una vera e propria ideologia della vittima, una strategia della lamentazione che divide la societ\u00e0 <em>a priori<\/em> in campi nemici: rei e innocenti, vittime e aguzzini. Ogni discussione pubblica si esprime in termini di vittime e carnefici. Le donne sono vittime degli uomini, i neri dei bianchi, gli omosessuali degli eterosessuali, gli invalidi dei non invalidi, i discendenti delle popolazioni native dei conquistatori di secoli fa, gli immigrati degli autoctoni.<\/p>\n<p style=\"text-align: justify;\">La lista potrebbe proseguire ed esistono ragioni per giustificare tale prospettiva. Il mondo \u00e8 stato ed \u00e8 una fabbrica di vittime; in molti casi questa condizione \u00e8 vincolata all\u2019appartenenza a determinate categorie. Per la prima volta, viviamo nello schema di una vera e propria cultura del vittimismo, che alimenta potentemente l\u2019odio di s\u00e9 dell\u2019umanit\u00e0 occidentale contemporanea.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/09\/legge_omofobia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34974 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/09\/legge_omofobia.jpg\" alt=\"\" width=\"262\" height=\"193\" \/><\/a>Il vittimismo si diffonde e dilaga mano a mano che la sinistra culturale, quella che Jean Claude Mich\u00e9a chiama \u201csinistra dei costumi\u201d avanza rivendicazioni sempre nuove, tutte legate all\u2019agenda dell\u2019identitarismo vittimista degli \u201cumiliati e offesi\u201d.<\/p>\n<p style=\"text-align: justify;\">Il libro di Giglioli, da sinistra, ne denuncia limiti, contraddizioni e miti incapacitanti. \u00c8 ovvio che nessuno intende pronunciare un giudizio contrario alle vittime autentiche, ma \u00e8 utile riconoscere l\u2019esistenza e i guasti drammatici della cultura del vittimismo, ristabilendo altres\u00ec una delimitazione tra torti veri e immaginari.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_schiavismo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47626 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_schiavismo-1-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>Per i nazisti, essere ebreo era una colpa anteriore a qualunque azione, buona o cattiva, compiuta dagli israeliti. Per i bolscevichi, era una colpa essere nobili, proprietari, borghesi, ecclesiastici, credenti. Ci stiamo tornando: siamo testimoni quotidiani di situazioni nelle quali prima di valutare un fatto, domandiamo chi lo ha commesso e chi lo ha subito.<\/p>\n<p style=\"text-align: justify;\">In base alla scala vittimistica corrente, emettiamo il verdetto, riscriviamo la legge, riformuliamo il senso comune. Il bene e il male dipendono dalle circostanze, da qual \u00e8 l\u2019identit\u00e0 collettiva del carnefice (uomo, bianco, europeo, marito, padre, eterosessuale, preferibilmente) e della vittima. Non si perde solo il senso del diritto, ma si vive di <em>priori<\/em>, ossia di nuovi pregiudizi.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/immigrazionismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40565 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/immigrazionismo.jpg\" alt=\"\" width=\"285\" height=\"177\" \/><\/a>Alcuni rei lo sono pi\u00f9 di altri, a prescindere da fatti e circostanze, alcune vittime si convertono in martiri. Essere vittima conferisce un\u2019identit\u00e0. In un tempo che ha gettato tra i rifiuti le vecchie identit\u00e0 comuni, inventarne di nuove, artificiose, rivendicative, aggressive, \u00e8 il gesto di una rivoluzione che dissolve e nega, il segno dei tempi.<\/p>\n<p style=\"text-align: justify;\">Le sinistre culturali hanno sostituito quelle politiche. Alla tradizionale domanda \u201cche fare? \u201c, con l\u2019obiettivo della trasformazione del mondo attraverso il ribaltamento dei \u201crapporti di produzione\u201d hanno sostituito un interrogativo falsamente introspettivo, solipsistico: chi sono? \u201cChe fare\u201d porta all\u2019esterno e all\u2019azione. \u201cChi sono\u201d conduce all\u2019interno di ogni soggettivit\u00e0, all\u2019indagine sul terreno delle singolarit\u00e0 che ciascuno pu\u00f2 attribuirsi, a ci\u00f2 che \u00e8 gi\u00e0 dato.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47610 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo.jpg\" alt=\"\" width=\"299\" height=\"168\" \/><\/a>Da \u201cche fare \u201cpu\u00f2 scaturire una rivoluzione; da \u201cchi sono\u201d, deriva un manuale di lamenti, il massimario del vittimismo. Il problema lambisce il perimetro del diritto: tornano i \u201cdelitti d\u2019autore\u201d, nei quali non si giudicano l\u2019azione e le sue circostanze, ma la natura e le caratteristiche dell\u2019imputato e della vittima.<\/p>\n<p style=\"text-align: justify;\">\u00c8 un delitto di genere? Lo ha commesso un uomo o una donna? Un nero o un bianco? Un etero o un gay? Un cittadino autoctono, un discendente di conquistatori o un immigrato?<\/p>\n<p style=\"text-align: justify;\">Quel che \u00e8 fatto, persino se lo si \u00e8 fatto, passa in secondo piano. Il caso di George Floyd in America \u00e8 l\u2019esempio pi\u00f9 lampante, ma non hanno meno importanza la tendenza a considerare diversamente gli atti di violenza se commessi da uomini verso donne e la continua estensione di legislazioni che colpiscono idee, pensieri, sentimenti.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47576 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-300x169.png 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-768x432.png 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-1024x576.png 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra.png 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Da una parte il mondo delle vittime a prescindere \u2013 in quanto membri di gruppi con l\u2019etichetta di perseguitati \u2013 dall\u2019altro, per lo stesso motivo, uguale e contrario, i carnefici \u201cstrutturali\u201d, gli oppressori Se non si trattasse di una drammatica distorsione della realt\u00e0 con effetti devastanti, sarebbe comica la deriva illiberale e collettiva della societ\u00e0 aperta, liberale e individualista.<\/p>\n<p style=\"text-align: justify;\">L\u2019elemento centrale, inaccettabile, distrugge l\u2019idea di societ\u00e0: la cultura del vittimismo presuppone che la condizione di vittima o colpevole non dipenda da fatti concreti, reali, da qualcosa che si \u00e8 subito o commesso, non \u00e8 cio\u00e8 circostanziale, ma essenziale.<\/p>\n<p style=\"text-align: justify;\">Siamo vittime o carnefici in funzione dell\u2019identit\u00e0 a cui apparteniamo, della categoria o etichetta che ci viene attribuita o che rivendichiamo. L\u2019unica differenza con il passato, nella forma caricaturale descritta dall\u2019armata del Progresso, \u00e8 il capovolgimento. Il pregiudizio \u00e8 uguale, cambia soltanto la definizione di bene e male.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Africa_razzismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47614 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Africa_razzismo.jpg\" alt=\"\" width=\"281\" height=\"180\" \/><\/a>Se siamo nati in una famiglia che ci ha fornito un\u2019educazione, un\u2019 istruzione e principi \u201ctradizionali\u201d; se, orrore, siamo maschi bianchi eterosessuali europei, possediamo tutte le condizioni per essere colpevoli, carnefici strutturali, malvagi per essenza. I privilegi ereditati dal postmoderno <em>malommo<\/em> sono individuati a priori, poich\u00e9 il concetto di colpa (personale, individuale) si \u00e8 secolarizzato e si \u00e8 trasformato in debito.<\/p>\n<p style=\"text-align: justify;\">La pena a carico del privilegiato\/carnefice strutturale \u00e8 un debito inestinguibile, imprescrittibile, eterno. In bizzarra controtendenza con il soggettivismo liberale (e con la civilt\u00e0 giuridica dal tempo di Roma) regna una particolare concezione in base alla quale la condizione di vittima e di colpevole \u00e8 ereditaria, si trasmette di generazione in generazione al punto che si ha pieno titolo di sentirsi vittima di ci\u00f2 che soffr\u00ec 500 anni fa un antenato della comunit\u00e0 cui si appartiene.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/01\/giustizia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28976 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/01\/giustizia.jpg\" alt=\"\" width=\"284\" height=\"177\" \/><\/a>Queste rivendicazioni tentano \u2013 con crescente successo per paralisi degli oppositori \u2013 di diventare effettive attraverso specifiche politiche pubbliche e discutibili fattispecie giuridiche. L\u2019idea dell\u2019esistenza di carnefici \u201cessenziali\u201d con obbligazioni per definizione inestinguibili dovrebbe escludere le dispute dal terreno delle decisioni giudiziarie.<\/p>\n<p style=\"text-align: justify;\">Lo stato di diritto dovrebbe impedire l\u2019estensione del concetto, poich\u00e9 il suo compito \u00e8 decidere su fatti specifici delimitati nello spazio e nel tempo. Non esistono, n\u00e9 possono esistere, in regimi retti dal senso comune e dalla legge scritta, colpevoli strutturali, aprioristici.<\/p>\n<p style=\"text-align: justify;\">La figura che pi\u00f9 gli somiglia \u00e8 il capro espiatorio, l\u2019essere capace di accogliere sopra di s\u00e9 i mali e le colpe della comunit\u00e0, liberata da tale processo di trasferimento. Dopo il sacrificio, la comunit\u00e0 riprende il suo cammino senza macchia. Impossibile, non basta nel regime del debito eterno e della vittima collettiva ed ereditaria.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/gestapo_nazismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47459 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/gestapo_nazismo-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/gestapo_nazismo-300x150.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/gestapo_nazismo.jpg 318w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Notava Ren\u00e9 Girard ne\u00a0<em>La violenza e il sacro<\/em>\u00a0che anche i nichilisti pi\u00f9 conseguenti decostruiscono tutto salvo il principio dell\u2019innocenza della vittima. Nelle accuse del vittimismo contemporaneo, amplificate dalle reti sociali, dalle manifestazioni e dalla comunicazione di massa, il reo segnalato, il carnefice, l\u2019eterno Cattivik perde ogni presunzione di innocenza, deve farsi carico delle colpe storiche collettive degli antenati.<\/p>\n<p style=\"text-align: justify;\">La pena, automatica e priva di attenuanti o esimenti, poich\u00e9 la colpevolezza sta nell\u2019esistenza in vita dell\u2019erede, \u00e8 la condanna della memoria, la scomunica morale e culturale retroattiva da trasmettere all\u2019intera discendenza. Il debito \u00e8 pi\u00f9 inestinguibile di quello finanziario. Come per gli ergastolani, \u00e8 stampato a lettere di fuoco \u201cfine pena mai\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/nazismo_ebrei.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46613 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/nazismo_ebrei.jpg\" alt=\"\" width=\"186\" height=\"271\" \/><\/a>La questione della verit\u00e0 si opacizza: nella cultura del vittimismo, chi ottiene lo statuto di vittima, diventa immune da ogni critica. Alla vittima si perdona tutto ed \u00e8 vietata ogni discussione con argomenti razionali. La condizione postmoderna di vittima intrattiene una relazione speciale con la verit\u00e0, indiscutibile, scolpita nel marmo, paradossale in tempi convinti che tutto \u00e8 relativo, nulla \u00e8 vero, ogni sguardo non \u00e8 che una prospettiva, che le grandi narrazioni si sono esaurite (Jean Fran\u00e7ois Lyotard, La condizione post moderna).<\/p>\n<p style=\"text-align: justify;\">La realt\u00e0 \u00e8 diversa: semplicemente, i grandi \u201cracconti\u201d di verit\u00e0 non sono stati sostituiti. Tuttavia, abbiamo bisogno di credere in qualcosa di solido anche in tempi liquidi: la fede nel vittimismo e in chi riesca ad affermare la condizione di vittima. In conclusione, se il criterio per distinguere il giusto dall\u2019ingiusto \u00e8 ambiguo, chi sta con la vittima non sbaglia mai.<\/p>\n<p style=\"text-align: justify;\">Questo spiega l\u2019abbraccio collettivo che riceve chi \u00e8 o \u00e8 creduto tale. Nessuna obiezione alla solidariet\u00e0 umana, ma l\u2019essenziale, divenuto invisibile, \u00e8 che l\u2019appoggio a chi appare vittima serve per rassicurarsi, convincersi di essere dalla parte giusta in un mondo in cui tutto \u00e8 liquido. \u00c8 una posizione adottata per comodit\u00e0, per se stessi, pi\u00f9 per debolezza che per empatia. Infatti, in genere nessuno muove un dito per la vere vittime e le grandi sofferenze: \u00e8 sufficiente mettersi a posto a buon mercato con la coscienza infelice.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31556 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg\" alt=\"\" width=\"272\" height=\"185\" \/><\/a>La verit\u00e0 \u00e8 un dettaglio insignificante, quando interessa afferrarsi a qualche certezza. Quel che importa \u00e8 che la vittima appaia tale, designata, proclamata: tanto basta alla maggioranza. Nessuna verit\u00e0; dibattito interrotto prima di cominciare, comodo, rassicurante.<\/p>\n<p style=\"text-align: justify;\">La vittima diventa un Dio dei tempi secolarizzati. Quando parliamo di verit\u00e0, parliamo anche di potere. Giglioli mette il dito nella piaga: <em>\u201cLa vittima \u00e8 irresponsabile, non risponde di nulla, non ha bisogno di giustificarsi: \u00e8 il sogno di ogni tipo di potere\u201d<\/em>. La retorica del vittimismo non sta innalzando le vere vittime, ma creando una grottesca concorrenza tra veri e presunti dannati della terra, in cui le oligarchie sono pi\u00f9 a loro agio che mai e assorbono, cooptano le figure emergenti dal discorso ribelle, nella misura in cui le rivendicazioni non mettono in pericolo i loro privilegi di classe.<\/p>\n<div id=\"attachment_28119\" style=\"width: 225px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sigmund-Freud.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28119\" class=\"wp-image-28119 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sigmund-Freud.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sigmund-Freud.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sigmund-Freud-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><p id=\"caption-attachment-28119\" class=\"wp-caption-text\">Sigmund Freud<\/p><\/div>\n<p style=\"text-align: justify;\">In effetti, la cultura del piagnisteo sta facendo emergere una forma nuova di potere irresistibile, un potere totale che annulla ogni dibattito in quanto predica dal pulpito una verit\u00e0 dichiarata inappellabile. \u00c8 un potere tanto devastante che persino i veri potenti ne adottano il linguaggio per legittimarsi, un sintomo ulteriore di un cinismo formidabile che- dice il filosofo tedesco Peter Sloterdijk, non si esercita contro, ma dall\u2019interno del potere.<\/p>\n<p style=\"text-align: justify;\">Quando Sigmund Freud parlava di psicologia delle masse, affermava che l\u2019attrazione verso i leader carismatici derivava dal fascino del potere come potenza; oggi capita esattamente il contrario: si celebra l\u2019impotenza. Non avr\u00e0 il comando chi avr\u00e0 realizzato azioni encomiabili, ma chi avr\u00e0 sofferto, o fatto credere di aver patito gravi ingiustizie.<\/p>\n<p style=\"text-align: justify;\">Azzardiamo un\u2019ipotesi: viviamo tempi controrivoluzionari, nel senso che l\u2019idea di rivoluzione \u00e8 stata sempre associata a valori come l\u2019attivismo, la potenza, la responsabilit\u00e0. Al contrario, la post modernit\u00e0, interminabile tempo supplementare manierista, innalza (dis)valori opposti: un\u2019identit\u00e0 spuria, ancorata alla sofferenza \u2013 propria o ancestrale \u2013 passivit\u00e0 e impotenza, assenza di responsabilit\u00e0, vittimismo.<\/p>\n<div id=\"attachment_32387\" style=\"width: 259px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Immanuel-Kant.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32387\" class=\"wp-image-32387 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Immanuel-Kant.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a><p id=\"caption-attachment-32387\" class=\"wp-caption-text\">Immanuel Kant<\/p><\/div>\n<p style=\"text-align: justify;\">Se la modernit\u00e0, per Immanuel Kant, fu la scommessa dell\u2019umanit\u00e0 per abbandonare l\u2019infanzia, la post modernit\u00e0 sembra un tempo in cui si torna a supplicare tutela e in cui si vuole incatenare l\u2019umanit\u00e0 nel carcere di un\u2019identit\u00e0 cristallizzata dalla condizione di vittime o di carnefici, come se il destino fosse fissato per sempre. Il contrario della pretesa progressista.<\/p>\n<p style=\"text-align: justify;\">Una singolare eterogenesi dei fini: dalla liberazione proclamata, dal soggettivismo assoluto a un nuovo comunitarismo invalicabile delle vittime, degli umiliati e degli offesi. Il clima \u00e8 velenoso, da fine impero; <em>che fare<\/em> \u00e8 sostituito da <em>chi sono<\/em> in un mondo diviso programmaticamente tra innocenti e colpevoli <em>ab initio<\/em>, in cui la verit\u00e0 riguarda solo chi riesce a convincere di aver subito un\u2019ingiustizia o di esserne il legittimo erede.<\/p>\n<p style=\"text-align: justify;\">Il cambiamento culturale si percepisce e ha ormai diretta incidenza nelle architetture istituzionali e nelle politiche pubbliche, tra azioni \u201caffermative\u201d, quote e discriminazioni \u201cpositive\u201d a vantaggio delle ex vittime, condizioni assai comode in un\u2019epoca sospesa tra due estremi: lo scetticismo generalizzato unito all\u2019acritico desiderio di credenza, delega, affidamento nichilistico a chi impone che cosa si deve fare, pensare, essere.<\/p>\n<p style=\"text-align: justify;\">Tempi di conflitto, l\u2019era paradossale in cui il trionfo dell\u2019ideologia vittimista \u00e8 una buona notizia per pochi, non per le vere vittime.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricognizioni 22 Luglio 2020 di Roberto Pecchioli \u201cLa vittima \u00e8 l\u2019eroe del nostro tempo. Essere vittime d\u00e0 prestigio, impone ascolto, promette e promuove riconoscimento, attiva un potente generatore di identit\u00e0, diritto, autostima. Immunizza da ogni critica, garantisce innocenza al di l\u00e0 di ogni ragionevole dubbio. Come potrebbe la vittima essere colpevole, e anzi responsabile di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":47969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[558],"class_list":["post-47965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-sguardo-sul-nostro-tempo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-29T22:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La vittima, l\u2019eroe del nostro tempo\",\"datePublished\":\"2020-07-29T22:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/\"},\"wordCount\":2247,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vittimismo.png\",\"keywords\":[\"sguardo sul nostro tempo\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/\",\"name\":\"La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vittimismo.png\",\"datePublished\":\"2020-07-29T22:00:41+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vittimismo.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vittimismo.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-vittima-leroe-del-nostro-tempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vittima, l\u2019eroe del nostro tempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/","og_locale":"it_IT","og_type":"article","og_title":"La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-07-29T22:00:41+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La vittima, l\u2019eroe del nostro tempo","datePublished":"2020-07-29T22:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/"},"wordCount":2247,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png","keywords":["sguardo sul nostro tempo"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/","name":"La vittima, l\u2019eroe del nostro tempo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png","datePublished":"2020-07-29T22:00:41+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/vittimismo.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-vittima-leroe-del-nostro-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La vittima, l\u2019eroe del nostro tempo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=47965"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47965\/revisions"}],"predecessor-version":[{"id":47970,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47965\/revisions\/47970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/47969"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=47965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=47965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=47965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}