{"id":47590,"date":"2020-06-18T00:00:34","date_gmt":"2020-06-17T22:00:34","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=47590"},"modified":"2020-06-15T20:00:09","modified_gmt":"2020-06-15T18:00:09","slug":"la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/","title":{"rendered":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_vandalismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47573 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_vandalismo.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>L\u2019Occidentale <\/strong>15 Giugno 2020<\/p>\n<p style=\"text-align: center;\">di <strong>Eugenio Capozzi<\/strong><\/p>\n<p style=\"text-align: justify;\">Chi si sorprende ancora per il fatto che le proteste sedicenti \u201cantirazziste\u201d americane ed europee si siano tradotte in abbattimenti delle statue, in oltraggi ai monumenti, in censura alle opere d\u2019arte \u2013 e insomma nel dichiarato intento di riscrivere la storia \u201cepurandola\u201d di qualsiasi parte oggi giudicata \u201crazzista\u201d da una minoranza autonominatasi portatrice dei valori di progresso e civilt\u00e0 \u2013 non ha evidentemente ancora compreso la natura dell\u2019ideologia di cui quell&#8217;\u201dantirazzismo\u201d \u00e8 portatore.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">I rivoltosi che nella loro furia iconoclasta travolgono simboli, personaggi illustri, opere del passato non sono preda di un impeto di furore alimentato da autentiche ingiustizie sociali, ma al contrario mettono coerentemente in pratica un sistema di pensiero che da decenni ha egemonizzato la cultura politica delle sinistre occidentali, e che con la lotta alle diseguaglianze sociali, attuali o passate, non ha nulla a che spartire.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47576 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-300x169.png 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-768x432.png 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra-1024x576.png 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_razzismo_sinistra.png 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Quel sistema di pensiero \u00e8 il progressismo \u201cdiversitario\u201d, tradotto nell\u2019insieme di precetti, censure, delegittimazioni noto come \u201cpoliticamente corretto\u201d. \u00c8 l\u2019ideologia delle \u00e9lites borghesi \u201cimmateriali\u201d, \u201cliquide\u201d, sganciate dalle dinamiche otto-novecentesche di produzione e lavoro, e legate invece all\u2019economia digitalizzata, alle tecno-burocrazie, al sistema mediatico globalizzato.<\/p>\n<p style=\"text-align: justify;\">\u00c9lites \u201cpost-sessantottine\u201d che rifiutano l\u2019idea stessa di essere gli eredi di una lunga storia, quella della civilt\u00e0 occidentale. Se ne ritengono indipendenti, scisse, come se la societ\u00e0 in cui vivono fosse immersa in una sorta di indefinito presente \u201cfluido\u201d, aperto su un futuro di infinite potenziali gratificazioni per i desideri soggettivi, liberati dal peso dei condizionamenti di un qualsiasi passato.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 quelle \u00e9lites sono tanto strettamente eredi della storia occidentale da riassumere in s\u00e9, in una forma estenuante ed esasperata, tutte le pretese di eliminare il male dal mondo manifestate dalle ideologie sorte in Europa tra Otto e Novecento.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_manifestazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47575 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Usa_manifestazione-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>In particolare, il progressismo da loro abbracciato si fonda sull\u2019idea che per raggiungere il paradiso in Terra sia necessario estirpare la tendenza al dominio e alla discriminazione del \u201cdiverso\u201d stratificata per secoli (se non per millenni) nella mentalit\u00e0 dell\u2019Occidente, per approdare ad una cultura \u201cinclusiva\u201d, cio\u00e8 priva di principi fissi, aperta a qualunque suggestione, integralmente relativistica.<\/p>\n<p style=\"text-align: justify;\">La visione del mondo da esse propugnata si traduce, dunque, in una forma rudimentale di illuminismo fondata su una contrapposizione radicale tra oscurantismo (ogni tradizione ereditata, ogni codice morale universalistico) e progresso (l\u2019assoluta \u201cdiversit\u00e0\u201d e fluidit\u00e0 del vitale come unica norma, la distruzione di ogni gerarchia).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Boldrini_parlamento.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47571 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Boldrini_parlamento.jpg\" alt=\"\" width=\"250\" height=\"202\" \/><\/a>In tale luce, la concezione del \u201crazzismo\u201d indicato come nemico assoluto dai rivoltosi ultra-borghesi e dalla propaganda politicalcorrettista si chiarisce nel suo specifico significato, che in realt\u00e0 \u00e8 lontanissimo da quello tradizionalmente consolidato nel linguaggio comune, e riflesso nella cultura politico-giuridica liberaldemocratica.<\/p>\n<p style=\"text-align: justify;\">Per quest\u2019ultima, infatti, il razzismo indica quel complesso di dottrine che tra Otto e Novecento hanno predicato la superiorit\u00e0 fisica o spirituale di una razza, una etnia, una cultura su altre, e dunque hanno giustificato la diseguaglianza civile e politica su quelle basi.<\/p>\n<p style=\"text-align: justify;\">Per la sinistra diversitaria in cui si inseriscono anche i movimenti come Black Lives Matter e Antifa, invece, razzismo \u00e8 qualsiasi fenomeno materiale e culturale che nella storia abbia condotto ad un qualsiasi vantaggio dell\u2019uomo \u201cbianco\u201d occidentale sul resto del mondo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Detenuti_Usa_prigione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47521 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Detenuti_Usa_prigione-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>E&#8217; razzista \u00e8 chiunque non voglia disconoscere interamente quella storia, chiunque la rivendichi, o addirittura chiunque, pur convinto dell\u2019uguaglianza tra tutti gli uomini, di fatto tragga qualche vantaggio dalle posizioni di potere sedimentatesi in quel percorso temporale.<\/p>\n<p style=\"text-align: justify;\">E\u2019 questo il razzismo \u201csistemico\u201d, il \u201cwhite privilege\u201d rispetto al quale i manifestanti mobilitati dopo i fatti di Minneapolis e i loro aedi intellettuali\/mediatici pretendono che venga dato ai \u201cneri\u201d \u2013 intesi in blocco come afroamericani, o addirittura in generale come tutti i \u201cnon bianchi\u201d, non euro-occidentali, del mondo \u2013 un adeguato \u201crisarcimento\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_Usa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47591 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_Usa.jpg\" alt=\"\" width=\"293\" height=\"172\" \/><\/a>Per tale motivo il progressista diversitario deve necessariamente \u201cabbattere le statue\u201d e censurare parole, idee e azioni dei suoi antenati in base alla dottrina che vorrebbe imporre a tutti nel presente, accomunando in pratica sotto l\u2019etichetta di razzista e oppressore ogni protagonista rilevante della storia occidentale.<\/p>\n<p style=\"text-align: justify;\">Secondo la sua manichea contrapposizione tra luce e tenebre, la storia non \u00e8 una dialettica, anche conflittuale, attraverso la quale si edificano gradualmente istituzioni, princ\u00ecpi, modelli, spazi di convivenza pi\u00f9 adeguati ad esprimere il valore assoluto della vita umana, ma al contrario \u00e8 un cumulo di violenze, soprusi, sopraffazioni operate in nome dell\u2019imposizione di \u201cverit\u00e0\u201d in realt\u00e0 funzionali al dominio, e da cancellare con un tratto di penna per tornare ad un\u2019innocenza edenica perduta, ad una libert\u00e0 senza il peso della responsabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/animalismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22668 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/animalismo.jpg\" alt=\"\" width=\"251\" height=\"201\" \/><\/a>Mentre, insomma, la cultura liberaldemocratica occidentale \u00e8 pervenuta alla condanna della schiavit\u00f9, del colonialismo, delle discriminazioni civili fondate su razza ed etnia recuperando e implementando una concezione universalistica dell\u2019uomo derivata direttamente dalla radice ebraico-cristiana dell\u2019Occidente (tutti gli esseri umani sono uguali in quanto fatti ad immagine e somiglianza di Dio), e intendendo i diritti umani in senso individualistico (cio\u00e8 come propri di ogni essere umano in quanto tale, non per la sua appartenenza ad un determinato gruppo), l&#8217;\u201dantirazzismo\u201d ideologico predicato dal progressismo politicamente corretto \u00e8 fondato invece su un \u201cassolutismo relativista\u201d, secondo il quale tutte le storie e le culture sono equivalenti, e l\u2019appartenenza ad un gruppo \u201cdiscriminato\u201d deve assicurare non tanto l\u2019eguaglianza della dignit\u00e0 e dei diritti, quanto un trattamento preferenziale dei \u201cdiversi\u201d, che garantisca loro una qualit\u00e0 della vita, uno \u201cstile di vita\u201d pari ai loro desideri.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_Usa-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47592 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_Usa-1.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>Per gli appartenenti alla civilt\u00e0 occidentale il progresso non pu\u00f2 consistere, secondo questa visione del mondo, che nell&#8217;\u201despiazione\u201d dei propri \u201cpeccati\u201d, nella mortificazione, nel mettere in dubbio tutte le proprie certezze per accogliere la \u201credenzione\u201d portata dall\u2019Altro.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019ideologia politicalcorrettista, dunque, la lotta contro il razzismo come \u201cprivilegio bianco\u201d non pu\u00f2 non essere strettamente legata a quella contro il \u201csessismo\u201d, inteso come privilegio \u201cpatriarcale\u201d, da scalzare in nome di una totale \u201cfluidit\u00e0\u201d di genere. E persino al rifiuto verso ogni idea di una centralit\u00e0 della specie umana rispetto alle altre forme di vita, in nome di una torsione \u201cpanica\u201d e \u201cantispecista\u201d dell\u2019ambientalismo, concepito come difesa dell&#8217;\u201decosistema\u201d al di fuori di qualsiasi scala di valori imperniata sul perseguimento della civilt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/massa_eguaglianza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44765 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/massa_eguaglianza.jpg\" alt=\"\" width=\"261\" height=\"193\" \/><\/a>In tutte le tre principali espressioni del \u201cdiversitarismo\u201d emerge, insomma, lo stesso disprezzo per la storia, per la sua interpretazione razionale, per il valore universale di alcuni traguardi raggiunti dalla civilt\u00e0 occidentale, per la democrazia liberale come patrimonio comune da salvaguardare.<\/p>\n<p style=\"text-align: justify;\">La sua furia distruttiva punta a sostituire all\u2019umanesimo occidentale uno spazio vuoto, un luogo anomico di libert\u00e0 senza scopo, sospeso tra aspirazioni superomistiche e attrazione del nulla. Specchio fedele di una classe dominante senza una morale e senza una fede, che cinicamente si serve dei ceti marginali come strumenti del suo dominio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Occidentale 15 Giugno 2020 di Eugenio Capozzi Chi si sorprende ancora per il fatto che le proteste sedicenti \u201cantirazziste\u201d americane ed europee si siano tradotte in abbattimenti delle statue, in oltraggi ai monumenti, in censura alle opere d\u2019arte \u2013 e insomma nel dichiarato intento di riscrivere la storia \u201cepurandola\u201d di qualsiasi parte oggi giudicata \u201crazzista\u201d &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":47593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[1835,558,1223],"class_list":["post-47590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-politicamente-corretto","tag-sguardo-sul-nostro-tempo-2","tag-sinistra","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-17T22:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto\",\"datePublished\":\"2020-06-17T22:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/\"},\"wordCount\":1111,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/antiraz_sinistra.jpg\",\"keywords\":[\"politicamente corretto\",\"sguardo sul nostro tempo\",\"sinistra\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/\",\"name\":\"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/antiraz_sinistra.jpg\",\"datePublished\":\"2020-06-17T22:00:34+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/antiraz_sinistra.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/antiraz_sinistra.jpg\",\"width\":1400,\"height\":933,\"caption\":\"Foto Roberto Monaldo \\\/ LaPresse 07-06-2020 Roma Cronaca Black Lives Matter - Manifestazione in memoria di George Floyd e contro il razzismo Nella foto Un momento della manifestazione a p.zza del Popolo Photo Roberto Monaldo \\\/ LaPresse 07-06-2020 Rome (Italy) Black Lives Matter - Demonstration in memory of George Floyd and against the racism In the pic A moment of the demonstration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/","og_locale":"it_IT","og_type":"article","og_title":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-06-17T22:00:34+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto","datePublished":"2020-06-17T22:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/"},"wordCount":1111,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg","keywords":["politicamente corretto","sguardo sul nostro tempo","sinistra"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/","name":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg","datePublished":"2020-06-17T22:00:34+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/antiraz_sinistra.jpg","width":1400,"height":933,"caption":"Foto Roberto Monaldo \/ LaPresse 07-06-2020 Roma Cronaca Black Lives Matter - Manifestazione in memoria di George Floyd e contro il razzismo Nella foto Un momento della manifestazione a p.zza del Popolo Photo Roberto Monaldo \/ LaPresse 07-06-2020 Rome (Italy) Black Lives Matter - Demonstration in memory of George Floyd and against the racism In the pic A moment of the demonstration"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-condanna-moralistica-della-storia-occidentale-e-il-cardine-del-politicamente-corretto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La condanna moralistica della storia occidentale \u00e8 il cardine del politicamente corretto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=47590"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47590\/revisions"}],"predecessor-version":[{"id":47594,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47590\/revisions\/47594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/47593"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=47590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=47590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=47590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}