{"id":47467,"date":"2020-06-11T00:00:49","date_gmt":"2020-06-10T22:00:49","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=47467"},"modified":"2020-06-07T14:50:17","modified_gmt":"2020-06-07T12:50:17","slug":"cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/","title":{"rendered":"Cambia sesso a 13 anni e la madre ne fa un&#8217;icona Lgbt"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Lgbt_trans_gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47468 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Lgbt_trans_gender.jpg\" alt=\"\" width=\"284\" height=\"177\"><\/a>La Verit\u00e0<\/strong> 21 maggio 2020<\/p>\n<p style=\"text-align: justify;\"><em>Nata Marco, ora assume farmaci per bloccare <\/em><em>la <\/em><em>pubert\u00e0 e si racconta in un libro. Sollevando pi\u00f9 di una perplessit\u00e0<\/em><\/p>\n<p style=\"text-align: center;\">di<strong> Francesco Borgonovo<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00abIo sono Greta e ho tredici anni, anzi ne ho molti meno perch\u00e9 fino all&#8217;anno scorso ero Marco\u00bb. Greta, di Ravenna, \u00e8 nata Marco, \u00e8 minorenne e ha iniziato il percorso per cambiare sesso. Che non abbia paura di farlo sapere al mondo \u00e8 poco ma sicuro.<\/p>\n<p style=\"text-align: justify;\">\u00c8 poco pi\u00f9 di una bambina, ma negli ultimi tempi ha partecipato a vari programmi tv, ha rilasciato interviste, assieme ad altri ragazzi transgender \u00e8 stata protagonista di un lungo servizio su <em>Vanity Fair. <\/em>I suoi genitori hanno fatto di tutto perch\u00e9 Greta diventasse un simbolo, una sorta di portavoce dei minorenni intenzionati a cambiare sesso.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Gay_Lgbt-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37671 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Gay_Lgbt-1.jpg\" alt=\"\" width=\"267\" height=\"189\"><\/a>Cinzia Messina<strong>, <\/strong>la madre, fa parte dell&#8217;Agedp (Associazione genitori, amici, parenti di persone Lgbt+) e gestisce la pagina Facebook \u00ablosonogretais\u00bb, i cui contenuti riflettono perfettamente il pensiero delle associazioni arcobaleno. Qualche mese fa i \u00abgenitori di Greta\u00bb (cos\u00ec si sono firmati) hanno persino lanciato una petizione online per chiedere una nuova legge sulle persone transgender, che prevedesse anche \u00abnelle scuole di ogni ordine e grado percorsi di formazione di contrasto al bullismo omo-trans-fobico obbligatori per la comunit\u00e0 educante\u00bb. Insomma, la signora Messina\u00e8 un&#8217;attivista.<\/p>\n<p style=\"text-align: justify;\">E ha trovato il tempo di dare alle stampe un libro, appena uscito, intitolato Io sono <em>io <\/em>(II Ponte Vecchio editrice), che viene presentato come un racconto d&#8217;avventura: \u00abL&#8217;eroina si chiama Greta ed \u00e8 una giovanissima ragazza transgender la cui storia \u00e8 raccontata da Cinzia, sua madre, in minute ricostruzioni di giorni e sentimenti, emozioni e progetti\u00bb. In effetti, il volume racconta la storia di Marco diventato Greta e contiene anche una robusta testimonianza autobiografica firmata dalla giovanissima trans.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/05\/ideologia_lgbt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25464 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/05\/ideologia_lgbt.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>Anche se, ovviamente, a prendersi la scena \u00e8 quasi sempre la madre. Il rischio, infatti, \u00e8 che le intemerate politiche sovrastino il racconto in prima persona della tredicenne che invece merita di essere letto con attenzione, perch\u00e9 fornisce informazioni importanti su un fenomeno che comincia a diventare piuttosto rilevante.Il racconto di Greta contiene passaggi che colpiscono allo stomaco.<\/p>\n<p style=\"text-align: justify;\">Ad esempio quando illustra il suo rapporto con gli organi genitali maschili. \u00abPensavo che tutti fossero cattivi con me, soprattutto la mamma che mi comprava vestiti da maschio\u00bb, scrive. \u00abLa mia nonna, che amo molto e che ora con tanto amore mi chiama Greta (sbagliando nove volte su dieci!!), mi diceva: &#8220;Se sei femmina, fammi vedere la passerotta!&#8221;. Io non capivo, ma aveva ragione. Io per\u00f2 non potevo farle vedere ci\u00f2 che non avevo ed era terribile, perch\u00e9 dentro mi sentivo femmina &#8230; a dire il vero, non sapevo nemmeno cosa fosse la passerotta!! Cominciai cos\u00ec a odiare la mia codina: avevo capito che non andava bene per me\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/04\/trans.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23178 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/04\/trans.jpg\" alt=\"\" width=\"280\" height=\"180\"><\/a>La sofferenza che trasuda da questi passaggi non pu\u00f2 passare inosservata. Greta dice tanto di s\u00e9, del rapporto con il fratello gemello, del legame con i genitori. \u00abAvevo solo tre anni quando si sono separati per cui non ho ricordi di loro due assieme. In effetti, ogni volta che guardo i video in cui erano ancora sposati, mi chiedo perch\u00e9 si siano lasciati &#8230; in fondo li vedevo bene! Loro dicono che si sono lasciati perch\u00e9 litigavano sempre &#8230; Allora mi chiedo perch\u00e9 mai si siano messi assieme!\u00bb scrive.<\/p>\n<p style=\"text-align: justify;\">\u00abLa mia mamma Cinzia mi fa sempre notare ogni imperfezione e mi dice: &#8220;Greta, hai i punti neri, ti \u00e8 colato il trucco, hai i capelli sporchi e gli occhiali appannati!&#8221;. Il mio babbo Luigi invece mi dice: &#8220;Greta, sei bellissima. Ora che ti vedo come una ragazza devo ammettere che sei proprio molto bella!&#8221;\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43212 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/gender.jpg\" alt=\"\" width=\"276\" height=\"183\"><\/a>A quanto sembra, la famiglia ha supportato la transizione di Greta. \u00abA casa del suo pap\u00e0 teneva addirittura abiti femminili bellissimi, da principessa delle favole. Quella casa era diventata il suo rifugio\u00bb, spiega la madre. \u00abCi aveva portato anche un paio di scarpe col tacco e qualche trucco che gli avevo regalato io, bench\u00e9 con me, forse leggendo nei miei occhi un senso quasi di disagio, faticasse a esprimersi liberamente.<\/p>\n<p style=\"text-align: justify;\">Ogni volta che lo andavo a prendere dal babbo e lo trovavo vestito e truccato, mi saliva dentro un&#8217;angoscia che sono sicura intuisse, visto che il sorriso gli moriva sulle labbra. La neuropsichiatra ci aveva consigliato di assecondare le sue tendenze almeno all&#8217;interno delle pareti domestiche ma, oltre all&#8217;ansia e alla tristezza, io provavo un profondo senso di colpa per averlo partorito con un corpo biologicamente diverso rispetto a come si sentiva\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/01\/gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35453 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/01\/gender.jpg\" alt=\"\" width=\"251\" height=\"201\"><\/a>\u00c8 in seconda media che Greta decide di mostrarsi al mondo come transgender: \u00abNon potevo ancora immaginare che quel pugno di sillabe nascondesse un vissuto sofferto e un sentire profondo, come non ero a conoscenza del fatto che queste percezioni di genere potessero esistere gi\u00e0 nell&#8217;infanzia e non solo in et\u00e0 adulta. Quanta ignoranza&#8230;\u00bb, commenta la madre.<\/p>\n<p style=\"text-align: justify;\">Il risultato \u00e8 che, ora, la trans tredicenne assume farmaci per fermare la pubert\u00e0: \u00abFinalmente ho cominciato i bloccanti e ora sono pi\u00f9 serena per il fatto che la mia voce non cambier\u00e0 e che non mi svilupper\u00f2 nella direzione maschile\u00bb, dice.Da fuori, giudicare \u00e8 fin troppo facile e per questo, forse, anche ingiusto. Alcune affermazioni della madre di Greta sull&#8217;identit\u00e0 sessuale lasciano molto perplessi. Cos\u00ec come l&#8217;approccio affermativo (cio\u00e8 confermativo dell&#8217;identit\u00e0 femminile) adottato nei confronti di un minorenne a cui, a un certo punto, viene anche diagnosticato un \u00abritardo emotivo\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/05\/gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27302 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/05\/gender.jpg\" alt=\"\" width=\"241\" height=\"209\"><\/a>Soprattutto, suscita qualche dubbio l&#8217;attivismo politico e \u00abper i diritti\u00bb dei genitori di Greta che, in fin dei conti, ha appena 13 anni. Nel testo autobiografico si esprime come una bambina, ma sembra che venga trattata gi\u00e0 come una donna: trucco, scarpe col tacco.<\/p>\n<p style=\"text-align: justify;\">Viene da pensare che, su argomenti delicati come questo, sia necessario sgombrare il campo dall&#8217;ideologia e concentrarsi sulla singola persona. Ma \u00e8 diventato impossibile farlo. Una vicenda privata -come testimoniano il libro di Greta e tutte le attivit\u00e0 connesse- diventa immediatamente politica.<\/p>\n<p style=\"text-align: justify;\">E se dovesse mai passare la legge bavaglio contro l&#8217;omotransfobia di cui a luglio ricomincer\u00e0 a discutere il Parlamento, ogni approccio critico verr\u00e0 di fatto bandito. Chi osasse avanzare dubbi sarebbe immediatamente identificato come \u00abodiatore\u00bb dei trans. Diventerebbe impossibile porsi una domanda fondamentale: davvero un bambino di 11 o 13 anni \u00e8 in grado di fare una scelta che determiner\u00e0 la sua intera esistenza?<\/p>\n<p style=\"text-align: justify;\">Una cosa \u00e8 certa: una volta iniziata la terapia farmacologica, non si torna indietro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Verit\u00e0 21 maggio 2020 Nata Marco, ora assume farmaci per bloccare la pubert\u00e0 e si racconta in un libro. Sollevando pi\u00f9 di una perplessit\u00e0 di Francesco Borgonovo<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":47479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[437,2499,323],"class_list":["post-47467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-ideologia-del-gender-2","tag-lgbt","tag-transessualita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambia sesso a 13 anni e la madre ne fa un&#039;icona Lgbt - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambia sesso a 13 anni e la madre ne fa un&#039;icona Lgbt - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T22:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Cambia sesso a 13 anni e la madre ne fa un&#8217;icona Lgbt\",\"datePublished\":\"2020-06-10T22:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/\"},\"wordCount\":1063,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trans_gender_lgbt.jpg\",\"keywords\":[\"ideologia del gender\",\"Lgbt\",\"transessualit\u00e0\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/\",\"name\":\"Cambia sesso a 13 anni e la madre ne fa un'icona Lgbt - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trans_gender_lgbt.jpg\",\"datePublished\":\"2020-06-10T22:00:49+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trans_gender_lgbt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trans_gender_lgbt.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambia sesso a 13 anni e la madre ne fa un&#8217;icona Lgbt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambia sesso a 13 anni e la madre ne fa un'icona Lgbt - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/","og_locale":"it_IT","og_type":"article","og_title":"Cambia sesso a 13 anni e la madre ne fa un'icona Lgbt - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-06-10T22:00:49+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Cambia sesso a 13 anni e la madre ne fa un&#8217;icona Lgbt","datePublished":"2020-06-10T22:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/"},"wordCount":1063,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg","keywords":["ideologia del gender","Lgbt","transessualit\u00e0"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/","name":"Cambia sesso a 13 anni e la madre ne fa un'icona Lgbt - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg","datePublished":"2020-06-10T22:00:49+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/trans_gender_lgbt.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cambia-sesso-a-13-anni-e-la-madre-ne-fa-unicona-lgbt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Cambia sesso a 13 anni e la madre ne fa un&#8217;icona Lgbt"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=47467"}],"version-history":[{"count":7,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47467\/revisions"}],"predecessor-version":[{"id":47480,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47467\/revisions\/47480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/47479"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=47467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=47467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=47467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}