{"id":4743,"date":"2011-10-20T00:00:00","date_gmt":"2011-10-19T22:00:00","guid":{"rendered":""},"modified":"2015-11-27T12:57:39","modified_gmt":"2015-11-27T11:57:39","slug":"hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/","title":{"rendered":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28247\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg\" alt=\"hezbollah\" width=\"250\" height=\"150\" \/><\/a>Tempi <\/strong>15 ottobre 2011<\/div>\n<p style=\"text-align: justify;\"><em>\u00abHezbollah ha difeso il Libano da Israele ma non per questo pu\u00f2 usare le armi in politica e pretendere di rappresentare la comunit\u00e0 sciita. I partiti muoiono, la comunit\u00e0 resta\u00bb. A parlare a Tempi.it \u00e8 Ibrahim M.M. Shamseddine, libanese figlio dell\u2019imam Shamseddine, il secondo presidente del Consiglio supremo islamico sciita. Parla della situazione del Libano e dei cristiani: \u00abI cristiani libanesi non sono intrusi. I musulmani non solo li vogliono, ne hanno bisogno\u00bb<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Leone Grotti<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">\u00ab<strong>Hezbollah<\/strong> \u00e8 un partito sciita ed \u00e8 il pi\u00f9 forte in Libano ma non rappresenta la comunit\u00e0 sciita e non potr\u00e0 mai pretendere di farlo. Anche se hanno difeso il <strong>Libano<\/strong> da <strong>Israele<\/strong>, non hanno nessun diritto di usare armi in politica. E\u2019 come se il presidente di Bankitalia, potentissimo, tornasse a casa sua e pretendesse di comportarsi anche con la moglie e i figli allo stesso modo in cui si comporta in banca.<\/div>\n<p style=\"text-align: justify;\">I partiti nascono, crescono e muoiono: la comunit\u00e0 invece resta\u00bb.<strong>Ibrahim M.M. Shamseddine <\/strong>\u00e8 libanese, musulmano e sciita e ci tiene molto che l\u2019ordine dei tre elementi che costituiscono la sua identit\u00e0 non vengano invertite. \u00c8 figlio dell\u2019imam Mohamed Mahdi Shamseddine, il secondo presidente del Consiglio supremo islamico sciita. Nato in Iraq, la sua famiglia \u00e8 stata esiliata da Saddam Hussein, emigrando in Libano.<\/p>\n<p style=\"text-align: justify;\">Il 13 aprile 1975, data d\u2019inizio della guerra civile libanese, Ibrahim Shamseddine \u00e8 a Beirut, ha 14 anni, lo stanno operando di appendicite e \u00abho sentito gli spari sotto il palazzo dove mi trovavo\u00bb. Il 13 ottobre 1990, quando \u00e8 finita la guerra civile, \u00e8 sempre a Beirut.\u00abHo 52 anni oggi, sono cresciuto con la guerra civile e sono stato testimone di tutte le guerre libanesi\u00bb racconta a <strong><em>Tempi.it<\/em><\/strong> in occasione della sua visita all&#8217;Italia per presentare &#8220;Il rischio educativo&#8221; di don Luigi Giussani, invitato dal <strong>Centro culturale di Milano<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00abEro l\u00ec durante l\u2019invasione di Israele e sono l\u00ec ora. Ho perso molti amici. Non mi sono mai sentito minacciato da un cristiano in tutta la mia vita, anche durante la guerra, lo stesso non posso dire dei <strong>musulmani<\/strong>\u00bb. Difensore della convivenza pacifica, \u00abessenziale per il Libano\u00bb, tra musulmani e <strong>cristiani<\/strong>, il fondatore dell\u2019Imam Shamseddine Foundation for Dialogue di Beirut e presidente dell&#8217;Associazione per la carit\u00e0 e la cultura analizza i problemi del suo paese e indica come pu\u00f2 uscirne.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 sostiene che Hezbollah non rappresenta gli sciiti?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abIntanto facciamo chiarezza sui termini: gli sciiti in generale non esistono, ci sono i libanesi musulmani sciiti. Questa \u00e8 la gerarchia che definisce la loro identit\u00e0. L\u2019appartenenza nazionale viene prima, perch\u00e9 non esiste un movimento sciita internazionale a cui i libanesi sciiti sarebbero connessi. Come voi siete italiani, noi siamo libanesi. Poi siamo musulmani e infine sciiti\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Il vostro partito politico \u00e8 Hezbollah, per\u00f2. Giusto?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abOgni comunit\u00e0 in Libano ha un partito politico e quasi tutti dettati da una appartenenza confessionale, legati a una comunit\u00e0 specifica. Questo non significa che un partito politico sia l\u2019unica manifestazione della comunit\u00e0. Un partito interno alla comunit\u00e0 non potr\u00e0 mai pretendere di rappresentare tutta la comunit\u00e0. Hezbollah \u00e8 il partito pi\u00f9 forte, ha moltissimi seguaci, ma non \u00e8 \u201cil\u201d partito sciita, bens\u00ec \u201cun\u201d partito sciita. Non ha mai rappresentato e non avverr\u00e0 mai che rappresenti tutta la comunit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Per\u00f2 Hezbollah pretende di rappresentare la comunit\u00e0 sciita.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abLo so, nessuno l\u2019ha mai fatto prima di loro. Mio padre \u00e8 stato il secondo presidente del Consiglio supremo islamico sciita: neanche lui pretendeva che il Consiglio rappresentasse l&#8217;intera comunit\u00e0. Per quanto Hezbollah sia forte, non pu\u00f2 identificarsi perch\u00e9 i partiti nascono, crescono e muoiono: la comunit\u00e0 resta. Il testamento che ha lasciato mio padre dice che il Libano non \u00e8 un paese di transizione da trasformare, non c\u2019\u00e8 nessun altro potere che i libanesi sciiti cercano di raggiungere se non la costruzione, insieme ai cristiani, del nostro Stato\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Dove sbaglia Hezbollah?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abIo non li considerer\u00f2 mai nemici, perch\u00e9 hanno difeso il Libano dall&#8217;invasione di Israele. Per\u00f2 resistere a Israele non ti d\u00e0 nessun diritto a usare le armi in politica: le armi non devono essere usate per raggiungere risultati politici. \u00c8 come se il capo di Bankitalia, che ha un grande potere e nel suo lavoro \u00e8 un\u2019autorit\u00e0, andasse a casa e pretendesse di comportarsi anche con la moglie e i figli allo stesso modo. Invece no, finito il lavoro torna un cittadino come gli altri, deve fermarsi al rosso dei semafori. Questo vale anche per Hezbollah, aver difeso il paese non d\u00e0 il diritto di avere diritti speciali o privilegi. E poi, come detto, sbagliano nel dare l\u2019impressione di agire in rappresentanza di tutta la comunit\u00e0 sciita, che \u00e8 falso. La comunit\u00e0 rester\u00e0 in Libano anche dopo la fine di Hezbollah, non sono pochi quelli che non condividono le loro idee e bisogna trovare il modo giusto di manifestare il dissenso rispetto alla politica\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Cristiani e musulmani sono ancora coessenziali alla costruzione del paese?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abIo sono un musulmano osservante, non culturale, porto la barba per questo e non perch\u00e9 cos\u00ec sono bello. Credo che i cristiani in Libano siano molto importanti, esattamente come i musulmani e prima di tutto per i musulmani. Al di l\u00e0 della religione, \u00e8 fondamentale per il Libano la presenza cristiana: siamo veri partner nella costruzione del Libano, vinciamo perdiamo e agonizziamo insieme. Il Libano \u00e8 una vita unica con delle diversit\u00e0 culturali\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>I cristiani per\u00f2 sono in minoranza.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abNo. Io non accetto, rifiuto e nego che siano una minoranza. Ci sono due grandi maggioranze in Libano: la prima \u00e8 quella musulmana, a cui gli sciiti appartengono, la seconda \u00e8 quella araba, a cui appartengono i cristiani. Bisoga partire da qui quando si valutano tutti i problemi in Libano. I cristiani non devono pensarsi una minoranza o tutti prima o poi cominceranno a guardarli cos\u00ec. Ma non lo sono mai stati. Mio padre diceva: \u201cIl Libano non esiste senza i suoi musulmani e non esiste senza i suoi cristiani\u201d.<\/p>\n<p style=\"text-align: justify;\">E anche se i musulmani sono ora numericamente in maggioranza, questo non conta. Si capisce con un esempio: l\u2019acqua \u00e8 la fonte della vita e la sua formula chimica \u00e8 l\u2019H2O. L\u2019idrogeno sono i musulmani e hanno due molecole ma senza la singola molecola dell\u2019ossigeno, i cristiani, l\u2019acqua non ci sarebbe. \u00c8 vero, i musulmani sono di pi\u00f9 ma senza i cristiani il Libano non esisterebbe. I cristiani libanesi fanno parte della societ\u00e0 araba, non sono intrusi, non sono stranieri. Il bello del Libano \u00e8 la variet\u00e0 delle sue comunit\u00e0 che vivono insieme e possono farlo. Il Libano ha bisogno della sua diversit\u00e0 anche da un punto di vista pragmatico. I musulmani non solo vogliono i cristiani, ne hanno bisogno\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Oggi, per\u00f2, tutto questo in Libano non si vede.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abE\u2019 vero, giusto, ne sono consapevole. Il punto per\u00f2 \u00e8 individuare la causa, che non \u00e8 religiosa ma politica. A combattere tra loro ora non sono le comunit\u00e0 ma i partiti politici dentro le comunit\u00e0. Ma il Libano non \u00e8 formato dai partiti. \u00c8 fatto da sciiti, ortodossi, maroniti, sunniti: non dai partiti politici, come Hezboallah o il Future party. Bisogna cambiare la legge elettorale, che premia i signori della guerra. Noi vogliamo un sistema proporzionale ma loro no, perch\u00e9 sanno che cos\u00ec perderanno potere, ne avranno meno di prima. Con un nuovo sistema elettorale e un nuovo sistema giudiziario le cose sarebbero di gran lunga migliori e si vedrebbe un Libano completamente diverso, quello vero\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Qual \u00e8 la via da seguire perch\u00e9 il Libano cambi?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abSinceramente non ho una risposta precisa: bisogna cambiare il sistema politico ma bisogna passare attraverso la democrazia. Il dilemma e il paradosso \u00e8 che il parlamento libanese dovrebbe cambiare il sistema elettorale per danneggiarsi, di questo si parla sempre in Libano da cinque anni. Per\u00f2, non c\u2019\u00e8 altro modo. L\u2019alternativa \u00e8 la violenza ma usare la violenza per cambiare il regime politico porter\u00e0 a un\u2019altra guerra. Noi dobbiamo fare pressione, bisogna avviare una discussione seria. La gente \u00e8 sempre pi\u00f9 consapevole del problema e fa sempre pi\u00f9 pressione. Io spero che vinceremo. La proposta per una nuova legge elettorale fatta da poco dal ministro degli Interni, che ha chiesto che venga introdotto il proporzionale, \u00e8 un fatto positivo\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Cosa pensa della cosiddetta primavera araba?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abIl mondo arabo si sta ribellando, vuole la libert\u00e0, \u00e8 stanco di bugie e menzogne. Vogliono vivere ed essere protagonisti, non comparse, vogliono camminare lungo le vie maestre, non nelle traverse. So che voi siete preoccupati per l\u2019islam, ma i musulmani non saranno mai una minaccia per i cristiani. Se in Iraq i cristiani sono assaliti \u00e8 perch\u00e9 manca lo Stato e tutti ne soffrono, non c\u2019\u00e8 pi\u00f9 il governo della legge. In Egitto quello che \u00e8 successo \u00e8 grave, non lo capisco bene.<\/p>\n<p style=\"text-align: justify;\">Il governatore di Assuan ha dato il pretesto di bruciare una chiesa perch\u00e9 mancava un permesso: ma che razza di storia \u00e8 questa? Il governo ha commesso una serie di errori. I responsabili per l&#8217;uccisione dei copti devono essere puniti. C&#8217;\u00e8 qualcosa che non va nel governo, non \u00e8 ancora stabile, non ha fatto tutto quello che doveva per proteggere i cristiani. C&#8217;\u00e8 qualcosa che non sta funzionando in Egitto ma i musulmani non sono e non saranno mai una minaccia per i cristiani\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi 15 ottobre 2011 \u00abHezbollah ha difeso il Libano da Israele ma non per questo pu\u00f2 usare le armi in politica e pretendere di rappresentare la comunit\u00e0 sciita. I partiti muoiono, la comunit\u00e0 resta\u00bb. A parlare a Tempi.it \u00e8 Ibrahim M.M. Shamseddine, libanese figlio dell\u2019imam Shamseddine, il secondo presidente del Consiglio supremo islamico sciita. Parla &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28247,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,108],"tags":[1328,373],"class_list":["post-4743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-paesi-e-continenti","tag-hezbollah","tag-libano","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-19T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-27T11:57:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno\",\"datePublished\":\"2011-10-19T22:00:00+00:00\",\"dateModified\":\"2015-11-27T11:57:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/\"},\"wordCount\":1522,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/hezbollah.jpg\",\"keywords\":[\"Hezbollah\",\"Libano\"],\"articleSection\":[\"Islam\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/\",\"name\":\"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/hezbollah.jpg\",\"datePublished\":\"2011-10-19T22:00:00+00:00\",\"dateModified\":\"2015-11-27T11:57:39+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/hezbollah.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/hezbollah.jpg\",\"width\":290,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/","og_locale":"it_IT","og_type":"article","og_title":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-10-19T22:00:00+00:00","article_modified_time":"2015-11-27T11:57:39+00:00","og_image":[{"width":290,"height":174,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno","datePublished":"2011-10-19T22:00:00+00:00","dateModified":"2015-11-27T11:57:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/"},"wordCount":1522,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg","keywords":["Hezbollah","Libano"],"articleSection":["Islam","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/","name":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg","datePublished":"2011-10-19T22:00:00+00:00","dateModified":"2015-11-27T11:57:39+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/10\/hezbollah.jpg","width":290,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/hezbollah-non-rappresenter-mai-i-libanesi-sciiti-abbiamo-bisogno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"&laquo;Hezbollah non rappresenter&agrave; mai i libanesi sciiti. Abbiamo bisogno"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4743"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4743\/revisions"}],"predecessor-version":[{"id":28248,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4743\/revisions\/28248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28247"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}