{"id":47200,"date":"2020-05-14T00:00:05","date_gmt":"2020-05-13T22:00:05","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=47200"},"modified":"2020-05-09T17:42:52","modified_gmt":"2020-05-09T15:42:52","slug":"la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/","title":{"rendered":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47201 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\"><\/a>da: <strong>La verit\u00e0 <\/strong>27 aprile 2020 <strong>&nbsp;<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Sono i queer, la Q della sigla LGBTQ*. Dicono di non essere n\u00e9 uomini n\u00e9 donne ma pretendono la nostra approvazione. Se li assecondassimo, come vuole la legge sulla omotransfobia, li chiuderemmo nella gabbia desolata del loro \u2018non amore\u2019.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Silvana De Mari<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Queer <\/em>vuol dire \u201cstrano\u201d. Una definizione negativa che ha bisogno di una normalit\u00e0 cui sottrarsi. Ma spesso questa cultura riflette un\u2019assenza di identit\u00e0 che si rifugia nella bizzarria. II vocabolo <em>queer<\/em> rientra nella terminologia <em>Lgbt<\/em>, a cui, se si aggiunge una <em>Q<\/em>, diventa <em>Lgbtq<\/em>.<\/p>\n<p style=\"text-align: justify;\">Anzi, visto che qualcuno potrebbe sentirsi escluso, non sia mai, si aggiunge anche un segno \u00ab<em>*<\/em>\u00bb e diventa <em>Lgbtq*<\/em>. Per spiegare cosa vuoi dire <em>queer, la <\/em>cosa migliore \u00e8 ricorrere alle definizioni che ne danno le stesse persone che vi si identificano, ovvero andare a leggere i <em>blog<\/em> e i siti della galassia <em>Lgbtq*<\/em>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Lgbt_queer_gender.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47203 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Lgbt_queer_gender.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Lgbt_queer_gender.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Lgbt_queer_gender-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Fare-copia e incolla \u00e8 onesto e diminuisce il rischio di denunce. Diminuisce il rischio di guai, non lo annulla, perch\u00e9 la legge sull&#8217;omotransfobia colpirebbe anche il copia e incolla con 6 anni di prigione, ma qualcuno qualche rischio deve pur correrlo.<\/p>\n<p style=\"text-align: justify;\">Difficile trovare una definizione di <em>queer<\/em> perch\u00e9 <em>queer<\/em>, per definizione, \u00e8 assenza di definizione. Il <em>queer<\/em> ci dice cosa non \u00e8: non <em>\u00e8 <\/em>uomo, non \u00e8 donna, \u00e8 un \u00abnon\u00bb, senza etichette, senza schemi, senza definizione. In inglese, <em>queer <\/em>vuoi dire \u00abbizzarro\u00bb, \u00abstrano\u00bb. Il dizionario di Google: \u00abSessualmente, etnicamente o socialmente eccentrico rispetto alle definizioni di normalit\u00e0 codificate dalla cultura egemone\u00bb. La definizione non definisce quale dovrebbe essere la cultura egemone.<\/p>\n<p style=\"text-align: justify;\">Dopo il Sessantotto, la famiglia cattolica con papa, mamma ed <em>x<\/em> figli, tutti convinti che i maschi sono maschi e le femmine sono femmine, \u00e8 diventata grandiosamente minoritaria. La cultura egemone \u00e8 San Remo e San Remo \u00e8 Achille Lauro con la tutina. In questo momento, i trasgressivi sono quelli che vanno alla Messa in latino ed infatti <em>Report <\/em>invita alla gogna.<\/p>\n<div id=\"attachment_31062\" style=\"width: 184px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-31062\" class=\"wp-image-31062\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg\" alt=\"\" width=\"184\" height=\"184\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/04\/Mario-Mieli-150x150.jpg 150w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/a><p id=\"caption-attachment-31062\" class=\"wp-caption-text\">Mario Mieli<\/p><\/div>\n<p style=\"text-align: justify;\"><em>Queer<\/em> vuoi dire strano e si definisce per quello che non \u00e8. E questo \u00e8 il punto fondamentale. Chi ha una crisi di identit\u00e0 totale che \u00e8 dolore si rifugia nel non essere. Chi non si ama vuole essere strano. Chi non ama se stesso e teme d\u00ec non poter essere amato, si rende strano di proposito cos\u00ec la mancanza di amore non lo ferir\u00e0, perch\u00e9 sar\u00e0 stato lui a provocarla.<\/p>\n<p style=\"text-align: justify;\">Ognuno ha diritto di essere strano. Nessuno ha diritto di pretendere di essere accettato perch\u00e9 nessuno pu\u00f2 costringermi ad accettare qualcosa che \u00e8 al di fuori della mia etica e della mia estetica.<\/p>\n<p style=\"text-align: justify;\">La potenza liberticida del <em>queer<\/em> \u00e8 che accettare l&#8217;altro diventa un dovere anche se l&#8217;altro ha fatto tutto quello che poteva per essere ripugnante. I due maggiori intellettuali sono Mario Mieli e la\/il filosofa\/o <em>ex<\/em> Beatrice Preciado, attualmente Paul Preciado.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Paul_Beatrice_Preciado.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-47204 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/Paul_Beatrice_Preciado.jpg\" alt=\"\" width=\"240\" height=\"181\"><\/a>Mario Mieli \u00e8 considerato il paradigma della cultura gay, definito da <em>Liberazione<\/em> il pi\u00f9 grande intellettuale <em>queer<\/em> italiano. \u00c8 autore del testo <em>Elementi di critica<\/em> <em>omosessuale, <\/em>dove parla della sublime bellezza di pedofilia, necrofilia e coprofagia.<\/p>\n<p style=\"text-align: justify;\">Mieli faceva spettacoli teatrali dove mangiava gli escrementi suoi e del suo cane, crudi e sconditi. I colibatteri ne saranno stati lieti. Riporto un brano pubblicato il 17 gennaio 2014 su <em>Liberation: <\/em>\u00abDa questa modesta tribuna, io invito tutti i corpi (delle donne) allo sciopero dell&#8217;utero. Affermiamoci come cittadine intere e non come uteri riproduttivi. Attraverso l&#8217;astinenza, attraverso l\u2019omosessualit\u00e0 ma anche attraverso la masturbazione, la sodomia, il feticismo, la coprofagia, la zoofilia (<em>non vuol dire avere il micetto e mettere la foto su Facebook, ma vuol dire avere rapporti erotici con gli animali, nda<\/em>) e l&#8217;aborto. Non lasciamo penetrare nelle nostre vagine una sola goccia di sperma nazionale cattolico\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-45018 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/gender_gay_arcobaleno.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Il pensiero di Beatrice che ora \u00e8 Paul, ma che continua ad avere il genoma XX in tutte le sue cellule e anche se ha subito la castrazione, continua a non possedere testicoli, con\u00adsiste nello sciopero totale e definitivo per tutte le donne, sostituzione della dualit\u00e0 vagina\/pene, con la dualit\u00e0 ano\/vibratore.<\/p>\n<p style=\"text-align: justify;\">Questa persona ha un rapporto alterato col proprio corpo, al punto tale da credere che la sessualit\u00e0 consista nell&#8217;avere un corpo estraneo nell&#8217;ultima porzione del tubo digerente. Provare piacere a sentire il corpo di un uomo, del nostro uomo, dentro di noi e provare piacere a sentire il nostro bimbetto che se ne sta nove mesi dentro di noi, caldo e tiepido, \u00e8 una reazione biologica, non una costruzione sociale ed \u00e8 anche la reazione biologica in assoluto pi\u00f9 potente insieme al legame col neonato.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/coprofagia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47205 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/coprofagia.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/coprofagia.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/coprofagia-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>La coprofagia nella razza umana \u00e8 biologicamente ripugnante. Non \u00e8 cos\u00ec per tutti i mammiferi. I conigli la praticano e i cani ci giocherellano, ma per noi sarebbe un grosso rischio sanitario, motivo per cui troviamo nauseante la coprofagia. Beatrice \/Paul si limita al micio, ma non prova, almeno non denuncia, attrazione erotica per i minori. Mieli parla diffusamente della gaia riscossa della \u00abmerda\u00bb.<\/p>\n<p style=\"text-align: justify;\">Dal libro di Mario Mieli, <em>Elementi di critica omosessuale<\/em>: \u00abDel coito anale, gli eterosessuali maschi temono anche l&#8217;aureola escrementizia\u2026 \u2018Ma l&#8217;Amore ha eretto la sua dimora nel luogo degli escrementi\u2019 (Yeats): noi <em>gay<\/em> Lo sappiamo bene e la nostra condizione \u00e8 prossima alla gaia riscossa della merda (quando non lo \u00e8 gi\u00e0). Anche per quel che concerne la merda, al di l\u00e0 del ribrezzo repressivo, sta un ricco godimento [\u2026] e quando qualcuno dice: \u2018Questa merce \u00e8 di merda, questo pat\u00e9 \u00e8 merdoso\u2019, ignora che la merda \u00e8 disgustosa quanto certo scatolame e che esiste un parte delle feci, un cuore gustoso e prelibato paragonabile soltanto al pi\u00f9 gustoso <em>pat\u00e9 gras<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/07\/pedofilia_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21158 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/07\/pedofilia_2.jpg\" alt=\"\" width=\"252\" height=\"200\"><\/a>Pi\u00f9 avanti aggiunge: \u00abNoi checche rivoluzionarie sappiamo vedere nel bambino l\u2019essere umano potenzialmente libero Noi, s\u00ec, possiamo amare i bambini. Possiamo desiderarli eroticamente rispondendo alla loro voglia di Eros, possiamo cogliere a viso e a braccia aperte la sensualit\u00e0 inebriante che profondono, possiamo fare l&#8217;amore con loro\u00bb.<\/p>\n<p style=\"text-align: justify;\">Quanto odio c&#8217;\u00e8 in Mieli per s\u00e9 stesso, per la sua virilit\u00e0 e per quella di suo padre. Nel suo libro <em>Il Risveglio dei Faraoni <\/em>racconta di aver desiderato di avvelenarlo e alla fine si suicida per saldargli i conti. In tutta la sua vita ha incontrato solo persone che hanno rilanciato la sua follia, nessuno che abbia cercato di ritrovare l&#8217;umanit\u00e0 che era in lui, la virilit\u00e0 che era in lui, quella umanit\u00e0 e quella virilit\u00e0 che lui ha oltraggiato annegandole negli escrementi e che invece erano disperato desiderio di purezza.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47208 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-1.jpg\" alt=\"\" width=\"259\" height=\"194\"><\/a>Tornando a <em>queer, <\/em>su <em>donnamoderna.com <\/em>troviamo la cinguettosa definizione: \u00abLa parola <em>queer <\/em>racconta di una rivoluzione che \u00e8 anche estetica. Fatta di sguardi maschili segnati dal mascara o di capezzoli che spuntano da fisici androgini. Questo movimento porta con se un canone di bellezza nuovo, in cui la linea di confine maschio-femmina diventa una sfumatura\u00bb.<\/p>\n<p style=\"text-align: justify;\">Fosse tutto qui, chi se ne frega. Non vi illudete. <em>Queer <\/em>non vuol dire fascino androgino, <em>queer \u00e8 <\/em>odio di s\u00e9, odio di quello che si \u00e8, per cui ci si rifugia vuoto del non esserlo e si cerca di riempirlo di qualcosa, qualsiasi cosa. <em>Queer <\/em>quindi pu\u00f2 anche essere coprofagia, zoofilia ed attrazione erotica per i minori, secondo le affermazioni di quelli riconosciuti come maggiori intellettuali <em>queer<\/em>.<\/p>\n<p style=\"text-align: justify;\">Non tutti coloro che si dichiarano <em>queer<\/em> mangiano escrementi ma tutti coloro che dichiarano di mangaiare escrementi sono accettati nel mondo <em>queer <\/em>come eroi. Il punto \u00e8 che tutto questo ci \u00e8 imposto, noi non abbiamo il diritto di trovarli brutti, per quanto loro si sforzino di essere ripugnanti.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/05\/carcere.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22512 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/05\/carcere.jpg\" alt=\"\" width=\"253\" height=\"199\"><\/a>Se ce lo lasciamo sfuggire ci sono multe di migliaia di dollari in Canada e quando passer\u00e0 la legge sulla omotransfobia, ci saranno anni di galera in Italia A Mario Mieli \u00e8 intitolato un circolo che riceve denaro pubblico per combattere l&#8217;intolleranza. Non tollerate chi mangia escrementi? Non amate Mario Mieli? Vi cureranno. Faranno corsi di rieducazione con i soldi dei contribuenti.<\/p>\n<p style=\"text-align: justify;\">La tragedia del <em>queer <\/em>\u00e8 la sua incapacit\u00e0 di essere, la sua fuga nel non essere, il suo sforzo di essere il pi\u00f9 strano del reame, il nostro obbligo di accettare comportamenti che ci vengono imposti statalmente. E, accettandoli, rinchiudiamo per sempre queste persone nella gabbia desolata del loro non essere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da: La verit\u00e0 27 aprile 2020 &nbsp; Sono i queer, la Q della sigla LGBTQ*. Dicono di non essere n\u00e9 uomini n\u00e9 donne ma pretendono la nostra approvazione. Se li assecondassimo, come vuole la legge sulla omotransfobia, li chiuderemmo nella gabbia desolata del loro \u2018non amore\u2019. di Silvana De Mari<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":47212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[437,2499,1292],"class_list":["post-47200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-ideologia-del-gender-2","tag-lgbt","tag-queer","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-13T22:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita\",\"datePublished\":\"2020-05-13T22:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/\"},\"wordCount\":1348,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queer_Lgbt_gender-2.jpg\",\"keywords\":[\"ideologia del gender\",\"Lgbt\",\"queer\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/\",\"name\":\"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queer_Lgbt_gender-2.jpg\",\"datePublished\":\"2020-05-13T22:00:05+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queer_Lgbt_gender-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queer_Lgbt_gender-2.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/","og_locale":"it_IT","og_type":"article","og_title":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-05-13T22:00:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita","datePublished":"2020-05-13T22:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/"},"wordCount":1348,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg","keywords":["ideologia del gender","Lgbt","queer"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/","name":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg","datePublished":"2020-05-13T22:00:05+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/queer_Lgbt_gender-2.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fuga-nella-stranezza-e-spesso-incapacita-di-stare-di-fronte-alla-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La fuga nella stranezza \u00e8 spesso incapacit\u00e0 di stare di fronte alla vita"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=47200"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47200\/revisions"}],"predecessor-version":[{"id":47211,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/47200\/revisions\/47211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/47212"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=47200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=47200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=47200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}