{"id":4711,"date":"2011-09-22T00:00:00","date_gmt":"2011-09-21T22:00:00","guid":{"rendered":""},"modified":"2015-04-09T16:58:16","modified_gmt":"2015-04-09T14:58:16","slug":"risolto-lenigma-shakespeare-era-cattolico","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/","title":{"rendered":"Risolto l\u2019enigma: Shakespeare era cattolico"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22854\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg\" alt=\"Shakespeare\" width=\"250\" height=\"182\" \/><\/a>Ag Zenit<\/strong> (ZENIT.org).<\/div>\n<div style=\"text-align: center;\">venerd\u00ec, 16 settembre 2011<\/div>\n<p style=\"text-align: center;\"><em>Le prove in un libro scritto da Elisabetta Sala\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Antonio Gaspari <\/strong><\/p>\n<p style=\"text-align: justify;\">ROMA _ \u00a0William Shakespeare, il pi\u00f9 grande scrittore in lingua inglese, era cattolico? Secondo il libro \u201cL\u2019Enigma di Shakespeare. Cortigiano o dissidente?\u201d appena pubblicato da Ares, sono ormai copiosi gli indizi e le prove che confermano la fede cattolica del drammaturgo e poeta inglese.Ma cosa cambia sapere che Shakespeare fosse cattolico? Secondo Elisabetta Sala, autrice del libro in questione, la cattolicit\u00e0 del poeta britannico \u201cpotrebbe ricordare agli inglesi che, forse, la vera anima del loro Paese non \u00e8 quella che fu redatta a tavolino dalla minoranza che stava al governo\u201d.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Bisogna infatti ricordare che William Shakespeare \u00e8 vissuto in un periodo storico in cui manifestare il proprio essere cattolici significava venire pesantemente discriminati in ambito sociale a rischio della vita. Tanto \u00e8 che i suoi stessi parenti, amici e vicini di casa furono uccisi perch\u00e9 cattolici e fedeli al Papa.<\/p>\n<p style=\"text-align: justify;\">Per conoscere la storia e le implicazioni dello Shakespeare cattolico, ZENIT ha intervistato Elisabetta Sala, la quale insegna Lingua, Letteratura e Storia inglese nei Licei statali e collabora con diverse testate giornalistiche.<\/p>\n<p style=\"text-align: justify;\">Per le Edizioni Ares ha gi\u00e0 pubblicato \u201cL\u2019ira del Re \u00e8 morte\u201d, sullo scisma di Enrico VIII, ed \u201cElisabetta la Sanguinaria\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono le prove della cattolicit\u00e0 di Shakespeare di cui lei parla nel libro?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Le \u201cprove\u201d consistono in una serie impressionante di indizi, spesso taciuti e a volte persino occultati dalle correnti critiche tradizionali. Da un lato abbiamo numerosi particolari biografici, come il cattolicesimo della famiglia d\u2019origine e quello delle cerchie altolocate che Shakespeare frequent\u00f2 a Londra. Dall\u2019altro, abbiamo l\u2019inconfondibile connotazione cattolica di quasi tutte le sue opere, che rivelano in modo lampante la mentalit\u00e0 di chi le scrisse. Certo, sono particolari che possono sfuggire a lettori (e studiosi) non cattolici.<\/p>\n<p style=\"text-align: justify;\"><strong>La Regina sapeva della cattolicit\u00e0 di Shakesperare?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Non possiamo dirlo con certezza: probabilmente nutriva almeno qualche sospetto. Di lei, per\u00f2, possiamo senz\u2019altro dire che non era un\u2019estremista e che, se le faceva comodo, passava tranquillamente sopra a differenze religiose e politiche. Certamente apprezzava il genio del grande drammaturgo e pu\u00f2 darsi che non volesse privarsene. Sappiamo per certo che ella ag\u00ec in tal modo nei confronti del suo maestro di cappella, William Byrd, cattolico e ricusante, che i ministri regi avrebbero voluto e potuto distruggere se lei non l\u2019avesse protetto personalmente.<\/p>\n<p style=\"text-align: justify;\"><strong>Ai tempi di Shakespeare il cattolicesimo era fuorilegge. Come poteva il noto drammaturgo frequentare la corte e rappresentare le sue opere? Perch\u00e9 era tollerato e protetto?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Primo: Perch\u00e9 era un funambolo espertissimo, nell\u2019arte come nella vita. Secondo: perch\u00e9, semplicemente, non era possibile arrestare tutti coloro che simpatizzavano per il papismo, essendo essi in maggioranza, tra il popolo come tra le classi pi\u00f9 elevate. Dalle ricerche pi\u00f9 recenti emerge il fatto che erano proprio le potenti famiglie cattoliche a proteggere e a promuovere il grande drammaturgo. La regina certo non amava i cattolici, ma sapeva che erano molto meno pericolosi degli estremisti puritani, repubblicani e antimonarchici per eccellenza, i quali, non a caso, nel giro di mezzo secolo sarebbero riusciti a far decapitare il re e ad abolire la monarchia. Quanto all\u2019innegabile cattolicesimo shakespeariano, tanto evidente a chi abbia studiato l\u2019intero canone, non era allora cos\u00ec facile affermarlo senza ombra di dubbio: le sue opere infatti, non furono mai pubblicate in edizione completa prima del 1623, sette anni dopo la sua morte.<\/p>\n<p style=\"text-align: justify;\"><strong>Come faceva Shakespeare a conoscere cos\u00ec bene tanti luoghi e citt\u00e0 italiane?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Di fatto, l\u2019Italia andava di gran moda tra gli inglesi del Cinque-Seicento e chiunque volesse darsi un\u2019aria di distinzione citava luoghi e nomi italiani. Moltissimi si cimentarono anche nello studio della lingua e, come afferma un noto studioso, Shakespeare sarebbe stato il genio pi\u00f9 stupido della sua epoca se non si fosse adeguato. Italiane furono molte delle sue fonti, in lingua originale o in traduzione francese, e certo il pubblico era affascinato da drammi ambientati in Italia.<\/p>\n<p style=\"text-align: justify;\">Quanto alla sua accuratezza geografica, diciamo che lascia un po\u2019 a desiderare e che, probabilmente, neanche gli interessava: basti dire, ad esempio, che il protagonista dei Due Gentiluomini di Verona viaggia per nave da Verona a Milano o che quello della Tempesta, duca di Milano, viene detronizzato e immediatamente abbandonato in mare. In ogni caso, pur non essendo desumibile dalle sue opere, la questione se egli abbia mai visitato l\u2019Italia resta pi\u00f9 che mai aperta: come molti sanno, recentemente sono state individuate alcune firme nel registro del Collegio Inglese di Roma che potrebbero essere nomi in codice di William Shakespeare: se egli ebbe mai occasione di visitare i nostri lidi, dubito che sia stato per un viaggio di piacere.<\/p>\n<p style=\"text-align: justify;\"><strong>Come facevano i cattolici inglesi a mantenere i rapporti con Roma e con il Papa?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: La rete di collegamento era tanto fitta quanto pericolosa. Tra Roma e Londra era tutto un andirivieni di giovani fuggiaschi desiderosi di entrare in seminario, esuli politici e religiosi, agenti segreti governativi, missionari in borghese e chi pi\u00f9 ne ha pi\u00f9 ne metta. Un suddito inglese che avesse lasciato il proprio Paese per entrare in seminario e che fosse rientrato in patria come sacerdote era automaticamente colpevole di alto tradimento e, se catturato, subiva di norma l\u2019orrendo squartamento rituale riservato ai traditori della Corona; ci\u00f2 nonostante, la missione fu instancabile. Inutile dire che, qualora i missionari avessero studiato a Roma, conoscevano molto bene l\u2019italiano.<\/p>\n<p style=\"text-align: justify;\"><strong>Shakesperare ha conosciuto Giordano Bruno? Quali erano i rapporti tra i due?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Di questo non abbiamo alcuna prova e, anzi, si tratta a mio avviso di un\u2019ipotesi piuttosto improbabile, giacch\u00e9 Bruno lasci\u00f2 per sempre l\u2019Inghilterra nel 1585, quando Shakespeare, ventunenne, era (forse) alle primissime armi come attore e non si era ancora cimentato con la drammaturgia. Pi\u00f9 probabilmente lo conobbe Christopher Marlowe, altro grande poeta e drammaturgo, che, come Bruno, lavorava per i servizi segreti governativi diretti da Francis Walsingham.<\/p>\n<p style=\"text-align: justify;\"><strong>In che modo la cattolicit\u00e0 di Shakesperare ha ispirato e influenzato le sue opere?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Il cattolicesimo shakespeariano \u00e8 l\u2019unica chiave che permetta di far quadrare il puzzle della sua opera; lungi dall\u2019esaurirne la profondit\u00e0, la aumenta enormemente. Come afferma John Waterfield, \u201cShakespeare non sarebbe \u2018cattolico\u2019\u2026, poeta universale del cuore umano, se non fosse stato prima di tutto un cattolico. In altre parole, la sua umanit\u00e0 procedette di pari passo con la sua fede religiosa\u201d.<\/p>\n<p style=\"text-align: justify;\">Afferma Clare Asquith nel suo splendido studio: \u201cIl pi\u00f9 grande scrittore di Inghilterra visse e lavor\u00f2 nel periodo pi\u00f9 turbolento per il Paese. \u00c8 impossibile credere che non avesse nulla da dire sul dramma dei suoi giorni. Di fatto, esso diede vita a tutto ci\u00f2 che scrisse: la crisi dell\u2019Inghilterra fu la passione di Shakespeare\u201d. Censura, persecuzione, condanna, silenzio imposto, apostasia forzata, senso di isolamento e, a volte, di disperazione\u2026 Tutto ci\u00f2, che faceva parte della vita quotidiana dei cattolici inglesi, emerge lungo tutto il canone e ne diventa l\u2019elemento unificatore.<\/p>\n<p style=\"text-align: justify;\"><strong>Cosa cambia nel dibattito letterario e storico, sapere che Shakesperare fosse un fedele cattolico?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sala: Nel medesimo intervento in cui propendeva per il cattolicesimo shakespeariano, l\u2019attuale arcivescovo di Canterbury, Rowan Williams, ha tenuto a specificare che il fatto non gli appaia di grande importanza. Io trovo invece che ne abbia moltissima. Innanzitutto perch\u00e9 ci\u00f2 va a demolire un\u2019immagine falsata dalla storia, quella che volle identificare Shakespeare con il paladino del regime elisabettiano.<\/p>\n<p style=\"text-align: justify;\">Poich\u00e9, secondo la vulgata whig, fu quello il momento che forgi\u00f2 l\u2019identit\u00e0 degli inglesi, \u00e8 di un certo rilievo scoprire che il poeta nazionale si rifaceva in realt\u00e0 a radici molto pi\u00f9 profonde, a radici che condivideva con la maggioranza del suo popolo. Con la profonda crisi odierna dell\u2019anglicanesimo, uno Shakespeare cattolico potrebbe ricordare agli inglesi che, forse, la vera anima del loro Paese non \u00e8 quella che fu redatta a tavolino dalla minoranza che stava al governo.<\/p>\n<p style=\"text-align: justify;\">___________________________<\/p>\n<p><strong>Enigma di Shakespeare (L&#8217;). Cortigiano o dissidente?\u00a0<\/strong>di Sala Elisabetta<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.theseuslibri.it\/product\/2649\/Enigma-di-Shakespeare-(L').-Cortigiano-o-dissidente-.html\" target=\"_blank\">ACQUISTA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag Zenit (ZENIT.org). venerd\u00ec, 16 settembre 2011 Le prove in un libro scritto da Elisabetta Sala\u00a0 di Antonio Gaspari ROMA _ \u00a0William Shakespeare, il pi\u00f9 grande scrittore in lingua inglese, era cattolico? Secondo il libro \u201cL\u2019Enigma di Shakespeare. Cortigiano o dissidente?\u201d appena pubblicato da Ares, sono ormai copiosi gli indizi e le prove che confermano &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":22854,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,17,18],"tags":[1973],"class_list":["post-4711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-libri","category-personaggi","tag-shakesperare","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-21T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-09T14:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"263\" \/>\n\t<meta property=\"og:image:height\" content=\"191\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Risolto l\u2019enigma: Shakespeare era cattolico\",\"datePublished\":\"2011-09-21T22:00:00+00:00\",\"dateModified\":\"2015-04-09T14:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/\"},\"wordCount\":1326,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/Shakespeare.jpg\",\"keywords\":[\"Shakesperare\"],\"articleSection\":[\"Chiesa\",\"Libri\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/\",\"name\":\"Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/Shakespeare.jpg\",\"datePublished\":\"2011-09-21T22:00:00+00:00\",\"dateModified\":\"2015-04-09T14:58:16+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/Shakespeare.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/Shakespeare.jpg\",\"width\":263,\"height\":191},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risolto-lenigma-shakespeare-era-cattolico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risolto l\u2019enigma: Shakespeare era cattolico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/","og_locale":"it_IT","og_type":"article","og_title":"Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-09-21T22:00:00+00:00","article_modified_time":"2015-04-09T14:58:16+00:00","og_image":[{"width":263,"height":191,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Risolto l\u2019enigma: Shakespeare era cattolico","datePublished":"2011-09-21T22:00:00+00:00","dateModified":"2015-04-09T14:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/"},"wordCount":1326,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg","keywords":["Shakesperare"],"articleSection":["Chiesa","Libri","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/","name":"Risolto l\u2019enigma: Shakespeare era cattolico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg","datePublished":"2011-09-21T22:00:00+00:00","dateModified":"2015-04-09T14:58:16+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/09\/Shakespeare.jpg","width":263,"height":191},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risolto-lenigma-shakespeare-era-cattolico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Risolto l\u2019enigma: Shakespeare era cattolico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4711"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4711\/revisions"}],"predecessor-version":[{"id":22855,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4711\/revisions\/22855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/22854"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}