{"id":471,"date":"2005-05-11T17:17:05","date_gmt":"2005-05-11T15:17:05","guid":{"rendered":""},"modified":"2016-02-04T17:10:03","modified_gmt":"2016-02-04T16:10:03","slug":"ignorato-il-genocidio-nel-sudan-cristiano","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/","title":{"rendered":"Ignorato il genocidio nel Sudan cristiano"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30335\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg\" alt=\"Sudan_genocide\" width=\"250\" height=\"140\" \/><\/a>Articolo pubblicato su <strong>Il Corriere del Sud<\/strong><\/div>\n<div style=\"text-align: center;\">n. 4\/2002; 16- 28 febbraio<\/div>\n<p style=\"text-align: justify;\"><em>I mass media di tutto il mondo ignorano il Paese pi\u00f9 grande del continente africano. I corrispondenti di guerra ignorano la pi\u00f9 lunga guerra che ancora si stia combattendo.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Domenico Bonvegna<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La guerra nel Paese pi\u00f9 grande dell\u2019Africa dura da oltre 45 anni, ma in Occidente vi sono ancora molti che non hanno conoscenza del genocidio sudanese.<\/div>\n<p style=\"text-align: justify;\">Sulla rivista <em>Cristianit\u00e0<\/em> di Piacenza (n.308 di novembre-dicembre 2001 <em>www.alleanzacattolica.org<\/em>) \u00e8 stata pubblicata una intervista a cura di Geoff Metcalf al dottor Peter Hammond, direttore di Frontline Fellowship [associazione di sostegno alle comunit\u00e0 <em>evangelical<\/em> in difficolt\u00e0] che cerca d\u2019informare il mondo sull\u2019oppressione dei cristiani in Sudan. Negli ultimi diciassette anni sono morti due milioni di persone.<\/p>\n<p style=\"text-align: justify;\">E\u2019 una guerra fra il settentrione arabo-musulmano e il Meridione nero e cristiano. Si tratta di due Paesi, due popoli diversi dal punto di vista culturale, religioso ed etnico. Il governo sudanese di Khartum mira a imporre la legge islamica anche ai cristiani del Meridione. E quando i cristiani vi si sono opposti, il governo ha cominciato a bombardarne gli ospedali e le scuole, e a ridurne i bambini in schiavit\u00f9.<\/p>\n<p style=\"text-align: justify;\">La situazione \u00e8 gravissima<em>.<\/em> Ma di questa tragedia l\u2019opinione pubblica non sa nulla e questo \u00e8 uno scandalo: come possono i mass-media di tutto il mondo ignorare il Paese pi\u00f9 grande dell\u2019Africa? Come possono i corrispondenti di guerra ignorare la pi\u00f9 lunga guerra che si stia combattendo ancora? Il governo musulmano ha lanciato un <em>jihad, <\/em>una guerra santa dei mujahedin(guerrieri santi) contro il meridione del Paese. Per il governo sudanese si tratta decisamente di una guerra di religione e di imposizione di una politica di &#8220;arabizzazione&#8221; e di &#8220;islamizzazione&#8221;, tutti devono diventare arabi e islamici, oppure vengono ridotti in schiavit\u00f9, uccisi o esiliati.<\/p>\n<p style=\"text-align: justify;\">Il governo islamico per combattere i cristiani del Sud ha provocato addirittura la carestia, la fame. Sono stati date alle fiamme i raccolti del Paese, avvelenati i pozzi e sterminati gli armenti. E\u2019 la politica della <em>&#8220;terra bruciata&#8221;<\/em>. Tra l\u2019altro nel Sudan, l\u2019influente leader dei <em>Fratelli Musulmani <\/em>Hassan al-Turabi, l\u2019architetto della rivoluzione islamica sudanese, nel 1992 ha accolto bin Laden. Il dottor Hammond denuncia l\u2019ONU che d\u00e0 soccorsi alimentari al governo guidato dagli islamici, che poi dovrebbe distribuirli equamente a tutta la popolazione. Invece il popolo cristiano del Sud per ricevere qualche aiuto deve convertirsi all\u2019islam e quindi mendicare in nome di <em>Allah<\/em>: chi non lo fa muore di fame.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Tutte le popolazioni<\/em> <em>che ho visitato sui Monti Nuba affermano che mai, dico mai, \u00e8 arrivato loro qualcosa dalle Nazioni Unite [\u2026] Se vi \u00e8 gente che vuole aiutare le popolazioni africane, \u00e8 necessario che faccia le proprie donazioni direttamente a iniziative private, a gruppi precisi, a singole persone oppure alle Chiese [\u2026] invece, dando il denaro ai governi, tutto quello che si ottiene \u00e8 il foraggiamento della corruzione e dell\u2019oppressione&#8221;<\/em>, afferma il dott. Hammond che \u00e8 testimone oculare, di diversi episodi sulle atrocit\u00e0 commesse in Sudan, come il bombardamento di una chiesa piena di fedeli, miracolosamente rimasti illesi.<\/p>\n<p style=\"text-align: justify;\">Nel Sudan prospera il commercio degli schiavi, incoraggiato dallo stesso governo, manda nel sud del Paese le truppe arabe, dove \u00e8 possibile abbandonarsi ai saccheggi e alle razzie di persone di colore per arricchirsi attraverso la vendita o l\u2019asservimento.<\/p>\n<p style=\"text-align: justify;\">Molte sono le personalit\u00e0 politiche internazionali che si sono recati in Sudan, ospitati dagli schiavisti arabi, ma nessuno ha detto nulla sulla tratta degli schiavi. Nel 1998, Bill Clinton, si scus\u00f2 per la partecipazione americana al commercio degli schiavi avvenuto circa 180 anni prima, ma anche lui non ha detto una parola sull\u2019attuale commercio degli schiavi che si sta consumando oggi. Costa poco scusarsi per i peccati commessi da altri in un altro tempo e in un altro luogo, per poi ignorare quanto accade oggi. La Cina comunista \u00e8 il primo fornitore di armi al governo sudanese del Fronte Nazionale Islamico.<\/p>\n<p style=\"text-align: justify;\">Il direttore di Frontline Fellowship, afferma: <em>&#8220;Le bombe che ci sganciano sulla testa, gli aerei che pilotano e le armi che adoperano provengono tutte dalla Cina comunista&#8221;<\/em>. Inoltre i cinesi estraggono petrolio dal suolo sudanese. Ma non tutto \u00e8 perduto esiste un Sudan libero, controllato dai combattenti cristiani per la libert\u00e0: l\u201985% del Sud \u00e8 sotto il controllo della resistenza. I suoi membri stanno combattendo per le proprie vite, per la libert\u00e0 e per un Sudan meridionale cristiano e indipendente. Che cosa possiamo fare noi lettori per aiutare i cristiani del Sudan? Hammond, risponde che <em>vi \u00e8 bisogno d\u2019informazione<\/em>.<\/p>\n<p style=\"text-align: justify;\">Ai grandi <em>Media<\/em> non importa alcunch\u00e8 se i cristiani vengono perseguitati, crocifissi o resi schiavi dall\u2019altra parte del mondo in Sudan. Esiste di fatto una congiura del silenzio. Quando ci sono di mezzo i cristiani i <em>media<\/em> laici riscoprono il proprio becero pregiudizio e non raccontano nulla.<\/p>\n<p style=\"text-align: justify;\">Il Sud non sta ricevendo nessun aiuto n\u00e9 alimentare, n\u00e9 di armi; la gente dice: <em>&#8220;se il mondo musulmano aiuta militarmente il governo del Sudan, perch\u00e9 quello cristiano non aiuta noi? Per loro- <\/em>afferma il dott. Hammond<em>&#8211; \u00e8 molto difficile comprendere perch\u00e9 le nazioni islamiche sono felici di allinearsi al jihad decretato contro i cristiani e perch\u00e9 invece le nazioni cristiane non si schierano a fianco dei cristiani che lottano per la propria sopravvivenza&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">L\u2019ostacolo maggiore per le nazioni cristiane \u00e8 che non sanno che esiste il genocidio delle popolazioni cristiane nel Sudan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su Il Corriere del Sud n. 4\/2002; 16- 28 febbraio I mass media di tutto il mondo ignorano il Paese pi\u00f9 grande del continente africano. I corrispondenti di guerra ignorano la pi\u00f9 lunga guerra che ancora si stia combattendo. di Domenico Bonvegna<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,33,108],"tags":[2393,380,378],"class_list":["post-471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-cristiani-nell-islam","category-paesi-e-continenti","tag-africa","tag-cristiani-nellislam","tag-sudan","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-11T15:17:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-04T16:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Ignorato il genocidio nel Sudan cristiano\",\"datePublished\":\"2005-05-11T15:17:05+00:00\",\"dateModified\":\"2016-02-04T16:10:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/\"},\"wordCount\":889,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Sudan_genocide.jpg\",\"keywords\":[\"Africa\",\"cristiani nell'Islam\",\"Sudan\"],\"articleSection\":[\"Africa\",\"Cristiani nell'islam\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/\",\"name\":\"Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Sudan_genocide.jpg\",\"datePublished\":\"2005-05-11T15:17:05+00:00\",\"dateModified\":\"2016-02-04T16:10:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Sudan_genocide.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Sudan_genocide.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ignorato-il-genocidio-nel-sudan-cristiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ignorato il genocidio nel Sudan cristiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/","og_locale":"it_IT","og_type":"article","og_title":"Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-11T15:17:05+00:00","article_modified_time":"2016-02-04T16:10:03+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Ignorato il genocidio nel Sudan cristiano","datePublished":"2005-05-11T15:17:05+00:00","dateModified":"2016-02-04T16:10:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/"},"wordCount":889,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg","keywords":["Africa","cristiani nell'Islam","Sudan"],"articleSection":["Africa","Cristiani nell'islam","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/","name":"Ignorato il genocidio nel Sudan cristiano - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg","datePublished":"2005-05-11T15:17:05+00:00","dateModified":"2016-02-04T16:10:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Sudan_genocide.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ignorato-il-genocidio-nel-sudan-cristiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Ignorato il genocidio nel Sudan cristiano"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=471"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/471\/revisions"}],"predecessor-version":[{"id":30337,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/471\/revisions\/30337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30335"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}