{"id":46845,"date":"2020-04-09T00:00:07","date_gmt":"2020-04-08T22:00:07","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46845"},"modified":"2020-04-02T15:29:51","modified_gmt":"2020-04-02T13:29:51","slug":"dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/","title":{"rendered":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46849 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste-1.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>L\u2019Occidentale <\/strong>2 Aprile 2020<\/p>\n<p style=\"text-align: center;\">Intervista di <strong>Graziano Davoli <\/strong><\/p>\n<p style=\"text-align: justify;\">La pandemia ha attraversato tutte le fasi della storia dell\u2019umanit\u00e0. In questa intervista Francesco Agnoli ripercorre le tappe delle pestilenze e riflette sulle reazioni dell\u2019uomo e sul contributo che i principi cristiani hanno dato per superare le ore pi\u00f9 buie.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Chi invent\u00f2 le quarantene e in quale circostanza?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sembra che \u201cquarantena\u201d sia la forma veneta per <em>quarantina<\/em>. Fu Venezia ad imporre, durante la peste nera del 1347, a tutti i vascelli in arrivo di rimanere alla fonda per un periodo di 40 giorni. Certamente non si sapeva bene cosa la peste fosse, ma si intu\u00ec cosa bisognasse fare. Ciononostante la citt\u00e0 perse circa il 60% dei suoi abitanti<\/p>\n<p style=\"text-align: justify;\"><strong>Qual \u00e8 la prima grande pandemia di cui abbiamo notizie? Come nacque e come si diffuse?<\/strong><\/p>\n<p style=\"text-align: justify;\">Difficile dirlo. Per William Naphy e Andrew Spicer, autori de \u201cLa peste in Europa\u201d, fu la peste giustinianea del 541 dopo Cristo. Si parla di un crollo demografico tra il 50 e il 70 % in due generazioni. Allora in Italia si distinse l\u2019operato di papa Gregorio Magno (la pestilenza colp\u00ec Roma nel 590).<\/p>\n<p style=\"text-align: justify;\"><strong>Da dove le pandemie?<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_Asia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46850 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_Asia.jpg\" alt=\"\" width=\"268\" height=\"188\" \/><\/a>Il discorso \u00e8 troppo lungo. Mi limito all\u2019aspetto geografico. Nel mondo antico \u201c<em>le\u00a0malattie epidemico contagiose come le grandi pestilenze venivano importate nell\u2019area mediterranea dal subcontinente indiano, e, pi\u00f9 in generale, dall\u2019Estremo oriente tramite i porti mediorientali<\/em>\u201d (Cosmacini). Naphy e Spicer ricordano invece che la peste nera del 1347, che colpiva anche i polmoni, fu una pandemia nata molto probabilmente in Cina o in Mongolia (la Cina era stata colpita da epidemie di peste, tra il 1331 e il 1353 che uccisero circa il 50%).<\/p>\n<p style=\"text-align: justify;\">La causa della pandemia di fine Ottocento, definita terza pandemia di peste (1855-1899), la <em>Yersinia pestis<\/em>, infuri\u00f2 nell\u2019area di Hunan, di Canton e di Hong Kong prima di dilagare\u2026 anch\u2019essa poteva colpire proprio i polmoni. Nel secolo scorso si diceva che \u201c<em>Quando Mao starnutisce, l\u2019Europa si ammala<\/em>\u201d: ci si riferiva alle pandemie influenzali del Novecento (furono 3).<\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_virus-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-46803 size-medium alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_virus-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_virus-1-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_virus-1-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/Cina_virus-1-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Della prima, la terribile Spagnola, non \u00e8 certa l\u2019origine, ma diversi studiosi sostengono che si sia diffusa attraverso lavoratori cinesi in Europa; la seconda \u00e8 l\u2019 \u201cAsiatica\u201d (1957), la terza \u00e8 anch\u2019essa detta \u201cAsiatica\u201d (1968) e derivava dalla Cina\u2026 Dopo le Asiatiche, la Sars, ed ora il covid 19\u2026 sempre dalla Cina\u2026 Dico questo per far capire che certi fenomeni non sono affatto nuovi. Si ripete anche il meccanismo del passaggio da animale ad uomo, con roditori e pipistrelli a fare la parte dei leoni (dai pipistrelli derivano la rabbia, la sindrome respiratoria mediorientale, o MERS, la sars, covid 19, Ebola\u2026<a href=\"http:\/\/www.vitares.org\/index.php\/it\/magazine\/130-influenza-a-il-virus-dei-pipistrelli-potrebbe-infettare-altre-specie?fbclid=IwAR1L3Ikff4NkaI00xP053U6HweBqr4MAodlOYHymHjKk-vBJjxGfAD2QJ6I\" target=\"_blank\" rel=\"noopener noreferrer\">vedi<\/a>)<\/p>\n<p style=\"text-align: justify;\"><strong>Quali le reazioni, in generale, della gente, e delle religioni?<\/strong><\/p>\n<p style=\"text-align: justify;\">Per gli islamici \u201c<em>il morbo doveva essere accettato e sopportato con rassegnazione<\/em>\u201d. Inutile fuggire o reagire, il morbo non si propagava per contagio, ma colpiva specifiche persone: \u201c<em>Dio aveva specificamente e individualmente selezionato i suoi bersagli<\/em>\u201d. In generale questa visione \u00e8 definibile fatalista, e attraverser\u00e0 tutti i popoli. Gli storici notano per esempio che una posizione analoga fu presa dagli Olandesi calvinisti\/puritani fautori della predestinazione, durante la peste del 1628 e seguenti. Accanto al fatalismo, la reazione di rigetto: la peste non c\u2019\u00e8, non esiste (si arrivano anche ad uccidere i medici che la hanno denunciata); oppure la scelta epicurea: quella di chi decideva di fuggire e di cercare di scongiurare la paura divertendosi per quanto possibile.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/suore_ospedale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32155 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/suore_ospedale.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>I cattolici hanno visto nelle malattie una conseguenza del peccato originale. Alessandro Manzoni esprimer\u00e0 bene questo concetto ne \u201c<em>I Promessi sposi<\/em>\u201d: Don Rodrigo sta morendo di peste, ha la possibilit\u00e0 di pentirsi dei suoi peccati, e ci\u00f2 pu\u00f2 essere \u201c<em>castigo o misericordia<\/em>\u201d. Prima di Manzoni, un altro grande letterato, Francesco Petrarca, conosce la peste da vicino: perde l\u2019amata Laura e l\u2019unico figlio, Giovanni, mentre il fratello Gherardo, monaco, assiste i trenta religiosi della certosa di Montrieux, tutti uccisi dal morbo, ascoltando con gran fede le loro confessioni, somministrando loro i sacramenti e seppellendoli.<\/p>\n<p style=\"text-align: justify;\">Petrarca si chiede: \u201c<em>E che? Potrebbe essere vero quello di cui taluni dottissimi uomini sospettano, non darsi cura Iddio degli eventi mortali<\/em>? \u201d; ma poi conclude, rivolgendosi a Dio: \u201c<em>N\u00e9 perch\u00e9 ascosti ne siano i motivi, \u00e8 il tuo giudizio men giusto<\/em>\u201d. Di sicuro si convinse davvero che \u201c<em>quanto piace al mondo, \u00e8 breve sogno\u201d.<\/em> Il fatto che le pestilenze fossero una conseguenza della colpa dell\u2019uomo, non significa per\u00f2 che si dicesse di non reagire, al contrario. Come? Carit\u00e0, preghiera, medicina\u2026<\/p>\n<p style=\"text-align: justify;\">Bisogna ricordare che la Cristianit\u00e0 ha generato l\u2019istituzione ospedaliera, e che l\u2019Italia cattolica \u00e8 stata per secoli la patria degli ospedali e della medicina (qui per esempio \u00e8 nata, nel 1316, l\u2019anatomia). Parlando degli ospedali italiani e romani, Martin Lutero racconter\u00e0 con entusiasmo di \u201c<em>edifici regali<\/em>\u201d, \u201c<em>ottimi cibi e bevande<\/em>\u201d \u201c<em>servitori diligentissimi, medici dottissimi, i letti e i vestiti pulitissimi<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Come veniva gestita la paura?<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_lazzaretto_Manzoni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46851 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_lazzaretto_Manzoni.jpg\" alt=\"\" width=\"256\" height=\"197\" \/><\/a>Di fronte alla pestilenza che colp\u00ec il Nord Africa nel 251 il vescovo di Cartagine san Cipriano scriveva: \u201c<em>Questa pestilenza che pare ad alcuni orribile e micidiale, mette invece a prova la santit\u00e0 di ognuno e pesa sulla bilancia il cuore umano, giudica cio\u00e8 se i sani servono gli infermi, se i parenti assistono pietosamente i parenti, se i padroni hanno piet\u00e0 dei servi languenti, se i medici abbandonano i malati che li cercano, se i delinquenti frenano le loro violenze, se gli usurai smorzano gli ardori indomabili della loro avarizia<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">C\u2019erano dunque gli eroi, che non abbandonavano i loro cari, che facevano una quantit\u00e0 di elemosine e donazioni, ma anche i medici che fuggivano a gambe levate, come aveva fatto Galeno. E c\u2019erano coloro che non accettavano, e cercavano un capro espiatorio. Tutti abbiamo presente la caccia agli untori di Manzoni. E\u2019 sempre stato cos\u00ec: gli ateniesi incolpavano gli spartani; i francesi gli inglesi; i tedeschi, soprattutto durante la peste del 1347, gli ebrei.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/ospedale_medioevo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32141 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/ospedale_medioevo.jpg\" alt=\"\" width=\"188\" height=\"268\" \/><\/a>In Germania durante la peste nera si diffondono movimenti ereticali come i Flagellanti, che incolpano in particolare gli ebrei e i preti cattolici, arrivando a violenze incredibili (vedi N. Chon, \u201cI fanatici dell\u2019Apocalisse\u201d, oppure G. Fourquin, \u201cLe sommosse popolari nel Medioevo\u201d). Molto pi\u00f9 \u201ctolleranti\u201d come li definisce lo storico della medicina Giorgio Cosmacini ne \u201cL\u2019Arte lunga. Storia della medicina dall\u2019antichit\u00e0 ad oggi\u201d, gli italiani (l\u2019anomalia italiana \u00e8 studiata, per esempio Da Francesco Mandis in \u201cGli ebrei come capro espiatorio della peste del 1348. L\u2019eccezione italiana\u201d.<\/p>\n<p style=\"text-align: justify;\">Non deve stupire: anche la caccia alle streghe, di et\u00e0 moderna, sar\u00e0 soprattutto in terra germanica, e quasi nulla in Italia). Bisogna rammentare che papa Clemente VI, che risiedeva ad Avignone, scomunic\u00f2 coloro che incolpavano gli ebrei della diffusione della peste, notando tra il resto che morivano anche loro, come gli altri. Fu anche il papa che nel 1340 incaric\u00f2 il celebre Guy De Chauliac di fare ricerche anatomiche sui cadaveri per capire meglio le origini della peste.<\/p>\n<p style=\"text-align: justify;\"><strong>Qual era l\u2019atteggiamento degli stati italiani davanti a quadri sanitari di questo tipo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Gli storici delle pestilenze notano che gli Stati italiani furono i primi in assoluto a \u201cprevenire, contenere e curare la peste\u201d a partire dal XV secolo in particolare. \u201cPer circa tre secoli tali ordinanze e regolamenti furono i punti di riferimento, in tema di gestione delle pestilenze, per tutta l\u2019Europa occidentale\u201d. Cosa si faceva? I Consigli di sanit\u00e0 pubblica di Milano, Venezia, Firenze ecc\u2026 imponevano quarantene,limitazione o blocco dei commerci, disinfestazioni, bandi contro i vagabondi,denuncia dei malati, fosse comuni per i morti \u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/06\/ospedale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22469 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/06\/ospedale.jpg\" alt=\"\" width=\"240\" height=\"180\" \/><\/a>Soprattutto si costruivano i celebri lazzaretti (dove di solito a curare erano i cappuccini, i religiosi o le religiose, pronti a dare la vita). Il lazzaretto \u00e8 posto fuori della citt\u00e0, isolato, ed \u00e8 luogo di segregazione per impedire il contagio. Non si pu\u00f2 entrare o uscire da esso, \u201csotto pena della vita\u201d. I controlli sono rigidissimi, inflessibili, \u201cspietati\u201d. Certamente non manca chi cerca di incendiare i lazzaretti, o di fuggire\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>I frutti delle quarantene?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il lazzaretto anticipa l\u2019ospedale moderno. Scrive il Cosmacini: \u201c<em>La peste era dunque un agente non solo destrutturante a pi\u00f9 livelli, ma anche mutante, in positivo. Era una spada di Damocle che induceva gli Stati \u2013 quelli italiani prima degli altri in Europa \u2013 a darsi uomini e strutture capaci di farvi fronte<\/em>\u201d. In altre parole, nasce la sanit\u00e0 pubblica.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 la Chiesa decide di sospendere le funzioni funebri durante una pandemia?<\/strong><\/p>\n<p style=\"text-align: justify;\">La Chiesa \u00e8 sempre stata in prima linea di fronte alle epidemie. Se si calcolano i morti, di solito i religiosi sono quelli che in proporzione muoiono di pi\u00f9. Spesso sono stati gli unici \u201cinfermieri\u201d, e hanno gestito non solo questioni spirituali (confessioni, funerali\u2026) ma anche materiali. Per\u00f2 certamente non si sono adottati sempre e ovunque gli stessi metodi. Del resto non si sapeva molto delle malattie. Per alcuni dotti medici la causa erano i miasmi, per altri le congiunzioni astrali\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carlo_borromeo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44169 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carlo_borromeo.jpg\" alt=\"\" width=\"192\" height=\"242\" \/><\/a>Non sempre si sapeva che fare. E\u2019 noto per esempio che il cardinal Federigo Borromeo durante la peste di Milano, fece l\u2019impossibile per la sua gente. Ma richiesto insistentemente dai Decurioni della citt\u00e0 (i magistrati), di organizzare una processione religiosa imponente, per calmare la popolazione, dopo lunghi indugi cedette. E ci\u00f2 aument\u00f2 il contagio. In generale per\u00f2 la Chiesa ha collaborato con gli Stati pre-unitari anche per le quarantene.<\/p>\n<p style=\"text-align: justify;\">Celebre il caso della peste di Roma del 1656, gestita dal papa Alessandro VII e dal cardinal Gastaldi. Nello Stato pontificio la quarantena fu gestita con estremo rigore, generando prima forti lamentele, poi grandi elogi (Roma ne usc\u00ec con meno morti di tante altre citt\u00e0). Furono sospesi i commerci, le quarantore, le processioni pubbliche, privilegiando \u201cforme private e personali di devozione e preghiera\u201d.<\/p>\n<p style=\"text-align: justify;\">Durante la peste di Marsiglia, del 1721, il vescovo alla fine fece chiudere tutte le chiese. I preti celebravano da soli, dal momento che ci\u00f2 non toglie nulla al valore della Messa. A Pasqua per\u00f2 in alcune chiese la gente fece irruzione sfondando le porte sprangate\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/peste.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44179 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/peste.jpg\" alt=\"\" width=\"270\" height=\"187\" \/><\/a>In generale abbiamo una grande ricchezza di escamotage: preti che confessavano stando sulla soglia delle porte, o che davano la comunione tramite una canna; preti che giravano con il Santissimo, perch\u00e9 la gente pregasse dalle finestre; altari o colonne rialzati, al centro di piazze vuote, visibili da lontano\u2026 Ma abbiamo anche processioni soppresse, defunti senza funerale (per scarsit\u00e0 di clero, per divieti, per paura\u2026) ecc\u2026 magari senza la fretta e l\u2019eccesso di \u201cprudenza\u201d che c\u2019\u00e8 stata, ultimamente, a Roma\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Per concludere?<\/strong><\/p>\n<p style=\"text-align: justify;\">Due concetti, uno \u201cmedico\u201d, l\u2019altro filosofico. Il primo: siamo abituati a considerare le malattie infettive malattie del passato (recente, ma passato): questo soprattutto a causa \u201cdelle migliori condizioni igieniche ed alimentari\u201d affermatesi gradualmente in Occidente soprattutto dopo la II guerra mondiale . Condizioni che per\u00f2 non riguardano tutto il mondo. In un mondo globalizzato, infatti, le malattie infettive possono ritornare, visto che in una buona parte del globo le condizioni igieniche ed alimentari <a href=\"https:\/\/scienze.fanpage.it\/perche-i-virus-nascono-in-cina\/\" target=\"_blank\" rel=\"noopener noreferrer\">sono ancora pessime<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/creato.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-30505 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/creato.jpg\" alt=\"\" width=\"352\" height=\"197\" \/><\/a>Il secondo concetto lo lascio alle parole di Louis Pasteur, a cui dobbiamo la nascita della microbiologia, e cio\u00e8 dello studio di virus e batteri. Oltre che scienziato era un uomo di fede, e meditando sull\u2019uomo, mortale, ma capace di infinito, affermava: \u201c<em>Al di l\u00e0 di questa volta stellata che cosa c\u2019\u00e8? Nuovi cieli stellati. Sia pure! E al di l\u00e0 ancora? Lo spirito umano, spinto da una forza irresistibile, non smetter\u00e0 mai di chiedersi: che cosa c\u2019\u00e8 al di l\u00e0? Vuole esso fermarsi, sia nel tempo, sia nello spazio? Poich\u00e9 il punto dove esso si ferma \u00e8 solo una grandezza finita, soltanto pi\u00f9 grande di tutte quelle che l\u2019hanno preceduta, non appena egli comincia ad esaminarlo ritorna la domanda implacabile senza che egli possa far tacere il grido della sua curiosit\u00e0\u2026 Colui che proclama l\u2019esistenza dell\u2019infinito, e nessuno pu\u00f2 sfuggirvi, accumula in questa affermazione pi\u00f9 sovrannaturale di quanto non ce ne sia in tutti i miracoli, perch\u00e9 la nozione dell\u2019infinito ha la doppia caratteristica di imporsi e di essere insieme incomprensibile\u2026 Io vedo ovunque l\u2019inevitabile espressione della nozione dell\u2019infinito nel mondo. Attraverso essa, il soprannaturale \u00e8 in fondo a tutti i cuori<\/em>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Occidentale 2 Aprile 2020 Intervista di Graziano Davoli La pandemia ha attraversato tutte le fasi della storia dell\u2019umanit\u00e0. In questa intervista Francesco Agnoli ripercorre le tappe delle pestilenze e riflette sulle reazioni dell\u2019uomo e sul contributo che i principi cristiani hanno dato per superare le ore pi\u00f9 buie.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[2802,2338,162],"class_list":["post-46845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storia","tag-epidemie","tag-peste-nera","tag-storia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-08T22:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1580\" \/>\n\t<meta property=\"og:image:height\" content=\"888\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli\",\"datePublished\":\"2020-04-08T22:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/\"},\"wordCount\":1986,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/virus_peste.jpg\",\"keywords\":[\"epidemie\",\"peste nera\",\"storia\"],\"articleSection\":[\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/\",\"name\":\"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/virus_peste.jpg\",\"datePublished\":\"2020-04-08T22:00:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/virus_peste.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/virus_peste.jpg\",\"width\":1580,\"height\":888},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-04-08T22:00:07+00:00","og_image":[{"width":1580,"height":888,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli","datePublished":"2020-04-08T22:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/"},"wordCount":1986,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg","keywords":["epidemie","peste nera","storia"],"articleSection":["Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/","name":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg","datePublished":"2020-04-08T22:00:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/virus_peste.jpg","width":1580,"height":888},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dalla-peste-al-covid-19-luomo-di-fronte-alla-pandemia-intervista-a-francesco-agnoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"\u201cDalla peste al Covid-19, l\u2019uomo di fronte alla pandemia\u201d. Intervista a Francesco Agnoli"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=46845"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46845\/revisions"}],"predecessor-version":[{"id":46853,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46845\/revisions\/46853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46846"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=46845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=46845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=46845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}