{"id":46593,"date":"2020-03-12T00:00:48","date_gmt":"2020-03-11T23:00:48","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46593"},"modified":"2020-03-04T15:35:22","modified_gmt":"2020-03-04T14:35:22","slug":"i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/","title":{"rendered":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46600 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano-300x188.jpg\" alt=\"\" width=\"250\" height=\"157\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano-300x188.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano-768x480.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano-1024x640.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg 1280w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><a href=\"http:\/\/itresentieri.it\/\" data-rich-text-format-boundary=\"true\">l Cammino dei Tre Sentieri<\/a><\/strong><\/p>\n<p style=\"text-align: center;\">3 Marzo 2020<\/p>\n<p style=\"text-align: justify;\">Ormai \u00e8 frequentissimo vedere fedeli che vanno a comunicarsi prendendo l\u2019Eucaristia in mano. Chi \u00e8 favorevole, dice che Ges\u00f9 nel Cenacolo diede la prima Eucaristia nelle mani degli Apostoli. E inoltre che nei primi tempi della Chiesa non vi sarebbe stata l\u2019usanza di ricevere l\u2019Eucaristia direttamente in bocca. Ma \u00e8 proprio cos\u00ec?<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Prima di tutto facciamo parlare papa Giovanni Paolo II che nell\u2019<em>Ecclesia de Eucharistia<\/em> scrive al n.61:<em>\u201cDobbiamo badare con ogni premura a non attenuare alcuna dimensione o esigenza dell\u2019Eucaristia. Cos\u00ec ci dimostriamo veramente consapevoli della grandezza di questo dono. (\u2026) Non c\u2019\u00e8 pericolo di esagerare nella cura di questo Mistero!\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">Fatta questa autorevole premessa, veniamo al dunque.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/10\/comunione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-15317 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/10\/comunione.jpg\" alt=\"\" width=\"226\" height=\"169\" \/><\/a>A proposito del fatto che Ges\u00f9 nell\u2019Ultima Cena non diede agli Apostoli l\u2019Eucaristia direttamente in bocca ma in mano, va detto che ci\u00f2 non \u00e8 affatto scontato. Anzi, \u00e8 possibile supporre che Ges\u00f9 abbia dato il pane direttamente in bocca a ciascun apostolo. In Medio Oriente, al tempo di Ges\u00f9 vi era un\u2019usanza che perdura tuttora: il capofamiglia nutre i suoi ospiti con la propria mano, mettendo un pezzo simbolico di cibo nella bocca degli ospiti. Ma, ammesso e non concesso che sia andata davvero cos\u00ec, cio\u00e8 che Ges\u00f9 abbia dato l\u2019Eucaristia nelle mani degli apostoli, va fatta una precisazione importante: in quel momento gli Apostoli gi\u00e0 erano stati ordinati sacerdoti, addirittura sacerdoti in pienezza, quindi vescovi.<\/p>\n<p style=\"text-align: justify;\">Per quanto invece riguarda il secondo argomento e cio\u00e8 che i primi cristiani ricevessero la Comunione in mano vanno fatte due premesse.<\/p>\n<p style=\"text-align: justify;\"><strong>Prima premessa<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/Ges\u00f9_comunione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46601 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/Ges\u00f9_comunione.jpg\" alt=\"\" width=\"200\" height=\"199\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/Ges\u00f9_comunione.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/Ges\u00f9_comunione-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Non \u00e8 detto che ci\u00f2 che vi era nell\u2019antichit\u00e0 \u00e8 sempre migliore di ci\u00f2 che si \u00e8 approfondito e si \u00e8 istituzionalizzato in seguito. Liturgicamente, come \u00e8 sbagliato il <em>progressismo<\/em>, per cui ci\u00f2 che viene dopo sarebbe sempre migliore di ci\u00f2 che \u00e8 venuto prima, \u00e8 altrettanto sbagliato l\u2019<em>archeologismo<\/em>, ovvero ci\u00f2 che \u00e8 venuto prima sarebbe sempre migliore di ci\u00f2 che viene dopo.<\/p>\n<p style=\"text-align: justify;\"><strong>Seconda premessa<\/strong><\/p>\n<p style=\"text-align: justify;\">Nei primi secoli del Cristianesimo si facevano forti penitenze per l\u2019Eucaristia, per esempio ci si asteneva da qualsiasi cibo e bevanda dalla vigilia fino al momento della Comunione. Ora, se valesse il principio <em>archeologista<\/em>, bisognerebbe chiedere a tanti sostenitori della Comunione nella mano: perch\u00e9 non recuperare anche le rigide penitenze dei primi secoli? Se \u00e8 giusto riprendere ci\u00f2 che vi era all\u2019inizio, allora si riprendano anche le dure penitenze dell\u2019inizio. E\u2019 da prevedere che molti si tirerebbero indietro.<\/p>\n<p style=\"text-align: justify;\"><strong>Veniamo ai fatti<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/comunione_mano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32786 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/comunione_mano.jpg\" alt=\"\" width=\"247\" height=\"164\" \/><\/a>Davvero nei primi tempi della Chiesa l\u2019Eucaristia si riceveva nella mano? No, si tratta di un falso.<\/p>\n<p style=\"text-align: justify;\">Ci sono testimonianze certe che attestano come sin dall\u2019inizio era diffusa la consuetudine di deporre le sacre Specie sulle labbra dei comunicandi e anche della proibizione ai laici di toccare l\u2019Eucaristia con le mani. Solo in caso di necessit\u00e0 e in tempo di persecuzione, assicura per esempio san Basilio, si poteva derogare da questa norma e quindi era concesso anche ai laici di comunicarsi con le proprie mani.<\/p>\n<p style=\"text-align: justify;\">Papa Sisto I fu papa dal 115 al 125. Questi proib\u00ec ai laici di toccare i vasi sacri, per cui \u00e8 ampiamente fondato supporre che vietasse agli stessi di toccare le Sacre Specie eucaristiche.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/06\/comunione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7638 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/06\/comunione.jpg\" alt=\"\" width=\"227\" height=\"156\" \/><\/a>Sant\u2019Eutichiano, papa dal 275 al 283, affinch\u00e9 non toccassero l\u2019Eucaristia con le mani, proib\u00ec ai laici di portare le sacre Specie agli ammalati.<\/p>\n<p style=\"text-align: justify;\">Il Concilio di Saragozza, nel 380, eman\u00f2 la scomunica contro coloro che si fossero permessi di trattare la santissima Eucaristia come in tempo di persecuzione, tempo nel quale \u2013come abbiamo gi\u00e0 detto- anche i laici potevano trovarsi nella necessit\u00e0 di toccarla con le proprie mani.<\/p>\n<p style=\"text-align: justify;\">Sant\u2019Innocenzo I, dal 404, impose il rito della Comunione solo sulla lingua.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/comunione_lingua.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-21381 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/comunione_lingua.jpg\" alt=\"\" width=\"251\" height=\"167\" \/><\/a>Papa Sant\u2019Innocenzo I (401-417), nel 416, nella Lettera a Decenzio, Vescovo di Gubbio, che gli chiedeva direttive riguardo alla liturgia romana che intendeva adottare, rispose affermando per tutti l\u2019obbligo di rispettare al riguardo la Tradizione della Chiesa di Roma, perch\u00e9 essa discende dallo stesso Pietro, primo Papa. Ebbene, lo stesso Sant\u2019Innocenzo \u2013come abbiamo detto prima- dal 404 aveva imposto il rito della Comunione solo sulla lingua.<\/p>\n<p style=\"text-align: justify;\">San Gregorio Magno narra che sant\u2019Agapito, papa dal 535 al 536, durante i pochi mesi del suo pontificato, recatosi a Costantinopoli, guar\u00ec un sordomuto all\u2019atto in cui <em>\u201cgli metteva in bocca il Corpo del Signore\u201d,<\/em> dunque l\u2019Eucaristia si dava direttamente in bocca.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/comunione_ginocchio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32923 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/comunione_ginocchio.jpg\" alt=\"\" width=\"252\" height=\"168\" \/><\/a>Il Concilio di Rouen, verso il 650, proib\u00ec al ministro dell\u2019Eucaristia di deporre le sacre Specie sulla mano del comunicando laico: <em>\u201c(Il sacerdote) badi a comunicarli (i fedeli) di propria mano, non ponga l\u2019Eucaristia in mano a nessun laico o donna, ma la deponga solo sulle labbra con queste parole\u2026\u201d <\/em><\/p>\n<p style=\"text-align: justify;\">Sulla medesima linea il Concilio Costantinopolitano III (680-681), sotto i pontefici Agatone e Leone II, viet\u00f2 ai fedeli di comunicarsi con le proprie mani e minacci\u00f2 la scomunica a chi avesse avuto la temerariet\u00e0 di farlo.<\/p>\n<p style=\"text-align: justify;\">Il Sinodo di Cordoba dell\u2019anno 839 condann\u00f2 la setta dei \u201ccasiani\u201d a causa del loro rifiuto di ricevere la sacra Comunione direttamente in bocca.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/Comunione_ginocchio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-39895 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/Comunione_ginocchio.jpg\" alt=\"\" width=\"222\" height=\"166\" \/><\/a>In Occidente, il gesto di prostrarsi e inginocchiarsi prima di ricevere il Corpo del Signore si osservava negli ambienti monastici gi\u00e0 a partire dal VI secolo (per esempio nei monasteri di san Colombano) Pi\u00f9 tardi nei secoli X e XI questo gesto si diffuse ancora di pi\u00f9.<\/p>\n<p style=\"text-align: justify;\">Quando san Tommaso d\u2019Aquino espose nella <em>Summa<\/em> (III, 9, 82) i motivi che vietavano ai laici di toccare le sacre Specie, non parl\u00f2 di un rito di recente invenzione, bens\u00ec di consuetudine liturgica antica come la Chiesa.<\/p>\n<p style=\"text-align: justify;\">Ecco perch\u00e9 il Concilio di Trento (Decreto sull\u2019Eucaristia, Sessione III) pot\u00e9 affermare che non solo nella Chiesa di Dio fu una consuetudine costante che i laici ricevessero la Comunione dai sacerdoti, mentre i sacerdoti si comunicassero da s\u00e9, ma anche che tale consuetudine \u00e8 di origine apostolica: <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/06\/adorazione_eucaristica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-31578 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/06\/adorazione_eucaristica.jpg\" alt=\"\" width=\"234\" height=\"187\" \/><\/a>\u201c<em>Nell\u2019assunzione di questo Sacramento (l\u2019Eucaristia) fu<\/em> <strong><em>sempre<\/em><\/strong> <em>costume nella Chiesa di Dio che i laici ricevessero la comunione dai Sacerdoti e i Sacerdoti celebranti invece comunicassero se stessi,<\/em> <strong><em>costume che con ogni ragione deve ritenersi come proveniente dalla Tradizione apostolica<\/em><\/strong><em>.\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">Abbiamo iniziato con papa Giovanni Paolo II, concludiamo con lui. Sempre nella <em>Ecclesia de Eucharistia<\/em>, al n.49, scrive:\u00a0<em>\u201cSull\u2019onda dell\u2019elevato senso del mistero si comprende come la fede della Chiesa nel mistero eucaristico si sia espressa nella storia non solo attraverso l\u2019istanza di un interiore atteggiamento di devozione, ma anche attraverso una serie di espressioni esterne.\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>l Cammino dei Tre Sentieri 3 Marzo 2020 Ormai \u00e8 frequentissimo vedere fedeli che vanno a comunicarsi prendendo l\u2019Eucaristia in mano. Chi \u00e8 favorevole, dice che Ges\u00f9 nel Cenacolo diede la prima Eucaristia nelle mani degli Apostoli. E inoltre che nei primi tempi della Chiesa non vi sarebbe stata l\u2019usanza di ricevere l\u2019Eucaristia direttamente in &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,42],"tags":[157,1487,458],"class_list":["post-46593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-dottrina-e-morale","tag-chiesa-2","tag-comunione-sulla-mano","tag-dottrina-e-morale-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T23:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano\",\"datePublished\":\"2020-03-11T23:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/\"},\"wordCount\":1067,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chiesa_comunione_mano.jpg\",\"keywords\":[\"chiesa\",\"comunione sulla mano\",\"dottrina e morale\"],\"articleSection\":[\"Chiesa\",\"Dottrina e morale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/\",\"name\":\"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chiesa_comunione_mano.jpg\",\"datePublished\":\"2020-03-11T23:00:48+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chiesa_comunione_mano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chiesa_comunione_mano.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/","og_locale":"it_IT","og_type":"article","og_title":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-03-11T23:00:48+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano","datePublished":"2020-03-11T23:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/"},"wordCount":1067,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg","keywords":["chiesa","comunione sulla mano","dottrina e morale"],"articleSection":["Chiesa","Dottrina e morale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/","name":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg","datePublished":"2020-03-11T23:00:48+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/chiesa_comunione_mano.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-documenti-parlano-chiaro-la-comunione-si-e-sempre-presa-direttamente-in-bocca-e-non-in-mano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I documenti parlano chiaro:\u00a0 la Comunione si \u00e8 sempre presa direttamente in bocca e non in mano"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=46593"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46593\/revisions"}],"predecessor-version":[{"id":46603,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46593\/revisions\/46603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46600"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=46593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=46593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=46593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}