{"id":46397,"date":"2020-02-27T00:00:40","date_gmt":"2020-02-26T23:00:40","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46397"},"modified":"2020-02-13T15:25:01","modified_gmt":"2020-02-13T14:25:01","slug":"senza-comunione-nessuna-salvezza","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/","title":{"rendered":"Senza comunione nessuna salvezza"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/Stanislaw_Grygiel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45387 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/Stanislaw_Grygiel.jpg\" alt=\"\" width=\"225\" height=\"164\"><\/a>Tempi<\/strong> n.1 Gennaio 2020<\/p>\n<p style=\"text-align: justify;\"><em>Un grande filosofo si interroga sulla crisi dell\u2019Europa, \u00abche non \u00e8 politica o economica ma di ammirazione della Trascendenza\u00bb. Solo tornando al principio potr\u00e0 recuperare le sue fondamenta, racchiuse nella risposta alla domanda \u00abQuid est Veritas? Vir qui adest\u00bb. <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Stanislaw Grygiel<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">L&#8217;Europa \u00e8 un evento spirituale, non geografico o puramente politico. Avviene nelle persone. Non \u00e8 perci\u00f2 possibile comprendere l&#8217;Europa senza prima porre la domanda su chi sia la persona umana, perch\u00e9 \u00e8 solo in lei che accadono gli eventi spirituali.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-44141 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa-300x218.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa-768x558.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa-1024x744.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Europa_medioevo_mappa.jpg 1629w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La domanda sull&#8217;Europa \u00e8 in fondo la domanda &#8220;qual \u00e8 la verit\u00e0 dell&#8217;uomo?&#8221;. \u00c8 l&#8217;uomo o, meglio, \u00e8 ci\u00f2 che accade in lui come un dono particolare da lui ricevuto nel Principio che decise e continua a decidere dell&#8217;evento spirituale che si chiama Europa.<\/p>\n<p style=\"text-align: justify;\">Dobbiamo, quindi, ogni giorno ritornare a questo Principio, se vogliamo non solo conoscere l&#8217;Europa ma anche essere europei. Non basta saper fare la sociologia, la psicologia, l&#8217;ecologia e altre scienze di questo genere per poter edificare la casa europea.<\/p>\n<p style=\"text-align: justify;\">Le fondamenta dell&#8217;Europa sono gettate laddove si delinea l&#8217;orizzonte che il domandare metafisico e l&#8217;aspettare la risposta appena sfiorano. Quando parlano dell&#8217;Europa, le cosiddette scienze esatte parlano di qualcosa d&#8217;altro, perch\u00e9 essa non s&#8217;identifica con oggetti costituiti e formati da calcoli che spiegano sempre ipoteticamente il loro funzionamento d&#8217;oggi e cercano di prevedere quello di domani.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/Europa_bandiera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38732 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/Europa_bandiera.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>L&#8217;Europa ridotta ad un oggetto di calcoli economici e politici \u00e8 sempre da riformare in modo economico e politico. Gli eventi spirituali non sono per\u00f2 da riformare. Chi cerca di riformare la persona umana, deve prima renderla oggetto, cio\u00e8 deve negarla. La riforma non salva la persona. Di conseguenza, non salver\u00e0 nemmeno l&#8217;Europa.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Europa o rinasce nelle persone in cui nasce oppure muore, quando queste persone dimenticano chi siano e chi, allora, debbano divenire. Ci\u00f2 significa che per l&#8217;Europa non c&#8217;\u00e8 alcuna salvezza fuori delle persone nelle quali \u00e8 nata. Quando parlo del rinascere della persona, parlo insieme con san Tommaso d&#8217;Aquino del ritornare dell&#8217;uomo ai Principi che decidono del suo inizio. Parlo allora dell&#8217;atto della creazione da cui scaturisce la bellezza della verit\u00e0 e del bene di ogni essere creato. Se non c&#8217;\u00e8 Dio, non c&#8217;\u00e8 la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/stelle_Europa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31436 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/stelle_Europa.jpg\" alt=\"\" width=\"187\" height=\"269\"><\/a>Tutto ci\u00f2 che funziona come verit\u00e0 non \u00e8 che un&#8217;opinione tra le altre opinioni. Il loro principio si trova nell&#8217;uomo che si mette a crearle sotto l&#8217;effetto di costruzioni emozionali, chiamate amore, giustizia, misericordia, pace e cos\u00ec via. Esse dipendono dal passare del tempo, dai venti di moda e dagli interessi del momento, e in fin dei conti dalle voglie degli uomini ridotti a essere individui.<\/p>\n<p style=\"text-align: justify;\">Se la rinascita non ha niente a che fare con i processi tecnici, tutti coloro che pensano di poter riformare l&#8217;uomo lo chiudono nel tempo e nello spazio, cos\u00ec che in quei processi si chiudono anche il progresso e lo sviluppo, perdendo senso e valore. La visione dello sviluppo e del progresso dell&#8217;Europa dipende dalla visione del progresso e dello sviluppo dell&#8217;uomo europeo.<\/p>\n<p style=\"text-align: justify;\">La visione del progresso e dello sviluppo dipende dalla qualit\u00e0 delle domande in cui pensiamo l&#8217;uomo e il futuro da lui mirato. Non \u00e8 facile comprendere il significato del verbo &#8220;rinascere&#8221;, perch\u00e9 non \u00e8 facile pensare il futuro dell&#8217;uomo. Quando questo futuro viene chiuso nel tempo, la domanda sull&#8217;uomo e, di conseguenza, sul suo rinascere cade nelle trappole ideologiche.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Ges\u00f9_icona.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31467 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Ges\u00f9_icona.jpg\" alt=\"\" width=\"198\" height=\"255\"><\/a>Non basta guardarsi nello specchio La domanda sul significato del verbo &#8220;rinascere&#8221; tormentava Nicodemo, grande dotto d&#8217;Israele. Egli viene di notte da Ges\u00f9, perch\u00e9 ha paura degli altri dotti, i farisei, e Gli chiede: \u00abRabbi, sappiamo che sei un maestro venuto da Dio; nessu\u00adno infatti pu\u00f2 fare i segni che tu fai, se Dio non \u00e8 con lui\u00bb. La risposta di Ges\u00f9 lo stupisce. Il dotto non capisce che Ges\u00f9 gli parla della rinascita che viene dall&#8217;alto, dallo Spirito che \u00absoffia dove vuole\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00c8 tanto convinto che l&#8217;uomo nasca solo car\u00adnalmente da pensare che chi parla della rinascita dell&#8217;uomo parla del suo rientro nel grembo materno. Alla sua domanda di come l&#8217;uomo possa rientrare in sua madre, Cristo gli risponde con una domanda ironica: \u00abTu sei maestro in Israele e non sai queste cose?\u00bb (cfr. Gv 3,1 e ss.).<\/p>\n<p style=\"text-align: justify;\">L&#8217;uomo rinasce nello spirito e nella verit\u00e0 nell&#8217;incontro dell&#8217;altra persona. In quest&#8217;incontro avviene l&#8217;epifania della verit\u00e0, in cui l&#8217;uomo si rivela e si realizza come persona. L&#8217;evento della verit\u00e0 ha luogo sia nella domanda dell&#8217;antico epigramma: \u00abQuid sit veritas?\u00bb che nella risposta che indica l\u2019ad-venire di questa verit\u00e0 nell&#8217;altra persona: \u00abVeritas est vir qui adest\u00bb &#8211; verit\u00e0 \u00e8 la persona presente ad un&#8217;altra persona.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Europa_flag.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32014 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Europa_flag.jpg\" alt=\"\" width=\"271\" height=\"161\"><\/a>Nelle persone presenti l&#8217;una all&#8217;altra nascono le loro comunioni: il matrimonio, la famiglia, la nazione, la Chiesa. Non rinascono, allora, coloro che non dimorano che in se stessi. Non vedono chi essi stessi siano. Non basta guardarsi nello specchio oppure in quell&#8217;altro che sessualmente non \u00e8 differente.<\/p>\n<p style=\"text-align: justify;\">L&#8217;omosessualit\u00e0 non ha il carattere epifanico. Essa odora di narcisismo. La verit\u00e0 si rivela solo nelle persone e tra le persone, creando in loro la comunione, nella quale una persona per l&#8217;altra diventa munus &#8211; il dovere. Il loro vivere cum munere crea la communio personarum sul fondamento del reciproco affidarsi (la fede), sul riporre fiducia nelle conseguenze di questo affidarsi (la speranza) e sul donarsi all&#8217;altra fino ad offrire la vita per lei (l&#8217;amore).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/adamo_eva.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32239 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/adamo_eva.jpg\" alt=\"\" width=\"250\" height=\"202\"><\/a>Rinascono dunque gli uomini che ritornano alla verit\u00e0 che avviene tra di loro ma che scaturisce dal Principio, cio\u00e8 dall&#8217;atto della creazione in cui Dio crea l&#8217;uomo maschio e femmina. La primordiale comunione creata dall&#8217;affidamento di Eva ad Adamo e di Adamo ad Eva costituisce il dialogo primordiale in cui si rivela e si realizza la verit\u00e0 dell&#8217;uomo.<\/p>\n<p style=\"text-align: justify;\">Dall&#8217;esperienza di questo dialogo provengono gli obblighi morali, propri dell&#8217;amore, della fede e della speranza. Il latino munus significa dovere. Possiamo dire che gi\u00e0 nell&#8217;atto della creazione, cio\u00e8 nel Principio, l&#8217;uomo \u00e8 obbligato a vivere nella verit\u00e0 del suo essere persona. Perci\u00f2 solo chi vive ritornando continuamente all&#8217;atto della creazione, vivendo cio\u00e8 cum munere, rinasce. Rinasce in Spirito (dialogo) e in verit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Ges\u00f9_croce.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44362 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Ges\u00f9_croce.jpg\" alt=\"\" width=\"130\" height=\"194\"><\/a>In altre parole, extra communionem personarum nulla salus per noi, gli uomini. Paradigma di ogni comunione delle persone, paradigma creato da Dio, \u00e8 la relazione dei doveri che sono l&#8217;uomo per la donna e la donna per l&#8217;uomo. Cristo cerca di elevare lo sguardo di Nicodemo alle altezze divine dove paradigma di ogni comunione delle persone \u00e8 la Santissima Trinit\u00e0. Gli rivela ci\u00f2 dicendo che \u00abDio infatti ha tanto amato il mondo da dare il Suo Figlio unigenito, perch\u00e9 chiunque crede in lui non muoia, ma abbia la vita eterna\u00bb (Gv 3,16).<\/p>\n<p style=\"text-align: justify;\">Con il negare l&#8217;atto della creazione, l&#8217;ateismo nega la comunione primordiale delle persone e, di conseguenza, nega la verit\u00e0 dell&#8217;uomo che si rivela nella rela\u00adzione dialogale dell&#8217;uomo e della donna. Negando la fede nell&#8217;altro fino a dare la vita per lui, negando cos\u00ec grande amore e speranza, l&#8217;ateismo corrompe non solo la Chiesa, ma anche il matrimonio, la famiglia, la nazione.<\/p>\n<p style=\"text-align: justify;\">Non c&#8217;\u00e8 quindi da meravigliarsi che l&#8217;Europa come societ\u00e0 costruita per qualcosa di infinitamente pi\u00f9 grande del carbone e dell&#8217;acciaio degeneri in una massa di individui, cio\u00e8 in un&#8217;ombra della societ\u00e0 delle persone. L&#8217;Europa dimentica di essere evento spirituale, anzi l&#8217;Europa ha in odio l\u2019esserlo. Gli eventi spirituali non risultano dalle operazioni della ragione (ratio) illuminata dai numeri che vi sono presenti (Cartesio).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Europa_allegoria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32102 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Europa_allegoria.jpg\" alt=\"\" width=\"260\" height=\"194\"><\/a>Non risultano dalla praxis produttiva. Avvengono infatti nel dialogo dell&#8217;uomo con l&#8217;alterit\u00e0 che egli ritrova nell&#8217;altra persona. L&#8217;alterit\u00e0 lo trascende e l&#8217;affascina. La Trascendenza divina seduce e porta l&#8217;uomo nel paese proprio dell&#8217;Alterit\u00e0. Lo seduce e ve lo porta come Zeus, che travestito da toro bianco rapisce Europa, la figlia del re di Tiro e Sidone.<\/p>\n<p style=\"text-align: justify;\">In quanto evento spirituale l&#8217;Europa avviene nel nostro ammirare l&#8217;Alterit\u00e0 Divina e nella speranza che questa Alterit\u00e0 si stia avvicinando, speranza ridestata dalla bellezza della stessa Alterit\u00e0 nelle sue epifanie. Perci\u00f2 la crisi dell&#8217;Europa non \u00e8 tanto crisi politica oppure economica, quanto crisi dell&#8217;ammirazione della Trascendenza, crisi degli europei che non si affidano pi\u00f9 all&#8217;Alterit\u00e0 che li chiama a camminare verso di lei. Il qualunquismo delle procedure<\/p>\n<p style=\"text-align: justify;\">La crisi dell&#8217;evento che \u00e8 l&#8217;Europa accade su due livelli, poich\u00e9 \u00e8 da due sorgenti che essa scaturisce. L&#8217;Europa nasce infatti da un lato nella domanda dei greci sulla verit\u00e0 dell&#8217;uomo e nella loro ricerca della risposta ad essa, e, da un altro lato, nella profezia che in Gerusalemme sfidava il cielo con questa domanda.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Socrate_Filosofi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46402 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Socrate_Filosofi.jpg\" alt=\"\" width=\"174\" height=\"232\"><\/a>La domanda &#8220;chi \u00e8 l&#8217;uomo?&#8221; mirava alla sua salvezza, che dovrebbe cadere sulla terra come salvifica rugiada. I profeti di Gerusalemme avevano intravisto la salvezza per l&#8217;uomo nel Servo Giusto e Sofferente che, per quelli che vissero la croce e la resurrezione, \u00e8 Ges\u00f9 Cristo il Figlio del Dio vivente. In Atene primo europeo \u00e8 Socrate. Il suo domandare e cercare la verit\u00e0 provocarono la sua morte, nella quale l&#8217;Europa cominci\u00f2 a profilarsi al desiderio dei cuori e delle menti dei greci di conoscere come stessero le cose con l&#8217;universo e con l&#8217;uomo.<\/p>\n<p style=\"text-align: justify;\">La domanda sulla verit\u00e0 e la ricerca della risposta ad essa rendevano Socrate libero dalle opinioni (doxa) che, trattate come risposte alle domande fondamentali sulla verit\u00e0 dell&#8217;uomo, non sono che pi\u00f9 o meno intelligenti ideologie. I profeti conquistavano la libert\u00e0 ponendo la stessa domanda sulla verit\u00e0 dell&#8217;uomo ma per parte loro in modo orante, vale a dire adorando Colui dalle cui labbra aspettavano la risposta. Quest&#8217;evento salvifico accade sulla croce sulla quale muore Cristo, rendendo testimonianza alla verit\u00e0 divino-umana dell&#8217;uomo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/germoglio_pianta_agricoltura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46403 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/germoglio_pianta_agricoltura.jpg\" alt=\"\" width=\"222\" height=\"227\"><\/a>L&#8217;amore di Dio di cui Cristo parla a Nicodemo non conosce che un limite: l&#8217;amore stesso. Il chicco di grano che muore getta\u00adto nella terra per amore degli uomini reca loro il frutto centuplicato. Grande \u00e8 il contributo di Roma al costituirsi dell&#8217;Europa in una societ\u00e0 ordinata dalle leggi. Esse danno la forma sociale alle domande greche fondamentali per la vita ed anche alla profezia di Gerusalemme. Per\u00f2 la forma della vita non \u00e8 mai la vita stessa.<\/p>\n<p style=\"text-align: justify;\">Perci\u00f2 la domanda se l&#8217;Europa rinascer\u00e0 o morir\u00e0 ha per oggetto non tanto in che forma l&#8217;Europa continuer\u00e0 a vivere, quanto se gli europei saranno ancora europei indipendentemente dalla forma che l&#8217;Europa possa assumere. Questa domanda mira al futuro dell&#8217;evento spirituale dell&#8217;identit\u00e0 culturale (e non solo) degli europei.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/europa_allegoria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32041 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/europa_allegoria.jpg\" alt=\"\" width=\"270\" height=\"187\"><\/a>Senza dubbio nessuna riforma formale potr\u00e0 salvare questo evento nelle persone. Deve essere salvato l&#8217;evento stesso che si chiama Europa. L&#8217;Europa non \u00e8 da riparare, perch\u00e9 non si lascia ridurre ad un oggetto che esiga ogni tanto una qualche riparazione. In altri termini, non basta cambiare opinioni politiche oppure economiche sull&#8217;Europa perch\u00e9 essa migliori.<\/p>\n<p style=\"text-align: justify;\">La doxa funzioner\u00e0 sempre come principio della schiavit\u00f9. Friedrich H\u00f2lderlin metteva in guardia contro il qualunquismo delle leggi e delle procedure costruite da gente affidata soltanto al proprio cogito che le inventa:<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Le leggi sono buone, tuttavia Come i denti dei draghi tagliano E ammazzano la vita, quando le irrigidisce l&#8217;infuriato Villano oppure il re<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Gorgia_Platone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46404 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Gorgia_Platone.jpg\" alt=\"\" width=\"164\" height=\"234\"><\/a>Le leggi e le procedure staccate dall&#8217;evento spirituale lo annichiliscono. I politici del nihilismo hanno come modello quel Callide del Gorgia di Platone che, dopo aver separato le leggi della natura dalla natura dell&#8217;uomo, aveva rigettato i valori immutabili, non riconoscendo come bene comune che il benessere.<\/p>\n<p style=\"text-align: justify;\">La sete di potere nichilistico porta sempre disgra\u00adzie e calamit\u00e0 per lo Stato (cfr Platone, Repubblica, 520, d, 521, b). Il nihilismo giuridico e procedurale serpeggiava sempre in Europa. Ma cominci\u00f2 a dare la forma micidiale alla vita di quest&#8217;evento spirituale, quale \u00e8 l&#8217;Europa, quando, invece di continuare a legarsi con l&#8217;essere dell&#8217;uomo e dell&#8217;universo, il pensiero europeo inizi\u00f2 a far prevalere su di loro le opinioni e le voglie del cogito che impone alla realt\u00e0 ci\u00f2 che trova in se stesso. Esso vi trova i numeri.<\/p>\n<p style=\"text-align: justify;\">Chiuso in essi il cogito divenne pura ra\u00adtio, calcolo. Persino l&#8217;idea di Dio venne da esso ridotta cos\u00ec. Facendo parte della cultura razionalistica che non ha nulla a che fare con la profezia di Gerusalemme e con il suo compimento nella persona di Cristo, quest&#8217;idea di Dio cade insieme con la cultura razionalistica nel caos e con essa vi muore.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43042 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-300x199.jpg\" alt=\"\" width=\"249\" height=\"165\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-300x199.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-768x510.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-1024x680.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese.jpg 1401w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Le grandi rivoluzioni, francese, comunista, nazista e sessuale, sono soltanto sintomi mortali della ma\u00adlattia che oggi consuma la societ\u00e0 (anche quella ecclesiale) e che io chiamerei &#8220;bastard\u00eda&#8221; provocata dall&#8217;oblio del padre e della madre. Il nihilismo e il relativismo che in esso viene a spadroneggiare risultano dal tradimento di se stessa da parte dell&#8217;Europa.<\/p>\n<p style=\"text-align: justify;\">Le persone e quindi anche l&#8217;Europa che nasce in loro tradiscono se stesse non ritornando ai propri Principi, cio\u00e8 non rinascendo. Nel nihilismo in cui cadono, le parole vengono contraffatte. Nessuna di esse indica i valori non negoziabili, senza i quali la verit\u00e0 non \u00e8 pi\u00f9 verit\u00e0, l&#8217;amicizia non \u00e8 amicizia, il matrimonio non \u00e8 matrimonio, la famiglia non \u00e8 famiglia e in fin dei conti la Chiesa cessa di essere Chiesa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/censura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-45249 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/censura-300x168.jpg\" alt=\"\" width=\"257\" height=\"144\"><\/a>Se non sono profetiche, le parole non appartengono alla verit\u00e0 di ci\u00f2 che \u00e8. Possono essere assegnate a qualunque cosa. La postmodernit\u00e0, per potere cambiare il senso delle parole, deve per forza odiare la profezia e la domanda in essa presente: \u00abQuid sit veritas?\u00bb<\/p>\n<p style=\"text-align: justify;\">Non si accorge che l&#8217;uomo, privo della Parola nelle sue parole, si fa catturare dal niente. Cristo dice in modo &#8220;chiaro e distinto&#8221;: \u00abSe rimanete fedeli alla mia parola, sarete davvero miei discepoli; conoscerete la verit\u00e0 e la verit\u00e0 vi far\u00e0 liberi\u00bb (Gv 8,31-32).<\/p>\n<p style=\"text-align: justify;\">Non crediamo di credere I greci identificavano la verit\u00e0 con la giu\u00adstizia, in cui vedevano \u00abla figlia di Zeus\u00bb (Eschilo, Coefore, v. 970-972). Diventa giusto chi rende giustizia alla verit\u00e0. Allora l&#8217;uomo giusto \u00e8 libero. Socrate disse che \u00abvive peggio (\u2026) chi ha malvagit\u00e0 nell&#8217;anima, e non se ne libera\u00bb (Platone, Gorgia, 478). Queste parole dovrebbero essere incise sulle porte di tutti gli uffici pubblici in Europa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/matematica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33489 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/matematica.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>I greci credevano che l&#8217;ingiustizia fosse \u00abfiglia della tracotanza\u00bb (hybris &#8211; Platone, Leggi, 691 c). La tracotanza della gente postmoderna consegue dalla convinzione che, dominando i numeri, la ragione umana pu\u00f2 dominare tutto. La ragione calcolante costringe l&#8217;uomo a non riconoscere le leggi che nascono nell&#8217;esperienza dei doveri, cio\u00e8 nell&#8217;esperienza della presenza delle altre persone, e ad arrogarsi il diritto di decidere persino della vita e della morte di tutto e di tutti.<\/p>\n<p style=\"text-align: justify;\">Non vivendo in timore Dei, l&#8217;uomo calco\u00adlante ha per\u00f2 paura dei pi\u00f9 forti di lui, cos\u00ec da non dire la verit\u00e0 persino quando la dice. \u00c8 lui che oggi sta distruggendo l&#8217;Europa e la Chiesa in tutti i continenti. Egli sradica dalla verit\u00e0 coloro che si sono affidati al greco domandare su di essa e a cercarla. Ne sradica ancora pi\u00f9 crudel\u00admente quelli che nella fede e nell&#8217;amore hanno posto la loro speranza in Dio, indicato e chiamato a discendere dal cielo sulla terra dai profeti di Gerusalemme, e che Lo hanno incontrato nel Suo Figlio venuto ad abitare in mezzo a noi per ricordarci l&#8217;atto della creazione in cui Egli \u00e8 \u00abcentro dell&#8217;universo e della storia\u00bb (Redemptor hominis, 1).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/Cristo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35526 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/Cristo.jpg\" alt=\"\" width=\"159\" height=\"226\"><\/a>La vita degli uomini sradicati dall&#8217;atto della creazione non ha n\u00e9 senso, n\u00e9 valore. Gli uomini sradicati dal \u00abcentro dell&#8217;universo e della storia\u00bb si sottomettono a effimere leggi e procedure cos\u00ec da dire, seguendo il Kirilow dei Demoni di Dostoevskij, che \u00abse crediamo, non crediamo di credere, e se non crediamo, non crediamo di non credere\u00bb. Vengono in mente le parole di Cristo: \u00abMa il Figlio dell&#8217;uomo, quando verr\u00e0, trover\u00e0 la fede sulla terra?\u00bb (Le 18,8). Hanno paura della domanda<\/p>\n<p style=\"text-align: justify;\">Potr\u00e0 l&#8217;Europa rinascere dalle ceneri in cui solo qua e l\u00e0 si vede ancora la brace ardente di Dio? Affinch\u00e9 il dono della speranza non sia tolto ai nostri cuori e alle nostre menti, dobbiamo non solo alzarci, ma anche andare ai Principi (efr 1 Mac 9,8; Gv 14,31).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/01\/manif_pour_tous.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34222 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/01\/manif_pour_tous.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>Solo entrando nella dimora indicata dalla domanda: \u00abQuid sit veritas?\u00bb e dalla risposta: \u00abVeritas est vir qui adest\u00bb, possiamo diventare luogo della rinascita dell&#8217;Europa. Questa domanda e questa risposta avvengono laddove si \u00e8 in due o tre&#8230; Perci\u00f2 dobbiamo rimetterci a edificare le amicizie, i matrimoni, le famiglie, le nazioni e permettere a Dio di edificare in essi la Sua Chiesa.<\/p>\n<p style=\"text-align: justify;\">\u00c8 in queste comunioni delle persone che la bellezza della verit\u00e0 e del bene avverr\u00e0 e risveglier\u00e0 nel nostro intimo la memoria di essere soggetti quali siamo in Principio, liberandoci dalle opinioni su chi siamo. I padroni del nihilismo hanno paura di queste epifanie comunionali della verit\u00e0 dell&#8217;uomo, cio\u00e8 delle amicizie, dei matrimoni, delle famiglie e della Chiesa.<\/p>\n<p style=\"text-align: justify;\">Ognuna di queste epifanie limita il loro potere e lo mette in questione. Hanno paura dell&#8217;affidamento reciproco delle persone e della voce di Dio che nelle loro coscienze morali le chiama a non uscire dalla via dell&#8217;amore, della speranza e della fede che le conduce alla verit\u00e0 cercata e allo stesso tempo attesa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/famiglia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40720 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/famiglia.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>Hanno paura della domanda che matura fino a diventare preghiera, con la quale le persone chiedono al cielo che lasci scendere la verit\u00e0 sulla terra. Hanno paura della sovranit\u00e0 e della libert\u00e0 delle persone. Hanno paura delle persone che, come Socrate a Callide, nel Gorgia di Platone, direbbero a ciascuno di loro: \u00abCredo, o carissimo, che sarebbe meglio che la mia lira fosse scordata e stonata, e che lo fosse il coro che io dirigessi, e che la maggior parte della gente non fosse d&#8217;accordo con me e mi contraddicesse, piuttosto che sia io, anche se sono uno solo, ad essere in disaccordo con me stesso e a contraddirmi\u00bb (Platone, Gorgia, 482 b-c).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/matrimonio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28543 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/matrimonio.jpg\" alt=\"\" width=\"257\" height=\"153\"><\/a>La storia si ripete. Anche oggi l&#8217;eterno domandante, Abramo, sta cercando i dieci giusti per salvare l&#8217;Europa. La loro giustizia resa alla verit\u00e0 \u00abnon si confuta mai\u00bb (Platone, Gorgia, 473 b). Difende gli uomini dal caos della loro ragione calcolante e, di conseguenza, dalla schiavit\u00f9 dai padroni del nihilismo, aiutando gli uomini a edificare la casa (oikos) la cui legge (n\u00f3mos) nata dall&#8217;amore per la terra natale (nom\u00f3s) che si estende negli uomini gliela fa coltivare per il bene comune.<\/p>\n<p style=\"text-align: justify;\">I confini di tale oiko-nomia sono tracciati dai caratteri delle persone che mirano al \u00abcentro dell&#8217;universo e della storia\u00bb. Nella casa dell&#8217;oiko-nomia divino-umana non c&#8217;\u00e8 posto per i pretendenti di Penelope, che rendono la casa di Odisseo una taverna di piacere e gridano a Telemaco, che sta per partire alla ricerca del padre: \u00abScemo! Andiamo a mangiare e bere!\u00bb (Omero, Odissea, II).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/deserto_solitudine.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44368 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/deserto_solitudine.jpg\" alt=\"\" width=\"277\" height=\"182\"><\/a>L&#8217;oiko-nomia divino-umana rifiuta categoricamente il principio che oggi sta rovinando l&#8217;Europa, e in essa anche la Chiesa: la praxis precede il Logos fino ad essere eretta alla dignit\u00e0 di \u00abcentro dell&#8217;universo e della storia\u00bb. Chi professa questo principio marxista, fosse anche vescovo, espelle gli uomini dalla casa paterna, oiko-nomia, e li condanna a vivere \u00abin un paese lontano\u00bb dove privi della terra natale (nom\u00f3s) e delle sue leggi (n\u00f3mos) dimorano nella miseria della solitudine. \u00abAlzatevi, andiamo via di qui!\u00bb (Gv 14,31)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi n.1 Gennaio 2020 Un grande filosofo si interroga sulla crisi dell\u2019Europa, \u00abche non \u00e8 politica o economica ma di ammirazione della Trascendenza\u00bb. Solo tornando al principio potr\u00e0 recuperare le sue fondamenta, racchiuse nella risposta alla domanda \u00abQuid est Veritas? Vir qui adest\u00bb. di Stanislaw Grygiel<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1347,166],"class_list":["post-46397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa-e-ue","tag-crisi-morale","tag-europa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senza comunione nessuna salvezza - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senza comunione nessuna salvezza - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T23:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2670\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Senza comunione nessuna salvezza\",\"datePublished\":\"2020-02-26T23:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/\"},\"wordCount\":3225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/decadenza.jpg\",\"keywords\":[\"crisi morale\",\"Europa\"],\"articleSection\":[\"Europa e UE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/\",\"name\":\"Senza comunione nessuna salvezza - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/decadenza.jpg\",\"datePublished\":\"2020-02-26T23:00:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/decadenza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/decadenza.jpg\",\"width\":2670,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/senza-comunione-nessuna-salvezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senza comunione nessuna salvezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senza comunione nessuna salvezza - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/","og_locale":"it_IT","og_type":"article","og_title":"Senza comunione nessuna salvezza - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-02-26T23:00:40+00:00","og_image":[{"width":2670,"height":1335,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Senza comunione nessuna salvezza","datePublished":"2020-02-26T23:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/"},"wordCount":3225,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg","keywords":["crisi morale","Europa"],"articleSection":["Europa e UE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/","name":"Senza comunione nessuna salvezza - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg","datePublished":"2020-02-26T23:00:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/decadenza.jpg","width":2670,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/senza-comunione-nessuna-salvezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Senza comunione nessuna salvezza"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=46397"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46397\/revisions"}],"predecessor-version":[{"id":46406,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46397\/revisions\/46406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46398"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=46397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=46397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=46397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}