{"id":46388,"date":"2020-02-20T00:00:59","date_gmt":"2020-02-19T23:00:59","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46388"},"modified":"2020-02-13T12:27:42","modified_gmt":"2020-02-13T11:27:42","slug":"mio-padre-era-un-sovversivo-perche-cristiano","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/","title":{"rendered":"Mio padre era un sovversivo. Perch\u00e9 cristiano"},"content":{"rendered":"<p style=\"text-align: center;\"><strong> <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/corea_nord_comunismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46394 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/corea_nord_comunismo.jpg\" alt=\"\" width=\"226\" height=\"160\" \/><\/a>Tempi <\/strong>n. 1 gennaio 2020 <strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Quando Sang-Hwa scopr\u00ec che i genitori avevano un Bibbia, avrebbe dovuto denunciarli. Storia di una conversione nel &#8220;paradiso dei Kim&#8217;<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Cristian Nani<\/strong> (*)<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Corea del Nord, un folle esperimento antropologico per oltre 25 milioni di abi\u00adtanti, costretti a vivere nel &#8220;paradiso dei Kim&#8221;, un regno eremita, isolato dal mondo, perennemente in stato di guerra contro un immaginario nemico alle porte imperialista, in cui alla dinastia dei leader, i Kim, \u00e8 dovuto un vero e proprio culto, supportato da una ideologia ufficiale socialista che ha di fatto portato la nazione al fallimento.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Corea_Nord.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44184 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Corea_Nord-300x180.jpg\" alt=\"\" width=\"282\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Corea_Nord-300x180.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Corea_Nord.jpg 620w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/a>Qui, nelle viscere di una societ\u00e0 plagiata dalla follia del regime, si muovono tra i 200 e i 400 mila cristiani, costretti a vivere la fede in segreto, ad incontrarsi nei boschi, in cantine, braccati dalle autorit\u00e0, sorvegliati da tutti, dove a denunciarti \u00e8 l&#8217;amico, il parente, il vicino, poich\u00e9 la delazione \u00e8 materia di studio obbligatoria, propedeutica al bene della nazione.<\/p>\n<p style=\"text-align: justify;\">Tra i 40 e i 70 mila cristiani languono nei brutali campi di rieducazione nordcoreani: chi ne \u00e8 uscito vivo, racconta di torture ed esecuzioni degne dei campi di concentramento nazisti.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/corea_cristiani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41068 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/corea_cristiani.jpg\" alt=\"\" width=\"284\" height=\"177\" \/><\/a>Sang-Hwa \u00e8 stata istruita a tradire famiglia, amici e vicini. Ma quando per caso scopr\u00ec la Bibbia segreta dei suoi genitori, scelse di intraprendere il loro pe\u00adricoloso viaggio di fede. E scopr\u00ec la Chiesa segreta, un network clandestino di fedeli che sopravvivono solo grazie al supporto della famiglia cristiana fuori dal paese.<\/p>\n<p style=\"text-align: justify;\">\u00abSiamo morti\u00bb, furono le parole che pronunci\u00f2 Kim Sang-Hwa, nordcoreana fuggita dal paese, quando si rese conto di cosa avesse trovato. Ci parla con voce monotona e calma, con sospiri lunghi e improvvise piccole accelerazioni. Disse di aver lanciato quel libro lontano da s\u00e9, come se scottasse. Aveva 12 anni quando rinvenne per puro caso la Bibbia segreta dei genitori mentre erano fuori casa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/corea_gulag.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27526 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/corea_gulag.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>\u00abAvevo letto solo la prima frase: &#8220;In principio Dio cre\u00f2 il cielo e la terra&#8221; e mi vennero i brividi. Ero cos\u00ec spaventata!\u00bb. E aveva ragione ad essere terrorizzata. Era stata istruita per questa impensabile eventualit\u00e0 sin da quando aveva iniziato la scuola primaria. A scuola, aveva imparato a leggere, scrivere e denunciare i propri familiari. Il sistema scolastico nordcoreano era ed \u00e8 costruito per scovare e punire chiunque devii dalla &#8220;religione di Stato&#8221;.<\/p>\n<p style=\"text-align: justify;\">Avendo vissuto l&#8217;intera vita in quello Stato-prigione, Sang-Hwa seppe immediatamente che quello strano libro dei genitori era pericoloso: s\u00ec, perch\u00e9 in Corea del Nord la Bibbia \u00e8 un libro illegale. Sapeva anche che era suo dovere denunciare i genitori. Non avevano alcuna importanza le conseguenze: l&#8217;amore non significa nulla, la lealt\u00e0 alla nazione veniva prima. E nella sua nazione era permesso adorare solo il leader e la sua famiglia.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Ges\u00f9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-41328 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Ges\u00f9.jpg\" alt=\"\" width=\"126\" height=\"182\" \/><\/a>Se i suoi genitori adoravano Ges\u00f9, solo un destino era possibile: \u00abFu uno shock per me vedere la Bibbia. Quel libro era anti-rivoluzionario. Se qualcuno veniva trovato in possesso di una Bibbia, nel 100 per cento dei casi finiva in un campo di lavori forzati\u00bb.<\/p>\n<p style=\"text-align: justify;\">Che fare dunque? Denunciarli alle autorit\u00e0 o affrontarli, chiedere loro conto del &#8220;libro&#8221; e rischiare lei stessa di essere uccisa? Le autorit\u00e0 non erano leggere con chi esitava in questi casi e comminavano la stessa pena. \u00abA malapena riuscii a nasconderla dov&#8217;era, tanto ero sconvolta. Non sapevo che fare. Ero piccola: dovevo dirlo alla mia maestra a scuola o alle autorit\u00e0?\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Vangelo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32023 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Vangelo.jpg\" alt=\"\" width=\"245\" height=\"205\" \/><\/a>Sang-Hwa mantenne il segreto per alcune settimane, poi: \u00abAlla fine decisi di affrontare mio padre: quella fu l&#8217;occasione in cui mi introdusse al Vangelo\u00bb. Non sapeva che il padre, nel segreto, pregava incessantemente da cinque anni per capire quale fosse il momento giusto per condividere questo segreto con la figlia.<\/p>\n<p style=\"text-align: justify;\">In Corea del Nord i cristiani non hanno una chiesa, non si possono incontrare o pregare Dio: Sang-Hwa era cresciuta in una famiglia cristiana senza saperlo. Esistono delle chiese fantoccio a Pyongyang, usate dal regime per convincere il resto del mondo che in Corea del Nord c&#8217;\u00e8 libert\u00e0 di fede.<\/p>\n<p style=\"text-align: justify;\">Sang-Hwa fu sopraffatta dalle parole del padre. La sua vita cambi\u00f2 totalmente, abbracci\u00f2 la fede cristiana rompendo ogni resistenza. Il suo cuore era ricolmo di qualcosa di nuovo e mai provato: speranza e amore. La sua vita divenne ad un tratto pericolosa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46395 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>Venne presto introdotta in un network clandestino, una chiesa segreta, composta da uomini e donne, costretti a incontrarsi al calare del buio, come spie, in luoghi appartati e sempre diversi. \u00c8 un vero miracolo che questa rete di credenti nascosti esista, ma la cosa ancor pi\u00f9 miracolosa \u00e8 che secondo le stime di Open Doors\/Porte Aperte tale rete \u00e8 cresciuta negli ultimi vent&#8217;anni. Open Doors\/Porte Aperte raggiunge con aiuti di prima necessit\u00e0 (cibo, medicine e vestiario) 60.000 nordcoreani, offrendo anche rifugio e soccorso a coloro che fuggono in Cina.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/05\/preghiera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-31587 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/05\/preghiera.jpg\" alt=\"\" width=\"223\" height=\"150\" \/><\/a>Ogni volta che qualcuno decide di condividere un incoraggiamento, una parola o attitudine cristiana o direttamente il Vangelo, di fatto mette la propria vita in pericolo.<\/p>\n<p style=\"text-align: justify;\">\u00abI nordcoreani si affidano interamente a Dio e l&#8217;un l&#8217;altro. C&#8217;\u00e8 un detto nel nostro paese: &#8220;Quando tre di noi si incontrano, uno \u00e8 una spia&#8221;. Devi per forza affidare l&#8217;intera tua vita a Dio\u00bb conclude Sang-Hwa, la quale oggi \u00e8 fuggita dal paese e vive all&#8217;estero.<\/p>\n<p style=\"text-align: justify;\"><strong>(*)<\/strong> Direttore Porte Aperte\/Open Doors Onlus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi n. 1 gennaio 2020 \u00a0 Quando Sang-Hwa scopr\u00ec che i genitori avevano un Bibbia, avrebbe dovuto denunciarli. Storia di una conversione nel &#8220;paradiso dei Kim&#8217; di Cristian Nani (*)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,71,44,108],"tags":[139,2397,470,545],"class_list":["post-46388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-corea-del-nord","category-cristiani-perseguitati","category-paesi-e-continenti","tag-comunismo","tag-corea-del-nord","tag-cristiani-perseguitati-2","tag-paesi-e-continenti-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T23:00:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Mio padre era un sovversivo. Perch\u00e9 cristiano\",\"datePublished\":\"2020-02-19T23:00:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/\"},\"wordCount\":863,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Corea_soldati_comunismo.jpg\",\"keywords\":[\"comunismo\",\"Corea del Nord\",\"cristiani perseguitati\",\"paesi e continenti\"],\"articleSection\":[\"Comunismo\",\"Corea del Nord\",\"Cristiani perseguitati\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/\",\"name\":\"Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Corea_soldati_comunismo.jpg\",\"datePublished\":\"2020-02-19T23:00:59+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Corea_soldati_comunismo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Corea_soldati_comunismo.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mio-padre-era-un-sovversivo-perche-cristiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mio padre era un sovversivo. Perch\u00e9 cristiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/","og_locale":"it_IT","og_type":"article","og_title":"Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-02-19T23:00:59+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Mio padre era un sovversivo. Perch\u00e9 cristiano","datePublished":"2020-02-19T23:00:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/"},"wordCount":863,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg","keywords":["comunismo","Corea del Nord","cristiani perseguitati","paesi e continenti"],"articleSection":["Comunismo","Corea del Nord","Cristiani perseguitati","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/","name":"Mio padre era un sovversivo. Perch\u00e9 cristiano - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg","datePublished":"2020-02-19T23:00:59+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/Corea_soldati_comunismo.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mio-padre-era-un-sovversivo-perche-cristiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Mio padre era un sovversivo. Perch\u00e9 cristiano"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=46388"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46388\/revisions"}],"predecessor-version":[{"id":46396,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46388\/revisions\/46396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46391"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=46388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=46388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=46388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}