{"id":46155,"date":"2020-01-27T00:00:06","date_gmt":"2020-01-26T23:00:06","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46155"},"modified":"2020-01-28T09:14:45","modified_gmt":"2020-01-28T08:14:45","slug":"il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/","title":{"rendered":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/Salvini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41454 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/Salvini.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/Salvini.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/Salvini-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>L\u2019Occidentale<\/strong> 27 gennaio 2020<\/p>\n<p style=\"text-align: center;\">di <strong>Eugenio Capozzi <\/strong><\/p>\n<p style=\"text-align: justify;\">Per interpretare subito sgombrare il campo da due letture assolutamente fuorvianti: dalla tesi, cio\u00e8, secondo cui il risultato emiliano-romagnolo rappresenti una vittoria del Partito democratico, e da quella secondo cui esso sia una sconfitta personale di Salvini.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Riguardo al primo punto, \u00e8 evidente che quello del centrosinistra \u00e8 stato innanzitutto un successo personale di <strong>Stefano Bonaccini<\/strong>. Il governatore ha fatto campagna evitando ostentatamente ogni simbolo di partito, puntando tutto sulla propria leadership, cercando di mantenere il pi\u00f9 possibile la contesa su un piano locale senza coinvolgere gli equilibri nazionali, e i risultati lo hanno premiato.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Giorgia_Meloni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46159 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Giorgia_Meloni.jpg\" alt=\"\" width=\"267\" height=\"160\" \/><\/a>Dei quasi 8 punti di vantaggio con cui ha prevalso sulla sfidante Lucia Borgonzoni, soltanto 2,7 provengono dalla differenza di voti tra le due coalizioni (centrosinistra 48,1, centrodestra 45,4), mentre i rimanenti circa 5 sono dovuti al voto disgiunto a suo favore, da parte di elettori che non hanno votato alcun partito o addirittura da elettori di 5Stelle e destra. In pi\u00f9, nella somma dei voti di coalizione il Pd ha conseguito il 34,7%, quasi 10 punti in meno delle elezioni del 2014, mentre ben l\u20198,4% dei consensi proviene da 2 liste civiche \u201cpersonalizzate\u201d (contro lo scarso 2% di liste analoghe nelle precedenti regionali).<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Stefano_Bonaccini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46160 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Stefano_Bonaccini.jpg\" alt=\"\" width=\"253\" height=\"161\" \/><\/a>Bonaccini, insomma, vince non tanto grazie al Pd, ma nonostante il Pd<\/strong>, e costruendo un profilo autonomo da quel partito, secondo una strategia completamente opposta a quella perseguita qualche mese fa, con risultati rovinosi, dal centrosinistra nelle consultazioni umbre.<\/p>\n<p style=\"text-align: justify;\">Egli si \u00e8 proposto in primo luogo come garante in prima persona della sopravvivenza del sistema di potere socio-economico locale, fondato sul legame tra intervento pubblico (Ue, governo, regione) e la rete delle cooperative, dei sindacati, dei servizi sociali, delle banche locali, compattandolo (soprattutto nel nucleo forte Bologna-Modena-Reggio) contro il rischio di ridimensionamento associato ad una possibile vittoria della Lega, e quindi del modello amministrativo liberista\/federalista proprio di Lombardia o Veneto.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/PD_crisi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-40682 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/PD_crisi.jpg\" alt=\"\" width=\"263\" height=\"158\" \/><\/a>Di questo sistema corporativista regionale il Pd \u00e8 ormai poco pi\u00f9 che il referente nazionale, la cinghia di raccordo, ancora necessario in quanto l\u2019alternativa grillina si \u00e8 rivelata, per la salvaguardia di quegli interessi, inutile e fallimentare.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma come soggetto politico autonomo esso si limita ad andare al traino, attestandosi poco pi\u00f9 sopra dei livelli \u2013 rispetto alla sua tradizione locale per nulla esaltanti \u2013 raggiunti nelle elezioni europee, e al massimo riassorbendo una minima parte dei consensi che erano sfuggiti verso i lidi pentastellati.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/primarie-Pd.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30572 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/primarie-Pd.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>Se si somma questa situazione ai risultati calabresi (e alle prospettive attuali per le altre regioni che si avvicinano al voto) si comprende chiaramente come questa tornata elettorale non smentisca il processo di progressiva marginalizzazione del Pd e della sinistra in Italia, in corso da anni, ma si inserisca in quel processo.<\/p>\n<p style=\"text-align: justify;\">Se in tutto l\u2019Occidente le sinistre di radici socialiste si vanno sempre pi\u00f9 riducendo a partito minoritario delle \u00e9lite urbane, \u201cpartito ZTL\u201d, in Italia la sinistra gi\u00e0 comunista e post-comunista si limita a sommare a quella base sociale neo-borghese i sistemi di potere locali radicati in due regioni \u2013 Emilia e Toscana \u2013 che comunque, elezione dopo elezione, appaiono sempre pi\u00f9 come un \u201cbunker\u201d sotto assedio.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/grillini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28561 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/grillini.jpg\" alt=\"\" width=\"252\" height=\"168\" \/><\/a>Sul piano della politica nazionale, in questo momento la posizione di vantaggio del Pd \u00e8 data dalla fortunosa conquista del governo, messa in atto qualche mese fa con la collaborazione dei 5Stelle gi\u00e0 in grave crisi, e dalla disperata resistenza di gran parte dei rappresentanti di quel movimento alla prospettiva di elezioni anticipate per la quasi certezza di essere esclusi dal prossimo parlamento \u2013 resistenza assecondata dal Quirinale e dai vertici Ue.<\/p>\n<p style=\"text-align: justify;\">Ma il vero e proprio tracollo sub\u00ecto dai grillini nelle elezioni emiliane crea uno squilibrio talmente accentuato nell\u2019equilibrio di coalizione che potrebbe generare ben presto effetti ben diversi da quel consolidamento oggi atteso dai pi\u00f9, ed anzi un rapido degenerare della situazione politica nella totale ingovernabilit\u00e0, ponendo il Pd bruscamente di fronte a tutte le proprie difficolt\u00e0 strutturali.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-42608 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega-300x215.jpg\" alt=\"\" width=\"269\" height=\"193\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega-300x215.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega-768x549.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega-1024x732.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Salvini_lega.jpg 2000w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" \/><\/a>Per quanto riguarda poi il secondo punto, \u00e8 un errore sostenere che il risultato emiliano-romagnolo rappresenti una sconfitta personale di <strong>Salvini<\/strong>, sottolineata dalla forte personalizzazione da lui imposta alla campagna elettorale. Il centrodestra da lui guidato ha infatti conseguito, come ricordato sopra, il 45,4% dei voti di lista, rispetto al 29,7% del 2014, colmando il vuoto lasciato dai 5Stelle e attestandosi a pochi punti dalla sinistra indiscutibilmente egemone in quei territori da 70 anni.<\/p>\n<p style=\"text-align: justify;\">La Lega ha quasi raddoppiato i voti non solo rispetto al 2014, ma anche alle politiche del 2018, mantenendosi, con il 31,9%, praticamente ai livelli raggiunti lo scorso anno alle europee (33,7%), ma nel contesto ben pi\u00f9 arduo di una contesa locale in una regione in cui il suo radicamento, rispetto a quello del Pd, \u00e8 molto minore.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Lega.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-40397 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Lega.png\" alt=\"\" width=\"190\" height=\"190\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Lega.png 224w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Lega-150x150.png 150w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/a>Si critica Salvini perch\u00e9 ha impostato tutta la campagna sul piano nazionale molto pi\u00f9 che locale, e perch\u00e9 la ha ostentatamente personalizzata trasformandola in una sorta di referendum su se stesso e in una sfida per o contro il governo, oscurando cos\u00ec la sua candidata.<\/p>\n<p style=\"text-align: justify;\">Ma nelle condizioni date \u2013 la sfida ad una \u201cfortezza\u201d di potere locale consolidata da decenni, e la classe dirigente a disposizione del centrodestra locale attualmente \u2013 sarebbe stato molto difficile per lui pensare ad una differente strategia per poter almeno tentare di cambiare gli equilibri e sovvertire il pronostico.<\/p>\n<p style=\"text-align: justify;\">L\u2019arroccamento del sistema locale ha prevalso, ma il risultato della Lega, come quello di Fratelli d\u2019Italia, testimonia che una forte breccia nel campo avversario \u00e8 stata aperta, e difficilmente il leader leghista \u2013 cos\u00ec come la Borgonzoni \u2013 oggi poteva fare di pi\u00f9.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/forza-italia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29100 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/forza-italia.jpg\" alt=\"\" width=\"169\" height=\"239\" \/><\/a>Il segno pi\u00f9 preoccupante che arriva al centrodestra dai risultati di queste consultazioni, semmai, \u00e8 la vera e propria d\u00e9bacle di Forza Italia, crollata alla percentuale irrisoria del 2,56% dal 9,9% delle politiche 2018 e dal 5,87% delle europee 2019. Una d\u00e9bacle a cui si somma il risultato \u201cdi testimonianza\u201d della lista Cambiamo! Insieme al Popolo della Famiglia (0,3%).<\/p>\n<p style=\"text-align: justify;\"><strong>Questi dati testimoniano nella maniera pi\u00f9 immediata il vuoto che si \u00e8 creato nell\u2019area liberale e cattolica della destra a trazione sovranista, rimasta praticamente sguarnita. E dovrebbero indurre l\u2019intera coalizione ad una riflessione e ad un confronto su come riempire efficacemente quel vuoto.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/immigrati_disordini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-39903 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/immigrati_disordini.jpg\" alt=\"\" width=\"257\" height=\"156\" \/><\/a>Se insomma sull\u2019immigrazione, il confronto con l\u2019Ue, l\u2019ordine pubblico e la sicurezza Lega e Fdi riescono a incontrare con successo le richieste di una parte consistente dell\u2019opinione pubblica, viceversa sui temi della crescita economica, della libert\u00e0 d\u2019impresa, delle garanzie contro gli abusi giudiziari, delle politiche familiari viceversa manca ancora, evidentemente, una voce abbastanza forte ed autorevole, soprattutto in contesti locali difficili come quello emiliano-romagnolo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/bunker_guerra.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46161 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/bunker_guerra.jpg\" alt=\"\" width=\"263\" height=\"158\" \/><\/a>In queste elezioni, ad esempio, per abbattere l\u2019ultimo muro del \u201cbunker\u201d sarebbe stato necessario convincere i tanti elettori legati all&#8217;\u201dindotto\u201d del corporativismo emiliano che in termini di lavoro, benessere, sviluppo, welfare, il modello amministrativo lombardo e veneto \u00e8 pi\u00f9 vantaggioso, oltre che pi\u00f9 rispettoso delle libert\u00e0 individuali e delle scelte familiari.<\/p>\n<p style=\"text-align: justify;\">Ma a tale scopo \u00e8 necessaria una forza ben pi\u00f9 strutturata, dal punto di vista organizzativo e culturale, in senso liberal-conservatore. Da questo punto di vista, la destra attuale ha ancora parecchio lavoro da fare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Occidentale 27 gennaio 2020 di Eugenio Capozzi Per interpretare subito sgombrare il campo da due letture assolutamente fuorvianti: dalla tesi, cio\u00e8, secondo cui il risultato emiliano-romagnolo rappresenti una vittoria del Partito democratico, e da quella secondo cui esso sia una sconfitta personale di Salvini.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[442,2788,2701,1183,297],"class_list":["post-46155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","tag-centrodestra","tag-lega","tag-matteo-salvini","tag-pd","tag-politica-nazionale-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-26T23:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-28T08:14:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale\",\"datePublished\":\"2020-01-26T23:00:06+00:00\",\"dateModified\":\"2020-01-28T08:14:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/\"},\"wordCount\":1159,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Lega_Salvini_Emilia.jpg\",\"keywords\":[\"centrodestra\",\"Lega\",\"Matteo Salvini\",\"PD\",\"politica nazionale\"],\"articleSection\":[\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/\",\"name\":\"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Lega_Salvini_Emilia.jpg\",\"datePublished\":\"2020-01-26T23:00:06+00:00\",\"dateModified\":\"2020-01-28T08:14:45+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Lega_Salvini_Emilia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Lega_Salvini_Emilia.jpg\",\"width\":1600,\"height\":616},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/","og_locale":"it_IT","og_type":"article","og_title":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2020-01-26T23:00:06+00:00","article_modified_time":"2020-01-28T08:14:45+00:00","og_image":[{"width":1600,"height":616,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale","datePublished":"2020-01-26T23:00:06+00:00","dateModified":"2020-01-28T08:14:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/"},"wordCount":1159,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg","keywords":["centrodestra","Lega","Matteo Salvini","PD","politica nazionale"],"articleSection":["Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/","name":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg","datePublished":"2020-01-26T23:00:06+00:00","dateModified":"2020-01-28T08:14:45+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Lega_Salvini_Emilia.jpg","width":1600,"height":616},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-pd-e-sempre-piu-marginale-e-localistico-ma-la-destra-ha-bisogno-di-una-nuova-spinta-liberale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il Pd \u00e8 sempre pi\u00f9 marginale e localistico, ma la destra ha bisogno di una\u00a0nuova spinta liberale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=46155"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46155\/revisions"}],"predecessor-version":[{"id":46162,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/46155\/revisions\/46162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46156"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=46155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=46155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=46155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}