{"id":452,"date":"2005-05-11T15:19:48","date_gmt":"2005-05-11T13:19:48","guid":{"rendered":""},"modified":"2016-03-10T14:16:51","modified_gmt":"2016-03-10T13:16:51","slug":"reo-pentito-la-pena-deve-continuare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/","title":{"rendered":"Reo pentito? La pena deve continuare"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31556\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg\" alt=\"carcere\" width=\"250\" height=\"170\" \/>Il Timone<\/strong> n. 31, Marzo 2004<\/div>\n<p style=\"text-align: justify;\"><em>Riflessioni in margine al caso Sofri: la pena deve ristabilire l&#8217;uguaglianza tra gli uomini infranta dal reo, perci\u00f2 non basta il pentimento per reclamarne la conclusione. Essa restituisce dignit\u00e0 al reo, ma moltissimi cattolici lo hanno dimenticato.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giacomo Samek Lodovici<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Mentre scrivo questo articolo non so come andr\u00e0 avanti la proposta di legge per ottenere la grazia per Sofri, che svariati processi hanno dichiarato essere il mandante dell&#8217;assassinio di Luigi Calabresi. Non so se la potentissima lobby degli amici di Sofri riuscir\u00e0 nel suo intento, ma questa ennesima puntata del caso Sofri offre lo spunto per fare alcune considerazioni sulla funzione della pena. Infatti, molti ripetono continuamente che Sofri \u00e8 cambiato ed \u00e8 pentito, perci\u00f2 non ha pi\u00f9 senso la continuazione della pena.<\/div>\n<p style=\"text-align: justify;\">Ora, anche se ammettessimo che sia vero il pentimento di Sofri, quest&#8217;argomentazione denuncia un gravissimo errore circa la funzione della pena, ed esprime una teoria della pena sbagliatissima, che \u00e8 ormai purtroppo dilagata paurosamente anche nel mondo cattolico, tra teologi, sacerdoti, credenti, ecc., secondo cui la pena ha due funzioni: 1) rieducativa, cio\u00e8 ha lo scopo di produrre il pentimento, il ravvedimento del reo; 2) preventiva-difensiva, cio\u00e8 ha lo scopo di evitare nuove minacce all&#8217;incolumit\u00e0 della societ\u00e0, esercitando un&#8217;azione intimidatrice nei confronti del reo e di coloro che potrebbero emularlo.<\/p>\n<p style=\"text-align: justify;\">Queste due funzioni della pena sono giuste, ma non sono sufficienti e debbono essere integrate da una terza fondamentale funzione, quella retributiva. Essa consiste in un atto di contraccambio al reato compiuto, \u00e8 il corrispettivo, proporzionato, del male commesso dal reo, che ristabilisce la giustizia. Infatti, ciascun uomo vive con gli altri uomini in un rapporto di uguaglianza, di reciprocit\u00e0, di simmetria. Ora, che cosa fa il reo?<\/p>\n<p style=\"text-align: justify;\">Egli cancella questa uguaglianza, infrange questa reciprocit\u00e0, ottiene un vantaggio indebito a spese degli altri. Perci\u00f2, come chi ha guadagnato un vantaggio ingiusto deve risarcirlo, come chi si \u00e8 arricchito illecitamente deve restituire il maltolto e come una squadra sportiva che ha barato deve essere penalizzata, cos\u00ec il reo che ha commesso un reato che ha rilevanza penale deve subire una pena afflittiva, per scontare il male che ha compiuto.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 afflittiva? Perch\u00e9 il reo ha prevaricato con la sua volont\u00e0 e la sua libert\u00e0 sulla volont\u00e0 e la libert\u00e0 dei suoi simili, perci\u00f2 la pena deve affliggere la sua volont\u00e0 e la sua libert\u00e0 per riequilibrare il male che egli ha compiuto. Non solo, ma il reo, prevaricando sui suoi simili, ha abdicato alla propria dignit\u00e0, perci\u00f2 la pena, facendogli espiare il male compiuto, gli restituisce quella dignit\u00e0 che egli ha perso; in tal modo, come dice Platone, la cosa peggiore che pu\u00f2 capitare ad un uomo non \u00e8 commettere ingiustizia, ma commettere ingiustizia e non venire punito, perch\u00e9 chi non viene punito non recupera la propria dignit\u00e0 che ha leso. Ci\u00f2 significa che esiste un diritto-dovere dello Stato di punire, ma anche un diritto del reo di essere punito dallo Stato (anche se il reo non ne \u00e8 quasi mai consapevole): il reo ha il diritto di essere punito per poter recuperare la propria dignit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Qual \u00e8 la differenza con la vendetta? La vendetta vuole danneggiare il reo, invece la pena come retribuzione ha un&#8217;intenzione diversa: ristabilire l&#8217;uguaglianza infranta dal reo e ridargli la dignit\u00e0 che egli ha perso, quindi non vuole il male del reo, ma il suo bene. Fare del male a qualcuno non vuol dire sempre fare il male morale: il padre che punisce il figlio che ha sbagliato gli fa male, ma non fa del male morale, anzi fa del bene morale, e fa il bene del figlio.\u00a0Qual \u00e8 la differenza con la legge del taglione?<\/p>\n<p style=\"text-align: justify;\">\u00c8 vero che la pena dev&#8217;essere proporzionata, ma non guarda solo ai fatti (occhio per occhio), ma anche alle intenzioni, alla consapevolezza e alla premeditazione del reo; inoltre la logica del taglione colpisce anche chi non c&#8217;entra (se x uccide i figli di y, y per ritorsione uccide i figli di x), mentre la pena retributiva affligge solo il responsabile di un male.<\/p>\n<p style=\"text-align: justify;\">Un ultima obiezione dice che il male compiuto non si pu\u00f2 cancellare, e che la pena aggiunge un nuovo male a quello gi\u00e0 compiuto. In realt\u00e0, come ho gi\u00e0 accennato, nessuno pretende che il male sia cancellato, il male resta; con la pena si vuole ristabilire l&#8217;uguaglianza tra gli uomini, quindi la pena non aggiunge un nuovo male a quello gi\u00e0 esistente, bens\u00ec fa del bene.<\/p>\n<p style=\"text-align: justify;\">Il discorso che ho fin qui sviluppato \u00e8 stato teorizzato in modo simile da grandi filosofi come Platone, Kant ed Hegel. Ma non \u00e8 contrario al cristianesimo? Mi basta citare il pi\u00f9 grande filosofo e teologo cristiano di tutti i tempi, S. Tommaso, che spiega che la pena \u00abtende principalmente a un bene al quale si giunge mediante la punizione dei colpevoli, per esempio al loro emendamento [funzione rieducativa], o almeno alla repressione del male per la pubblica quiete [funzione preventiva-difensiva], oppure alla tutela della giustizia e all&#8217;onore di Dio [funzione retributiva]\u00bb (<em>Somma teologica,<\/em> II-II, q. 108).<\/p>\n<p style=\"text-align: justify;\">Ma il cristianesimo non dice di perdonare? Certo, ma il perdono concerne il colpevole e non toglie la colpa: se la pena fosse solo rieducativa, nel sacramento della confessione non avrebbe senso comminare la penitenza al peccatore, che \u00e8 gi\u00e0 pentito. Invece, pur essendo gi\u00e0 pentito e pur essendo gi\u00e0 stato perdonato, il peccatore riceve una penitenza, che \u00e8 una retribuzione afflittiva del male che ha compiuto, e ci\u00f2 dimostra che il perdono e la punizione non sono alternativi, bens\u00ec complementari.<\/p>\n<p style=\"text-align: justify;\">Del resto la funzione retributiva della pena \u00e8 chiaramente indicata dal <em>Catechismo della Chiesa Cattolica<\/em>: \u00abLa pena ha innanzi tutto lo scopo di riparare il disordine introdotto dalla colpa\u00bb (2266). Un altro esempio clamoroso di retribuzione \u00e8 l&#8217;inferno, come si comprende chiaramente dal fatto che esso perdurer\u00e0 anche dopo la fine del mondo.<\/p>\n<p style=\"text-align: justify;\">Infatti, \u00e8 chiaro che dopo la fine del mondo la pena dell&#8217;inferno non pu\u00f2 avere una funzione rieducativa, in quanto i dannati non possono essere rieducati, n\u00e9 una funzione preventiva ed intimidatrice, perch\u00e9 non esiste pi\u00f9 nessuno che sulla terra possa ricavare un monito da essa: dunque dopo la fine del mondo l&#8217;inferno conserva solo una funzione retributiva.<\/p>\n<p style=\"text-align: justify;\">Il vangelo non \u00e8 almeno incompatibile con la funzione difensiva della pena? Non chiede di porgere l&#8217;altra guancia? Si, ma porgere l&#8217;altra guancia non esclude la liceit\u00e0 della legittima difesa che, dice il Catechismo, \u00aboltre che un diritto, pu\u00f2 anche essere un grave dovere, per chi \u00e8 responsabile della vita degli altri\u00bb (n. 2265), perch\u00e9 io posso scegliere di porgere l&#8217;atra guancia se qualcuno aggredisce me, ma ho il dovere di reagire se qualcuno aggredisce chi \u00e8 sotto la mia responsabilit\u00e0 (per es. se io sono un padre e qualcuno aggredisce mio figlio, oppure se sono un governante e qualcuno mette in pericolo i cittadini che io devo tutelare).<\/p>\n<p style=\"text-align: justify;\">Per mancanza di spazio devo fermarmi qui, sperando che dal poco che ho potuto dire sia chiaro che non basta il pentimento di un reo per chiedere la conclusione della pena. E se proprio si ritiene di concedergli la grazia \u00e8 imprescindibile che egli la chieda.<\/p>\n<p style=\"text-align: justify;\"><strong>Ricorda<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abL&#8217;arte di procurar ricchezze [&#8230;] libera dalla povert\u00e0, la medicina dalla malattia, e la giustizia libera dalla dissolutezza e dall&#8217;ingiustizia. [&#8230;] Dunque [&#8230;] il fare ingiustizia e non scontare la pena \u00e8 veramente il pi\u00f9 grande e il primo di tutti i mali\u00bb. (Platone, <em>Gorgia<\/em>, 478 A &#8211; 479 E).<\/p>\n<p style=\"text-align: justify;\"><strong>Bibliografia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Vittorio Mathieu,<\/strong><em>Perch\u00e9 punire? Il collasso della giustizia penale<\/em>, Rusconi 1978, specialmente pp. 73-298. Catechismo della Chiesa Cattolica, punti 2261-2266.<\/p>\n<div style=\"text-align: justify;\" align=\"justify\"><strong>Tommaso d&#8217;Aquino<\/strong>, <em>Somma teologica<\/em>, II-II, q. 108. Platone, Gorgia, 477 E &#8211; 479 E.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n. 31, Marzo 2004 Riflessioni in margine al caso Sofri: la pena deve ristabilire l&#8217;uguaglianza tra gli uomini infranta dal reo, perci\u00f2 non basta il pentimento per reclamarne la conclusione. Essa restituisce dignit\u00e0 al reo, ma moltissimi cattolici lo hanno dimenticato. di Giacomo Samek Lodovici<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[180],"class_list":["post-452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto","tag-diritto-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-11T13:19:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-10T13:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"272\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Reo pentito? La pena deve continuare\",\"datePublished\":\"2005-05-11T13:19:48+00:00\",\"dateModified\":\"2016-03-10T13:16:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/\"},\"wordCount\":1258,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/carcere.jpg\",\"keywords\":[\"diritto\"],\"articleSection\":[\"Diritto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/\",\"name\":\"Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/carcere.jpg\",\"datePublished\":\"2005-05-11T13:19:48+00:00\",\"dateModified\":\"2016-03-10T13:16:51+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/carcere.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/carcere.jpg\",\"width\":272,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/reo-pentito-la-pena-deve-continuare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reo pentito? La pena deve continuare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/","og_locale":"it_IT","og_type":"article","og_title":"Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-11T13:19:48+00:00","article_modified_time":"2016-03-10T13:16:51+00:00","og_image":[{"width":272,"height":185,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Reo pentito? La pena deve continuare","datePublished":"2005-05-11T13:19:48+00:00","dateModified":"2016-03-10T13:16:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/"},"wordCount":1258,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg","keywords":["diritto"],"articleSection":["Diritto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/","name":"Reo pentito? La pena deve continuare - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg","datePublished":"2005-05-11T13:19:48+00:00","dateModified":"2016-03-10T13:16:51+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/carcere.jpg","width":272,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/reo-pentito-la-pena-deve-continuare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Reo pentito? La pena deve continuare"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=452"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/452\/revisions"}],"predecessor-version":[{"id":31557,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/452\/revisions\/31557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31556"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}