{"id":45105,"date":"2019-11-10T00:00:34","date_gmt":"2019-11-09T23:00:34","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=45105"},"modified":"2019-11-10T12:37:46","modified_gmt":"2019-11-10T11:37:46","slug":"la-francia-profanata-nel-silenzio-dei-media-europei","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/","title":{"rendered":"La Francia profanata nel silenzio dei media europei"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-45108 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni-300x188.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni-768x480.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni-1024x640.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/lanuovabq.it\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\">La Nuova Bussola<\/a> <\/strong>quotidiana<\/p>\n<p style=\"text-align: center;\">6 Novembre 2019<strong> &nbsp; <\/strong><\/p>\n<p style=\"text-align: justify;\"><em>\u00c8 una Francia che non viene immortalata, quella delle ultime settimane. Ancora profanazioni, saccheggi e atti vandalici. Nel cimitero di Breuil a Cognac divelte croci e immagini religiose. La notte di Halloween un&#8217;ondata di violenza con incendi e veicoli dati a fuoco: oltre una dozzina gli episodi. E nelle banlieue parigine la rivolta contro le forze dell&#8217;ordine \u00e8 all&#8217;ordine del giorno. <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Lorenzo Formicola <\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00c8 una Francia che non viene immortalata, quella delle ultime settimane. Eppure non inedita.<\/p>\n<p style=\"text-align: justify;\"><strong>Ancora una profanazione<\/strong>, un saccheggio e un atto vandalico contro una chiesa nella Francia che fu cattolica. Alla lunghissima lista di templi che hanno preso fuoco per autocombustione &#8211; mai \u00e8 emerso un colpevole &#8211; si aggiunge la <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/quels-sont-les-tresors-disparus-de-la-cathedrale-d-oloron-sainte-marie-20191104\" target=\"_blank\" rel=\"noopener noreferrer\">cattedrale<\/a> di Oloron Sainte-Marie, nei Pirenei Atlantici. Nelle scorse ore trafugata di calici, croci e ostensori. Oltre a un indumento liturgico del XVI secolo, donato da Francesco I al vescovo di Oloron e tanti altri piccoli pezzi preziosi.<\/p>\n<p style=\"text-align: justify;\"><strong> <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/chiesa_brucia_persecuzioni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-45111 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/chiesa_brucia_persecuzioni.jpg\" alt=\"\" width=\"299\" height=\"168\"><\/a>Da tempo nel Paese si discute<\/strong> sul come proteggere le tantissime chiese e cappelle assediate da una strana epidemia di cristianofobia, e se per tanti la soluzione \u00e8 ormai tenerle chiuse fuori dall\u2019orario della messa, lo stesso non pu\u00f2 farsi per i cimiteri.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 cos\u00ec che una gang di teppisti<\/strong> ha invaso il cimitero di Breuil a Cognac, due giorni prima della commemorazione che la Chiesa Cattolica fa dei defunti, per profanare circa 100 tombe. L\u2019obiettivo non sono state per\u00f2 le salme, ma croci, statuette dei santi, immagini religiose e ogni riferimento alla Vergine Maria: ogni simbolismo cattolico \u00e8 andato distrutto. Il sindaco ci ha tenuto a sottolineare che il gesto non merita poi cos\u00ec tanta eco dal momento che \u201cnon c&#8217;\u00e8 nulla che indichi una motivazione religiosa\u201d. Daniel Hamiche per <em>L&#8217;Observatoire de la Christianophobie, <\/em>ha replicato, \u201cuna pila di croci rotte non \u00e8 abbastanza per lui, evidentemente\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/islam_Francia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-40481 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/islam_Francia-300x145.jpg\" alt=\"\" width=\"300\" height=\"145\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/islam_Francia-300x145.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/06\/islam_Francia.jpg 322w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Marzo scorso, in prossimit\u00e0 della Pasqua<\/strong>, \u00e8 stato il mese che ha registrato il numero pi\u00f9 alto &#8211; dodici &#8211; di chiese attaccate e vandalizzate in una sola settimana. Il Central Criminal Intelligence Service (SCRC) ha <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/2019\/03\/28\/01016-20190328ARTFIG00098-les-eglises-victimes-d-un-inquietant-vandalisme.php\" target=\"_blank\" rel=\"noopener noreferrer\">riferito<\/a> in primavera che una media di quasi tre chiese al giorno sono state oggetto di atti di vandalismo negli ultimi tre anni. Nel 2018, il Ministero degli Interni ha registrato 541 atti antisemiti, 100 atti anti-musulmani e 1063 atti anti-cristiani.<\/p>\n<p style=\"text-align: justify;\"><strong>E nel frattempo \u00e8 anche l\u2019espressione\u201c<\/strong><em><strong>tir de mortiers<\/strong><\/em><strong>\u201d<\/strong> a rimbalzare sulla cronaca d\u2019oltralpe. Espressione che suona militare, ma che in questo caso coinvolge direttamente la polizia perch\u00e9 vittima di continue aggressioni. La notte di Halloween, tra gioved\u00ec 31 ottobre e venerd\u00ec 1&nbsp;novembre, \u00e8 stata caratterizzata da un&#8217;ondata di <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/policiers-et-pompiers-attaques-la-liste-incomplete-mais-deja-longue-des-derniers-cas-20191103\" target=\"_blank\" rel=\"noopener noreferrer\">violenza<\/a>, ovunque in Francia, con incendi e veicoli dati a fuoco: oltre una dozzina gli episodi registrati. I fatti pi\u00f9 sorprendenti si sono verificati in particolare nell\u2019 Yvelines.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/banlieu.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21631 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/banlieu.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>A Chanteloup, ma anche in altri quattro comuni dello stesso dipartimento (Mantes-la-Jolie, Les Mureaux, Carri\u00e8res-sous-Poissy, Trappes). A Seine-Saint-Denis, la stazione di polizia di <em>La Courneuve<\/em> \u00e8 stata presa di mira dalle bande per il Giorno dei Morti. Per non parlare delle aggressioni ai danni delle forze dell\u2019ordine nell&#8217;Ile-de-France, durante le vacanze scolastiche di Ognissanti. La stessa notte \u00e8 stato segnalato anche un incendio alla scuola media Maurice Et Katia Krafft. E quando la polizia e i vigili del fuoco sono arrivati sulla scena, sono stati nuovamente attaccati da una trentina di persone, a volto coperto, armate di pietre, fuochi d&#8217;artificio e altri proiettili.<\/p>\n<p style=\"text-align: justify;\"><strong>Mai la polizia, i pompieri e pi\u00f9 in generale le istituzioni<\/strong> sono state soggette a un tale livello di odio in Francia. Nei primi nove mesi dell&#8217;anno, la violenza contro le forze dell\u2019ordine \u00e8 <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/banlieues-l-escalade-de-la-haine-anti-policiers-20191103\" target=\"_blank\" rel=\"noopener noreferrer\">aumentata<\/a> di quasi il 14%, passando da 25.674 incidenti a 29.254 aggressioni. Per una media di 107 casi al giorno.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Banlieu.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31877 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Banlieu.jpg\" alt=\"\" width=\"275\" height=\"183\"><\/a>Il copione delle ultime settimane \u00e8 stato sempre lo stesso<\/strong>. Come quello che il 22 ottobre \u00e8 stato messo in scena a Champigny-sur-Seine, quando la <a href=\"http:\/\/www.leparisien.fr\/val-de-marne-94\/champigny-trois-mineurs-interpelles-apres-des-tirs-de-mortiers-sur-des-policiers-22-10-2019-8177670.php\" target=\"_blank\" rel=\"noopener noreferrer\">polizia \u00e8 stata bersagliata da colpi di mortaio<\/a> dopo essere stata chiamata dai vigili del fuoco intervenuti per un incendio procurato a cumuli di spazzatura.<\/p>\n<p style=\"text-align: justify;\"><strong>Da settimane nel quartiere di Noah<\/strong>, <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/chanteloup-les-vignes-theatre-de-graves-incidents-20191103\" target=\"_blank\" rel=\"noopener noreferrer\">Chanteloup-les-Vignes<\/a>, l\u2019illuminazione pubblica viene regolarmente distrutta. Come il presagio di un brutto colpo. E le immagini di vere e proprie rivolte di sabato notte hanno rispedito la questione della sicurezza dei sobborghi, di nuovo, al centro del dibattito. Polizia presa di mira e rogo ad un tendone del circo sono stati i protagonisti dell\u2019ennesima notte di guerriglia nella nota <em>banlieu<\/em> francese. Gi\u00e0 famosa per l\u2019altissima percentuale di immigrati, da settimane \u00e8 in prima pagina per le imboscate tese alla polizia e si contano gi\u00e0 800.000 euro di danni.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/banlieu1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21793 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/banlieu1.jpg\" alt=\"\" width=\"290\" height=\"174\"><\/a>Sulla scrivania del Ministro degli Interni<\/strong>, Christophe Castaner, da tempo piovono cos\u00ec sempre pi\u00f9 episodi di \u201cagguati\u201d, \u201catti ribellione\u201d, \u201clancio di proiettili\u201d contro le stazioni di polizia.<\/p>\n<p style=\"text-align: justify;\"><strong>Il Paese di Macron brucia e la violenza<\/strong> dilaga soprattutto nelle <em>banlieue <\/em>densamente abitate da immigrati, come a Mantes-la-ville, Trappes e Les Mureaux, comuni del dipartimento francese della regione dell&#8217;\u00cele-de-France.<\/p>\n<p style=\"text-align: justify;\"><strong>Trappes, a circa trenta chilometri da Parigi<\/strong>, \u00e8 la <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/banlieues-l-escalade-de-la-haine-anti-policiers-20191103\" target=\"_blank\" rel=\"noopener noreferrer\">cittadina<\/a> che desta maggiore preoccupazione. Nota per essere la \u201cMolenbeek francese\u201d, per un periodo \u00e8 stata considerata la citt\u00e0 sulla quale misurare gli esprimenti anti-radicalizzazione del governo. E tra attacchi di coltello, bambini che vengono ritirati dalle mense perch\u00e9 non c\u2019\u00e8 carne halal e condanne per l\u2019invio di fondi ai jihadisti francesi in Siria, adesso sono iniziate anche le aggressioni violente contro la <a href=\"https:\/\/www.lefigaro.fr\/flash-actu\/mantes-la-jolie-nunez-denonce-un-guet-apens-extremement-violent-contre-des-policiers-20191025\" target=\"_blank\" rel=\"noopener noreferrer\">polizia<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>La Francia \u00e8 febbricitante e non riesce a guarire<\/strong>. Mentre secondo <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/2017\/10\/24\/01016-20171024ARTFIG00309-ces-francais-juifs-qui-fuient-la-violence-des-banlieues.php\">Le Figaro<\/a> c\u2019\u00e8 di mezzo anche un aumento delle aggressioni antisemite che impediscono agli ebrei di sentirsi al sicuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola quotidiana 6 Novembre 2019 &nbsp; \u00c8 una Francia che non viene immortalata, quella delle ultime settimane. Ancora profanazioni, saccheggi e atti vandalici. Nel cimitero di Breuil a Cognac divelte croci e immagini religiose. La notte di Halloween un&#8217;ondata di violenza con incendi e veicoli dati a fuoco: oltre una dozzina gli episodi. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":45108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111,108],"tags":[219,663,2408,545,264],"class_list":["post-45105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam-in-europa","category-paesi-e-continenti","tag-francia","tag-innigrazione","tag-islam-in-europa","tag-paesi-e-continenti-2","tag-persecuzioni","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-09T23:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-10T11:37:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La Francia profanata nel silenzio dei media europei\",\"datePublished\":\"2019-11-09T23:00:34+00:00\",\"dateModified\":\"2019-11-10T11:37:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/\"},\"wordCount\":919,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cimitero_Francia_persecuzioni.jpg\",\"keywords\":[\"Francia\",\"innigrazione\",\"Islam in Europa\",\"paesi e continenti\",\"persecuzioni\"],\"articleSection\":[\"Islam in Europa\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/\",\"name\":\"La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cimitero_Francia_persecuzioni.jpg\",\"datePublished\":\"2019-11-09T23:00:34+00:00\",\"dateModified\":\"2019-11-10T11:37:46+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cimitero_Francia_persecuzioni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cimitero_Francia_persecuzioni.jpg\",\"width\":2000,\"height\":1250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-francia-profanata-nel-silenzio-dei-media-europei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Francia profanata nel silenzio dei media europei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/","og_locale":"it_IT","og_type":"article","og_title":"La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-11-09T23:00:34+00:00","article_modified_time":"2019-11-10T11:37:46+00:00","og_image":[{"width":2000,"height":1250,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La Francia profanata nel silenzio dei media europei","datePublished":"2019-11-09T23:00:34+00:00","dateModified":"2019-11-10T11:37:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/"},"wordCount":919,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg","keywords":["Francia","innigrazione","Islam in Europa","paesi e continenti","persecuzioni"],"articleSection":["Islam in Europa","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/","name":"La Francia profanata nel silenzio dei media europei - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg","datePublished":"2019-11-09T23:00:34+00:00","dateModified":"2019-11-10T11:37:46+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/cimitero_Francia_persecuzioni.jpg","width":2000,"height":1250},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-francia-profanata-nel-silenzio-dei-media-europei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La Francia profanata nel silenzio dei media europei"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/45105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=45105"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/45105\/revisions"}],"predecessor-version":[{"id":45114,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/45105\/revisions\/45114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/45108"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=45105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=45105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=45105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}