{"id":4453,"date":"2011-03-11T12:12:59","date_gmt":"2011-03-11T11:12:59","guid":{"rendered":""},"modified":"2016-01-24T19:48:22","modified_gmt":"2016-01-24T18:48:22","slug":"con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/","title":{"rendered":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29820\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg\" alt=\"eutanasia_Dat\" width=\"145\" height=\"200\" \/><\/a>Avvenire<\/strong> 26 febbraio 2011<\/div>\n<p style=\"text-align: center;\"><em>Una retta interpretazione del disegno di legge sulla fine della vita<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Rocco Buttiglione<\/strong><br \/>\n(<em>vicepresidente della Camera e presidente dell\u2019Udc)<\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Per capire la legge che stiamo facendo sulle Dichiarazioni Anticipate di trattamento (Dat) dobbiamo domandarci: \u00abQuale \u00e8 il telos (il fine), quale \u00e8 l\u2019interesse che la legge intende proteggere?\u00bb. \u00c8 l\u2019interesse ed il diritto della persona a vivere fino al termine naturale della propria esistenza. Questo implica il rifiuto della eutanasia ed il rifiuto dell\u2019accanimento terapeutico. L\u2019eutanasia pone alla vita un termine artificiale, fa morire una persona prima che la vita sia giunta al suo termine naturale.<\/div>\n<p style=\"text-align: justify;\">L\u2019accanimento terapeutico prolunga la vita oltre il suo termine naturale. Vediamo adesso di fornire alcune chiarificazioni su alcuni artifici retorici che spesso ricorrono nella discussione intorno a questa legge. Alcuni dicono che la legge non serve a nulla. Non \u00e8 vero. A che cosa serve la legge?<\/p>\n<p style=\"text-align: justify;\">Immaginiamo che un paziente sia in cura intensiva e che siano esaurite le probabilit\u00e0 di una guarigione. Il paziente ha lasciato un documento in cui dice di non volere essere mantenuto in vita artificialmente. Il medico sospende le cure straordinarie. A questo punto in genere il paziente muore. Il medico avrebbe comunque dovuto sospendere le cure, prima o poi.<\/p>\n<p style=\"text-align: justify;\">Il fatto di avere la dichiarazione del paziente lo aiuta per\u00f2 a prendere la decisione (insieme con il fiduciario indicato nelle dichiarazioni anticipate) e lo tutela anche contro possibili azioni legali dei familiari. La decisione verr\u00e0 presa (probabilmente) prima e con minori difficolt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Definire in concreto dove finisce il dovere di cura e dove inizia l\u2019accanimento terapeutico non \u00e8 facile. La dichiarazione anticipata di trattamento aiuta a definire questo confine. Nella stragrande maggioranza dei casi le cose vanno in questo modo. Quasi tutti noi moriremo cos\u00ec. Alcuni dicono che la legge impone l\u2019alimentazione forzata a chi non la vuole. Non \u00e8 vero. Se uno non vuole la alimentazione artificiale e la rifiuta nessuno pu\u00f2 imporgliela.<\/p>\n<p style=\"text-align: justify;\">La legge dice un\u2019altra cosa: il rifiuto di terapie salvavita o di ordinarie misure di assistenza e cura che preservano la vita \u00e8 un atto personalissimo assolutamente non delegabile. La persona deve esprimerlo direttamente. Non basta scriverlo in una dichiarazione anticipata di trattamento. La ragione \u00e8 che ogni atto di volont\u00e0 si colloca in un contesto. Il contesto della imminente minaccia di vita \u00e8 un contesto assolutamente straordinario. \u00c8 elevata la probabilit\u00e0 che in quel contesto la persona esprimerebbe una indicazione diversa da quella che ha lasciato scritta in un documento.<\/p>\n<p style=\"text-align: justify;\">Ne abbiamo la riprova nel caso, ben noto, di chi tenta il suicidio. La sua volont\u00e0 di morire \u00e8, in questo caso, evidente e comprovata da un gesto ben pi\u00f9 eloquente di una dichiarazione scritta. Noi tuttavia lo assistiamo e, se questo \u00e8 possibile, gli salviamo la vita. Nella maggioranza dei casi l\u2019aspirante suicida \u00e8 contento di essere stato salvato e non ripete il tentativo. Per questo \u00e8 ingiusto parlare di \u201calimentazione forzata\u201d. Semplicemente vale qui una presunzione a favore della vita in assenza di una indicazione contraria attuale.<\/p>\n<p style=\"text-align: justify;\">La semplice verit\u00e0 \u00e8 che noi non sappiamo cosa pensi o voglia chi \u00e8 in stato di incoscienza. In altre parole: se uno si suicida deve farlo lui personalmente, non pu\u00f2 delegare l\u2019incombenza ad altri e meno che mai al servizio sanitario nazionale.<\/p>\n<p style=\"text-align: justify;\">Ma, si dice, in questo modo noi neghiamo il principio costituzionalmente garantito della autodeterminazione del paziente. E si cita, a questo proposito, l\u2019art. 32 della Costituzione, secondo comma. Leggiamolo allora questo articolo 32, ma leggiamolo per intero e non in una versione abbreviata di comodo, come ha fatto anche di recente un autorevole commentatore del<em> Corriere della Sera .<\/em><\/p>\n<p style=\"text-align: justify;\">Ecco il testo abbreviato e falsificato: \u00abNessuno pu\u00f2 essere obbligato ad un determinato trattamento sanitario\u00bb. Ecco il testo autentico: \u00abNessuno pu\u00f2 essere obbligato ad un trattamento sanitario se non per disposizione di legge\u00bb. Invece di un divieto assoluto abbiamo qui una semplice riserva di legge.<\/p>\n<p style=\"text-align: justify;\">La riserva \u00e8 poi rafforzata da una clausola di chiusura: \u00abLa legge non pu\u00f2 in nessun caso violare i limiti imposti dal rispetto della persona umana\u00bb. In altre parole, ove venisse istituito un trattamento sanitario obbligatorio esso dovrebbe essere rivolto sempre (anche) al bene del paziente e dovrebbe trattarlo sempre come un fine in se e non semplicemente come un mezzo.<\/p>\n<p style=\"text-align: justify;\">E\u2019 risibile il tentativo di far derivare dal rispetto della persona umana il diritto alla eutanasia. Se alcuni vedono in tale diritto l\u2019espressione suprema della libert\u00e0 e dignit\u00e0 della persona, altri vedono in esso la rinuncia pi\u00f9 assoluta a tale libert\u00e0 e dignit\u00e0. \u00c8 giusto che se ne discuta nel Parlamento e nel Paese, ma \u00e8 bene che nessuno pretenda di chiudere le orecchie alle ragioni dell\u2019altro sequestrando a proprio favore la Costituzione.<\/p>\n<p style=\"text-align: justify;\">La Costituzione \u00e8 di tutti e non decide questo problema. Sar\u00e0 bene ricordare, inoltre, che la Costituzione \u00e8 il risultato di un patto fra cattolici, liberali laici e comunisti. Se una interpretazione capziosa ed estensiva altera i termini di questo patto e dichiara incostituzionali valori fondamentali dei cattolici, allora \u00e8 la ragione di vita della Costituzione che viene meno ed ha ragione chi dice che bisogno negoziare un nuovo patto costituzionale, ma non nelle aule dei tribunali bens\u00ec nel Parlamento e nel Paese.<\/p>\n<p style=\"text-align: justify;\">I cattolici possono accettare di essere sconfitti in una battaglia politica libera e democratica, ma non possono accettare di essere considerati come cittadini di seconda categoria, le cui convinzioni sono a priori contro la Costituzione. Nel caso specifico che ci riguarda \u00e8 per\u00f2 sbagliato scomodare l\u2019art. 32 della Costituzione.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 di cui stiamo parlando sono semplicemente le condizioni di validit\u00e0 di un atto di volont\u00e0 con cui si rinuncia a misure di sostegno vitale. Si dice semplicemente che questo atto non \u00e8 delegabile. Nel bilanciamento fra il principio costituzionale della difesa della vita e quello della autodeterminazione, si stabilisce un equilibrio per cui prevale il principio di autodeterminazione quando la volont\u00e0 viene espressa direttamente, e prevale il<em> favor vitae<\/em> quando manchi questa espressione diretta.<\/p>\n<p style=\"text-align: justify;\">Resta infine da considerare un\u2019ultima obiezione: la legge contraddirebbe gli indirizzi giurisprudenziali della Corte di Cassazione. Su questo punto basta replicare che le leggi non le fanno i giudici ma il Parlamento.<\/p>\n<p style=\"text-align: justify;\">(AMCI-Pisa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire 26 febbraio 2011 Una retta interpretazione del disegno di legge sulla fine della vita di Rocco Buttiglione (vicepresidente della Camera e presidente dell\u2019Udc)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[1925],"class_list":["post-4453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eutanasia","tag-dichiarazioni-anticipate-di-trattamento","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-11T11:12:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-24T18:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"191\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Con le Dat non si impone nulla Ma certe scelte non sono delegabili\",\"datePublished\":\"2011-03-11T11:12:59+00:00\",\"dateModified\":\"2016-01-24T18:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/\"},\"wordCount\":1022,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/eutanasia_Dat.jpg\",\"keywords\":[\"dichiarazioni anticipate di trattamento\"],\"articleSection\":[\"Eutanasia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/\",\"name\":\"Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/eutanasia_Dat.jpg\",\"datePublished\":\"2011-03-11T11:12:59+00:00\",\"dateModified\":\"2016-01-24T18:48:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/eutanasia_Dat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/eutanasia_Dat.jpg\",\"width\":191,\"height\":264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con le Dat non si impone nulla Ma certe scelte non sono delegabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/","og_locale":"it_IT","og_type":"article","og_title":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-03-11T11:12:59+00:00","article_modified_time":"2016-01-24T18:48:22+00:00","og_image":[{"width":191,"height":264,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili","datePublished":"2011-03-11T11:12:59+00:00","dateModified":"2016-01-24T18:48:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/"},"wordCount":1022,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg","keywords":["dichiarazioni anticipate di trattamento"],"articleSection":["Eutanasia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/","name":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg","datePublished":"2011-03-11T11:12:59+00:00","dateModified":"2016-01-24T18:48:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/eutanasia_Dat.jpg","width":191,"height":264},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/con-le-dat-non-si-impone-nulla-ma-certe-scelte-non-sono-delegabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Con le Dat non si impone nulla Ma certe scelte non sono delegabili"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4453"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4453\/revisions"}],"predecessor-version":[{"id":29821,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4453\/revisions\/29821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29820"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}