{"id":44459,"date":"2019-08-25T00:00:34","date_gmt":"2019-08-24T22:00:34","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=44459"},"modified":"2019-09-25T16:50:07","modified_gmt":"2019-09-25T14:50:07","slug":"la-questione-del-mezzogiorno","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/","title":{"rendered":"La questione del Mezzogiorno"},"content":{"rendered":"<p style=\"text-align: center;\">I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale<\/p>\n<p style=\"text-align: center;\"><strong>Voci per un Dizionario del Pensiero Forte<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-44460\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale-300x223.jpeg\" alt=\"\" width=\"250\" height=\"186\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale-300x223.jpeg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale-768x571.jpeg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale-1024x761.jpeg 1024w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\u00a0di <strong>Francesco pappalardo <\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>1. Per una definizione<\/strong><\/p>\n<p style=\"text-align: justify;\">La Questione del Mezzogiorno o Questione Meridionale nasce dall\u2019annessione forzata del Regno delle Due Sicilie al Regno d\u2019Italia, nel 1861, e la sua storia \u00e8 la storia dei tentativi compiuti dallo Stato italiano per sanare la lacerazione sociale e morale conseguente all\u2019incontro-scontro fra realt\u00e0 disomogenee.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Regno_sud.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28067 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Regno_sud.jpg\" alt=\"\" width=\"215\" height=\"188\" \/><\/a>Questo contrasto fra il \u201cNord\u201d e il \u201cSud\u201d &#8211; indicazioni geografiche che nascondono realt\u00e0 sociali complesse e differenziate &#8211; \u00e8 ricondotto dal politologo Ernesto Galli della Loggia a <em>\u201c<\/em>[\u2026] <em>una diversit\u00e0 etico-antropologica cos\u00ec radicale da farne il punto critico per antonomasia della problematica identit\u00e0 nazionale italiana\u201d<\/em> e dall\u2019antropologo Carlo Tullio Altan a <em>\u201cuno scontro di civilt\u00e0\u201d<\/em>, cio\u00e8 a un urto fra differenti modelli culturali e forme diverse di organizzazione sociale, che dopo l\u2019Unit\u00e0 sar\u00e0 affrontato soprattutto come un problema di sviluppo ineguale.<\/p>\n<p style=\"text-align: justify;\"><strong>2. Le origini<\/strong><\/p>\n<p style=\"text-align: justify;\">La rappresentazione del \u201cMezzogiorno\u201d, cio\u00e8 delle province continentali e insulari dell\u2019ex Regno delle Due Sicilie, come un blocco unitario d\u2019arretratezza economica e sociale non trova fondamento sul piano storico, ma ha genesi e natura ideologica.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/Risorgimento.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28332 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/Risorgimento-281x300.jpg\" alt=\"\" width=\"227\" height=\"241\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/Risorgimento-281x300.jpg 281w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/Risorgimento.jpg 285w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a>I primi a diffondere giudizi falsi sugl\u2019inferiori coefficienti di civilt\u00e0 di quell\u2019area sono gli esuli meridionali che, nel decennio 1850-1860, con la loro propaganda antiborbonica non solo contribuiscono a demolire il prestigio e l\u2019onore della dinastia, ma determinano anche una trasformazione decisiva nell\u2019immagine del Sud, riproponendo secolari stereotipi sul <em>\u201cparadiso abitato da diavoli\u201d<\/em>, presto ripresi dai titolari d\u2019inchieste pubbliche o private.<\/p>\n<p style=\"text-align: justify;\">Dopo il 1860, l\u2019intreccio di brigantaggio e di legittimismo borbonico spinge la classe politica unitaria a individuare nelle province annesse il luogo da cui proviene la pi\u00f9 grave minaccia interna di eversione e ad assegnarsi la missione d\u2019inserire nella nuova compagine statale l\u2019ex regno napoletano, anche a costo di cancellarne l\u2019identit\u00e0 storica.<\/p>\n<p style=\"text-align: justify;\"><em>\u201cLa differenza tra il Mezzogiorno e il resto del paese<\/em> &#8211; scrive lo storico siciliano Giuseppe Giarrizzo &#8211; <em>si configura come polarit\u00e0 simbolica di barbarie e civilt\u00e0, di borbonismo e liberalismo, di \u201cfeudalesimo\u201d nel Sud e vita borghese nel Nord &#8211; una polarit\u00e0 esasperata dal contrasto mitico tra la difficile natura del Centro-nord e la naturale disposizione del suolo e del clima meridionale alla fertilit\u00e0 e agli agi\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Italia_sud_economia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44464 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Italia_sud_economia.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>I temi del meridionalismo saranno enfatizzati, a partire dai primi decenni del secolo XX, dal nuovo ceto politico locale allo scopo di rivendicare ingenti provvidenze pubbliche e di porsi come mediatore nella loro distribuzione.<\/p>\n<p style=\"text-align: justify;\">Dopo la seconda guerra mondiale (1939-1945), la Questione del Mezzogiorno viene affrontata con una politica d\u2019interventismo statale, caratterizzata da una mole crescente di trasferimenti di risorse verso il Sud, che sono destinate prevalentemente a fini non produttivi e che in parte alimentano il circuito perverso politica-affari-criminalit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Le interpretazioni economiche<\/strong><\/p>\n<p style=\"text-align: justify;\">Da Pasquale Villari (1826-1917) ad Antonio Gramsci (1891-1937) il Mezzogiorno viene letto soprattutto nei termini di un grande problema sociale e, pur nella diversit\u00e0 delle interpretazioni, l\u2019analisi prende le mosse abitualmente dalla sua condizione materiale.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/07\/contadini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21180 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/07\/contadini.jpg\" alt=\"\" width=\"271\" height=\"186\" \/><\/a>Per il primo meridionalismo, definito \u201cclassico\u201d, la Questione del Mezzogiorno consiste nella mancata integrazione dell\u2019economia del Sud nel processo di sviluppo capitalistico, mentre per le correnti d\u2019ispirazione marxista &#8211; e anche per Rosario Romeo (1924-1987), che \u201caggiorna\u201d il meridionalismo liberal-democratico &#8211; questa integrazione \u00e8 avvenuta, ma nei modi peculiari con i quali il capitalismo avanzato subordina a s\u00e9 l\u2019economia dei paesi arretrati, rendendola funzionale al suo sviluppo.<\/p>\n<p style=\"text-align: justify;\">In entrambi i casi la lettura del Sud in termini di arretratezza &#8211; vista talvolta come divario d\u2019origine rispetto alle regioni settentrionali del paese, altre volte come frutto del processo di unificazione gestito dallo Stato unitario &#8211; ha come riferimenti il modello economico liberale, nato dalla rivoluzione industriale che determin\u00f2 anche una profonda trasformazione dei rapporti sociali, e un\u2019impostazione culturale idealistica, che giudica la storia del Mezzogiorno secondo il parametro della crescita della coscienza civile, che sarebbe giunta a maturazione solo grazie al Risorgimento.<\/p>\n<p style=\"text-align: justify;\">Il Meridione d\u2019Italia viene valutato, dunque, in ragione della sua devianza da quei modelli e viene descritto in termini d\u2019individualismo e di carente spirito civico, di arretratezza tecnologica e di resistenza alla modernizzazione, di corruzione e di clientelismo, utilizzando le dicotomie sviluppo\/sottosviluppo e progresso\/arretratezza come indicatori del livello raggiunto rispetto a una scala ideale da percorrere.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Regno_Napoli.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44465 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Regno_Napoli.png\" alt=\"\" width=\"195\" height=\"258\" \/><\/a>In realt\u00e0, nel 1860 la societ\u00e0 \u201cnapoletana\u201d viene incorporata in un sistema pi\u00f9 ampio, nel quale erano presenti i germi di uno sviluppo di tipo capitalistico e di una trasformazione della monarchia amministrativa in un regime liberale &#8211; cio\u00e8 i germi di un \u201caltro\u201d modello di sviluppo -, e ci\u00f2 determina la subordinazione economica e politica del Sud nei confronti delle altre parti d\u2019Italia, anche a causa della <em>\u201csistematica e non graduata demolizione di un\u2019immensit\u00e0 di istituzioni, di interessi, di amministrazioni\u201d<\/em> &#8211; denunciata dal giurista Pasquale Stanislao Mancini (1817-1888) -, che aveva prodotto <em>\u201cuna lesione troppo estesa e profonda\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>4. Le interpretazioni sociali e culturali<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel secondo dopoguerra la fioritura degli studi sociologici sul Mezzogiorno si concretizza nella elaborazione di alcune opinabili categorie interpretative &#8211; come quelle di <em>\u201cpaganesimo perenne\u201d<\/em> e di <em>\u201ccultura subalterna\u201d<\/em>, riferite al mondo contadino dallo scrittore Carlo Levi (1902-1975) e dall\u2019antropologo Alfonso Maria Di Nola (1926-1997) -, oppure nella lettura della specificit\u00e0 meridionale nei termini di una sua vocazione quasi antropologica a una religiosit\u00e0 elementare e superstiziosa, come per l\u2019etnologo Ernesto De Martino (1908-1965), o del Sud come sacca arretrata e deposito di mentalit\u00e0 pre-moderne, come per il sociologo statunitense Ernest C. Banfield, teorico del <em>\u201cfamilismo amorale\u201d<\/em>, a suo avviso causa determinante di una disgregazione permanente della societ\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Sardegna_Mezzogiono_Italia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-44466\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Sardegna_Mezzogiono_Italia.jpg\" alt=\"\" width=\"250\" height=\"172\" \/><\/a>La categoria dell\u2019arretratezza ricompare cos\u00ec come nodo ineliminabile della storia del Mezzogiorno, in relazione alla sua subordinazione economica o alla sua struttura sociale e culturale, entrambe legate a presunti, secolari condizionamenti.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0, i preconcetti di certi studiosi, alcuni dei quali stranieri, servono ad alimentare una letteratura d\u2019impostazione discutibile, diffusa soprattutto nel mondo protestante, secondo cui <em>\u201c<\/em>[\u2026] <em>la vita religiosa del Sud &#8211;<\/em> come nota lo stesso De Martino &#8211; <em>sta in fondo come pretesto fin troppo scoperto per condurre la polemica anticattolica\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Gli studi degli storici Gabriele De Rosa e Giuseppe Galasso hanno consentito, per\u00f2, di superare il luogo comune di una cristianizzazione superficiale delle regioni meridionali e d\u2019individuare in alcune sopravviventi pratiche magiche &#8211; ritenute comunemente parte integrante della religiosit\u00e0 delle popolazioni rurali &#8211; solo il relitto di arcaiche strutture psicologiche e religiose.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Famiglia_patriarcale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37770 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Famiglia_patriarcale.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>Anche il grande rilievo assunto dalla famiglia nella societ\u00e0 meridionale &#8211; e nelle altre regioni d\u2019Italia, dove la socialit\u00e0, secondo lo storico Marco Meriggi, <em>\u201csi sgrana quasi naturalmente in un ventaglio di famiglie, molto pi\u00f9 che in una miscela di individui\u201d<\/em> \u2013 non \u00e8 pi\u00f9 ritenuto un sintomo di arretratezza, anzi proprio questa tenace caratteristica sociale ha rappresentato un limite quasi invalicabile all\u2019espansione soffocante dello Stato unitario e il pi\u00f9 sicuro antidoto nei confronti dell\u2019individualismo politico ed economico.<\/p>\n<p style=\"text-align: justify;\">L\u2019unione forzata in un \u201cgrande Stato\u201d, nel 1861, ha determinato, prima ancora della spoliazione economica, la dispersione d\u2019una parte rilevante delle inestimabili ricchezze culturali del Mezzogiorno, ma l\u2019insieme dei caratteri e degli aspetti che contraddistinguono gli abitanti di queste contrade, soprattutto a livello del costume e della vita di relazione, s\u2019\u00e8 mostrato per lungo tempo resistente e impermeabile alla modernit\u00e0, intesa come insieme di valori globalmente alternativi al cristianesimo e alla sua incidenza politica e sociale.<\/p>\n<p style=\"text-align: justify;\">Il Sud, dunque, non \u00e8 un\u2019area arretrata o sottosviluppata, o un Nord mancato, ma piuttosto una societ\u00e0 dotata d\u2019una forte personalit\u00e0 storica e d\u2019una inconfondibile fisionomia, in cui si sono riconosciute per lunghissimo tempo tutte le sue componenti sociali, una \u201cnazione\u201d che ha le sue radici remote nella vigorosa sintesi, realizzata dopo il secolo VI, fra tradizioni autoctone, cultura greco-romana e apporti germanici.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/Napoli.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41149 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/Napoli-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>Il Sud non \u00e8 neppure una periferia d\u2019Europa, caratterizzata da una lunga separazione dal mondo civile o da note di subalternit\u00e0 o d\u2019arcaicit\u00e0, n\u00e9 \u00e8 il luogo di coltura della \u201cnapoletanit\u00e0\u201d, intesa come un isolato universo antropologico e culturale.<\/p>\n<p style=\"text-align: justify;\">Al contrario, la civilt\u00e0 del Mezzogiorno \u00e8 stata una delle molteplici versioni della civilt\u00e0 cristiana occidentale ed \u00e8 vissuta per secoli in uno stretto rapporto con l\u2019 \u201d<em>altra Europa\u201d<\/em> &#8211; presente ovunque nel continente durante l\u2019et\u00e0 moderna e collocata idealmente \u201csotto i Pirenei\u201d dal giurista e storico spagnolo Francisco El\u00edas de Tejada y Sp\u00ednola (1917-1978) -, che per molto tempo ha rappresentato la sopravvivenza di un\u2019area di Cristianit\u00e0 e ha costituito un limite all\u2019espansione della modernit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>5. Conclusioni<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Italia_Mezzogiorno_processione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44467 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Italia_Mezzogiorno_processione.jpg\" alt=\"\" width=\"191\" height=\"264\" \/><\/a>Negli ultimi centocinquant\u2019anni il popolo italiano ha sub\u00ecto un processo di alienazione della propria identit\u00e0 e della propria tradizione, romana e cattolica &#8211; che avevano vivificato e modellato nel corso dei secoli i costumi, la mentalit\u00e0 e il comportamento degli abitanti della penisola -, da parte di quello che il sociologo delle religioni Massimo Introvigne chiama<em>\u201c<\/em>[\u2026] <em>partito anti-italiano. Per questo partito \u201cfatta l\u2019Italia\u201d non si trattava soltanto di \u201cfare gli italiani\u201d; si trattava piuttosto di fare l\u2019Italia <\/em>contro<em> gli italiani, o di disfare il tradizionale <\/em>ethos<em> italiano radicato nel cattolicesimo\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Il Mezzogiorno, in particolare, \u00e8 stato aggredito contemporaneamente, e da pi\u00f9 parti, da fermenti incalzanti di trasformazione, ma ha costituito un luogo di resistenza alla modernizzazione forzata.<\/p>\n<p style=\"text-align: justify;\">Dunque, non il particolare modo d\u2019essere del popolo \u201cnapoletano\u201d, ma il tentativo diffuso d\u2019annientarne la personalit\u00e0 e di dissolverne l\u2019eredit\u00e0 ha innescato un processo di alienazione culturale, mentre il progressivo venir meno dei punti di riferimento sociali e istituzionali ha aperto la strada allo sviluppo della criminalit\u00e0 organizzata, la cui forza non \u00e8 il radicamento nel Mezzogiorno &#8211; dove tutt\u2019al pi\u00f9 ha riattivato i circuiti classici della delinquenza locale, ampliandone le cerchie &#8211; ma l\u2019incontro con fenomeni nuovi e poco \u201cmeridionali\u201d, come il commercio internazionale di droga e d\u2019armi e la lotta per il controllo di enormi risorse finanziarie.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Aborto_Repubblica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43421 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Aborto_Repubblica-217x300.jpg\" alt=\"\" width=\"186\" height=\"256\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Aborto_Repubblica-217x300.jpg 217w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Aborto_Repubblica.jpg 500w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" \/><\/a>A partire soprattutto dalla seconda met\u00e0 degli anni 1950 &#8211; con una nuova frana emigratoria, che ha prodotto la disarticolazione definitiva dell\u2019antica organizzazione sociale e territoriale, e con l\u2019assimilazione dei comportamenti proposti dal modello consumistico, ritenuto superiore a quello tradizionale &#8211; l\u2019identit\u00e0 del Mezzogiorno si sta dissolvendo nel crogiolo dell\u2019omologazione, favorita dalla scuola, dai partiti politici e dai grandi mezzi d\u2019informazione.<\/p>\n<p style=\"text-align: justify;\">Pertanto, quanti si accostano alla Questione del Mezzogiorno non possono ignorare che la sua soluzione passa attraverso una rinascita religiosa e civile, che pu\u00f2 essere perseguita soltanto con il ricupero di quanto sopravvive delle radici storiche e nazionali del Mezzogiorno stesso, da tempo conculcate e disprezzate, purtroppo non solamente da parte di estranei.<\/p>\n<p style=\"text-align: justify;\">______________________<\/p>\n<p style=\"text-align: justify;\"><strong>Per approfondire: <\/strong><\/p>\n<p style=\"text-align: justify;\">vedi Piero Bevilacqua, <em>Breve storia dell\u2019Italia meridionale dall\u2019Ottocento ad oggi<\/em>, Donzelli, Roma 1997;<\/p>\n<p style=\"text-align: justify;\">Giuseppe Galasso<em>. L\u2019altra Europa. Per un\u2019antropologia storica del Mezzogiorno d\u2019Italia<\/em>, nuova edizione accresciuta, Argo, Lecce 1997;<\/p>\n<p style=\"text-align: justify;\">Giuliano Minichiello, <em>Meridionalismo<\/em>, Editrice Bibliografica, Milano 1997; e Marta Petrusewicz, <em>Come il Meridione divenne una Questione. Rappresentazioni del Sud prima e dopo il Quarantotto<\/em>, Rubbettino, Soveria Mannelli (Catanzaro) 1998.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale Voci per un Dizionario del Pensiero Forte \u00a0di Francesco pappalardo<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":44460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,24,96],"tags":[1415,162,404],"class_list":["post-44459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-storia","category-storia-italiana","tag-mezzogiorno-ditalia","tag-storia-2","tag-storia-italiana-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La questione del Mezzogiorno - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La questione del Mezzogiorno - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-24T22:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-25T14:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2642\" \/>\n\t<meta property=\"og:image:height\" content=\"1963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La questione del Mezzogiorno\",\"datePublished\":\"2019-08-24T22:00:34+00:00\",\"dateModified\":\"2019-09-25T14:50:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/\"},\"wordCount\":1816,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Risorgimento_questione_meridionale.jpeg\",\"keywords\":[\"Mezzogiorno d'Italia\",\"storia\",\"storia italiana\"],\"articleSection\":[\"Paesi e continenti\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/\",\"name\":\"La questione del Mezzogiorno - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Risorgimento_questione_meridionale.jpeg\",\"datePublished\":\"2019-08-24T22:00:34+00:00\",\"dateModified\":\"2019-09-25T14:50:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Risorgimento_questione_meridionale.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Risorgimento_questione_meridionale.jpeg\",\"width\":2642,\"height\":1963},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-questione-del-mezzogiorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La questione del Mezzogiorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La questione del Mezzogiorno - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/","og_locale":"it_IT","og_type":"article","og_title":"La questione del Mezzogiorno - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-08-24T22:00:34+00:00","article_modified_time":"2019-09-25T14:50:07+00:00","og_image":[{"width":2642,"height":1963,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La questione del Mezzogiorno","datePublished":"2019-08-24T22:00:34+00:00","dateModified":"2019-09-25T14:50:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/"},"wordCount":1816,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg","keywords":["Mezzogiorno d'Italia","storia","storia italiana"],"articleSection":["Paesi e continenti","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/","name":"La questione del Mezzogiorno - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg","datePublished":"2019-08-24T22:00:34+00:00","dateModified":"2019-09-25T14:50:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Risorgimento_questione_meridionale.jpeg","width":2642,"height":1963},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-questione-del-mezzogiorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La questione del Mezzogiorno"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=44459"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44459\/revisions"}],"predecessor-version":[{"id":44468,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44459\/revisions\/44468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/44460"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=44459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=44459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=44459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}