{"id":4437,"date":"2011-03-05T17:35:50","date_gmt":"2011-03-05T16:35:50","guid":{"rendered":""},"modified":"2015-03-26T16:46:08","modified_gmt":"2015-03-26T15:46:08","slug":"gheddafi-chi-era-costui","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/","title":{"rendered":"Gheddafi, chi era costui?"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22125\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg\" alt=\"Gheddafi\" width=\"250\" height=\"194\" \/><\/a>La Bussola<\/strong><strong> quotidiana<\/strong> 28 febbraio 2011<\/div>\n<p style=\"text-align: center;\">di <strong><strong>Robi Ronza<\/strong><\/strong><\/p>\n<p style=\"text-align: justify;\">Muammar Gheddafi, al cui cruento tramonto stiamo assistendo in questi giorni, \u00e8 o era al potere da 42 anni: un primato assoluto, tanto pi\u00f9 notevole se si considera che egli \u00e8 sempre rimasto un privato cittadino senza mai assumere alcuna carica istituzionale, forte solo del titolo, che si era dato da s\u00e9, di \u201cGuida della Rivoluzione\u201d.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Non volle nemmeno procedere nella carriera militare conservando <em>sine die<\/em> il grado di colonnello che ricopriva quando, nel 1969, guid\u00f2 il colpo di Stato che port\u00f2 alla caduta del regno di Idris I e alla nascita della Repubblica di Libia \u201caraba, libera e democratica\u201d.<\/div>\n<p style=\"text-align: justify;\"><strong>Il potere non \u00e8 qualcosa che nessuno vuole<\/strong> e che perci\u00f2 resta infine in mano al pi\u00f9 sciocco della compagnia. Come \u00e8 noto si tratta di una merce richiestissima. Perci\u00f2 chi conquista il potere e lo conserva pu\u00f2 essere magari anche perfido e squilibrato (si pensi ad esempio a Hitler), ma non \u00e8 mai stupido. Venendo al caso di Gheddafi, considerarlo un matto non aiuta n\u00e9 a capire chi sia, n\u00e9 a capire come la Libia pu\u00f2 sopravvivergli.<\/p>\n<p style=\"text-align: justify;\"><strong>Nei suoi 42 anni di potere Gheddafi \u00e8 riuscito a restare in sella giostrando con abilit\u00e0<\/strong> sia all\u2019interno del paese che sullo scacchiere internazionale. And\u00f2 al potere proponendosi come campione di una \u201cterza via\u201d tra comunismo e capitalismo secondo un programma in cui la dottrina del nazionalismo pan-arabo s\u2019intrecciava con principi di matrice socialista europea. Ci\u00f2 gli assicur\u00f2 per diversi anni la benevolenza dell\u2019Internazionale socialista e pi\u00f9 in generale di quegli ambienti dell\u2019establishment progressista europeo che oggi fanno la parte degli anti-Gheddafi della prima ora.<\/p>\n<p style=\"text-align: justify;\"><strong>Questo gli consent\u00ec di espellere dalla Libia nel 1970 nell\u2019arco di due mesi 20 mila coloni italiani,<\/strong> dopo aver sequestrato senza il minimo indennizzo tutti i loro beni, senza grandi mobilitazioni da parte della stampa italiana e senza nemmeno alcuna seria resistenza da parte del governo di Roma dell\u2019epoca. Si ebbe allora l\u2019impressione che si barattasse l\u2019acquiescenza nei confronti di questa espulsione di massa con il tranquillo sviluppo della presenza dell\u2019ENI in Libia. La massima parte di questi coloni erano agricoltori, che coltivavano in Cirenaica poderi loro assegnati dal regime fascista quando ancora la Libia era una colonia italiana.<\/p>\n<p style=\"text-align: justify;\">Quindi pu\u00f2 darsi che la loro presenza in Libia non fosse pi\u00f9 politicamente sostenibile. Resta il fatto che il nostro governo del tempo non solo si lasci\u00f2 cogliere di sorpresa dall\u2019iniziativa di Gheddafi ma anche nemmeno tent\u00f2 di ottenere che l\u2019esodo avvenisse in modo graduale e che ai coloni si riconoscesse un indennizzo per il valore che il loro lavoro aveva aggiunto a terreni che al momento dell\u2019assegnazione erano o mal coltivati o pi\u00f9 spesso incolti.<\/p>\n<p style=\"text-align: justify;\"><strong>La vicenda \u00e8 importante anche ai fini della comprensione dei successivi sviluppi<\/strong> del regime di Gheddafi. Il colonnello ne ricav\u00f2 il convincimento che pestando i pugni sul tavolo all\u2019Italia e all\u2019Occidente in genere si poteva far ingoiare qualunque cosa.<\/p>\n<p style=\"text-align: justify;\">In seguito assunse una posizione sempre pi\u00f9 fortemente anti-americana e anti-israeliana fino a sostenere gruppi terroristici. Nell\u2019aprile 1986 il presidente americano Reagan arriv\u00f2 al punto di ordinare un bombardamento improvviso sulla sua residenza. I bombardieri lanciati da una portaerei in navigazione nel Mediterraneo distrussero l\u2019edificio ma Gheddafi sfugg\u00ec all\u2019attentato, a quanto pare perch\u00e9 il presidente del Consiglio italiano del tempo, Bettino Craxi, lo avvis\u00f2 di quanto stava per accadere ritenendo (molto probabilmente a ragione) che la sua repentina scomparsa avrebbe creato in Libia un vuoto politico che sarebbe stato probabilmente colmato da qualcuno peggiore di lui.<\/p>\n<p style=\"text-align: justify;\"><strong>Caduto il muro di Berlino e finita la \u201cGuerra fredda\u201d nel 1991<\/strong> con la disfatta dell\u2019Unione Sovietica, per Gheddafi e per molti altri personaggi simili a lui viene meno la possibilit\u00e0 di continuare a giostrare giocando sull\u2019antagonismo Usa\/Urss. Il colonnello decide perci\u00f2 di cambiare politica: cessa ogni sostegno al terrorismo, interviene in alcuni conflitti africani nel ruolo per lui inusitato del pacificatore, e infine dal 2003 in avanti si avvicina apertamente all\u2019Occidente e in primis al nostro Paese, che era restato comunque il principale partner economico della Libia.<\/p>\n<p style=\"text-align: justify;\">Da parte italiana si tratta di un processo che si compie con Berlusconi (per ragionevoli motivi su cui qui non mi soffermo dal momento che gi\u00e0 sono stati bene illustrati da <a href=\"http:\/\/www.labussolaquotidiana.it\/ita\/articoli-dopo-gheddafi-si-rischiauna-nuova-somalia-1089.htm\" target=\"_blank\">Rodolfo Casadei<\/a>) ma era iniziato con D\u2019Alema, come varrebbe la pena di ricordare a quei leader del PD che ora attaccano l\u2019attuale premier per aver firmato il trattato di Bengasi (30 agosto 2008) e aver poi invitato Gheddafi in visita di Stato a Roma con gli inevitabili risvolti pittoreschi.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cosa fare adesso?<\/strong> Adesso occorre fare di tutto perch\u00e9 la transizione in atto in Libia abbia luogo nel modo meno catastrofico possibile. Il nostro Paese ha molte carte da giocare al riguardo. Speriamo che le sappia giocare bene.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bussola quotidiana 28 febbraio 2011 di Robi Ronza Muammar Gheddafi, al cui cruento tramonto stiamo assistendo in questi giorni, \u00e8 o era al potere da 42 anni: un primato assoluto, tanto pi\u00f9 notevole se si considera che egli \u00e8 sempre rimasto un privato cittadino senza mai assumere alcuna carica istituzionale, forte solo del titolo, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":22125,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,18],"tags":[1915,1916],"class_list":["post-4437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-personaggi","tag-libia","tag-muammar-gheddafi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gheddafi, chi era costui? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gheddafi, chi era costui? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-05T16:35:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-26T15:46:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Gheddafi, chi era costui?\",\"datePublished\":\"2011-03-05T16:35:50+00:00\",\"dateModified\":\"2015-03-26T15:46:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/\"},\"wordCount\":797,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/Gheddafi.jpg\",\"keywords\":[\"Libia\",\"Muammar Gheddafi\"],\"articleSection\":[\"Paesi e continenti\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/\",\"name\":\"Gheddafi, chi era costui? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/Gheddafi.jpg\",\"datePublished\":\"2011-03-05T16:35:50+00:00\",\"dateModified\":\"2015-03-26T15:46:08+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/Gheddafi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/Gheddafi.jpg\",\"width\":255,\"height\":198},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gheddafi-chi-era-costui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gheddafi, chi era costui?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gheddafi, chi era costui? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/","og_locale":"it_IT","og_type":"article","og_title":"Gheddafi, chi era costui? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-03-05T16:35:50+00:00","article_modified_time":"2015-03-26T15:46:08+00:00","og_image":[{"width":255,"height":198,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Gheddafi, chi era costui?","datePublished":"2011-03-05T16:35:50+00:00","dateModified":"2015-03-26T15:46:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/"},"wordCount":797,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg","keywords":["Libia","Muammar Gheddafi"],"articleSection":["Paesi e continenti","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/","name":"Gheddafi, chi era costui? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg","datePublished":"2011-03-05T16:35:50+00:00","dateModified":"2015-03-26T15:46:08+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/03\/Gheddafi.jpg","width":255,"height":198},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gheddafi-chi-era-costui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Gheddafi, chi era costui?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4437"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4437\/revisions"}],"predecessor-version":[{"id":22126,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4437\/revisions\/22126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/22125"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}