{"id":44330,"date":"2019-09-19T00:00:40","date_gmt":"2019-09-18T22:00:40","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=44330"},"modified":"2019-09-17T13:14:49","modified_gmt":"2019-09-17T11:14:49","slug":"44330","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/","title":{"rendered":"Appassionato del volto umano di Cristo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-44333\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli.jpg\" alt=\"\" width=\"250\" height=\"166\" \/><\/a>Litterae Communionis<\/strong> Anno VIII n.5 \u2013 Maggio 1981 <strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Cercate ogni giorno il volto dei santi\u202624 aprile Vincenzo de\u2019 Paoli <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Maria Ida Cislaghi<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">In Cristo e per Cristo, Dio si \u00e8 rivelato pienamente all&#8217;umanit\u00e0 e si \u00e8 definitivamente avvicinato ad essa e, nello stesso tempo, in Cristo e per Cristo, l&#8217;uomo ha acquistato piena coscienza della sua dignit\u00e0, della sua elevazione, del valore trascendente della propria umanit\u00e0, del senso della sua esistenza (R. H., II).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7364\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\" alt=\"\" width=\"175\" height=\"200\" \/><\/a>Queste parole di Giovanni Paolo II esprimono sinteticamente la coscienza di fede che Vincenzo de&#8217; Paoli matur\u00f2 giorno dopo giorno nella sua lunga e travagliata esistenza di contadino, di prete e di santo (1581\/1660). Ed \u00e8 proprio il graduale emergere di questa coscienza che fa nascere dal suo cuore e dalle sue mani quella fantasiosa serie di interventi caritativi a favore dell&#8217;uomo, sempre pi\u00f9 frequenti e stabili fino ad organizzarsi in veri e propri movimenti e congregazioni.<\/p>\n<p style=\"text-align: justify;\">Il suo nome \u00e8 legato alla carit\u00e0, specialmente alla carit\u00e0 organizzata; gigante della carit\u00e0 lo chiam\u00f2 Giovanni Paolo I il 27 settembre 1978, ma forse per questo oggi, in una societ\u00e0 che si ritiene specialista in fatto di organizzazione, pu\u00f2 sembrare anacronistico il confronto con un uomo del 1600. Vincenzo de&#8217; Paoli per\u00f2 \u00e8 un santo e proprio perch\u00e9 tale la sua \u00abmemoria\u00bb \u00e8 profezia per la Chiesa e l&#8217;umanit\u00e0 di ogni stagione.<\/p>\n<p style=\"text-align: justify;\">La sua vita, infatti, non \u00e8 isolata all&#8217;interno della storia della Chiesa, ma una particolare e precisa modalit\u00e0 di quella vita perenne e meravigliosa che costituisce la storia stessa della Chiesa.<\/p>\n<p style=\"text-align: center;\"><strong>Dal suo progetto a quello del Padre <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44335 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-1.jpg\" alt=\"\" width=\"184\" height=\"275\" \/><\/a>Vincenzo nasce il 24 aprile 1581 a Pouy presso Dax, nelle Lande, a circa 100 km. da Lourdes. La sua famiglia \u00e8 contadina, perci\u00f2 vive la fanciullezza a contatto con la natura, facendo il pastore e il guardiano di porci, come amava definirsi pi\u00f9 tardi, appollaiato su alti trampoli.<\/p>\n<p style=\"text-align: justify;\">Riceve la cultura della sua gente, fondata su fede solida e sincera, sulla fedelt\u00e0 alla famiglia e sul senso della giustizia. Matura la vocazione sacerdotale non senza l&#8217;audacia e l&#8217;ambizione di fare carriera ecclesiastica; la sua aspirazione non ha i confini del cielo che contempla pascolando i porci, si accontenta infatti di vivere di rendita, senza fastidi n\u00e9 grossi incomodi. I suoi orizzonti sono ristretti e le sue ambizioni limitate.<\/p>\n<p style=\"text-align: justify;\">Diventa prete nel settembre 1600 e per alcuni anni accarezza le sue ambizioni e insegue il suo mediocre progetto, non tanto per s\u00e9, egli dice, quanto per ricompensare la madre e i parenti per gli enormi sacrifici che hanno fatto per farlo studiare \u2014 avevano venduto due buoi \u2014.<\/p>\n<p style=\"text-align: justify;\">Vincenzo comincia a viaggiare e proprio durante un viaggio viene fatto prigioniero, venduto e rivenduto come schiavo al mercato di Tunisi; riesce a rimpatriare dopo due anni col suo padrone, un cristiano rinnegato poi convertito. Pu\u00f2 finalmente riprendere la carriera desiderata e diventa cappellano di corte, ma Dio ha altri piani su Vincenzo de&#8217; Paoli e non tarda a manifestarli.<\/p>\n<div id=\"attachment_44336\" style=\"width: 152px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Pietro_de_Berulle.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44336\" class=\"wp-image-44336\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Pietro_de_Berulle.jpg\" alt=\"\" width=\"152\" height=\"200\" \/><\/a><p id=\"caption-attachment-44336\" class=\"wp-caption-text\">Pietro de&#8217; Berulle<\/p><\/div>\n<p style=\"text-align: justify;\">Proprio nel momento in cui entra nel mondo dei \u00abgrandi\u00bb del regno di Francia, si manifesta in lui un profondo cambiamento di prospettiva. Vincenzo incontra Pietro de&#8217; Berulle, uno dei padri della riforma della Chiesa di Francia del &#8216;600, e si pone sotto la sua guida spirituale. Accetta di diventare parroco della Parrocchia di Clichy, nei pressi di Parigi, e qui prova il gusto di essere prete e prete degli umili, ma dopo appena un anno diventa cappellano della famiglia Gondi, ricchi fiorentini residenti alla corte.<\/p>\n<p style=\"text-align: justify;\">Ora Dio lo attende, quasi in agguato, per manifestargli il suo progetto e fare di lui un docile ed infaticabile manovale della sua Chiesa.<\/p>\n<p style=\"text-align: center;\"><strong>Nell&#8217;uomo l&#8217;incontro con Cristo<\/strong><\/p>\n<p style=\"text-align: justify;\">Vincenzo vive un periodo di dure prove contro la fede, da cui uscir\u00e0 nel &#8216;617, mentre promette a Dio di dedicare il resto dei suoi giorni al servizio dei poveri. Sempre nel &#8216;617, durante un viaggio nei possedimenti dei Gondi, Vincenzo apre gli occhi sui poveri, si accorge del loro abbandono spirituale, fa l&#8217;esperienza del tremendo bisogno dell&#8217;uomo senza annuncio e senza pane. Proprio qui, nella carne del povero. Dio fa irruzione nella sua vita. \u00abGuardando l&#8217;uomo, Vincenzo incontra Dio e percepisce la sua chiamata\u00bb. Il povero diventa per lui ci\u00f2 che il roveto ardente fu per Mos\u00e8.<\/p>\n<p style=\"text-align: justify;\">Vincenzo risponde a Dio coinvolgendo altri preti e con loro si dedica alle Missioni Popolari. E&#8217; l&#8217;inizio della Congregazione della Missione (gennaio 1617). Nello stesso anno, diventato parroco a Chatillon, viene informato che una famiglia muore di fame; Vincenzo, durante la predica, sensibilizza tutta la popolazione, che attua una reale condivisione dei beni. Da questo avvenimento nasce la \u00abprima carit\u00e0\u00bb, cio\u00e8 un embrione di Chiesa organizzato per far partecipare i pi\u00f9 poveri ai beni di tutti. In tal modo Vincenzo scopre ai laici la loro vocazione di collaborazione attiva alla vita della Chiesa.<\/p>\n<p style=\"text-align: center;\"><strong>Vita come vocazione<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44337 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-2.jpg\" alt=\"\" width=\"159\" height=\"180\" \/><\/a>Pezzo dopo pezzo Vincenzo distrugge una fede fondata sulle proprie iniziative e percepisce la fede come adesione ad un progetto che gratuitamente Dio gli prepara e gli presenta giorno dopo giorno. La vita \u00e8 ormai \u00abvocazione\u00bb e non pi\u00f9 inseguimento di un progetto personale. Egli passa gradatamente da una fede piuttosto formale ad una fede che lo fa stupire di fronte alla scoperta che Cristo si \u00e8 fatto storia, incarnato negli avvenimenti, perci\u00f2 incontrollabile.<\/p>\n<p style=\"text-align: justify;\">Il disegno di Dio acquista una chiara luminosit\u00e0, svelando il suo mistero nella persona umana. Qui \u00e8 presente il volto stesso di Ges\u00f9 Cristo. Questa chiarezza si fa sempre pi\u00f9 lucente ed inequivocabile nel volto del Povero; proprio il Povero, perch\u00e9 abitato da Cristo, diventa il luogo privilegiato della sua contemplazione e la realt\u00e0 che mobilita e suscita il suo infaticabile servizio. La persona umana, soprattutto il Povero, diventa il \u00abluogo concreto e stabile\u00bb della sua alleanza con Dio.<\/p>\n<p style=\"text-align: justify;\">Tutte le sue opere nascono da questo incontro con Ges\u00f9 Cristo nell&#8217;uomo. Il santo vive un religioso ascolto della realt\u00e0, una sequela agli avvenimenti, perch\u00e9 abitati da Dio. E&#8217; per questo che, quando si presenta una povera ragazza di campagna disposta a servire i poveri col cuore pieno di Dio, Vincenzo, ancora una volta, riconosce l&#8217;appello del Padre e comprende che per servire meglio i Poveri, per garantire la continuit\u00e0 nel servizio, bisogna appartenere a Dio, bisogna essere poveri, avere il cuore vergine, colmo di amore per Dio e i fratelli e perci\u00f2 capaci di dedicarvi non solo un giorno o una stagione, ma la vita intera. Cos\u00ec nascono le Figlie della Carit\u00e0 \u2014 novembre 1633 \u2014 e Vincenzo dona loro:<\/p>\n<p style=\"text-align: justify;\"><em>per monastero la casa dei malati,<\/em><\/p>\n<p style=\"text-align: justify;\"><em>per cella una camera d&#8217;aff\u00ectto, <\/em><\/p>\n<p style=\"text-align: justify;\"><em>per cappella la chiesa parrocchiale, <\/em><\/p>\n<p style=\"text-align: justify;\"><em>per chiostro le vie della citt\u00e0 e le sale degli ospedali,<\/em><\/p>\n<p style=\"text-align: justify;\"><em>per clausura l&#8217;obbedienza, per grata il timor di Dio, <\/em><\/p>\n<p style=\"text-align: justify;\"><em>per velo la santa modestia. <\/em><\/p>\n<p style=\"text-align: center;\"><strong>Cristo amato e servito nell&#8217;uomo <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/ospedale_carit\u00e0_Parigi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44338 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/ospedale_carit\u00e0_Parigi.jpg\" alt=\"\" width=\"249\" height=\"203\" \/><\/a>La maniera vincenziana di seguire Cristo, adoratore del Padre, servitore del suo progetto di amore, evangelizzatore dei Poveri, \u00e8 di contemplarlo e servirlo nei Poveri con un amore semplice ed umile. Questa visione e questo servizio sono sempre l&#8217;ispirazione fondamentale di ogni sua opera; sono la \u00abvera profezia\u00bb di Vincenzo, il dono che lo Spirito offre alla Chiesa attraverso il suo cuore di santo e le sue mani di contadino guascone.<\/p>\n<p style=\"text-align: justify;\">E&#8217; evidente, quindi, che per Vincenzo la carit\u00e0 non \u00e8 semplicemente fare qualcosa o fare molte cose a favore dei Poveri. Percepisce infatti la sua vita e quella dei suoi figli come \u00abstato di carit\u00e0\u00bb per dono dello Spirito, ed \u00e8 proprio il permanere nella comunione che lo rende capace di vedere ogni persona come sacramento di Cristo, cos\u00ec come Cristo \u00e8 sacramento del Padre.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Servendo i Poveri, nostri signori e padroni, voi servite Ges\u00f9 Cristo; s\u00ec, una suora andr\u00e0 dieci volte al giorno dai malati e dieci volte vi trover\u00e0 Dio, oh che felicit\u00e0!&#8230; Non temete di lasciare l&#8217;orazione per il servizio dei Poveri, voi lasciate Dio per Dio, perch\u00e9 lo lasciate nell&#8217;orazione e lo ritrovate nel Povero!\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Ed ancora: \u00ab<em>Amiamo Dio, s\u00ec, ma col sudore della nostra fronte e la fatica delle nostre braccia<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ormai Vincenzo non si ferma pi\u00f9; l&#8217;esistenza toccata dall&#8217;incontro con Cristo nell&#8217;uomo, diventa segno della sua gloria; tutti i gesti e gli avveni\u00admenti sono condotti al significato: \u00ab<em>Bisogna santificare le proprie occupazioni cercandovi Dio e compierle pi\u00f9 per trovarvi Dio che per vederle fatte<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">La motivazione \u00e8 l&#8217;adesione alla volont\u00e0 di Dio alla quale, appunto, Vincenzo si consegna come un bimbo alle braccia della madre.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/poveri.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33635\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/poveri.jpg\" alt=\"\" width=\"250\" height=\"166\" \/><\/a>La vita diventa il mistero dell&#8217;unione di Dio con l&#8217;uomo in Ges\u00f9 Cristo, mistero ecclesiale, percepibile solamente con la fede; non esistono pi\u00f9 momenti neutri, senza significato, niente pi\u00f9 \u00e8 indifferente nella vita di Vincenzo; ogni momento \u00e8 \u00absacramentale\u00bb, evocativo della presenza di Dio: \u00ab<em>Bisogna vedere le cose come esse sono in Dio e non come esse appaiono, altrimenti ci inganneremmo gravemente<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Questa nuova cultura, nata dalla fede, implica una concezione della vita densissima, una attivit\u00e0 senza sosta e una responsabilit\u00e0 senza mezzi termini. Vincenzo non esita pi\u00f9 a compromettersi con la realt\u00e0, dal momento che vi riconosce e vi trova Ges\u00f9 Cristo. Egli segue il reale perch\u00e9 abitato da Cristo e la sua azione, allora, ha la dimensione della Carit\u00e0.<\/p>\n<p style=\"text-align: center;\"><strong>L&#8217;uomo abitato da Cristo<\/strong><\/p>\n<p style=\"text-align: justify;\">La sua passione per Ges\u00f9 Cristo si unifica e si esprime come passione per l&#8217;uomo, l&#8217;uomo concreto che incontra ogni giorno, l&#8217;uomo che si dibatte nella miseria, ma anche l&#8217;uomo che non conosce la strada per il ritorno a Dio. Il santo vive nella sua carne la passione di Cristo per l&#8217;uomo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/poveri.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30138 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/poveri.jpg\" alt=\"\" width=\"293\" height=\"172\" \/><\/a>Egli non separa mai n\u00e9 contrappone l&#8217;evangelizzazione alla promozione umana, la fedelt\u00e0 a Dio alla fedelt\u00e0 all&#8217;uomo, la contemplazione all&#8217;azione: \u00ab<em>Bisogna dall&#8217;amore affettivo passare all&#8217;amore effettivo che \u00e8 l&#8217;esercizio delle opere di carit\u00e0, il servizio dei Poveri eseguito con gioia, coraggio, costanza e amore&#8230; Non devo considerare un povero contadino o una povera donna dal loro aspetto, n\u00e9 dalla loro apparente mentalit\u00e0; molto spesso non hanno quasi fisionomia, n\u00e9 intelligenza delle persone ragionevoli, talmente sono rozzi e materiali. Ma rigirate la medaglia e vedrete con i lumi della fede che il Figlio di Dio, il quale ha voluto essere povero, vi \u00e8 raffigurato da questi poveri; Egli non aveva quasi le sembianze di uomo nella sua passione e passava per pazzo nella mente dei pagani e per pietra di scandalo in quella dei giudei; eppure Egli si qualifica l&#8217;evangelizzatore dei Poveri. O Dio! Quanto \u00e8 bello vedere i poveri, se li consideriamo in Dio e con la stima che Egli ne aveva!<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Nutrire e curare i poveri infermi senza aiutarli anche spiritualmente, secondo il volere di Dio, sarebbe fare troppo poco per Iddio e per il prossimo; solo questo duplice servizio varr\u00e0 a rendervi figlie di Dio e imitatrici di Ges\u00f9 Cristo. Come serviva i poveri Ges\u00f9? Corporalmente e spiritualmente. O che felicit\u00e0 continuare l&#8217;opera del Figlio di Dio!<\/em>\u00bb.<\/p>\n<p style=\"text-align: center;\"><strong>Svolgimento della carit\u00e0 <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-44339\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/Vincenzo_de_Paoli-3.jpg\" alt=\"\" width=\"159\" height=\"200\" \/><\/a>Vincenzo de&#8217; Paoli, ormai ricco di dolcezza conquistata e di una umilt\u00e0 scavata a fatica nella corteccia di un ex-arrivista, reagisce istintivamente di fronte al bisogno umano coinvolgendo e organizzando, ma non gi\u00e0 in base ad una riflessione sociologica \u2014 come fanno i suoi contemporanei \u2014, bens\u00ec perch\u00e9 vede manipolato il volto dell&#8217;uomo e cos\u00ec misconosciuto ed infangato il volto umano del suo Dio, sempre presente e rilucente nel \u00abmistero\u00bb di ogni persona umana.<\/p>\n<p style=\"text-align: justify;\">Senza questa percezione sacramentale o misterica della realt\u00e0, specialmente della realt\u00e0 umana, il Povero non avrebbe tutta la sua capacit\u00e0 evocativa ed il servizio sarebbe semplicemente gesto umanitario, non invece una proclamazione della paternit\u00e0 di Dio.<\/p>\n<p style=\"text-align: justify;\">Vincenzo, dunque, \u00e8 un contemplativo e proprio per questo \u00e8 creativo, un inventore di attivit\u00e0, un geniale organizzatore di interventi caritativi, \u00e8 veramente un uomo attivo, ma mai un attivista. Il suo sguardo su Cristo nell&#8217;uomo e sull&#8217;uomo in Cristo non solo si approfondisce, ma si dilata: \u00abNon mi basta di amare Dio, se il mio prossimo non lo ama\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il suo sguardo diventa universale; Vincenzo non \u00e8 l&#8217;uomo di una specializzazione pastorale, n\u00e9 pi\u00f9 l&#8217;uomo di un territorio definito, i limiti del suo sguardo sono \u00abdappertutto, ove a Dio piacer\u00e0\u00bb. L\u00e0 dove c&#8217;\u00e8 un uomo affamato di pane e di \u00abParola\u00bb, Vincenzo posa lo sguardo e vi fissa i suoi occhi fino a quando il suo cuore di santo non ha provveduto a darvi una risposta degna dell&#8217;uomo. Per questo invia le prime suore in Polonia e i missionari in Madagascar, Africa del Nord, Isole Britanniche, sapendo che ogni missionario \u00e8 candidato alla morte: o violenta o per fatiche.<\/p>\n<p style=\"text-align: center;\"><strong>Segno della tenerezza del Padre <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/09\/misericordia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26780\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/09\/misericordia.jpg\" alt=\"\" width=\"210\" height=\"200\" \/><\/a>Vincenzo de&#8217; Paoli, comunque, rimane semplicemente un uomo di grande attivit\u00e0 apostolica e sociale, un modello che al massimo insinua la nostra pigrizia, se non lo si incontra con una mentalit\u00e0 ecclesiale. Per conoscere realmente questo \u00abprofeta\u00bb bisogna aver incontrato Ges\u00f9 Cristo nel Povero, almeno una volta. Bisogna che il proprio cuore abbia la stoffa della comunione ecclesiale, perch\u00e9 il Padre ci vede sempre come Chiesa, cio\u00e8 nel Figlio.<\/p>\n<p style=\"text-align: justify;\">Vincenzo \u00e8 incantato e mobilitato da questa sorprendente ed affascinante verit\u00e0 sull&#8217;uomo<\/p>\n<p style=\"text-align: justify;\">Quasi fosse alla sequela di un Papa mai incontrato, come Giovanni Paolo II, cos\u00ec affascinato del mistero dell&#8217;uomo, Vincenzo riafferma proprio il valore dell&#8217;uomo nella sua unica ed irripetibile realt\u00e0 umana, in cui permane intatta l&#8217;immagine e la somiglianza con Dio stesso (cfr. R. H., 13).<\/p>\n<p style=\"text-align: justify;\">Con le categorie e i metodi del suo tempo, ma col perenne cuore della Chiesa di sempre, colmo di tenerezza e di passione per ogni uomo, Vincenzo continua a dirci quanto sia grande e ricco di misericordia quel Padre che ha voluto fare dell&#8217;uomo vivente la sua gloria. Lui, piccolo contadino delle Lande, sembra essere un&#8217;amorevole carezza del Padre verso i suoi figli \u2014 la cresta di un&#8217;onda di quel quieto mare di immenso ed eterno Amore che \u00e8 il cuore della Trinit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Litterae Communionis Anno VIII n.5 \u2013 Maggio 1981 \u00a0 Cercate ogni giorno il volto dei santi\u202624 aprile Vincenzo de\u2019 Paoli di Maria Ida Cislaghi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":44331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,65],"tags":[157,466],"class_list":["post-44330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-santi","tag-chiesa-2","tag-santi-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T22:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Appassionato del volto umano di Cristo\",\"datePublished\":\"2019-09-18T22:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/\"},\"wordCount\":2296,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/carit\u00e0_poveri.jpg\",\"keywords\":[\"chiesa\",\"santi\"],\"articleSection\":[\"Chiesa\",\"Santi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/\",\"name\":\"Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/carit\u00e0_poveri.jpg\",\"datePublished\":\"2019-09-18T22:00:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/carit\u00e0_poveri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/carit\u00e0_poveri.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/44330\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appassionato del volto umano di Cristo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/","og_locale":"it_IT","og_type":"article","og_title":"Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-09-18T22:00:40+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Appassionato del volto umano di Cristo","datePublished":"2019-09-18T22:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/"},"wordCount":2296,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg","keywords":["chiesa","santi"],"articleSection":["Chiesa","Santi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/","name":"Appassionato del volto umano di Cristo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg","datePublished":"2019-09-18T22:00:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/carit\u00e0_poveri.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/44330\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Appassionato del volto umano di Cristo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=44330"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44330\/revisions"}],"predecessor-version":[{"id":44340,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44330\/revisions\/44340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/44331"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=44330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=44330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=44330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}