{"id":4427,"date":"2011-02-24T00:00:00","date_gmt":"2011-02-23T23:00:00","guid":{"rendered":""},"modified":"2015-03-27T10:09:13","modified_gmt":"2015-03-27T09:09:13","slug":"quando-la-madonna-indoss-il-tricolore","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/","title":{"rendered":"Quando la Madonna indoss&ograve; il Tricolore&#8230;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22163\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia-300x300.png\" alt=\"azzurro_savoia\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia-150x150.png 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Libero<\/strong> 13 febbraio 2011<\/div>\n<p style=\"text-align: center;\">di <strong>Antonio Socci<\/strong><\/p>\n<p style=\"text-align: justify;\">Gli italiani sono \u201cgli azzurri\u201d. Nessuno sa che con i 150 anni dell\u2019Italia unita, si festeggiano anche i 100 anni dell\u2019 \u201cazzurro\u201d come colore nazionale. Viene dall\u2019iconografia mariana e la dinastia sabauda ne fece un suo simbolo. Scrive Luigi Cibrario, storico della monarchia: \u201cquel colore di cielo consacrato a Maria \u00e8 l\u2019origine del nostro color nazionale\u201d.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>Tutto cominci\u00f2<\/strong> il 21 giugno 1366. Amedeo VI di Savoia salpa da Venezia per la Terra Santa, per la crociata voluta da papa Urbano V e sulla sua nave ammiraglia \u2013 accanto al vessillo dei Savoia \u2013 fa sventolare uno stendardo azzurro con una corona di stelle attorno all\u2019 immagine della Madonna, per invocare \u201cMaria Santissima, aiuto dei cristiani\u201d.<\/div>\n<p style=\"text-align: justify;\">L\u2019azzurro di quel vessillo mariano fu ripreso da alcuni cavalieri sabaudi che, in onore alla Santa Vergine, cinsero delle sciarpe azzurre sull\u2019uniforme. Ne nacque una tradizione, fra gli ufficiali savoiardi. L\u2019azzurro entr\u00f2 a far parte dei simboli dinastici e il 10 gennaio 1572, con Emanuele Filiberto, la sciarpa azzurra divent\u00f2 ufficialmente parte dell\u2019uniforme. E poi dell\u2019araldica del Regno d\u2019Italia.<\/p>\n<p style=\"text-align: justify;\"><strong>Pare che sia diventato<\/strong> il nostro colore ufficiale nelle competizioni sportive, per la prima volta, a Milano, il 6 gennaio 1911, per la partita di calcio Italia-Ungheria: quindi cento anni fa. La piccola storia di questo simbolo fa capire che la tradizione cattolica impregna totalmente la storia italiana. D\u2019altra parte il Regno dei Savoia \u00e8 sempre stato cattolicissimo. Con la restaurazione fu l\u2019unico regno italiano, insieme allo Stato pontificio, ad abolire il Codice napoleonico: \u201cla dinastia sabauda\u201d scrive De Leonardis \u201caveva dato alla Chiesa cinque beati e vantava titoli di fedelt\u00e0 al Cattolicesimo che fino al 1848 erano forse superiori a quelli dei Borbone e degli Asburgo; a differenza di questi ultimi i sovrani sabaudi non si erano compromessi con le idee illuministe e massoniche\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Sar\u00e0 l\u2019ultimo re d\u2019Italia<\/strong> infine a donare alla Chiesa la pi\u00f9 preziosa delle reliquie: la Sindone. Che l\u2019unificazione d\u2019Italia sotto il re sabaudo \u2013 con Cavour \u2013 abbia preso la forma di un conflitto contro la Chiesa \u00e8 una di quelle tragedie storiche che probabilmente nessuno volle in maniera deliberata. Basti pensare che il Regno sabaudo nel suo Statuto proclamava il Cattolicesimo come sua religione ufficiale. E poi c\u2019\u00e8 anche il cattolicesimo di molti patrioti (come il Pellico) e infine il fatto che lo stesso Pio IX era un entusiastico sostenitore dell\u2019unificazione nazionale (per via federale). Non solo quando fu eletto, con il Motu proprio \u201cBenedite, Gran Dio, l\u2019Italia\u201d, quando il nome del Pontefice veniva invocato dai patrioti (ed erroneamente costoro pretesero di trascinare il Papa a far la guerra all\u2019Austria: da qui il no e la rottura).<\/p>\n<p style=\"text-align: justify;\"><strong>Pio IX rest\u00f2 legato<\/strong> all\u2019ideale dell\u2019Italia sempre, anche nel pieno del conflitto risorgimentale. E questo \u00e8 un aspetto quasi sconosciuto. Come i cattolicissimi Savoia, anche il Papa visse un drammatico conflitto interiore fra il dovere di difendere la Chiesa \u2013 che veniva aggredita e spogliata dal nuovo Stato \u2013 e la sua personale simpatia per la causa nazionale. Un giorno un conte germanico in visita al Santo Padre gli manifest\u00f2 il suo sdegno per l\u2019aggressione in corso ai danni dello Stato Pontificio e della Chiesa, e, dopo averlo ascoltato, Pio IX mormor\u00f2 ai suoi: \u201cQuesto bestione tedesco non capisce la grandezza e la bellezza dell\u2019idea nazionale italiana\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Errori tragici<\/strong> ve ne furono da entrambe le parti. E certamente l\u2019idea di unificare l\u2019Italia non per via pacifica e federale come prospettava il Papa, ma per via militare e sotto una sola dinastia fu devastante anche per il meridione d\u2019Italia, dove da secoli governava una monarchia legittima quanto quella sabauda. Ben ventidue anni fa, nel 1988, quando ancora non era emersa la Lega Nord, scrissi un libro di denuncia contro il Risorgimento come \u201cconquista piemontese\u201d e \u2013 curiosamente \u2013 fu pubblicato dalla Sugarco di Massimo Pini, un editore molto vicino al garibaldino Bettino Craxi. Il libro \u2013 riedito sei anni fa col titolo \u201cLa dittatura anticattolica\u201d usc\u00ec quando nessuno metteva in discussione il Risorgimento. Oggi che \u2013 al contrario \u2013 \u00e8 diventata una moda, vorrei sommessamente dire il mio \u201cViva l\u2019Italia!\u201d e penso che si debba festeggiare il 17 marzo.<\/p>\n<p style=\"text-align: justify;\"><strong>Per noi cattolici<\/strong> c\u2019\u00e8 comunque qualcosa di provvidenziale nel Risorgimento italiano (anche nella fine del potere temporale dei papi, come ebbe a dire Paolo VI), perch\u00e9 Dio sa scrivere diritto anche sulle righe storte degli uomini. E infine ha fatto salvare l\u2019indipendenza, l\u2019unit\u00e0 e la libert\u00e0 dell\u2019Italia proprio ai cattolici e al Papa, il 18 aprile 1948, a cento anni esatti dalla preghiera per l\u2019Italia di Pio IX. Del resto il cattolicesimo era il solo cemento degli italiani. Infatti cosa li univa nell\u2019Ottocento? La lingua no. Nel 1861 gli italiofoni erano solo il 2,5 per cento della popolazione, perlopi\u00f9 toscani (gli stessi Savoia a corte parlavano francese). Nemmeno l\u2019economia li univa: la Sicilia era pi\u00f9 integrata economicamente all\u2019Inghilterra che alla Lombardia e il Piemonte pi\u00f9 alla Francia che alla Sicilia.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci\u00f2 che univa il Paese<\/strong> erano Roma e le tradizioni cattoliche. Tanto \u00e8 vero che il poema della risorgente nazione italiana fu il poema della Provvidenza, \u201cI promessi sposi\u201d del cattolicissimo Manzoni. E fu deciso \u201ca tavolino\u201d che la lingua italiana fosse, da allora, quella della Divina Commedia dantesca, cio\u00e8 il pi\u00f9 grande poema mistico e addirittura liturgico della storia della Chiesa. Perfino il tricolore adottato dai Savoia \u2013 nato apparentemente ghibellino \u2013 \u00e8 intriso di tradizione cattolica. Lo studente bolognese Luigi Zamboni, che col De Rolandis lo concep\u00ec nel settembre 1794, nell\u2019entusiastica attesa dell\u2019arrivo napoleonico che avrebbe liberato dal giogo dello Stato pontificio, part\u00ec dallo stemma di Bologna, quella croce rossa in campo bianco che viene dalle crociate e dalla Lega lombarda (a cui Bologna appartenne).<\/p>\n<p style=\"text-align: justify;\"><strong>Al bianco e rosso<\/strong> lui aggiunse \u201cil verde\u201d, che \u2013 disse \u2013 era \u201csegno della speranza\u201d. In effetti simboleggiava la speranza nella tradizione cattolica, come virt\u00f9 teologale, insieme alla fede, che aveva come simbolo il bianco, e alla carit\u00e0 (il rosso). Non a caso il primo \u201cbianco, rosso e verde\u201d lo troviamo proprio nella Divina Commedia, sono i vestiti delle tre fanciulle che, nel Paradiso terrestre, accompagnano Beatrice e che simboleggiano appunto le virt\u00f9 teologali (Purg. XXX, 30-33). Lo stesso \u201cmangiapreti\u201d Carducci, che certo non era ignaro di Dante, n\u00e9 di dottrina cattolica, nel suo discorso ufficiale per il primo centenario della nascita del Tricolore, a Reggio Emilia, d\u00e0, a quei tre colori, proprio il significato della Divina Commedia (fede, speranza e amore, sia pure in senso laico).<\/p>\n<p style=\"text-align: justify;\"><strong>E\u2019 ovvio che la Chiesa<\/strong> sia intimamente legata a questa terra \u201conde Cristo \u00e8 romano\u201d e pare evidente la missione religiosa dell\u2019Italia (sembra che la parola I-t-a-l-y-a in ebraico significhi \u201cisola della rugiada divina\u201d). Nessuno per\u00f2 sa che \u00e8 stata addirittura la Madonna in persona a \u201cconsacrare\u201d il tricolore nell\u2019importante apparizione del 12 aprile 1947 a Roma, alle Tre Fontane, a Bruno Cornacchiola (il mangiapreti che si convert\u00ec). Era un fanciulla di sfolgorante bellezza e indossava un lungo abito bianco, con una fascia rossa in vita e un mantello verde. Consegn\u00f2 al Cornacchiola un importante messaggio per il Santo Padre. E poi alla mistica Maria Valtorta spieg\u00f2 che apparve \u201cvestita dei colori della tua Patria, che sono anche quelli delle tre virt\u00f9 teologali, perch\u00e9 virt\u00f9 e patria sono troppo disamate, trascurate, calpestate, ed io vengo a ricordare, con questa mia veste inusitata, per me, che occorre tornare all\u2019amore, alle Virt\u00f9 e alla Patria, al vero Amore\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Aggiunse che era apparsa<\/strong> a Roma perch\u00e9 \u201csede del papato e il Papa avr\u00e0 tanto e sempre pi\u00f9 a soffrire, questo, e i futuri, per le forze d\u2019Inferno scagliate sempre pi\u00f9 contro la S. Chiesa\u201d. Aggiunse che apparve per la terribile minaccia del \u201cComunismo, la spada pi\u00f9 pungente infissa nel mio Cuore, quella che mi fa cadere queste lacrime\u201d. Essa \u00e8 \u201cla piovra orrenda, veleno satanico\u201d che \u201cstringe e avvelena e si estende a far sempre nuove prede\u201d, una minaccia \u201cmondiale, che abbranca e trascina al naufragio totale: di corpi, anime, nazioni\u201d. Era in effetti il 1947. L\u2019Armata Rossa stava marciando su mezza Europa, fino a Trieste. E l\u2019Italia il 18 aprile 1948 si salv\u00f2 solo per l\u2019impegno del papa e della Chiesa, da cui venne alla patria uno statista come De Gasperi, che salv\u00f2 la libert\u00e0 e cos\u00ec comp\u00ec davvero il Risorgimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libero 13 febbraio 2011 di Antonio Socci Gli italiani sono \u201cgli azzurri\u201d. Nessuno sa che con i 150 anni dell\u2019Italia unita, si festeggiano anche i 100 anni dell\u2019 \u201cazzurro\u201d come colore nazionale. Viene dall\u2019iconografia mariana e la dinastia sabauda ne fece un suo simbolo. Scrive Luigi Cibrario, storico della monarchia: \u201cquel colore di cielo consacrato &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":22163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[1287,1510],"class_list":["post-4427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storia-italiana","tag-150-unita","tag-unita-ditalia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-23T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-27T09:09:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Quando la Madonna indoss&ograve; il Tricolore&#8230;\",\"datePublished\":\"2011-02-23T23:00:00+00:00\",\"dateModified\":\"2015-03-27T09:09:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/\"},\"wordCount\":1377,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/azzurro_savoia.png\",\"keywords\":[\"150 Unit\u00e0\",\"unit\u00e0 d'Italia\"],\"articleSection\":[\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/\",\"name\":\"Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/azzurro_savoia.png\",\"datePublished\":\"2011-02-23T23:00:00+00:00\",\"dateModified\":\"2015-03-27T09:09:13+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/azzurro_savoia.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/azzurro_savoia.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-la-madonna-indoss-il-tricolore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando la Madonna indoss&ograve; il Tricolore&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/","og_locale":"it_IT","og_type":"article","og_title":"Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-02-23T23:00:00+00:00","article_modified_time":"2015-03-27T09:09:13+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Quando la Madonna indoss&ograve; il Tricolore&#8230;","datePublished":"2011-02-23T23:00:00+00:00","dateModified":"2015-03-27T09:09:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/"},"wordCount":1377,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png","keywords":["150 Unit\u00e0","unit\u00e0 d'Italia"],"articleSection":["Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/","name":"Quando la Madonna indoss&ograve; il Tricolore... - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png","datePublished":"2011-02-23T23:00:00+00:00","dateModified":"2015-03-27T09:09:13+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/02\/azzurro_savoia.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-la-madonna-indoss-il-tricolore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Quando la Madonna indoss&ograve; il Tricolore&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4427"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4427\/revisions"}],"predecessor-version":[{"id":22164,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4427\/revisions\/22164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/22163"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}