{"id":44209,"date":"2019-09-05T00:00:39","date_gmt":"2019-09-04T22:00:39","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=44209"},"modified":"2020-02-24T12:16:37","modified_gmt":"2020-02-24T11:16:37","slug":"dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/","title":{"rendered":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/repubblica_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-44211 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/repubblica_cover-218x300.jpg\" alt=\"\" width=\"218\" height=\"300\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/repubblica_cover-218x300.jpg 218w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/09\/repubblica_cover.jpg 436w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/a>Da <strong><a href=\"http:\/\/www.atlanticoquotidiano.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Atlantico<\/a> <\/strong><\/p>\n<p style=\"text-align: center;\">2 Settembre 2019<\/p>\n<p style=\"text-align: center;\">di <strong>Martino Loiacono<\/strong><\/p>\n<p style=\"text-align: justify;\">Qualche settimana fa <em>la Repubblica<\/em>, dopo le sanguinose sparatorie avvenute in America, titolava <em>\u201cLe stragi dell\u2019uomo bianco\u201d<\/em>. Un titolo apparentemente neutro ma che in realt\u00e0 celava un messaggio specifico. Un messaggio di sapore razzista (pensate se <em>la Verit\u00e0<\/em> o <em>Libero <\/em>avessero aperto con un titolo del genere), ma non solo.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Ad un\u2019analisi pi\u00f9 profonda, e tenendo a mente il contesto dei media e dell\u2019accademia anglosassoni, il titolo rappresentava una critica alla cosiddetta <em>Western Civilization<\/em>, di cui l\u2019uomo bianco sarebbe il maggiore interprete. L\u2019aggettivo \u201cbianco\u201d, in questo caso, anche se non troppo esplicitamente, voleva ricollegare le sparatorie alla cultura occidentale.<\/p>\n<p style=\"text-align: justify;\">Un\u2019operazione maldestra, che pu\u00f2 essere compresa solo se inquadrata nella logica del politicamente corretto in cui attaccare l\u2019uomo bianco, meglio se maschio, significa colpire la cultura occidentale. Una cultura che secondo i suoi critici sarebbe responsabile del razzismo, del colonialismo, del maschilismo, dell\u2019omofobia e di ogni forma di discriminazione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-42816 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto-1024x682.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Questa tendenza, come dimostra il titolo di <em>Repubblica<\/em>, \u00e8 sempre pi\u00f9 diffusa. Certo, l\u2019Italia \u00e8 ancora molto lontana dagli estremismi registrati nei campus americani, ma grazie ad alcune avanguardie intellettuali si sta gradualmente avvicinando a certe battaglie culturali. Per questo \u00e8 bene capire qual \u00e8 il meccanismo alla base di una moda culturale in chiara espansione.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che la fonda, a ben vedere, \u00e8 una concezione distorta della storia, e forse pi\u00f9 in generale della cultura, che si basa su un presentismo assoluto. In altre parole, il passato non viene quasi mai contestualizzato e storicizzato ma interpretato esclusivamente alla luce del presente e delle sue necessit\u00e0 politiche. Tale metodo permette di distorcere senza grossi problemi testi, eventi e autori del passato.<\/p>\n<p style=\"text-align: justify;\">Astratti dal contesto e inseriti nella battaglia ideologica contemporanea possono essere utilizzati per una causa politica. Vediamo qualche esempio. Dante, essendo accusato di omofobia e islamofobia, pu\u00f2 essere sfruttato per promuovere l\u2019agenda LGBTQ e il multiculturalismo; Francesco De Sanctis, avendo peccato di virilismo nazionalista, come evidenzia Raimo nel suo pamphlet <em>\u201cContro l\u2019identit\u00e0 italiana\u201d<\/em>, per promuovere l\u2019europeismo e l\u2019accoglienza; infine, Colombo essendo un colonizzatore, pu\u00f2 essere utilizzato per tutelare le minoranze.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/Dante.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35402 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/Dante.jpg\" alt=\"\" width=\"217\" height=\"232\" \/><\/a>Come si nota, la produzione letteraria e intellettuale e il passato non vengono considerati nella loro complessit\u00e0, ma negli aspetti che pi\u00f9 hanno a che fare con l\u2019attualit\u00e0. E che perci\u00f2 possono essere spesi a seconda dei bisogni del momento. \u00a0Il frame entro cui i personaggi storici controversi vengono inquadrati \u00e8, come abbiamo anticipato, quello dell\u2019uomo bianco \u201ccattivo\u201d, il <em>mean white man<\/em> evocato da Michael Eric Dyson in un dibattito con Jordan Peterson sul politicamente corretto.<\/p>\n<p style=\"text-align: justify;\">L\u2019utilizzo di tale categoria non \u00e8 affatto casuale. In effetti, secondo una narrazione sempre pi\u00f9 diffusa, il maschio rappresenta l\u2019oppressore tradizionale delle donne e della comunit\u00e0 LGBTQ e il bianco compendia il colonialismo e il razzismo. E quindi, per rovesciare il canone occidentale e la <em>Western Civilization<\/em>, serve colpire colui che l\u2019ha costruita, il maschio bianco, cos\u00ec da porre fine a tutte le discriminazioni di cui sarebbe promotore.<\/p>\n<p style=\"text-align: justify;\">Ad oggi, \u00e8 difficile prevedere come evolver\u00e0 questa preoccupante tendenza. Ad osservare il titolo di <em>Repubblica <\/em>e a leggere il volume di Raimo la via sembra tracciata. Star\u00e0 agli uomini e alle donne di cultura, a prescindere dal loro orientamento politico, contrastare una barbarie culturale in grado di distruggere il passato, la societ\u00e0 e la politica.<\/p>\n<p>_________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=41767\" target=\"_blank\" rel=\"noopener noreferrer\">L\u2019ideologia del politicamente corretto e i dogmi del neoprogressismo: intervista a Eugenio Capozzi<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=42815\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abPoliticamente corretto, religione che vieta la dialettica e il dissenso\u00bb<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=41954\" target=\"_blank\" rel=\"noopener noreferrer\">Politicamente corretto. L\u2019effetto farfalla<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=46438\" target=\"_blank\" rel=\"noopener noreferrer\">Corso intensivo sul politicamente corretto<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=36897\" target=\"_blank\" rel=\"noopener noreferrer\">Il politicamente corretto ha corrotto l\u2019Europa<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=29393\" target=\"_blank\" rel=\"noopener noreferrer\">Politicamente corretto, la nuova religione della \u201csottomissione\u201d al \u201cnon pensiero\u201d del potere<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Atlantico 2 Settembre 2019 di Martino Loiacono Qualche settimana fa la Repubblica, dopo le sanguinose sparatorie avvenute in America, titolava \u201cLe stragi dell\u2019uomo bianco\u201d. Un titolo apparentemente neutro ma che in realt\u00e0 celava un messaggio specifico. Un messaggio di sapore razzista (pensate se la Verit\u00e0 o Libero avessero aperto con un titolo del genere), &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":42816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[1835,558],"class_list":["post-44209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-politicamente-corretto","tag-sguardo-sul-nostro-tempo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T22:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-24T11:16:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale\",\"datePublished\":\"2019-09-04T22:00:39+00:00\",\"dateModified\":\"2020-02-24T11:16:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/\"},\"wordCount\":621,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/politicamente-corretto.jpg\",\"keywords\":[\"politicamente corretto\",\"sguardo sul nostro tempo\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/\",\"name\":\"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/politicamente-corretto.jpg\",\"datePublished\":\"2019-09-04T22:00:39+00:00\",\"dateModified\":\"2020-02-24T11:16:37+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/politicamente-corretto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/politicamente-corretto.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/","og_locale":"it_IT","og_type":"article","og_title":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-09-04T22:00:39+00:00","article_modified_time":"2020-02-24T11:16:37+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale","datePublished":"2019-09-04T22:00:39+00:00","dateModified":"2020-02-24T11:16:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/"},"wordCount":621,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg","keywords":["politicamente corretto","sguardo sul nostro tempo"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/","name":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg","datePublished":"2019-09-04T22:00:39+00:00","dateModified":"2020-02-24T11:16:37+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/politicamente-corretto.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dietro-le-distorsioni-del-politicamente-corretto-lattacco-alla-civilta-occidentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Dietro le distorsioni del politicamente corretto l\u2019attacco alla civilt\u00e0 occidentale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=44209"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44209\/revisions"}],"predecessor-version":[{"id":46481,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/44209\/revisions\/46481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/42816"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=44209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=44209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=44209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}