{"id":43879,"date":"2019-08-01T00:00:49","date_gmt":"2019-07-31T22:00:49","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43879"},"modified":"2019-07-30T16:05:56","modified_gmt":"2019-07-30T14:05:56","slug":"teologia-della-liberazione-o-liberazione-dalla-teologia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/","title":{"rendered":"Teologia della liberazione o liberazione dalla teologia?"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Osservatorio Internazionale cardinale Van Tu\u00e2n sulla Dottrina sociale della Chiesa <\/strong>17 luglio 2019<\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-43880 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">di <strong>Riccardo Pedrizzi<\/strong><\/p>\n<p style=\"text-align: center;\">Presidente Nazionale del Comitato Scientifico UCID<\/p>\n<p style=\"text-align: justify;\">La cosiddetta teologia della liberazione sembra aver acquisito da qualche anno a questa parte un vero e proprio diritto di cittadinanza nell\u2019ambito della Chiesa e del Mondo cattolico.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">La prova ci viene fornita da un recente articolo pubblicato, come tutte le domenica, su \u201c<em>Il Sole 24 Ore<\/em>\u201d dal Cardinale Gianfranco Ravasi in occasione del cinquantenario (1969-2019) della pubblicazione del volume \u201cHacia una teologia de la liberacion\u201d (Verso una teologia della liberazione) del giovane teologo Gustavo Cutierrez, testo tradotto tre anni dopo dalle Edizioni Queriniana di Brescia nota per aver pubblicato e diffuso da noi vari libri dei teologi eretici Hans King e Edward Schillebeeckx.<\/p>\n<div id=\"attachment_43883\" style=\"width: 133px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Gianfranco_Ravasi.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43883\" class=\"wp-image-43883\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Gianfranco_Ravasi.jpg\" alt=\"\" width=\"133\" height=\"200\" \/><\/a><p id=\"caption-attachment-43883\" class=\"wp-caption-text\">Gianfranco Ravasi<\/p><\/div>\n<p style=\"text-align: justify;\">Il cardinale nel suo articolo scrive che il sintagma \u00ab\u201c<em>teologia della liberazione\u201d sarebbe diventato un vessillo sventolato in tutta l\u2019America Latina e una sorta di incubo invece in certi ambiti ecclesiastici, a partire dalle Curia Romana<\/em>\u201d\u00bb. Le cose, per\u00f2, non stanno proprio come le racconta il Cardinale.<\/p>\n<p style=\"text-align: justify;\">Infatti Benedetto XVI, quando era Prefetto della Congregazione per la Dottrina delle Fede, affront\u00f2 il tema della Teologia della Liberazione, offrendo con due documenti \u201c<em>Libertatis nuntius<\/em>\u201d del 6 agosto 1984 e \u201c<em>Libertatis conscientia<\/em>\u201d del 22 marzo 1986, un determinante ed indispensabile contributo al suo contrasto e dando una risposta chiarissima ai dubbi dei molti. In tal modo venne incontro alle tante richieste e preghiere che erano salite da ogni parte del mondo ed in particolare dall\u2019America Latina, che supplicavano interventi chiarificatori su questo scottante problema da parte del Magistero.<\/p>\n<p style=\"text-align: justify;\">Altro che \u201cuna sorta di incubo\u201d, invece, in certi ambiti ecclesiastici, a partire dalla Curia Romana\u201d, che assolse niente altro che al suo compito di difendere l\u2019ortodossia della fede cattolica.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/teologia_liberazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33738\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/teologia_liberazione.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/teologia_liberazione.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/teologia_liberazione-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Si tratt\u00f2 di una risposta estremamente chiara ed esauriente, nella quale fu esaminato compiutamente quel fenomeno straordinariamente complesso, che \u00e8 e resta la Teologia della Liberazione, nel cui ambito alcuni teologi \u201c<em>hanno fatto propria la opzione fondamentale marxista<\/em>\u201d. In quel senso \u2013 venne rilevato \u2013 la teologia della liberazione diventava un pericolo fondamentale per la fede della Chiesa, anche se non \u00e8 pi\u00f9 tale oggi, come scrive il Cardinale Ravasi \u201cla riflessione di Gutierrez rimane uno snodo ancor vivo nella teologia e nella pastorale, come \u00e8 attestato dal magistero di papa Francesco\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019allora Cardinale Ratzinger esaminava, innanzitutto, la situazione venutasi a creare dopo il Concilio Vaticano II, e rilevava che;<\/p>\n<p style=\"text-align: justify;\">a) \u201c<em>si cre\u00f2 l\u2019opinione che la tradizione teologica esistente fino ad allora non era pi\u00f9 accettabile e che di conseguenza si doveva cercare, a partire dalla Scrittura e dai segni dei tempi, orientamenti teologici e spirituali totalmente nuovi<\/em>;<\/p>\n<p style=\"text-align: justify;\">b) <em>l\u2019idea di apertura al mondo si trasform\u00f2 spesso in una fede ingenua nelle scienze\u2026 La psicologia, la sociologia e l\u2019interpretazione marxista della storia furono considerate come scientificamente sicure..<\/em>;<\/p>\n<p style=\"text-align: justify;\">c) <em>la critica della tradizione da parte della esegesi evangelica moderna, specialmente di Bultman e della sua scuola, divenne una istanza teologica inamovibile..<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">A tale situazione ecclesiale si aggiunse \u201c<em>il nuovo clima filosofico degli anni sessanta. L\u2019analisi marxista della storia e della societ\u00e0 fu considerata, nel frattempo, come l\u2019unica a carattere scientifico. Ci\u00f2 significava che il mondo veniva interpretato alla luce dello schema della lotta di classe e che l\u2019unica scelta possibile era quella tra capitalismo e marxismo. Significava, inoltre che tutta la realt\u00e0 \u00e8 politica e che deve essere giustificata politicamente. <\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/teologia_liberazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33171\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/teologia_liberazione.jpg\" alt=\"\" width=\"144\" height=\"200\" \/><\/a>Il concetto biblico del povero offre il punto di partenza per la confusione tra l\u2019immagine biblica della storia e la dialettica marxista<\/em>\u201d. \u201c<em>Se fino ad ora la Chiesa, cio\u00e8 la Chiesa cattolica nella sua totalit\u00e0 che, trascendendo tempo e spazio, ha abbracciato i laici (sensum fidei) e la gerarchia (magistero) era stata l\u2019istanza ermeneutica fondamentale oggi lo \u00e8 diventato la comunidad\u2026 <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Popolo diventa cos\u00ec un concetto opposto a quello di gerarchia e in antitesi a tutte le istituzioni indicate come forze dell\u2019oppressione. Infine \u00e8 popolo chi partecipa alla lotta di classe; la Iglesia popular si pone in opposizione alla Chiesa gerarchica<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Emergeva, come si vede, una nuova interpretazione del cristianesimo, nella quale secondo il Prefetto del tempo della Congregazione per la Dottrina della Fede, la \u201c<em>fede<\/em>\u201d viene sostituita dalla \u201c<em>fedelt\u00e0 alla storia<\/em>\u201d (Sobrino); \u201c<em>la speranza<\/em>\u201d diventa la \u201c<em>fiducia nel futuro<\/em>\u201d e quindi nella storia delle classi; \u201c<em>l\u2019amore<\/em>\u201d coincide con \u201c<em>l\u2019opzione per la lotta di classe<\/em>\u201d; la verit\u00e0 si socializza nella storia e nella prassi: solo l\u2019azione diventa ed \u00e8 la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/10\/teologia-liberazione.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-24328\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/10\/teologia-liberazione.png\" alt=\"\" width=\"189\" height=\"230\" \/><\/a>Ciononostante il Cardinale Ravasi a cinquant\u2019anni dalla pubblicazione di quel libro scrive che \u201cIn realt\u00e0 erano molti anche gli aspetti positivi, a partire proprio dal concetto di libert\u00e0 che non pu\u00f2 essere considerato solo in astratto ma nel suo esercizio concreto all\u2019interno dei processi storici e socio-culturali, trasformandosi cos\u00ec in \u201cliberazione\u201d\u201d.<\/p>\n<p style=\"text-align: justify;\">Eppure questa nuova teoria fin dall\u2019inizio fu ben altro dal Cristianesimo secondo il Cardinale Ratzinger che si poneva e ci poneva un interrogativo: \u201c<em>cosa si possa e si debba fare<\/em>\u201d di fronte a questo fenomeno cosi devastante della \u201c<em>Teologia della Liberazione<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">La risposta non poteva che partire da un\u2019analisi della genesi della \u201c<em>Teologia della Liberazione<\/em>\u201d, per poi prendere in considerazione alcune situazioni locali ove pi\u00f9 penetrante era stata l\u2019attivit\u00e0 dei fautori di questa nuova teologia, infine individuare i possibili rimedi e le soluzioni pi\u00f9 praticabili.<\/p>\n<p style=\"text-align: justify;\"><strong>Genesi e storia della Teologia della Liberazione<\/strong><\/p>\n<p style=\"text-align: justify;\">Questa teologia nacque nell\u2019America Latina intorno al 1960 con il nome di \u201c<em>teologia dello sviluppo<\/em>\u201d sull\u2019onda dell\u2019entusiasmo suscitato dalle iniziative panamericane di John Kennedy, che andava promettendo la soluzione di tutti i problemi che allora come oggi continuano ad assillare il continente latinoamericano.<\/p>\n<p style=\"text-align: justify;\">All\u2019entusiasmo, per\u00f2, subentr\u00f2 lo scoraggiamento e quindi, da parte di tutti coloro che si erano illusi, venne imboccata la strada della rivoluzione armata: sono i tempi che Fidel Castro esporta la sua rivoluzione con Che Guevara, e che Camillo Torres inizia la guerra in Colombia (1965).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Castro_Guevara_Cuba.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-41354\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Castro_Guevara_Cuba.jpg\" alt=\"\" width=\"250\" height=\"166\" \/><\/a>A Medelin nel 1968 nasceva, nonostante le raccomandazioni di Paolo VI, che si reca personalmente in Colombia, la nuova teologia che prende, appunto, il nome \u201c<em>Teologia della Liberazione<\/em>\u201d e che, per certi versi, si ispirava ad alcuni modelli europei come quello della \u201c<em>teologia politica<\/em>\u201d di J. B. Metz.<\/p>\n<p style=\"text-align: justify;\">Nel continente latinoamericano principali sostenitori erano alcuni protestanti locali, come Jes\u00e8 Miguze Bonino, ed alcuni cattolici come Gustavo Gutierrez (oggi \u2013 egli scriveva \u2013 per forgiare una societ\u00e0 giusta si deve passare necessariamente per la partecipazione cosciente ed attiva della lotta di classe); come Hassmann, prima spretato e poi diventato pastore protestante (quel che veramente importa \u2013 diceva \u2013 \u00e8 creare le basi per una chiesa nuova, autrice della liberazione degli oppressi); come Juan Luis Segundo, Leonardo e Clodovis Boff (negarono i rischi ed i pericoli sottolineati dall\u2019allora Cardinale Ratzinger); come Raul Vidales (una chiesa popolare sar\u00e0 necessariamente \u2013 proclamava \u2013 sovversiva e pericolosa per l\u2019ordine stabilito, non solo civile ma anche religioso).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Ratzinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32885\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Ratzinger.jpg\" alt=\"\" width=\"250\" height=\"197\" \/><\/a>Dal 1968 con pubblicazioni, associazioni, riunioni, gruppi, i fautori di questa teologia diffusero non solo nelle chiese latinoamericane, ma anche in Africa, nelle Filippine, in India, nello Sri Lanka, a Taiwan e persino, in alcuni ambienti europei, le nuove idee che, in verit\u00e0, non trovarono nella gerarchia molti contraddittori ed oppositori, con un\u2019abbondanza di mezzi materiali e finanziari \u201c<em>il che lascia molte domande senza risposte<\/em>\u201d, come rilevava l\u2019arcivescovo Cabral Duarte, arcivescovo di Aracaj\u00f9 in Brasile, nel corso del sinodo che si svolse nel 1983, sul tema \u201c<em>La riconciliazione e la penitenza nella missione della Chiesa<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Bisogna, per completezza, anche aggiungere che se nei primi tempi, quando si parlava di teologia della liberazione, si avevano di vista diverse correnti di questo nuovo corso pastorale: quella ispirata al Vangelo, alle sue esigenze ed alla sua purezza; quella sociologica ma pur sempre distante dalla teoria marxista; quella, infine, dichiaratamente marxista.<\/p>\n<p style=\"text-align: justify;\">E proprio recentemente, quando ha accettato il Cristo con falce e martello di Padre Espiral durante il suo viaggio in Bolivia, Papa Bergoglio ha ricordato che in quel tempo \u201c<em>la Teologia della liberazione aveva tanti filoni diversi, uno di essi usava l\u2019analisi marxista della realt\u00e0<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Oggi, per\u00f2, quando si parla di teologia della liberazione, pur con le debite eccezioni, tutti intendono che si tratta di quel complesso di idee, schemi e canoni interpretativi proprio e solo della concezione marxista. Ci sembra assai significativo, perci\u00f2, far conoscere la storia personale di un sacerdote che aveva abbracciato le teorie della teologia della liberazione.<\/p>\n<p style=\"text-align: justify;\"><strong>La confessione pubblica di Luis Eduardo Pellecer<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/teologia_liberaz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29599\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/09\/teologia_liberaz.jpg\" alt=\"\" width=\"247\" height=\"200\" \/><\/a>Entrato nella Compagnia di Ges\u00f9 e consacrato sacerdote nel 1976 nel Salvador, Padre Luis Eduardo Pellecer si un\u00ec in Guatemala all\u2019\u201c<em>esercito della guerriglia dei poveri<\/em>\u201d ed abbracci\u00f2 in quel periodo tutti i nuovi orientamenti teologici. Dopo aver partecipato ai movimenti rivoluzionari del Salvador, del Nicaragua e del Guatemala, il gesuita nel 1981 dinanzi a giornalisti, a diplomatici di diversi paesi ed a uomini di governo rese una confessione pubblica su tutta la sua attivit\u00e0 e, pi\u00f9 in generale, sulle tecniche operative dei movimenti rivoluzionari dell\u2019America centromeridionale.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Teologia della liberazione<\/em> \u2013 raccont\u00f2 il gesuita \u2013 <em>fu la prima arma che imparai a maneggiare. Non v\u2019\u00e8 bisogno di polvere da sparo per farla funzionare\u2026 Essa riusc\u00ec a cambiare profondamente l\u2019attivit\u00e0 di tutti gli ordini religiosi operanti nell\u2019America Latina. Questa teologia presenta un nuovo Cristo ai poveri, un Cristo diverso da quello del Vangelo e del catechismo. Quel Ges\u00f9 \u00e8 nemico giurato del capitalismo; \u00e8 un rivoluzionario che si d\u00e0 a un solo partito. E\u2019 un ribelle, un rivoluzionario, appartenente al solo partito dei poveri, venuto com\u2019\u00e8 per la salvezza dei soli poveri, mentre non esiste la salvezza per i potenti e i ricchi, che ne sono esclusi. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Noi andavamo predicando che i soli poveri avevano il diritto di celebrare il Natale del Dio dei poveri. Il nuovo Ges\u00f9 ha la missione di costruire il regno del socialismo per i poveri. Per farlo dobbiamo acquisire il potere all\u2019infuori di tutte le strutture istituzionali e le gerarchie della Chiesa\u2026 La seconda<\/em> (arma n.d.a.) <em>era l\u2019ideologia marxista-leninista che ho studiato per quattro anni nel Messico e nel Salvador. Ci dissero che i preti avevano bisogno di impadronirsene bene. <\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/guerriglia_Sudamerica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43884\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/guerriglia_Sudamerica.jpg\" alt=\"\" width=\"267\" height=\"200\" \/><\/a>Se volevano soddisfare i bisogni della gente, dovevano specializzarsi, diventare esperti in questa filosofia. La terza arma veniva fornita dal nuovo orientamento che la congregazione generale della Compagnia di Ges\u00f9 aveva dato, due anni prima ai suoi membri. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Il nostro lavoro consisteva da allora nel concentrarsi sui settori della popolazione pi\u00f9 poveri delle citt\u00e0 e delle campagne, per far entrare nelle teste, con le loro prediche, le idee della teologia della liberazione e del marxismo-leninismo, destando una coscienza politica diretta alla sovversione. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nel Salvador si lavor\u00f2 su due fronti: il primo, della religione; il secondo, della politica<\/em>\u201d. Da quella testimonianza risulta evidente, contrariamente alle parole d\u2019ordine che, ancora oggi, si fanno circolare anche nel mondo cattolico sul conto della teologia della liberazione, che:<\/p>\n<ul>\n<li style=\"text-align: justify;\">non si trattava di un fenomeno religioso spontaneo, perch\u00e8, se cos\u00ec fosse stato, sarebbe stato diverso da paese a paese ed avrebbe assunto caratteristiche diverse le une dalle altre a seconda delle situazioni politiche, economiche e sociali locali;<\/li>\n<li style=\"text-align: justify;\">non nasceva da esigenze religiose e spirituali della cosiddetta base, in quanto la diffusione contemporanea, simultanea ed \u201c<em>a comando<\/em>\u201d di certi slogans e di certi leit-motiv univoci presupponeva, viceversa, una rete capillare di operatori pastorali, di attivisti, di organizzazioni e di mezzi finanziari di notevole entit\u00e0;<\/li>\n<li style=\"text-align: justify;\">non attecch\u00ec, esclusivamente in zone agricole e tra le popolazioni indie o sottosviluppate, ma viceversa con pi\u00f9 virulenza nelle periferie dei grossi centri urbani, tra il proletariato pi\u00f9 sindacalizzato e politicizzato.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Brasile e Cile: due situazioni sconcertanti<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7364\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\" alt=\"\" width=\"175\" height=\"200\" \/><\/a>E veniamo a questo punto all\u2019esame di due situazioni particolari, relative a due paesi dell\u2019America Latina, ove pi\u00f9 era stata vivace e penetrante l\u2019attivit\u00e0 dei sostenitori della nuova Teologia, prescindendo dal Nicaragua, essendo risultato qui assai chiaro il connubio tra la chiesa popolare, non istituzionale, alternativa e governo sandinista, connubio che fu fermamente condannato anche da San Giovanni Paolo II in occasione di un suo viaggio nel Centroamerica.<\/p>\n<p style=\"text-align: justify;\">Sulla scia di una interpretazione molto forzata e assai parziale, secondo la quale a Medellin nel 1968 e, poi, a Puebla nel 1979, la Chiesa avrebbe denunciato la realt\u00e0 dell\u2019America Latina come una \u201c<em>situazioni di peccato<\/em>\u201d, di \u201c<em>oppressione<\/em>\u201d e di \u201c<em>ingiustizia strutturale<\/em>\u201d, nei confronti della quale la Chiesa stessa doveva porsi come movimento rivoluzionario per il rovesciamento dello status quo, si andarono formando ed organizzando sempre pi\u00f9 capillarmente in Brasile le cosiddette CEB (Comunidades Eclesiais de base), Comunit\u00e0 ecclesiali di base.<\/p>\n<p style=\"text-align: justify;\">Si trattava di piccoli gruppi organizzati nell\u2019ambito delle parrocchie da sacerdoti e operatori pastorali (laici impegnati, appositamente addestrati per il lavoro di \u201c<em>coscientizzazione<\/em>\u201d dei fedeli che avrebbero dovuto prendere coscienza delle ingiustizie della realt\u00e0 brasiliana).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/teologia_liberazione_CEB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43888\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/teologia_liberazione_CEB.jpg\" alt=\"\" width=\"192\" height=\"200\" \/><\/a>Le CEB raggruppavano di solito persone delle stesse condizioni economiche, culturali e sociali: giovani, lavandaie, soldati, persino prostitute (\u201c<em>l\u2019olocausto<\/em>\u201d della prostituta se fatto bene, la pone al di sopra della suora e della madre di famiglia, essendo la prostituzione un servizio alla comunit\u00e0, dichiar\u00f2 mons. Jos\u00e8 Maria Pires, arcivescovo di Paraiba e leader delle CEB,); oppure raggruppavano la gente secondo criteri geografici: membri di una famiglia, di un condominio, di una via, di un quartiere; di solito proliferavano alla periferia della citt\u00e0 ed erano costituite da operai, piccoli e medi impiegati, commercianti, casalinghe, ovvero nelle zone rurali ed erano frequentate da salariali agricoli, affittuari, piccoli agricoltori.<\/p>\n<p style=\"text-align: justify;\">Le CEB, che a loro volta si suddividevano, quando erano grandi, in gruppi di riflessione, biblici, di preghiera, ed in certi momenti, assommavano in tutto il Brasile a circa 100 mila con 2 milioni di persone coinvolte e \u201c<em>coscientizzate<\/em>\u201d. Queste cifre, considerato il numero di abitanti del Brasile, potrebbero apparire assai modeste, se non si conoscessero le tecniche propagandistiche, d\u2019infiltrazione e di pressione psicologica adottate, che sono proprie della moderna guerra psicologica.<\/p>\n<p style=\"text-align: justify;\">Le comunit\u00e0 ecclesiali di base, infatti, attraverso le comunicazioni sociali, con informazioni di tipo sensazionalistico, attraverso i corsi obbligatori per fidanzati, per padrini di battesimo, ecc., attraverso l\u2019uso delle chiese per manifestazioni sindacali e scioperi ispirati se non promossi direttamente da elementi legati alle CEB, miravano a dare la sensazione al grande pubblico che tutta la popolazione brasiliana fosse ormai pronta e favorevole all\u2019instaurazione di quel socialismo autogestonario, per il quale analogamente si battevano il partito comunista e quello socialista.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Vescovi_Brasile.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43889\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Vescovi_Brasile.jpg\" alt=\"\" width=\"250\" height=\"156\" \/><\/a>L\u2019atteggiamento della CNBB (Cofer\u00eancia Nacional dos Bispos do Brasil), lungi dall\u2019aver ostacolato quest\u2019opera d\u2019indottrinamento delle CEB, ne sembr\u00f2 orientare tutta l\u2019attivit\u00e0, avendo fatto proprio il progetto per una \u201c<em>riforma globale della societ\u00e0, secondo gli schemi della Teologia della liberazione<\/em>\u201d, salvo evidentemente eccezioni.<\/p>\n<p style=\"text-align: justify;\"><strong>Il Cile<\/strong><\/p>\n<p style=\"text-align: justify;\">Dopo un\u2019ultradecennale opera di \u201c<em>decatechizzazione<\/em>\u201d svolta da un clero progressista ed impegnato politicamente, la situazione del Cile fu dettagliatamente rappresentata da una lettera aperta, che 336 madri cattoliche di Santiago indirizzarono a S. E. Mons. Juan Francisco Fresno, arcivescovo di Santiago, nell\u2019ottobre del 1983 e comparsa su \u201c<em>El Mercurio<\/em>\u201d nella quale veniva presentato uno stato di malessere estremo e di disorientamento in cui versava la comunit\u00e0 ecclesiale.<\/p>\n<p style=\"text-align: justify;\">Tale lettera lamentava \u201c<em>l\u2019allontanamento di molti dalla pratica religiosa<\/em>\u201d, \u201c<em>l\u2019accesso ai sacramenti si fa ogni giorno pi\u00f9 difficile<\/em>\u201d, \u201c<em>il battesimo \u00e8 negato ai neonati<\/em>\u201d, \u201c<em>neppure la prima comunione si d\u00e0 ai fanciulli se i loro genitori non prendono parte ai corsi corrispondenti; e la cresima si concede solamente ai giovani che abbiano fatto un corso di preparazione che dura due anni<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Nella lettera si faceva presente che, nei corsi, invece di ricevere un insegnamento religioso si parla \u201c<em>di diritti umani, di prigionieri politi, di oppressore e di protesta ed i bambini che li hanno frequentati sono ritornati a casa con idee cos\u00ec cambiate che molte di noi si sono viste nella dolorosa alternativa o di proibire loro di continuare ad assistere a queste lezioni di catechismo\u2026 oppure di vederli progredire non nell\u2019amore di Dio ed ai buoni costumi ma sulla via del risentimento, dell\u2019odio e dell\u2019agitazione<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/teologia_liberazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43890\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/teologia_liberazione.jpg\" alt=\"\" width=\"250\" height=\"164\" \/><\/a>La lettera individuava infine anche con precisione il ruolo che avevano assunto certi preti, certe religiose, certi seminaristi (\u201c<em>si sono viste religiose diffondere volantini per le case e per gli isolati, battendo padelle, suonando le campane delle cappelle, prendendo parte agli incendi ed ai turbamenti dell\u2019ordine pubblico<\/em>\u201d \u2026 \u201c<em>le parrocchie si sono viste ridursi a punti di riunioni di una minoranza che attira e raggruppa noti rivoltosi, mentre la maggioranza dei cattolici si \u00e8 vista emarginata, allontanata e come resa estranea nella nostra stessa Chiesa<\/em>\u201d).<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusioni<\/strong><\/p>\n<p style=\"text-align: justify;\">In conclusione i due documenti della Congregazione per la Dottrina delle Fede del 1984 e del 1986, guidata allora dal cardinale Joseph Ratzinger, quando ne era Prefetto, rappresentano un richiamo, ancora oggi assai valido ed attuale, alla responsabilit\u00e0 dell\u2019episcopato ed un invito a tutti quei cattolici, che continuano a sottovalutare i pericoli di <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Gustavo_Gutierrez_teologia_liberazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43891 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/Gustavo_Gutierrez_teologia_liberazione.jpg\" alt=\"\" width=\"193\" height=\"262\" data-wp-editing=\"1\" \/><\/a>questa teologia e giungono a riproporre la figura di Gustavo Gutierrez, il teologo peruviano come un punto di riferimento, \u201cper il rigore e il calore del suo pensiero che \u00e8 stato capace \u2013 come scrive il Cardinale Ravasi \u2013 di evitare certe derive socio-politiche, senza per\u00f2 edulcorare l\u2019incidenza concreta della sua visione. Essa si basa, infatti, su una liberazione \u201cintegrale\u201d (SIC!!!) perch\u00e9 compatta e unitaria \u00e8 la persona umana e, quindi, la teologia esige di essere sempre incarnata e contestualizzata\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio Internazionale cardinale Van Tu\u00e2n sulla Dottrina sociale della Chiesa 17 luglio 2019 di Riccardo Pedrizzi Presidente Nazionale del Comitato Scientifico UCID La cosiddetta teologia della liberazione sembra aver acquisito da qualche anno a questa parte un vero e proprio diritto di cittadinanza nell\u2019ambito della Chiesa e del Mondo cattolico.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":43880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,29],"tags":[157,2390,630],"class_list":["post-43879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-eresie-cristiane","tag-chiesa-2","tag-eresie-cristiane","tag-teologia-della-liberazione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-31T22:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Teologia della liberazione o liberazione dalla teologia?\",\"datePublished\":\"2019-07-31T22:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/\"},\"wordCount\":2848,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/teologia_liberazione.jpg\",\"keywords\":[\"chiesa\",\"Eresie cristiane\",\"teologia della liberazione\"],\"articleSection\":[\"Chiesa\",\"Eresie cristiane\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/\",\"name\":\"Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/teologia_liberazione.jpg\",\"datePublished\":\"2019-07-31T22:00:49+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/teologia_liberazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/teologia_liberazione.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/teologia-della-liberazione-o-liberazione-dalla-teologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teologia della liberazione o liberazione dalla teologia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/","og_locale":"it_IT","og_type":"article","og_title":"Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-07-31T22:00:49+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Teologia della liberazione o liberazione dalla teologia?","datePublished":"2019-07-31T22:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/"},"wordCount":2848,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg","keywords":["chiesa","Eresie cristiane","teologia della liberazione"],"articleSection":["Chiesa","Eresie cristiane"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/","name":"Teologia della liberazione o liberazione dalla teologia? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg","datePublished":"2019-07-31T22:00:49+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/teologia_liberazione.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-liberazione-o-liberazione-dalla-teologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Teologia della liberazione o liberazione dalla teologia?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=43879"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43879\/revisions"}],"predecessor-version":[{"id":43893,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43879\/revisions\/43893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/43880"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=43879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=43879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=43879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}