{"id":43856,"date":"2019-08-01T00:00:30","date_gmt":"2019-07-31T22:00:30","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43856"},"modified":"2019-07-30T10:35:09","modified_gmt":"2019-07-30T08:35:09","slug":"la-legge-naturale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/","title":{"rendered":"La legge naturale"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43858\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale-300x169.jpg\" alt=\"\" width=\"250\" height=\"141\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg 1280w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>da <strong>Il Nuovo Arengario<\/strong> 8 Giugno 2019<\/p>\n<p style=\"text-align: justify;\"><em>La perversione del diritto, in oltraggio alla legge iscritta da Dio nel cuore umano, ha subito dovunque, specie nel mondo occidentale, un incremento prima inimmaginabile\u2026 la scienza medica ufficiale giudicava l\u2019omosessualit\u00e0 una deviazione del comportamento umano e prevedeva cure adeguate. Oggi essa ha capovolto il giudizio. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Certo la scienza pu\u00f2 sbagliare e ha sbagliato anche fraudolentemente. Peccato che si riconoscano ufficialmente gli sbagli che dispiacciono ai padrone del vapore. Dio invece non pu\u00f2 sbagliare, e nella Rivelazione troviamo ampie condanne del peccato di sodomia e dei lesbici comportamenti, come viene chiaramente attestato da San Paolo e dal Vecchio Testamento<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Piero Nicola <\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">La legge naturale \u00e8 iscritta nel cuore umano, ma la natura dell\u2019uomo essendo corrotta dal peccato originale, chi non \u00e8 battezzato e in Grazia di Dio non pu\u00f2 (salvo l\u2019eccezione del <em>Battesimo di desiderio <\/em>e della conservazione della relativa Grazia) osservare la divina disposizione.<\/p>\n<p style=\"text-align: justify;\">Tuttavia gli empi trasgrediscono la legge naturale in misura differente, sebbene un solo grave abuso basti per incorrere nella condanna. Gli Stati separati dalla Chiesa legiferano calpestando la suprema norma della vita, ma vale la pena considerare l\u2019entit\u00e0 di questa infrazione e quanto essa sia cresciuta negli ultimi tempi contribuendo alla perdita delle anime.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/creazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8821\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/creazione.jpg\" alt=\"\" width=\"250\" height=\"174\" \/><\/a>Il chiarimento \u00e8 utile soprattutto per i giovani, i quali spesso non hanno un\u2019idea della decadenza civile protrattasi da circa sessant\u2019anni a questa parte, e suppongono che certe leggi siano sempre state in vigore nelle nazioni rette con l\u2019indifferentismo religioso, con un laicismo d\u2019ogni colore. Invece la perversione del diritto ha subito dovunque, specie nel mondo occidentale, un incremento prima inimmaginabile.<\/p>\n<p style=\"text-align: justify;\">Persino nella Unione Sovietica la morale non era scesa tanto in basso. In Russia la legge contraria all\u2019omosessualit\u00e0 fu abolita completamente nel 1993. Negli USA l\u2019aborto fu ammesso a partire dal 1973 (oggi una severa limitazione della pratica abortiva viene introdotta in Alabama).<\/p>\n<p style=\"text-align: justify;\">Il divorzio, in Italia, divenne <em>legittimo<\/em> solo nel 1970, 24 anni dopo che fu proclamata la Repubblica. E il sentimento popolare nei confronti dell\u2019aborto negli Stati Uniti? Niente come il cinema, diretto al pubblico gradimento, rivela l\u2019entit\u00e0 del consenso.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/abolizione_aborto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39463 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/abolizione_aborto.jpg\" alt=\"\" width=\"250\" height=\"142\" \/><\/a>Il film <em>Piet\u00e0 per i giusti <\/em>(1953) tratta il tema della procurata interruzione della gravidanza. Kirk Douglas (ebreo) nella parte di un agente di polizia \u00e8 indignato per l\u2019indulgenza secondo lui riservata ai delinquenti. Egli trascende bistrattando un medico che ha praticato l\u2019aborto; ma non \u00e8 in discussione la condanna dell\u2019aborto, che anzi \u00e8 del tutto implicita. Appare scontato il rammarico di vedere come quel <em>macellaio <\/em>possa sfuggire alla giusta e legale punizione.<\/p>\n<p style=\"text-align: justify;\">Nel 1957 la pellicola <em>I peccatori di Peyton Place <\/em>(premiato l\u2019anno successivo col l\u2019Oscar quale miglior film) mette sullo schermo le vicende tratte dal libro dell\u2019allora scandalosa scrittrice Grace Metalious. Nonostante ci\u00f2, quando la figliastra stuprata dal patrigno e rimasta incinta supplica il medico di procurarle l\u2019aborto, questi, che non figura essere particolarmente religioso, n\u00e9 passatista, le rivolge queste testuali parole: \u201cTu mi stai chiedendo di infrangere la legge di Dio e degli uomini!\u201d<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/omosessualit\u00e0_classica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26594 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/omosessualit\u00e0_classica.jpg\" alt=\"\" width=\"266\" height=\"190\" data-wp-editing=\"1\" \/><\/a>Ecco uno dei pi\u00f9 importanti motivi per cui le vecchie opere cinematografiche sono quasi scomparse dai programmi televisivi; mentre i film che, in seguito, rievocano la trascorsa epoca maggiormente sana ne nascondono certe peculiarit\u00e0 e cercano di denigrarla per pretese iniquit\u00e0, oppure mettono maliziosamente in risalto quelle vere, che non possono mai scomparire, in nessun secolo e in nessuna parte del mondo.<\/p>\n<p style=\"text-align: justify;\">Negli USA e altrove la scienza medica ufficiale giudicava l\u2019omosessualit\u00e0 una deviazione del comportamento umano e prevedeva cure adeguate. Oggi essa ha capovolto il giudizio. Certo la scienza pu\u00f2 sbagliare e ha sbagliato anche fraudolentemente. Peccato che si riconoscano ufficialmente gli sbagli che dispiacciono ai padrone del vapore.<\/p>\n<p style=\"text-align: justify;\">Dio invece non pu\u00f2 sbagliare, e nella Rivelazione troviamo ampie condanne del peccato di sodomia e dei lesbici comportamenti, come viene chiaramente attestato da San Paolo e dal Vecchio Testamento. La neochiesa, invece, accarezza e difende gli omosessuali, senza ammonirli, senza carit\u00e0: per non giudicarli, lascia che possano commettere un peccato che <em>grida vendetta al cospetto di Dio<\/em>, lascia che altri, ingannati da tali comportamenti, possano cadere.<\/p>\n<p style=\"text-align: justify;\">Ben lo sappiamo: in questi casi non c\u2019\u00e8 bisogno di produrre le prove, per le quali c\u2019\u00e8 l\u2019imbarazzo della scelta. Chiunque pu\u00f2 vedere che questo clero non vuol dispiacere al mondo, falsificatore della verit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Nuovo Arengario 8 Giugno 2019 La perversione del diritto, in oltraggio alla legge iscritta da Dio nel cuore umano, ha subito dovunque, specie nel mondo occidentale, un incremento prima inimmaginabile\u2026 la scienza medica ufficiale giudicava l\u2019omosessualit\u00e0 una deviazione del comportamento umano e prevedeva cure adeguate. Oggi essa ha capovolto il giudizio. Certo la &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":43858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,48],"tags":[484,322],"class_list":["post-43856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto","category-omosessualit","tag-diritto-naturale","tag-omosessualita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La legge naturale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La legge naturale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-31T22:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La legge naturale\",\"datePublished\":\"2019-07-31T22:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/\"},\"wordCount\":718,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/diritto_naturale.jpg\",\"keywords\":[\"diritto naturale\",\"omosessualit\u00e0\"],\"articleSection\":[\"Diritto\",\"Omosessualit&agrave;\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/\",\"name\":\"La legge naturale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/diritto_naturale.jpg\",\"datePublished\":\"2019-07-31T22:00:30+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/diritto_naturale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/diritto_naturale.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-legge-naturale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La legge naturale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La legge naturale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/","og_locale":"it_IT","og_type":"article","og_title":"La legge naturale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-07-31T22:00:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La legge naturale","datePublished":"2019-07-31T22:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/"},"wordCount":718,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg","keywords":["diritto naturale","omosessualit\u00e0"],"articleSection":["Diritto","Omosessualit&agrave;"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/","name":"La legge naturale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg","datePublished":"2019-07-31T22:00:30+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/diritto_naturale.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-legge-naturale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La legge naturale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=43856"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43856\/revisions"}],"predecessor-version":[{"id":43859,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43856\/revisions\/43859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/43858"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=43856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=43856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=43856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}