{"id":4365,"date":"2011-02-08T08:57:43","date_gmt":"2011-02-08T07:57:43","guid":{"rendered":""},"modified":"2015-03-26T13:14:02","modified_gmt":"2015-03-26T12:14:02","slug":"il-mondo-nuovo-di-aldous-huxley-recensione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/","title":{"rendered":"Il mondo nuovo, di Aldous Huxley &#8211; recensione"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9458\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg\" alt=\"mondo nuovo_cover\" width=\"173\" height=\"200\" \/><\/a>Tratto da <strong>libertaepersona.it<\/strong>\u00a0 27 gennaio 2010<\/div>\n<p style=\"text-align: center;\">\u00a0 di <strong>David Ressegotti<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0 Nell&#8217;ambito del romanzo di <em>science fiction<\/em>, si indica con il termine di <strong>distopia<\/strong> un determinato sotto-genere in cui l&#8217;autore immagina un tempo futuro o alternativo, solitamente frutto delle contraddizioni e dei pericoli contemporanei, in cui le peggiore paure prendono corpo e danno forma ad una societ\u00e0 umana iniqua e anti-libertaria.<\/p>\n<p style=\"text-align: justify;\">Il genere distopico, in circa un secolo di sviluppo dei temi fantascientifici, ha dato alla luce assoluti capolavori, specialmente nel mondo anglosassone: <em>Farenheit 451<\/em> di Ray Bradbury, per esempio, o ancora il celeberrimo <em>1984<\/em> di Orwell (per citare solo i pi\u00f9 noti), sono entrati a pieno titolo tra le opere che hanno segnato il &#8216;900.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">L&#8217;ideazione e descrizione di una distopia, peraltro, non ha lasciato indifferenti anche alcuni autori cattolici inglesi (\u00e8 il caso, per esempio, de <em>Il padrone del mondo<\/em> di Benson o del divertente romanzo <em>L&#8217;osteria volante<\/em> di G.K. Chesterton).Difficile, tuttavia, trovare fra le varie fantasie distopiche mai create una realt\u00e0 tanto sorprendente e terrificante quanto quella descritta ne <strong><em>Il mondo nuovo<\/em> di Aldous Huxley<\/strong>, pubblicato nel 1932 e primo vero successo editoriale di un autore originalissimo e molto controverso, uno spirito (a modo suo) profondamente religioso e precursore riconosciuto della celebre <em>beat generation<\/em> americana.<\/p>\n<p style=\"text-align: justify;\">Il motivo \u00e8 presto detto. Tutte le varie &#8216;distopie&#8217; letterarie o cinematografiche hanno quasi sempre alcuni tratti in comune: viene molto spesso descritta una forma di regime totalitaria, in cui un governo rigido e pervasivo amministra il potere con brutale violenza sia fisica sia psicologica.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 difficile riconoscere dietro quei sistemi meccanicamente perfetti di dominio <strong>la paura di una nuova tirannia di stampo hitleriano e\/o staliniano<\/strong> (a partire, per esempio, da <em>La svastica sul sole<\/em> di P.K. Dick): l&#8217;impressione suscitata da queste terrificanti esperienze di governo autoritario continua persino oggi a lasciare il segno nella produzione distopica, in un tempo in cui simili paure sono state -grazie al Cielo!- scongiurate.<\/p>\n<p style=\"text-align: justify;\">Il <em>brave new world<\/em> di Huxley, al contrario, in un certo senso oltrepassa anche quelle paure di governo dittatoriale: viene descritto una Terra in cui <strong>non c&#8217;\u00e8 pi\u00f9 scopo alla lotta politica<\/strong>. Nell&#8217;universo creato da Huxley lo stesso concetto di &#8216;politica&#8217; non ha pi\u00f9 senso: si \u00e8 sviluppata infatti la perfetta rivoluzione &#8216;psicologica&#8217; dell&#8217;umanit\u00e0, e non solo quella meramente sociale.<\/p>\n<p style=\"text-align: justify;\">Nel \u201cmondo nuovo\u201d vengono dunque immaginati dei procedimenti di controllo mentale ed emotivo in grado di garantire un perfetto dominio sull&#8217;umanit\u00e0: e se questo \u00e8 certamente un tema ben presente anche in altre, molto celebri distopie (come quella di Orwell, per esempio), la genialit\u00e0 dell&#8217;autore \u00e8 qui nel dare vita ad <strong>un controllo perfetto dell&#8217;umanit\u00e0 basato unicamente su <em>meccanismi mentali<\/em><\/strong>, senza alcun bisogno di repressione violenta.<\/p>\n<p style=\"text-align: justify;\">Con alcune semplici mosse, infatti, la vita dell&#8217;umanit\u00e0 viene incanalata in argini perfettamente ideati per negare alle persone anche solo la possibilit\u00e0 di <em>sentirsi dominati<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>La famiglia non esiste pi\u00f9<\/strong>: il governo si assume l&#8217;onere di programmare il numero di nascite e di immettere, grazie ad <strong>avanzate tecniche eugenetiche<\/strong> e \u201cdisgenetiche\u201d, l&#8217;esatto quantitativo di essere umani necessari alla societ\u00e0. Questi feti vengono divisi, fin dal concepimento in vitro, in cinque categorie gerarchiche di importanza (da Alfa Plus a Epsilon Minus) e condizionati fin dall&#8217;incubazione al lavoro cui sono destinati. Particolare cura \u00e8 destinata a inibire le capacit\u00e0 intellettuali e fisiche delle classi inferiori, in modo che siano perfettamente felici ed adatti agli incarichi pi\u00f9 bassi \u2013 senza alcun desiderio di avanzare lungo la scala sociale.<\/p>\n<p style=\"text-align: justify;\">L&#8217;educazione \u00e8 uniforme, fondata sulla divisione dei ceti e impartita attraverso condizionamenti forzati dell&#8217;inconscio: le lezioni (semplici e rassicuranti) vengono inculcate nel sonno (<em>ipnopedia<\/em>) e sono ripetute fino a diventare parte integrante e inscindibile della mente dei bambini. Vengono rafforzati soprattutto i comportamenti sessualmente disinibiti, la contraccezione, il consumismo sfrenato e la passione per lo sport, e <strong>demonizzati o resi privi di senso i rapporti d&#8217;amore, le coppie stabili, la maternit\u00e0, la creativit\u00e0, l&#8217;amore per la natura e per la riflessione<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Tutta la terra \u00e8 pacificata e riunita in un unico governo federale, diviso in dieci macro-settori senza alcun conflitto interno. Il concetto stesso di <em>patria<\/em> \u00e8 inesistente: tutti gli uomini sono uniformati e del tutto uguali gli uni agli altri in ogni parte del globo. <strong>Il corpo sociale \u00e8 l&#8217;unica cosa importante<\/strong>: ogni individuo ne deve far parte con gioia e godersi la vita senza occuparsi di politica o societ\u00e0. \u201c<em>Ognuno appartiene a tutti<\/em>\u201d \u00e8 una delle principali lezioni continuamente ripetute nel sonno.<\/p>\n<p style=\"text-align: justify;\">La vita si svolge infatti in una <strong>routine di lavoro leggero e privo di difficolt\u00e0<\/strong>, seguito da <strong>notti di vita sociale e sessuale sfrenata<\/strong> e da frequenti dosi di un <strong>potente allucinogeno e ansiolitico<\/strong>, il <em>soma<\/em>, in grado di inibire qualunque istinto violento o malinconico e qualunque cattivo pensiero. Nessuno <strong>ha mai fatto esperienza di desiderio insoddisfatto<\/strong>, di bisogno, di frustrazione, di malinconia o anche solo di malattia. Tutto ci\u00f2 che costa fatica, infatti, non vale neppure la pena di essere inseguito: per esempio, la donna desiderata (nel raro caso in cui non si conceda immediatamente) pu\u00f2 essere sostituita da dozzine d&#8217;altre, o da una generosa dose di buon <em>soma<\/em>. La scienza farmacologica ha fatto tali passi da gigante che a tutti \u00e8 garantita giovinezza e bellezza fisica fino alla morte.<\/p>\n<p style=\"text-align: justify;\">I morenti, solitamente vecchi non pi\u00f9 di 60 anni e consumati dall&#8217;interno dall&#8217;uso di droghe e dalla vita sfrenata, vengono cremati e usati come concime: l&#8217;umanit\u00e0 \u00e8 condizionata fin dalla tenerissima et\u00e0 a <strong>non temere la morte, a considerarla un atto necessario al benessere della societ\u00e0 e a non ritenere in nessun caso una persona insostituibile<\/strong>. Di nessun defunto viene coltivato o ravvivato il ricordo, se non del mitico fondatore dell&#8217;ordine mondiale, il grande Ford, <strong>la cui religione (l&#8217;unica esistente) \u00e8 modellata su una versione distorta del cristianesimo e basata sul massiccio uso di <em>soma<\/em> \u201csacro\u201d e di canti spersonalizzanti<\/strong>. Le \u201cmesse\u201d sono orge sfrenate ed anonime, basate su ritmi musicali ossessivi e su visioni allucinogene della divinit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Stanti cos\u00ec le cose, chi ha bisogno di lottare per avere la libert\u00e0?<\/strong> La \u201cfelicit\u00e0\u201d \u00e8 garantita dall&#8217;alto, e assicurata da un&#8217;intera struttura sociale che non riconosce altro valore che l&#8217;immediata soddisfazione dei sensi.<\/p>\n<p style=\"text-align: justify;\">Un giovane di nome <strong>John Watson<\/strong>, europeo e &#8220;civile&#8221; ma nato e cresciuto per caso in una delle poche &#8216;Riserve&#8217; non civilizzate della Terra (un Messico tribale e selvaggio), \u00e8 l&#8217;esploratore e critico di questo \u201cmondo nuovo\u201d. Avendo trovato da bambino un&#8217;antichissima <em>opera omnia<\/em> di Shakespeare, che legge e rilegge come un testo sacro fin dalla pi\u00f9 tenera et\u00e0, John usa frequenti citazioni del Grande Bardo per descrivere e criticare questa realt\u00e0, <strong>totalmente priva di Dio, di amore e di bellezza<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sull&#8217;altare della soddisfazione dei bisogni primari John riconosce perfettamente il sacrificio del senso del divino. Nessuno degli uomini civilizzati, infatti, \u00e8 in grado anche solo di comprendere le parole che lui recita: tutte le opere d&#8217;arte dell&#8217;umanit\u00e0 sono andate perdute dopo la fondazione del sistema Fordiano ed oggi sono ancor meno che vietate, essendo totalmente inutili ed oscure. Persino la scienza \u00e8 concepita ormai come mero sviluppo tecnologico, totalmente privata di ogni anelito di verit\u00e0 e di conoscenza.<\/p>\n<p style=\"text-align: justify;\">Nello splendido finale, che vede John contrapporsi ad uno dei padroni di quel mondo, viene posto il bivio finale: <em>rinunciando all&#8217;umanit\u00e0<\/em>, \u00e8 possibile creare un sistema in cui non v&#8217;\u00e8 che pace, uniformit\u00e0 e soddisfazione; <em>rivendicandola<\/em>, ci si estranea dalla collettivit\u00e0 e si \u00e8 destinati alla solitudine, come folli e anti-sociali. Arrendersi alla stolida e facile \u201cfelicit\u00e0\u201d dei propri simili, o \u201c<strong>reclamare il diritto di essere infelice<\/strong>\u201d?<\/p>\n<p style=\"text-align: justify;\">Questa descrizione del &#8220;mondo nuovo&#8221; vi ricorda per caso qualcosa del nostro mondo occidentale? Si rimane persino terrorizzati dall&#8217;esattezza di certe tendenze descritte nel libro, isolate e portate all&#8217;estremo dal genio di Huxley nel lontano 1931 e oggi, ottant&#8217;anni dopo, cos\u00ec tangibili e comuni. Terrore perch\u00e9, a differenza di nazismo e comunismo sovietico, questi <strong>tentativi di assicurare il benessere in cambio della rinuncia all&#8217;individualit\u00e0<\/strong> ed alla religiosit\u00e0 riuniscono il peggio dei due totalitarismi; e ancora oggi (pur vestendo un manto molto pi\u00f9 rassicurante) sono tutt&#8217;altro che sconfitti. Un mondo senza malinconia e senza paure, certo, ma solo a patto di annichilire anche la libert\u00e0, l&#8217;amore e la bellezza: ecco la peggiore delle distopie che lo scrittore inglese \u00e8 stato in grado di ideare. Un mondo, cio\u00e8, dove non esiste pi\u00f9 l&#8217;Uomo.<\/p>\n<p style=\"text-align: justify;\">I personaggi descritti nel <em>brave new world<\/em>, per quanto felici possano pensare di essere, sperimentano infatti la pi\u00f9 umiliante delle violenze e delle dominazioni: viene negato loro persino la possibilit\u00e0 di <strong>sentirsi schiavi<\/strong>. Non c&#8217;\u00e8 neppure bisogno di una polizia segreta.<\/p>\n<p style=\"text-align: justify;\">John infine <strong>sceglie la via pi\u00f9 dura<\/strong>, e ne paga le conseguenze morendo tristemente in solitudine. Ma vivere senza fare mai esperienza della bellezza, per lui e per Huxley, \u00e8 una opzione ancora peggiore della morte. Anche a patto di avere salute, pancia piena e completa libert\u00e0 sessuale vita natural durante. Chiss\u00e0 quanti, oggi, sarebbero in grado di fare ancora la stessa scelta&#8230;<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=4328\" target=\"_blank\">Leggi il romanzo<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tratto da libertaepersona.it\u00a0 27 gennaio 2010 \u00a0 di David Ressegotti \u00a0 Nell&#8217;ambito del romanzo di science fiction, si indica con il termine di distopia un determinato sotto-genere in cui l&#8217;autore immagina un tempo futuro o alternativo, solitamente frutto delle contraddizioni e dei pericoli contemporanei, in cui le peggiore paure prendono corpo e danno forma ad &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":9458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,59,80],"tags":[381],"class_list":["post-4365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri","category-tecnocrazia","category-totalitarismo","tag-huxley","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-08T07:57:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-26T12:14:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"209\" \/>\n\t<meta property=\"og:image:height\" content=\"241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il mondo nuovo, di Aldous Huxley &#8211; recensione\",\"datePublished\":\"2011-02-08T07:57:43+00:00\",\"dateModified\":\"2015-03-26T12:14:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/\"},\"wordCount\":1502,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/mondo-nuovo_cover.jpg\",\"keywords\":[\"Huxley\"],\"articleSection\":[\"Libri\",\"Tecnocrazia\",\"Totalitarismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/\",\"name\":\"Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/mondo-nuovo_cover.jpg\",\"datePublished\":\"2011-02-08T07:57:43+00:00\",\"dateModified\":\"2015-03-26T12:14:02+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/mondo-nuovo_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/mondo-nuovo_cover.jpg\",\"width\":209,\"height\":241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-mondo-nuovo-di-aldous-huxley-recensione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il mondo nuovo, di Aldous Huxley &#8211; recensione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/","og_locale":"it_IT","og_type":"article","og_title":"Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-02-08T07:57:43+00:00","article_modified_time":"2015-03-26T12:14:02+00:00","og_image":[{"width":209,"height":241,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il mondo nuovo, di Aldous Huxley &#8211; recensione","datePublished":"2011-02-08T07:57:43+00:00","dateModified":"2015-03-26T12:14:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/"},"wordCount":1502,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg","keywords":["Huxley"],"articleSection":["Libri","Tecnocrazia","Totalitarismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/","name":"Il mondo nuovo, di Aldous Huxley - recensione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg","datePublished":"2011-02-08T07:57:43+00:00","dateModified":"2015-03-26T12:14:02+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/mondo-nuovo_cover.jpg","width":209,"height":241},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-mondo-nuovo-di-aldous-huxley-recensione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il mondo nuovo, di Aldous Huxley &#8211; recensione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4365"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4365\/revisions"}],"predecessor-version":[{"id":22095,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4365\/revisions\/22095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/9458"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}