{"id":43569,"date":"2019-07-11T00:00:24","date_gmt":"2019-07-10T22:00:24","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43569"},"modified":"2019-07-11T08:21:31","modified_gmt":"2019-07-11T06:21:31","slug":"una-visione-teologica-della-regolazione-naturale-della-fertilita","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/","title":{"rendered":"Una visione teologica della regolazione naturale della fertilit\u00e0"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-43570 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati-300x152.jpg\" alt=\"\" width=\"250\" height=\"127\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati-300x152.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati-768x390.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati-1024x521.jpg 1024w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>dal sito: <strong><a href=\"http:\/\/www.mogliemammepervocazione.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mogli &amp; Mamme per vocazione<\/a><\/strong> 7 Febbraio 2019 <strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Elisa Cappellazzo <\/strong><\/p>\n<p style=\"text-align: justify;\">Oggi vi vogliamo provocare con una domanda secca: cosa ne pensa Dio dell\u2019unione sessuale tra uomo e donna? Cosa ci dice Lui di questo incontro cos\u00ec importante per la coppia? Daremo ascolto, con l\u2019aiuto di questo articolo, alla nostra spiritualit\u00e0\u2026pi\u00f9 intima.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Per fare questo San Giovanni Paolo II, oltre che riflettere da se stesso a partire dai testi biblici, decise di tuffarsi pienamente in uno scritto lasciatogli da quel Papa che ascolt\u00f2 il suo appello contro la contraccezione nel lontano 1968: l\u2019Humanae Vitae fu il testo di riferimento per parlare dell\u2019amore coniugale nella sua pienezza e il Papa non si lasc\u00f2 sfuggire l\u2019occasione per riportare al giusto onore quella famosa enciclica.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/02\/Humanae_vitae.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35220 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/02\/Humanae_vitae.jpg\" alt=\"\" width=\"230\" height=\"184\" \/><\/a>Il Sacramento del matrimonio innestato nella sessualit\u00e0 umana<\/strong> Anzitutto bisogna dire che il tema della Regolazione Naturale della Fertilit\u00e0 \u00e8 anticipato dal senso specifico del sacramento del matrimonio: seguendo le riflessioni del Papa,\u00a0<strong>il matrimonio \u00e8 il modo particolare dei coniugi di vivere secondo lo Spirito, per la Grazia ricevuta col sacramento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Esso, cio\u00e8, costituisce non solo un <em>remedium concupiscientiae,<\/em> ma esprime la consapevolezza da parte di entrambi di essere <strong>innestati fin dal principio nella Vita divina<\/strong> e che, tramite la loro unione, possono realizzare una nuova creazione <strong>prolungando l\u2019azione stessa di Dio<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/adamo_eva.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32239 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/adamo_eva.jpg\" alt=\"\" width=\"248\" height=\"200\" \/><\/a>Ci\u00f2 avviene grazie alla benedizione iniziale che Dio diede alla prima coppia: sebbene poi il disegno iniziale fu rovinato con l\u2019ingresso del peccato, il Creatore non tolse la sua parola benedicente, <em>ma la lasci\u00f2 come legame primordiale alla sua Persona per la redenzione dei corpi.<\/em> Perch\u00e9 il segno sia efficace, cio\u00e8 renda visibile l\u2019amore di Dio e sia via di redenzione, la differenza del maschile e del femminile deve sussistere e sostenersi scambievolmente attraverso la copula degli sposi, <strong>consegnandosi l\u2019uno all\u2019altra in modo irreversibile<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Diventa di importanza fondamentale, quindi, conoscere bene e costantemente il linguaggio del corpo, perch\u00e9 il dono reciproco sia espresso nella Verit\u00e0 e tramite questa ci si possa avvicinare sempre pi\u00f9 al mistero della vita trinitaria. A questo proposito il Papa scrive: \u201c[\u2026] il \u00ablinguaggio del corpo\u00bb <em>\u00e8 non soltanto il \u00absubstrato\u00bb<\/em> ma, <em>in certo senso, il contenuto costitutivo della comunione delle persone<\/em>. Le persone \u2013 uomo e donna \u2013 diventano per s\u00e9 un dono reciproco. Diventano quel dono nella loro mascolinit\u00e0 e femminilit\u00e0, scoprendo il significato sponsale del corpo e riferendolo reciprocamente a se stessi in modo irreversibile: nella dimensione di tutta la vita.\u201d<\/p>\n<div id=\"attachment_42738\" style=\"width: 250px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-42738\" class=\"wp-image-42738\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia-300x200.jpg\" alt=\"\" width=\"250\" height=\"167\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia-595x400.jpg 595w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/sesso_coppia.jpg 1536w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><p id=\"caption-attachment-42738\" class=\"wp-caption-text\">Couple having sex<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cIn questa verit\u00e0 del segno e, in seguito, nell\u2019<em>ethos (norma di vita)<\/em> della condotta coniugale, s\u2019inserisce prospetticamente il\u00a0<em>significato procreativo del corpo<\/em>, cio\u00e8 la paternit\u00e0 e la maternit\u00e0.\u201d<\/p>\n<p style=\"text-align: justify;\">I sensi, il desiderio di essere una sola carne, la consapevolezza di volersi appartenere vicendevolmente l\u2019uno all\u2019altra sono tutte <strong>espressioni del linguaggio del corpo che devono essere ripulite dalla concupiscenza<\/strong> per testimoniare la grandezza del sacramento del matrimonio.<\/p>\n<p style=\"text-align: justify;\">Per fare ci\u00f2 l\u2019ethos deve per forza essere giusta controparte dell\u2019eros, perch\u00e9 risalti la specificit\u00e0 della persona nel suo essere maschile e femminile: \u00e8 qui che <strong>i metodi naturali possono essere risposta concreta alla verit\u00e0 del linguaggio del corpo.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/amore_santo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27536 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/amore_santo.jpg\" alt=\"\" width=\"166\" height=\"204\" \/><\/a>L\u2019aspetto morale si fa pressante nel momento in cui la bellezza dell\u2019unit\u00e0 tra marito e moglie viene calata nella realt\u00e0 quotidiana: non sempre le coppie sono disponibili ad accogliere una nuova vita, non sempre il corpo viene letto nella sua verit\u00e0, non sempre si avvera la sperata \u201ccomunione di persone\u201d nell\u2019atto di unione tra i due soggetti. Tuttavia \u00e8 altrettanto vero che\u00a0<em>il Papa propone una via per una graduale crescita degli sposi<\/em>, soprattutto considerando che nessuno \u00e8 esente dal peccato e non \u00e8 possibile che ogni rapporto sia perfetto sotto ogni punto di vista.<\/p>\n<p style=\"text-align: justify;\">Diventa necessario allora specificare bene alcuni termini utilizzati nell\u2019<em>Humanae Vitae<\/em>, perch\u00e9 possano essere rettamente compresi dagli sposi. Ma per ora, lasciamoci il tempo per riflettere su queste parole!<\/p>\n<p style=\"text-align: justify;\">________________<\/p>\n<p style=\"text-align: justify;\"><strong>Elisa Cappellazzo<\/strong> <em>Sposata con Francesco da 10 anni, insieme hanno 5 bimbi, pi\u00f9 uno che sorride loro dal Cielo. E\u2019 insegnante di religione in un Istituto Professionale. Non sono stati loro a \u201ctrovare\u201d la Teologia del Corpo, ma \u00e8 lei che da lontano li ha chiamati\u2026 insieme hanno compreso con quale linguaggio Dio sta parlando e da sempre ha parlato loro e stanno gustando e accogliendo tutte le meraviglie che Lui sta donando<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>dal sito: Mogli &amp; Mamme per vocazione 7 Febbraio 2019 \u00a0 Elisa Cappellazzo Oggi vi vogliamo provocare con una domanda secca: cosa ne pensa Dio dell\u2019unione sessuale tra uomo e donna? Cosa ci dice Lui di questo incontro cos\u00ec importante per la coppia? Daremo ascolto, con l\u2019aiuto di questo articolo, alla nostra spiritualit\u00e0\u2026pi\u00f9 intima.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":43570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[187,156,1206],"class_list":["post-43569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","tag-contraccezione","tag-famiglia-2","tag-metodi-naturali","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-10T22:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-11T06:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2288\" \/>\n\t<meta property=\"og:image:height\" content=\"1163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Una visione teologica della regolazione naturale della fertilit\u00e0\",\"datePublished\":\"2019-07-10T22:00:24+00:00\",\"dateModified\":\"2019-07-11T06:21:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/\"},\"wordCount\":728,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/coppia_fidanzati.jpg\",\"keywords\":[\"contraccezione\",\"famiglia\",\"metodi naturali\"],\"articleSection\":[\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/\",\"name\":\"Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/coppia_fidanzati.jpg\",\"datePublished\":\"2019-07-10T22:00:24+00:00\",\"dateModified\":\"2019-07-11T06:21:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/coppia_fidanzati.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/coppia_fidanzati.jpg\",\"width\":2288,\"height\":1163},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-visione-teologica-della-regolazione-naturale-della-fertilita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una visione teologica della regolazione naturale della fertilit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/","og_locale":"it_IT","og_type":"article","og_title":"Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-07-10T22:00:24+00:00","article_modified_time":"2019-07-11T06:21:31+00:00","og_image":[{"width":2288,"height":1163,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Una visione teologica della regolazione naturale della fertilit\u00e0","datePublished":"2019-07-10T22:00:24+00:00","dateModified":"2019-07-11T06:21:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/"},"wordCount":728,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg","keywords":["contraccezione","famiglia","metodi naturali"],"articleSection":["Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/","name":"Una visione teologica della regolazione naturale della fertilit\u00e0 - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg","datePublished":"2019-07-10T22:00:24+00:00","dateModified":"2019-07-11T06:21:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/coppia_fidanzati.jpg","width":2288,"height":1163},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-visione-teologica-della-regolazione-naturale-della-fertilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Una visione teologica della regolazione naturale della fertilit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=43569"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43569\/revisions"}],"predecessor-version":[{"id":43602,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43569\/revisions\/43602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/43570"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=43569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=43569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=43569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}