{"id":43511,"date":"2019-07-25T00:00:19","date_gmt":"2019-07-24T22:00:19","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43511"},"modified":"2019-07-05T11:54:45","modified_gmt":"2019-07-05T09:54:45","slug":"la-massoneria-sia-con-noi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/","title":{"rendered":"La Massoneria sia con noi"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/09\/Concilio_massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-38386\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/09\/Concilio_massoneria.jpg\" alt=\"\" width=\"250\" height=\"178\" \/><\/a>da <strong>Il Sabato <\/strong>N.48<\/p>\n<p style=\"text-align: center;\">2 Dicembre 1989<\/p>\n<p style=\"text-align: justify;\"><em>Nel 1983 la Chiesa tolse la scomunica agl\u2019iscritti alle logge. Come si arriv\u00f2 a quella decisione? Per la prima volta ecco la vera storia <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Lucio Brunelli<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">UNA multa di mille scudi d&#8217;oro, confisca dei beni, galera &#8220;ad arbitrio&#8221; e, per i recidivi, la pena capitale. Oltre la scomunica, naturalmente. Tempi duri per i Liberi Muratori, quelli del cardinale Firrao, autore nell&#8217;Anno Domini 1739 del primo e severissimo Editto penale emanato contro la massoneria. Da allora di acqua ne \u00e8 passata parecchia sotto i vetusti ponti del Tevere.<\/p>\n<p style=\"text-align: justify;\">E il nostro porporato del XVIII secolo rimarrebbe un tantino disorientato, oggi, a sfogliare le pagine del nuovo Codice di Diritto canonico, promulgato il 25 gennaio 1983. Invano cercherebbe nell&#8217;indice analitico la voce &#8220;massoneria&#8221;: nessuna esplicita menzione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32999 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria.jpg\" alt=\"\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria.jpg 180w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria-150x150.jpg 150w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a>E se un suo moderno confratello gli indicasse infine il canone 1374 che prende di mira, genericamente, \u00able associazioni che complottano contro la Chiesa\u00bb, egli non si tranquillizzerebbe di certo. Pene miti per i semplici aderenti, l&#8217;esclusione dai sacramenti solo per i capi. Di scomunica nemmeno a parlarne. Possibile che dopo due secoli e mezzo di aspre battaglie e oltre 580 condanne pontificie della massoneria (di cui 250 emanate solo da Leone XIII) oggi la legislazione della Chiesa mostri tanta irenica indulgenza verso i Liberi Muratori? S\u00ec, possibile.<\/p>\n<p style=\"text-align: justify;\">Al\u00admeno se ci fermiamo alla lettera del canone 1374. In realt\u00e0, come vedremo, le cose sono un po&#8217; pi\u00f9 complicate. Ma per spiegare al sempre pi\u00f9 incredulo e demoralizzato cardinal Firrao come si \u00e8 arrivati alla situazione attuale bisogna partire da lontano. Dagli anni dell&#8217;immediato post\u2014 Concilio, cio\u00e8.<\/p>\n<p style=\"text-align: justify;\"><strong>FINE DELLE OSTILIT\u00c0? <\/strong><\/p>\n<p style=\"text-align: justify;\">Fine delle ostilit\u00e0. E titolato cos\u00ec l&#8217;ultimo paragrafo della voce &#8220;Chiesa cattolica&#8221;, nel Dictionnaire de la Franc-Maconnerie che esce a Parigi nel lontano 1971. Ne \u00e8 curatore l&#8217;avvocato cattolico Alee Mellor, Maestro venerabile della Grande Loggia nazionale di Francia. Mellor si mostra ben informato circa l&#8217;orientamento della Commissione vaticana incaricata di redigere il nuovo Codice.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/Benedetto-XV.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34658\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/Benedetto-XV.jpg\" alt=\"\" width=\"151\" height=\"200\" \/><\/a>\u00abUn numero apprezzabile di cattolici praticanti ha gi\u00e0 ricevuto l&#8217;iniziazione massonica. Ed \u00e8 prevedibile che la nuova legislazione ecclesiastica non riprodurr\u00e0 pi\u00f9 l&#8217;articolo 2335 del Codice di Benedetto XV (1917), che commina la scomunica agli iscritti alle Logge\u00bb. Il Gran Maestro pu\u00f2 contare su qualche buona &#8220;talpa&#8221; in Vaticano? Forse, ma le conclusioni cui giunger\u00e0 la Commissione sono, data la mentalit\u00e0 cattolica prevalente in quegli anni, largamente previste. Scontate, quasi.<\/p>\n<p style=\"text-align: justify;\">La &#8220;svolta giovannea&#8221;, ben oltre le intenzioni del Papa buono, crea un&#8217;atmosfera di sentimenti e pensieri in cui la Chiesa sembra non dover incontrare pi\u00f9, sul proprio cammino, &#8220;nemici&#8221; ma solo pecorelle sperdute da riportare all&#8217;ovile con la medicina della misericordia. E poi i Liberi Muratori, quelli doc almeno, non credono anch&#8217;essi in Dio, nella Legge morale e negli ideali di Pace e Fratellanza universale? L&#8217;intenzione di riformare il vecchio Codice benedettino \u00e8 annunciata da Giovanni XXIII il 25 gennaio 1959, insieme alla decisione di indire un Concilio ecumenico e il primo Sinodo romano dell&#8217;epoca contemporanea.<\/p>\n<p style=\"text-align: justify;\">Una speciale Commissione, composta da 40 porporati e presieduta dal cardinal Pietro Ciriaci (che nel 1966 muore e passa il testimone al cardinal Pericle Felici) viene costituita dal Papa il 28 marzo 1963. Di fatto essa comincia a lavorare solo al termine del Vaticano II, con l&#8217;ausilio di 70 consultori aggiunti successivamente da Paolo VI. Tra i suoi primi atti la Commissione formula dieci principi generali che devono orientare l&#8217;intero lavoro di ristesura del Codice.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/11\/Paolo-VI.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-13667\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/11\/Paolo-VI.jpg\" alt=\"\" width=\"131\" height=\"200\" \/><\/a>Il nono stabilisce una \u00abnotevole riduzione\u00bb di tutte le pene ecclesiastiche. Dopodich\u00e9 essa si divide in tredici sottogruppi, ognuno incaricato di redigere una parte del nuovo testo legislativo ecclesiastico. Quello che si occupa del capitolo &#8220;De iure poenali&#8221;, e quindi anche di massoneria, \u00e8 presieduto dall&#8217;eccellentissimo monsignor Agostino Casaroli. Si raduner\u00e0 180 volte, per un totale di 450 ore. Intanto, un po&#8217; dappertutto nel mondo, fioriscono come funghi i profeti del dialogo fra Chiesa e logge.<\/p>\n<p style=\"text-align: justify;\"><strong>IL MASSONE E IL GESUITA <\/strong><\/p>\n<p style=\"text-align: justify;\">11 aprile 1969. E una cena speciale quella che si consuma nella Casa del Divin Maestro, a Roma. Da una parte del tavolo tre massoni: un israelita, uno gnostico ed un valdese. Dall&#8217;altra tre religiosi: un gesuita (Giuseppe Caprile), un salesiano (Vincenzo Miano), un paolino (Rosario E-sposito). Al Gran Maestro Giordano Gamberini viene offerto il posto di capotavola. Quasi per ricambiare la cortesia il dignitario massonico intona il Padre Nostro. Tutti i commensali si uniscono alla sua preghiera.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/cattolic_massoni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32994\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/cattolic_massoni.jpg\" alt=\"\" width=\"250\" height=\"168\" \/><\/a>Poi, appena seduto, il Gran Maestro prende un pane e spezzandolo dice con tono ispirato: \u00abIl massone spezza il pane col gesuita\u00bb e ne porge un pezzo al padre Caprile. Tutti ripetono il gesto di \u00abcondivisione fraterna\u00bb. Non \u00e8 fantapolitica religiosa. L&#8217;episodio \u00e8 narrato con minuzia di particolari da uno dei commensali, il padre Esposito, nel libro Le grandi concordanze tra Chiesa e massoneria. I tre religiosi non agiscono a titolo esclusivamente personale.<\/p>\n<p style=\"text-align: justify;\">Vincenzo Miano in quegl&#8217;anni \u00e8 consultore del Sant&#8217;Uffizio e segretario del neonato dicastero per i non credenti, di cui presidente \u00e8 l&#8217;arcivescovo di Vienna cardinal Koenig. Giuseppe Caprile, storico ufficiale del Vaticano II e dei Sinodi dei vescovi, perora apertamente la causa della riconciliazione sulle colonne di Civilt\u00e0 Cattolica. Due vescovi, Dante Bernini e Alberto Ablondi, partecipano ad analoghi incontri con dirigenti massonici negli anni tra il 1968 e il 1977.<\/p>\n<p style=\"text-align: justify;\">Il caso italiano non costituisce affatto una eccezione nel panorama ecclesiale di quegli anni. Anzi. Il 23 ottobre 1966 i vescovi di Danimarca, Svezia, Islanda, Norvegia e Finlandia decidono di consentire la &#8220;doppia appartenenza&#8221; a quei massoni che chiedono di entrare nella Chiesa cattolica. Il 5 luglio 1970 viene pubblicata la Dichiarazione di Lichtenau, sottoscritta da autorevoli delegati cattolici e massonici di lingua tedesca.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Ratzinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32885\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Ratzinger.jpg\" alt=\"\" width=\"250\" height=\"197\" \/><\/a>Vi si legge: \u00abNoi siamo dell&#8217;opinione che le bolle pontificie, che si occupano della massoneria hanno ancora un significato puramente storico, ma non sono attuali nel nostro tempo. Pensiamo la stessa cosa anche delle condanne espresse dal Diritto canonico&#8230;\u00bb. Il 19 luglio 1974 \u00e8 il Sant&#8217;Uffizio ad alimentare le speranze dei riconciliatori. L&#8217;arcivescovo di Filadelfia, John Krol, domanda a Roma se la scomunica contro i cattolici iscritti alle logge debba ancora ritenersi valida.<\/p>\n<p style=\"text-align: justify;\">Il cardinal Seper (predecessore di Ratzinger), risponde cos\u00ec: \u00abSi pu\u00f2 sicuramente insegnare ed applicare l&#8217;opinione di quegli autori i quali ritengono che il canone 2335, del Codice di Benedetto XV, tocchi soltanto quei cattolici iscritti ad associazioni che cospirano veramente contro la Chiesa\u00bb.<\/p>\n<p style=\"text-align: justify;\">Una risposta rassicurante per i pi\u00f9 influenti prelati americani, persuasi che la massoneria yankee sia soltanto una tranquilla associazione filantropica, senza alcun intento complottardo contro il cattolicesimo. E infatti pochi mesi dopo (24 settembre 1974) ad un massone che si rivolge alla Curia di New York per chiedere spiegazioni il vice-cancelliere comunica: \u00abSono lieto di informarla che l&#8217;iscrizione alla massoneria non fa incorrere in nessuna scomunica. E proibito ad un cattolico unirsi ai massoni solo nel caso che la Loggia in questione sia anticattolica o anticlericale\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30056\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Massoneria.jpg\" alt=\"\" width=\"250\" height=\"147\" \/><\/a>La presa di posizione del cardinal Seper riflette un mutamento di attitudine ampiamente diffuso ormai nell&#8217;orbe cattolico. Il Sant&#8217;Uffizio nel 1968 ha inoltrato un questionario per sondare, su questa materia, gli orientamenti dei vari episcopati. Ebbene, la grande maggioranza dei vescovi si esprime per l&#8217;abrogazione della vecchia legislazione, considerata superata dallo spirito di apertura del Concilio. Nella breccia aperta dalla lettera di Seper a Krol si infilano prontamente sempre pi\u00f9 episcopati locali.<\/p>\n<p style=\"text-align: justify;\">Quello inglese (14 novembre 1974), brasiliano (12 marz0 1975, di Santo Domingo (29 gennaio 1975). In Francia il pi\u00f9 attivo \u00e8 il presidente della Conferenza episcopale, Roger Etchegaray. Il 4 maggio 1975 dichiara: \u00abLa Chiesa, pur attendendo la riforma del Diritto canonico per riesaminare la sua legislazione penale, lascia tuttavia intendere che la scomunica non \u00e8 operante e non pu\u00f2 riguardare che una loggia che agisca espressamente contro l&#8217;esistenza e la missione della Chiesa\u00bb. Massonerie buone e massonerie cattive, dunque. Ma vediamo a che punto sono giunti, nel frattempo, i lavori della Commissione incaricata di redigere il nuovo Codice.<\/p>\n<p style=\"text-align: justify;\"><strong>DUBBI DELL&#8217;ULTIMA ORA <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/massoneria_logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15332\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/massoneria_logo.jpg\" alt=\"\" width=\"184\" height=\"200\" \/><\/a>Il sottogruppo che si occupa delle &#8220;sanzioni nella Chiesa&#8221; approva la nuova formulazione del canone sulle associazioni che cospirano contro la Chiesa il 7 maggio 1977. Come previsto non si parla pi\u00f9 di scomunica e la massoneria non \u00e8 esplicitamente menzionata. Il professor Pio Ciprotti, presidente del tribunale della Citt\u00e0 del Vaticano nonch\u00e9 relatore al suddetto sottogruppo, da noi interpellato ricorda: \u00abS\u00ec, fummo tutti d&#8217;accordo, non ci fu grande discussione. Un altro canone, quello sull&#8217;aborto, di cui si voleva attenuare leggermente la pena, cre\u00f2 molti pi\u00f9 problemi\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ultimato l&#8217;intero schema del Codice inizia un lungo processo di consultazione. In questa fase gli unici a sollevare dubbi sono alcuni porporati di Curia considerati tradizionalisti e l&#8217;episcopato tedesco. I vescovi teutonici, proprio nel 1980, portano a termine l&#8217;esperimento di un dialogo ravvicinato e senza precedenti con la massoneria, iniziato sei anni prima.<\/p>\n<p style=\"text-align: justify;\">Il vescovo Josef Stimpfle, che guid\u00f2 la delegazione cattolica, spiega oggi a II Sabato: \u00abPervenimmo alla conclusione della totale incompatibilit\u00e0 delle due appartenenze; il problema non riguarda tanto o solo il carattere cospirativo (che non fummo in grado di accertare) ma la visione &#8220;religiosa&#8221; della massoneria, che ingloba e relativizza quella cattolica, facendola scadere a opinione soggettiva\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/vescovi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34757\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/vescovi.jpg\" alt=\"\" width=\"240\" height=\"162\" \/><\/a>All&#8217;assemblea plenaria della Commissione che incomincia a Roma il 20 ottobre del 1981 sei questioni aperte vengono segnalate all&#8217;attenzione dei Padri. Tra queste figura la decisione se conservare o meno la scomunica per i massoni. C&#8217;\u00e8 ancora margine per un ripensamento, dunque.<\/p>\n<p style=\"text-align: justify;\">Ma a votare per la conservazione dello status quo legislativo \u00e8 solamente una minoranza, sconfitta. Il 21 aprile 1982 la segreteria della Commissione pu\u00f2 presentare al Papa l&#8217;ultima stesura dell&#8217;intero testo legislativo. Giovanni Paolo II si circonda di un gruppo di 7 esperti per esaminarlo. Sono Mester, Egan, Betti, Ochoa, Diez Garcia, Grocholewski e Corecco.<\/p>\n<p style=\"text-align: justify;\">Se ne va tutto luglio e settembre. Vengono ridiscusse ben 158 questioni. Su 119 di esse si trova un accordo. Trentanove rimangono pendenti. \u00abQuale pena per coloro che aderiscono alla massoneria\u00bb \u00e8 una di queste. C&#8217;\u00e8 ancora indecisione. Il Papa, rispettoso del metodo della collegialit\u00e0, vuole che l&#8217;ultima parola spetti ad una Commissione ristretta composta da tre cardinali ed un vescovo: Casaroli, Ratzinger, Jubany (canonista rinomato, arcivescovo di Barcellona), e Vincenzo Fagiolo, allora vescovo di Chieti. Il segreto pontificio impedisce ai membri della Commissione rivelare se e in che misura ci furono dissensi tra loro.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/cattolici_massoni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37405\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/cattolici_massoni.jpg\" alt=\"\" width=\"250\" height=\"173\" \/><\/a>Alla fine comunque passa la formulazione gi\u00e0 approvata dal XIII sottogruppo nel 1977. \u00abNon \u00e8 stato ritenuto opportuno menzionare i massoni esplicitamente quando si parla di associazioni contrarie alla Chiesa e che agiscono contro la Chiesa\u00bb dichiara al Sabato monsignor Fagiolo \u00abper far comprendere che anche altre associazioni vi sono incluse\u00bb. Quali? \u00abTroppo lunga la lista per enumerarle tutte: i partiti comunisti, ad esempio, almeno quando tramavano contro la Chiesa&#8230;\u00bb.<\/p>\n<p style=\"text-align: justify;\">Un criterio di natura tecnica, redazionale. Questa l&#8217;interpretazione ufficiale. Che certamente non \u00e8 quella divulgata ed amplificata in quei giorni dai mass media. L&#8217;entusiasmo con cui gli ambienti massonici e i profeti della riconciliazione accolgono la promulgazione del nuovo Codice, il 25 gennaio 1983, non lascia dubbi al proposito. Sulla scia della nuova legislazione alcuni episcopati si apprestano gi\u00e0 a pubblicare istruzioni pastorali che sanciscono in pratica il principio della doppia appartenenza. Intanto, proprio in quei giorni, lo scandalo della Loggia P2 domina la vita politica italiana.<\/p>\n<div id=\"attachment_28922\" style=\"width: 250px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/Licio-Gelli.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28922\" class=\"wp-image-28922\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/Licio-Gelli.jpg\" alt=\"\" width=\"250\" height=\"140\" \/><\/a><p id=\"caption-attachment-28922\" class=\"wp-caption-text\">Licio Gelli<\/p><\/div>\n<p style=\"text-align: justify;\">\u00abS\u00ec, anche in Vaticano l&#8217;impressione fu notevole\u00bb, confida il cardinal Palazzini. \u00abNegli elenchi di Gelli figuravano, come \u00e8 noto, anche alcuni cattolici&#8230;\u00bb. Preoccupato delle ambigue interpretazioni &#8220;liberalizzatrici&#8221; del Codice il cardinal Ratzinger si persuade che occorre porre un saldo argine dottrinale al loro dilagare. Il &#8220;prefetto della fede&#8221;, secondo quanto rivelano fonti attendibili, deve faticare non poco per vincere le resistenze di alcuni alti prelati, anche in Vaticano.<\/p>\n<p style=\"text-align: justify;\">Fatto sta che solo un giorno prima della entrata in vigore della nuova legge ecclesiastica, il 26 novembre 1983, l&#8217;ex Sant&#8217;Uffizio pubblica un&#8217;asciutta ma eloquentissima dichiarazione. In essa si ribadiscono tre punti fermi. Primo, che il giudizio negativo della Chiesa nei riguardi delle associazioni massoniche non \u00e8 mutato. Secondo, che tutti i fedeli appartenenti alle associazioni massoniche (non solo i dirigenti), \u00absono in stato di peccato grave e non possono accedere alla santa comunione\u00bb. Terzo, che non compete alle conferenze episcopali \u00abpronunciarsi sulla natura delle associazioni massoniche con un giudizio che implichi deroga a quanto sopra stabilito\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Ratzinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29328\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Ratzinger.jpg\" alt=\"\" width=\"148\" height=\"200\" \/><\/a>Inutile dire che la dichiarazione \u00e8 vista come il fumo negli occhi in molti ambienti cattolici. \u00abUn fulmine a ciel sereno\u00bb ricorda padre Caprile che, in spirito di santa obbedienza, oggi non vuol dire di pi\u00f9. Diverse Conferenze episcopali, quella statunitense in testa, esigono chiarimenti da Roma. Specialmente nella Compagnia di Ges\u00f9, come ha riconosciuto in una intervista a 30Giorni il &#8220;Papa nero&#8221;, Peter-Hans Kolvenbach, non pochi &#8220;massonologi&#8221; manifestano delusione ed amarezza.<\/p>\n<p style=\"text-align: justify;\">\u00abA proposito dell&#8217;affermazione sull&#8217;inconciliabilit\u00e0 dei principi si va ora da qualche parte obiettando\u00bb nota L&#8217;Osservatore romano del 22-23 febbraio 1985 in un fondo chiaramente ispirato dall&#8217;ex Sant&#8217;Uffizio, \u00abche essenziale della massoneria sarebbe proprio il fatto di non imporre alcun &#8220;principio&#8221; ma piuttosto di raccogliere insieme, al di l\u00e0 dei confini delle diverse religioni e visioni del mondo, uomini di buona volont\u00e0 sulla base di valori umanistici comprensibili ed accettabili da tutti\u00bb.<\/p>\n<p style=\"text-align: justify;\">Una ecumene umanitaria ben disposta a tollerare al suo interno, per usare una felice espressione del professor Del Noce, la sezione di rito cattolico. Ma il cristiano \u00abal quale \u00e8 cara la sua fede\u00bb, replica il corsivista vaticano citando Leone XIII, percepisce di istinto che la \u00abforza relativizzante di una tale fraternit\u00e0 riduce la salda adesione alla verit\u00e0 di Dio, rivelata nella Chiesa, a semplice appartenenza ad una istituzione, considerata come una forma espressiva particolare, accanto ad altre forme espressive, pi\u00f9 o meno altrettanto possibili e valide, dell&#8217;orientarsi dell&#8217;uomo all&#8217;eterno\u00bb. Il cardinal Firrao legge queste righe e muove il capo in segno di consenso, finalmente rasserenato. I tempi sono cambiati e le pene ecclesiastiche possono ben essere meno severe, ma la fede \u00e8 la stessa.<\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: center;\"><strong>DOSTOEVSKIJ <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La parabola del massone Inquisitore<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massone_inquisitore_Dostoevskij.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43515 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massone_inquisitore_Dostoevskij.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">VOLTAIRE, il terribile, fu iniziato alla massoneria da un vescovo cattolico francese. Gli ecclesiastici francesi affollavano le logge nel Settecento. \u00abE\u2019 infondata\u00bb, ci fa sapere il professor Aldo A. Mola, \u00abl&#8217;equazione &#8220;massoni = persecutori dei gesuiti&#8221;, dal momento che molti gesuiti erano massoni, compreso Barruel!\u00bb. Per chi non lo ricordasse Barruel \u00e8 il veemente autore delle M\u00e9moires pour servir \u00e0 l&#8217;histoire du Jacobinisme, un grande affresco di dietrologia storica per dimostrare che la Rivoluzione francese e tutta la modernit\u00e0 sono il frutto di una congiura planetaria ordita dalle societ\u00e0 segrete ai danni del Trono e dell&#8217;Altare.<\/p>\n<p style=\"text-align: justify;\">Accanto alle affiliazioni massoniche di cattolici \u00abmodernisti\u00bb, ci s&#8217;imbatte nel massonismo, convinto e teorizzato profondamente, di Joseph De Maistre. Le edizioni Slatkine di Ginevra hanno pubblicato nell&#8217;83 un bel volumetto intitolato <em>Ecrits Ma\u00e7onniques de Joseph De Maistre,<\/em> dov&#8217;\u00e8 raccolto anche il suo saggio rivolto al duca di Brunswick, alla vigilia dello storico convegno massonico di Wilhemsbad, nel 1782. Maria Antonietta concludeva sarcasticamente: \u00abTutti ci sono dentro\u00bb.<\/p>\n<p style=\"text-align: justify;\">In effetti verrebbe da pensarlo a scorrere le varie liste di ecclesiastici massoni redatte negli anni. Il Taute, nel 1909, ne contava 500. Le liste sono altrettanto numerose. Da quella del Gamberini, ripresa da Rosario Esposito in Le grandi concordanze fra Chiesa e massoneria, si ricavano i nomi dei cardinali De Bernis, Brancaforte, Delci, monsignor Morosini, vescovo di Verona, monsignor Ventimiglia, vescovo di Catania, inquisitore generale di Sicilia. E moltissimi altri.<\/p>\n<p style=\"text-align: justify;\">Ma l&#8217;ecclesiastico massone pi\u00f9 rivelatore ha avuto solo esistenza letteraria: il Grande Inquisitore de <em>I <\/em>fratelli Karamazov di Dostoevskij. La scena \u00e8 ambientata in una calda Siviglia secentesca, per le cui strade \u00e8 tornato a camminare un uomo sconvolgente, Ges\u00f9 Cristo.<\/p>\n<p style=\"text-align: justify;\">Il Grande Inquisitore lo fa arrestare: infatti si sente un filantropo, vuole il bene degli uomini, si preoccupa della loro felicit\u00e0 garantita da un ordine sociale controllato. Per questo ha dovuto arrestare Ges\u00f9. La sua sola presenza, che parla alla libert\u00e0 del cuore umano \u00e8 \u2014 per il Grande Inquisitore \u2014 il pi\u00f9 tremendo pericolo per l&#8217;umanit\u00e0 fragile e impotente.<\/p>\n<p style=\"text-align: justify;\">\u00abE chi sa\u00bb racconta Ivan, che si identifica chiaramente con l&#8217;Inquisitore \u00abpu\u00f2 darsi che questo vecchio maledetto, che ama l&#8217;umanit\u00e0 cos\u00ec a modo suo e cos\u00ec ostinatamente, esi\u00adsta anche oggi, sotto l&#8217;aspetto di un&#8217;intera schiera di questi vecchi; e che esista non per caso, ma per un accordo, per un&#8217;alleanza nascosta, organizzata gi\u00e0 da molto tempo, allo scopo di custodire il segreto, di nasconderlo agli uomini deboli e disgraziati per farli felici.<\/p>\n<p style=\"text-align: justify;\">Certamente \u00e8 cos\u00ec, dev&#8217;essere cos\u00ec per forza. Io penso vagamente che i massoni, alla base, abbiano qualcosa del genere\u00bb. Alla fine, nel romanzo, il Grande Inquisitore, baciato sulle labbra da Ges\u00f9, forse per la prima volta nella vita commosso nell&#8217;intimo, decide di non metterlo a morte: \u00abVattene, e non venir pi\u00f9&#8230; Non venire mai&#8230; mai!\u00bb. A.S.<\/p>\n<p style=\"text-align: center;\">___________________________<\/p>\n<div id=\"attachment_43516\" style=\"width: 173px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Armando_Corona_massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43516\" class=\"wp-image-43516\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Armando_Corona_massoneria.jpg\" alt=\"\" width=\"173\" height=\"230\" \/><\/a><p id=\"caption-attachment-43516\" class=\"wp-caption-text\">Armando Corona<\/p><\/div>\n<p style=\"text-align: center;\"><strong>La gran pace \u00e8 con noi <\/strong><\/p>\n<p style=\"text-align: justify;\"><em>\u00abQuando fu tolta la parola scomunica le iniziazioni si moltiplicarono\u00bb. Il Gran Maestro ricorda i giorni felici.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Antonio Socci <\/strong><\/p>\n<p style=\"text-align: justify;\">IL giardino della roccaforte del Grande Oriente d&#8217;Italia, la Villa Medici Riccardi, confina da un lato con l&#8217;ambasciata sovietica in Italia e dall&#8217;altro con l&#8217;abitazione di un importante diplomatico americano a Roma. Armando Corona ce lo racconta tutto divertito. E ormai alla vigilia dell&#8217;abbandono della carica di Gran Maestro alla quale fu eletto il 27 marzo del 1982, dopo la tempesta della P2 che decapit\u00f2 i vertici di Palazzo Giustiniani. Si vanta di aver \u00abripulito\u00bb la massoneria dal fango in cui si trov\u00f2 sommersa con la P2.<\/p>\n<p style=\"text-align: justify;\">Ma soprattutto questi anni hanno visto consumarsi un evento storico: la cancellazione delle parole \u00abscomunica\u00bb e \u00abmassoneria\u00bb dal nuovo Codice di diritto canonico entrato in vigore nel 1983. Una svolta, dopo 250 anni di condanne della Chiesa, a cui Corona attribuisce l&#8217;effetto di una \u00abrifioritura\u00bb delle iniziazioni alla massoneria da parte di cattolici, nonostante il documento del 26 novembre 1983 della Congregazione per la dottrina della fede, dove si nega che sia possibile ai cattolici l&#8217;iniziazione alla massoneria.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/04\/chiesa-e-massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37594\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/04\/chiesa-e-massoneria.jpg\" alt=\"\" width=\"250\" height=\"195\" \/><\/a>\u00abNei Paesi latino\u2014americani i vescovi rifiutano l&#8217;interpretazione del cardinal Ratzinger perch\u00e9 asili, chiese, ospizi, perfino l&#8217;acquisto di arredi, sono dovuti quasi totalmente alla solidariet\u00e0 della massoneria. In Europa \u00e8 diverso. Qui c&#8217;\u00e8 stata la scomunica del 1739, che fu dovuta esclusivamente a motivi politici, perch\u00e9 la massoneria si opponeva alla commistione fra spirituale e temporale nella Chiesa\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>II<\/strong> <strong>Sinodo romano conferm\u00f2 la scomunica agli appartenenti alla massoneria. Nel Concilio invece la parola massoneria non fu neanche pronunciata. Lei sa darmi una spiegazione? <\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 nel Concilio c&#8217;erano tutte le componenti. C&#8217;erano ad esempio gli episcopati latinoamericani e Usa. La stessa Curia romana non aveva nessun contrasto con noi. Il cardinal Ottaviani, ad esempio, conosceva benissimo la massoneria. Anche il cardinal Siri conosceva molti \u00abfratelli\u00bb ed era continuamente informato della vita delle logge a Genova.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/concilio_vaticano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8751\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/concilio_vaticano.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/concilio_vaticano.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/concilio_vaticano-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Al Concilio gli stessi episcopati, francese, olandese, spagnolo, britannico, irlandese, tutti avevano una buona idea della massoneria, senza preconcetti. Comunque io sono fiducioso. Molti ecclesiastici, di diversi ordini, intrattengono continui rapporti con noi, partecipano alla nostra vita, sanno ci\u00f2 che facciamo e pensiamo. Sanno, ad esempio, che abbiamo aiutato moltissimo tanta gente nell&#8217;Est europeo.<\/p>\n<p style=\"text-align: justify;\">In Polonia i fratelli sono molti, molto attivi ed hanno avuto un ruolo importantissimo per accelerare i processi di liberalizzazione. Lo stesso esperimento di Gorbacev sarebbe fallito se non avesse avuto una certa accoglienza. In Russia c&#8217;\u00e8 una grandissima tradizione massonica (erano fra l&#8217;altro massoni Tolstoj e Kerenskij). Torniamo alla Chiesa. Che parte ha avuto il cardinal Koenig nel \u00abdialogo\u00bb? Gran parte del merito \u00e8 suo.<\/p>\n<p style=\"text-align: justify;\">Prima cominci\u00f2 un dialogo, del tutto riservato, con grandi esponenti massonici. Poi, una volta compreso, fece maturare il momento per proporre un diverso giudizio ai cattolici. La sua influenza sul Codice \u00e8 stata decisiva. Koenig sa bene cos&#8217;\u00e8 l&#8217;Istituzione. Ad esempio conosce bene cosa significa la \u00absolidariet\u00e0\u00bb massonica, perch\u00e9 ogniqualvolta ha chiesto aiuto ai massoni ha ottenuto abbondantemente anche senza dover spiegare a cosa servissero quei fondi.<\/p>\n<p style=\"text-align: justify;\"><strong>Sapevate di ci\u00f2 che stava maturando attorno al nuovo Codice?<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43512\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-300x200.jpg\" alt=\"\" width=\"250\" height=\"167\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-595x400.jpg 595w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>Sapevamo da alcuni anni che doveva cadere la parola \u00abscomunica\u00bb riferita a noi. Quando fu definitivamente approvato fra noi scoppi\u00f2 un grande entusiasmo. Ricevemmo lettere da tutto il mondo. Fu un grande sollievo. Molti fratelli che prima avevano avuto problemi in famiglia a causa della scomunica poterono rientrare in pace nell&#8217;Istituzione. Vi fu un fiorire di iniziazioni. Era qualcosa di straordinario: dopo centinaia di documenti di condanna da parte della Chiesa, finalmente i cattolici potevano farsi massoni senza condanne dalla Chiesa.<\/p>\n<p style=\"text-align: justify;\"><strong>Senonch\u00e9, il giorno precedente l&#8217;entrata in vigore del nuovo Codice, la Congregazione per la dottrina della fede corregge le interpretazioni \u00abpermissive\u00bb del canone<\/strong> 1734 <strong>e ribadisce che il giudizio della Chiesa sulla massoneria non \u00e8 affatto mutato. <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Ratzinger_Senato.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32092\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Ratzinger_Senato.jpg\" alt=\"\" width=\"250\" height=\"163\" \/><\/a>Nella Chiesa dev&#8217;essere accaduto qualcosa. Il momento di massima tensione morale per noi \u00e8 stata quella dichiarazione del cardinal Ratzinger, che solo dopo qualche mese fu collocata nella giusta posizione. In Spagna, dove esiste una facolt\u00e0 di Storia della massoneria, il padre Benimeli, che ne \u00e8 il preside, scrisse un intero libro per dimostrare che Ratzinger non poteva rilasciare quella dichiarazione a nome di una commissione che non era stata ancora insediata (quella per la corretta interpretazione del nuovo Codice).<\/p>\n<p style=\"text-align: justify;\"><strong>Veramente il cardinale non pubblic\u00f2 quella dichiarazione <\/strong>a <strong>nome della commissione di cui lei parla, bens\u00ec <\/strong>a <strong>nome della Congregazione per la dottrina della fede e con l&#8217;approvazione del Papa. Quindi <\/strong>a <strong>nome della Chiesa. <\/strong><\/p>\n<p style=\"text-align: justify;\">Fatto sta che noi continuammo i nostri contatti con una serie di esponenti della Chiesa i quali sostennero che nessuno pu\u00f2 cancellare n\u00e9 lo spirito, n\u00e9 la lettera del Codice. A dire il vero non fummo molto sorpresi di quella sortita di Ratzinger, perch\u00e9 gi\u00e0 sapevamo che egli \u00e8 un nostro avversario da sempre. Se non ricordo male, proprio lui ostacol\u00f2 i primi passi del nostro dialogo cominciato in Austria. In Germania, in questa lotta feroce che si fa alla nostra Istituzione, c&#8217;\u00e8 sicuramente la sua longa manus.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma<\/strong> <strong>perch\u00e9 continua <\/strong>a <strong>parlare del cardinale: quel documento usc\u00ec con l&#8217;approvazione del Papa.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Massoneria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-30069\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Massoneria.jpg\" alt=\"\" width=\"210\" height=\"200\" \/><\/a>S\u00ec, ma il Papa approv\u00f2 anche il Codice. Io non sono mai riuscito a spiegarmi questa contraddizione. E non mi sono nemmeno accontentato della spiegazione che circola: che cio\u00e8 il Papa avesse vicino a s\u00e9 un ordine religioso, di cui si fidava ciecamente e che gli fece firmare anche la dichiarazione di Ratzinger (dicono si tratti dei salesiani). Questa spiegazione non mi ha mai convinto. In coscienza, per\u00f2, non so darne un&#8217;altra.<\/p>\n<p style=\"text-align: justify;\"><strong>E perch\u00e9 non ne \u00e8 convinto? <\/strong><\/p>\n<p style=\"text-align: justify;\">Noi riteniamo che il Papa conosca bene personalmente l&#8217;azione che i massoni hanno svolto in Polonia, dove l&#8217;Istituzione \u00e8 viva e operante. Io dunque penso si tratti di una lotta all&#8217;interno della Curia: fra la novit\u00e0 e la conservazione.<\/p>\n<p style=\"text-align: justify;\"><strong>Entriamo nel merito. La dichiarazione dell&#8217;ex Santo Uffizio ribadisce la condanna, non tanto in forza di una presunta trama sovversiva di cui sarebbe soggetto la massoneria, ma per la stessa filosofia esoterica dell&#8217;iniziazione massonica (di cui peraltro si vogliono far conoscere solo i primi tre gradi) che sono in gravissima contraddizione con i dogmi della rivelazione cristiana. Dunque: posto che gi\u00e0 i primi tre gradi minano alla radice la verit\u00e0 cristiana, perch\u00e9 vi rifiutate di far conoscere il contenuto esoterico degli altri gradi? <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43517\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-1.jpg\" alt=\"\" width=\"224\" height=\"200\" \/><\/a>Noi non possiamo entrare in discussioni teologiche. Non possiamo e non vogliamo. L&#8217;obbedienza massonica principale, quella che fa capo alla Gran Loggia d&#8217;Inghilterra e al principe di Kent, con 50mila logge in tutto il mondo, pone, alla base della sua speculazione, la credenza in un Essere Supremo, ma non impone nessuna particolare confessione religiosa.<\/p>\n<p style=\"text-align: justify;\">I Landmarks prescrivono a ciascun massone di vivere secondo la legge morale e in coerenza con la propria coscienza. Entrare nel merito teologico delle varie confessioni \u00e8 per noi impossibile e assurdo: noi abbiamo fratelli delle pi\u00f9 diverse confessioni religiose.<\/p>\n<p style=\"text-align: justify;\"><strong>Dopo quei pronunciamenti cosa \u00e8 accaduto? <\/strong><\/p>\n<p style=\"text-align: justify;\">Niente di particolare. Noi continuiamo ad ospitare gesuiti, paolini ed altri ai nostri convegni. Da ci\u00f2 che dicono comprendiamo cosa sta accadendo. Il tempo, comunque, sar\u00e0 galantuomo, \u00e8 inevitabile che prima o poi, dopo la caduta della scomunica, si arrivi all&#8217;incontro ufficiale.<\/p>\n<p style=\"text-align: justify;\"><strong>Si \u00e8 detto che perfino i settori tradizionalisti avrebbero qualche rapporto con la massoneria. Si \u00e8 parlato addirittura del gruppo di Lefebvre. Ma egli \u00e8 feroce contro le commistioni di cattolici con la massoneria. Lei cosa ne pensa? Esiste davvero qualche rapporto?<\/strong><\/p>\n<div id=\"attachment_22378\" style=\"width: 159px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/04\/Lefebvre.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22378\" class=\"wp-image-22378\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/04\/Lefebvre.jpg\" alt=\"\" width=\"159\" height=\"200\" \/><\/a><p id=\"caption-attachment-22378\" class=\"wp-caption-text\">mons. Marcel Lefebvre<\/p><\/div>\n<p style=\"text-align: justify;\">Non c&#8217;\u00e8 dubbio. Ogni Gran Loggia prende le iniziative che vuole. Penso che in Francia Lefebvre, forse anche senza saperlo, abbia rapporti con quelle logge della massoneria francese che si oppongono al Grande Oriente di Francia, il quale \u2014 caso unico al mondo \u2014 \u00e8 ateo e razionalista (fra l&#8217;altro \u00e8 assai ramificato nel mondo politico). Gli aderenti alla Gran Loggia appartengono invece ai settori pi\u00f9 conservatori, sono governatori e ufficiali delle ex colonie francesi, gente dalla cultura tradizionalista (del resto lo stesso Lefebvre non \u00e8 stato vescovo missionario in Africa occidentale?).<\/p>\n<p style=\"text-align: justify;\"><strong>Adesso quali sono gli ecclesiastici pi\u00f9 vicini nel dialogo con voi?<\/strong><\/p>\n<p style=\"text-align: justify;\">Abbiamo l&#8217;impressione che all&#8217;interno della Chiesa si stiano ancora muovendo molte pedine, che ci sia una situazione molto fluida.<\/p>\n<p style=\"text-align: justify;\"><strong>I vostri tradizionali interlocutori, quelli della prima ora, ritiene siano stati emarginati dentro la Chiesa?\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43518\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-2-300x168.jpg\" alt=\"\" width=\"230\" height=\"129\" \/><\/a>No, non mi sembra. Probabilmente sono stati avvertiti di andare pi\u00f9 cauti perch\u00e9 la presenza del cardinal Ratzinger condiziona molto questi uomini di fede. Prenderanno slancio e vigore, ma in futuro.<\/p>\n<p style=\"text-align: justify;\"><strong>E con i vescovi italiani che rapporti intrattenete? <\/strong><\/p>\n<p style=\"text-align: justify;\">Con loro abbiamo rapporti locali, abbastanza diffusi. Posso dire che l&#8217;episcopato italiano negli ultimi dieci anni ha assai migliorato la sua posizione verso di noi. C&#8217;\u00e8 stato qualcuno, come il vescovo di Perugia, con cui in passato abbiamo avuto qualche scontro. Per\u00f2 noi abbiamo consentito con grande tolleranza che appurasse i fatti e tutto cos\u00ec \u00e8 tornato tranquillamente in ordine. Solitamente i vescovi ricevono le nostre riviste, i libri, i documenti, persone che contemporaneamente sono nostre e vicine ai vescovi. A noi interessa il convincimento continuo, non la polemica, perch\u00e9 quando verr\u00e0 questo momento ufficiale deve essere una svolta definitiva, come lo fu la caduta della scomunica.<\/p>\n<p style=\"text-align: justify;\"><strong>Pu\u00f2 fare altri esempi di comunanza d&#8217;intenti con la Chiesa su questioni internazionali?<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43519\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-3.jpg\" alt=\"\" width=\"240\" height=\"180\" \/><\/a>Per esempio il caso del Libano. Sono stato laggi\u00f9 un paio di anni fa a rifondare la Gran Loggia libanese (quella che c&#8217;era era asservita alla monarchia di Giordania). Ero ospite dei cristiani maroniti, ma attorno al tavolo c&#8217;erano tutti: cristiani, drusi, islamici. Erano tutti massoni, il generale Aoun come il capo del governo, che era un islamico. Allora ho detto: \u00abVedete: la loggia \u00e8 il momento unificante. Partendo da questo potete smettere di spararvi, l\u00e0 fuori\u00bb. D&#8217;altronde la massoneria nacque in Inghilterra proprio per mettere fine ai conflitti tra monarchici e repubblicani.<\/p>\n<p style=\"text-align: justify;\">Adesso devo tornare in Libano. Andr\u00f2 a dire che il grande nemico comune \u00e8 il materialismo e l&#8217;edonismo. Dalla loggia pu\u00f2 scaturire la pace. C&#8217;\u00e8 un precedente clamoroso in Medio Oriente: la pace fra Egitto e Israele fu stipulata appunto da due statisti, Sadat e Begin, che erano entrambi massoni. Noi vogliamo migliorare la societ\u00e0. Dovunque vi sia la nostra presenza cadono le barriere.<\/p>\n<p style=\"text-align: justify;\">La societ\u00e0 va in una certa direzione. Tutte le religioni e le istituzioni iniziatiche devono tendere a questo. La Chiesa comincia a prenderne coscienza adesso. Se si diriger\u00e0 alla liberazione dell&#8217;uomo dal materialismo e dalla quotidianit\u00e0 e spinger\u00e0 l&#8217;individuo alla ricerca di una sua interiorit\u00e0 si trover\u00e0 fatalmente al nostro fianco, visto che la nostra istituzione ha come scopo la costruzione del tempio interiore.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/06\/massoneria_religione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30062\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/06\/massoneria_religione.jpg\" alt=\"\" width=\"201\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/06\/massoneria_religione.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/06\/massoneria_religione-150x150.jpg 150w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a>Ma la Chiesa non deve occuparsi eccessivamente dei problemi materiali dell&#8217;uomo, perch\u00e9 la qualit\u00e0 spirituale dell&#8217;uomo \u00e8 la stessa, che abiti in un grattacielo di New York o in una capanna. La Chiesa secondo me dovrebbe incoraggiare soprattutto la spiritualit\u00e0 dell&#8217;uomo: a occuparsi dei problemi materiali dell&#8217;uomo ci pensano gi\u00e0 altri, i partiti, i sindacati, l&#8217;Onu.<\/p>\n<p style=\"text-align: justify;\"><strong>Vorrei concludere sull&#8217;argomento. Lei come \u00e8 intervenuto durante la fase preparatoria del nuovo Codice?<\/strong><\/p>\n<p style=\"text-align: justify;\">Ma no, guardi, io non ho fatto nulla. Ai primi di maggio del 1982, nei giorni del Congresso de, quando incontrai De Mita (che stava per essere eletto segretario) insieme con Flavio Carboni e Carlo Caracciolo, c&#8217;era anche monsignor Hilary. Chiesi a lui notizie sulle trattative fra Chiesa e massoneria per addivenire alla delicata cancellazione della scomunica dal nuovo Codice.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Rotary_massoneria.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-43520\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Rotary_massoneria.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Rotary_massoneria.png 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/Rotary_massoneria-150x150.png 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>In quell&#8217;occasione lui mi invit\u00f2 in Vaticano appunto per la questione del Codice, ma non fu un incontro molto produttivo. In compenso, l\u00e0 vidi per l&#8217;ultima volta Roberto Calvi. Mi fece l&#8217;impressione di uno sprovveduto, di un uomo un po&#8217; ingenuo. E poi che brutta fine ha fatto. Come sa si \u00e8 suicidato \u2014 \u00e8 sicuramente suicidio \u2014, e io penso anche di averne capito i motivi psicologici: era assillato dal terrore di vedere crollare il suo impero bancario e tornare ad essere un signor nessuno.<\/p>\n<p style=\"text-align: justify;\"><strong>Per finire, ci pu\u00f2 dare qualche notizia sul suo successore. Si sono fatti vari nomi&#8230;<\/strong> \u00a0Penso che ormai abbiano raggiunto un accordo su Enzo Paolo Tiberi; che era gi\u00e0 stato eletto Grande oratore. Sono molto soddisfatto di questo clima di concordia dentro l&#8217;Istituzione. E sono felice di tornare a svolgere l&#8217;attivit\u00e0 che pi\u00f9 mi preme, quella internazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Sabato N.48 2 Dicembre 1989 Nel 1983 la Chiesa tolse la scomunica agl\u2019iscritti alle logge. Come si arriv\u00f2 a quella decisione? Per la prima volta ecco la vera storia di Lucio Brunelli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":43512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,96],"tags":[2704,2396,404],"class_list":["post-43511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-massoneria","category-storia-italiana","tag-chiesa-e-massoneria","tag-massoneria","tag-storia-italiana-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Massoneria sia con noi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Massoneria sia con noi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-24T22:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La Massoneria sia con noi\",\"datePublished\":\"2019-07-24T22:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/\"},\"wordCount\":4814,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/massoneria.jpg\",\"keywords\":[\"chiesa e massoneria\",\"Massoneria\",\"storia italiana\"],\"articleSection\":[\"Massoneria\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/\",\"name\":\"La Massoneria sia con noi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/massoneria.jpg\",\"datePublished\":\"2019-07-24T22:00:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/massoneria.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/massoneria.jpg\",\"width\":2333,\"height\":1556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-sia-con-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Massoneria sia con noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Massoneria sia con noi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/","og_locale":"it_IT","og_type":"article","og_title":"La Massoneria sia con noi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-07-24T22:00:19+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria-1024x683.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"23 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La Massoneria sia con noi","datePublished":"2019-07-24T22:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/"},"wordCount":4814,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria.jpg","keywords":["chiesa e massoneria","Massoneria","storia italiana"],"articleSection":["Massoneria","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/","name":"La Massoneria sia con noi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria.jpg","datePublished":"2019-07-24T22:00:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/07\/massoneria.jpg","width":2333,"height":1556},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-sia-con-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La Massoneria sia con noi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=43511"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43511\/revisions"}],"predecessor-version":[{"id":43521,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/43511\/revisions\/43521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/43512"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=43511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=43511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=43511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}