{"id":4348,"date":"2011-01-25T21:26:12","date_gmt":"2011-01-25T20:26:12","guid":{"rendered":""},"modified":"2016-06-07T17:24:35","modified_gmt":"2016-06-07T15:24:35","slug":"quel-concilio-che-ci-fa-pensare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/","title":{"rendered":"Quel concilio che ci fa pensare!"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34310\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg\" alt=\"concilio\" width=\"172\" height=\"200\" \/>Corrispondenza Romana<\/strong> n. 1175 del 22 gennaio 2011<\/div>\n<p style=\"text-align: center;\"><em>Risposta di p. Serafino M. Lanzetta a P. Giovanni Cavalcoli<\/em><\/p>\n<p><!--more--><\/p>\n<div>Carissimo P. Giovanni,<\/div>\n<p style=\"text-align: justify;\">la ringrazio per la lettera aperta che ha voluto indirizzarmi, la quale mi d\u00e0 modo di approfondire i temi a cui allude e di spiegarmi meglio. Non dico che la rottura \u00e8 stata causata dal Concilio: per s\u00e9 il Vaticano II non pu\u00f2 causare la rottura e la continuit\u00e0 allo stesso tempo, \u00abper la contraddizion che nol consente\u00bb.<\/p>\n<p style=\"text-align: justify;\">Dico che alcuni teologi hanno letto i testi come rottura e altri nella continuit\u00e0. Questo evidenzia due cose: 1) che si danno due letture teologiche del Concilio (contraddittorie) per il fatto che i testi si lasciano leggere in modo duplice, dato il loro tenore fontalmente pastorale e non definitorio; 2) questo richiede, pertanto, un criterio ermeneutico a priori corretto per leggere, di conseguenza, correttamente il Concilio: questo criterio \u00e8 la Tradizione ininterrotta della Chiesa.<\/p>\n<p style=\"text-align: justify;\">Quando viene espunta la Tradizione si verifica la rottura. Porto un esempio recente. Il padre Paolo Cortesi, missionario passionista in Bulgaria, esultava sul suo blog (cf. <a href=\"http:\/\/cosebulgare.blogspot.com\/2010\/12\/e-arrivato-il-vaticano-ii-finalmente.html\" target=\"_blank\">http:\/\/cosebulgare.blogspot.com\/2010\/12\/e-arrivato-il-vaticano-ii-finalmente.html<\/a>), perch\u00e9 finalmente era giunta in Bulgaria la traduzione dei documenti del Vaticano II. E fin qui tutto bene.<\/p>\n<p style=\"text-align: justify;\">Ma, il motivo vero della sua esultanza, consisteva nel fatto che, dopo l\u2019affaccendarsi critico-conservatore di chi pretende di buttare il Concilio nel Tevere (forse si riferisce a noi), in Bulgaria invece era arrivato il vero Concilio. Dopo aver ricordato che il Vaticano II \u00e8 un dono dello Spirito Santo, il padre passionista si attesta sulle sue peculiarit\u00e0: \u00abIl Concilio ci educa ad essere non una Chiesa padrona e paladina della verit\u00e0, ma un Popolo di Dio che cammina nella storia insieme a tutta l&#8217;umanit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abIl Concilio ci insegna che la liturgia non \u00e8 assistere alla ripetizione sacrale dei gesti che compie la casta sacerdotale, ma la celebrazione della salvezza da parte di tutto il Popolo di Dio\u00bb. \u00abL&#8217;ecumenismo non \u00e8 ricondurre all&#8217;obbedienza pontificia i disgraziati scismatici, ma la ricerca di comunione da parte di tutti i cristiani\u00bb. Infine, ci vien ricordato che il Concilio ha scoperto la Parola di Dio.<\/p>\n<p style=\"text-align: justify;\">E tutto quello che la Chiesa era prima? La sua dottrina, la sua vita? Il Vaticano II sarebbe, in realt\u00e0, il vero volta-pagina. Qui si vede \u2013 \u00e8 un esempio tra tanti \u2013 che una carenza spaventosa del concetto di Traditio Ecclesiae, fa scadere in una visione stranamente dogmatista del Vaticano II. Eppure quegli ambiti rammentati dal padre Cortesi sono quelli che oggi maggiormente soffrono a causa della secolarizzazione.<\/p>\n<p style=\"text-align: justify;\">Ma veniamo nuovamente a noi. Il nostro convegno si \u00e8 attestato non sulla verifica delle nuove dottrine del Vaticano II, ma su un approccio (iniziale e a modo di status quaestionis) di tipo storico filosofico teologico. Quello teologico lo si potrebbe definire \u201cfondamentale\u201d, volto a verificare la natura del Concilio e vederla riflessa nei vari documenti (non in tutti ma nei principali), che sono 16 e sappiamo esser divisi in Costituzioni (di cui solo due godono dell\u2019appellativo \u201cdogmatiche\u201d e presentano un insegnamento dottrinale: Lumen gentium e Dei Verbum), Decreti e Dichiarazioni, con accenti e per un esercizio eminentemente pastorali.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 una cosa comunque che unisce la diversa tipologia magisteriale del Vaticano II (diversa gi\u00e0 in ragione di una distinzione tripartita che compare in questo modo solo nel Vaticano II), ed \u00e8 il tenore dei documenti: un tenore fontalmente pastorale, di annuncio della fede e non di una sua definizione, che esprime cos\u00ec il fine stesso del Concilio. Cos\u00ec volle Giovanni XXIII, cos\u00ec conferm\u00f2 Paolo VI.<\/p>\n<p style=\"text-align: justify;\">Da quanto lei dice, emerge un dato fondamentale, che \u00e8 il problema-chiave del Vaticano II: qual \u00e8 l\u2019esercizio magisteriale (complessivo) del Concilio? Lei vede il Vaticano II come un unicum, giustamente, perch\u00e9 un concilio, ma, a mio modo di vedere, si spinge pi\u00f9 in l\u00e0 del concilio, quando entra in merito all\u2019infallibilit\u00e0, non distinguendo nel tutto le sue parti, ovvero i diversi livelli magisteriali del Concilio (stabiliti egregiamente da Gherardini).<\/p>\n<p style=\"text-align: justify;\">Mi spiego riassumendo schematicamente lo status quaestionis sull\u2019esercizio magisteriale del Vaticano II, riconducibile a 5 posizioni teologiche:<\/p>\n<p style=\"text-align: justify;\">1) esercizio del magistero straordinario solenne;<\/p>\n<p style=\"text-align: justify;\">2) esercizio del magistero ordinario universale;<\/p>\n<p style=\"text-align: justify;\">3) esercizio del magistero autentico;<\/p>\n<p style=\"text-align: justify;\">4) esercizio di un magistero omiletico;<\/p>\n<p style=\"text-align: justify;\">5) esercizio di un magistero differenziato.<\/p>\n<p style=\"text-align: justify;\">Tra questi teologi ve sono anche alcuni insospettabili di conservatorismo o di tradizionalismo (cf. F. Kolfhaus, Pastorale Lehrverk\u00fcndigung \u2013 Grundmotiv des Zweiten Vatikanischen Konzils. Untersuchungen zu \u201cUnitatis Redintegratio\u201d, Dignitatis Humanae\u201d und \u201cNostra Aetate\u201d [tesi dottorale presso l\u2019Universit\u00e0 Gregoriana], Lit, Berlin 2010, pp. 23-34).<\/p>\n<p style=\"text-align: justify;\">Fin qui la teologia, che verifica, pur con accenti diversi, un magistero s\u00ec solenne (quanto alla forma) ma ordinario (quanto al normale esercizio). Il Magistero stesso, specialmente nella persona di Paolo VI, ha riassunto l\u2019intera portata magisteriale del Vaticano II, definendolo magistero ordinario autentico (cf. Allocuzione del 7 dicembre 1965 e Udienza Generale del 12 gennaio 1966). Ora, il magistero ordinario non \u00e8 infallibile perch\u00e9 \u00e8 magistero, sia pur di un concilio, ma solo quando \u00e8 reiterato e quando appura la definitivit\u00e0 di una dottrina di fede o di morale, anche se non definita ma definitiva.<\/p>\n<p style=\"text-align: justify;\">L\u2019infallibilit\u00e0 nel Vaticano II \u00e8 solo di riflesso rispetto a precedenti definizioni dogmatiche o a dottrine definitive; questa infallibilit\u00e0, sussiste poi solo in alcune dottrine ma non nel Concilio in quanto tale, altrimenti sarebbe stata inutile la precisazione del Segretariato del Concilio per la giusta lettura di Lumen gentium, posta come Nota previa.<\/p>\n<p style=\"text-align: justify;\">Riporto i due punti salienti di detta nota che ci riguardano: \u00abTenuto conto dell&#8217;uso conciliare e del fine pastorale del presente Concilio, questo definisce come obbliganti per tutta la Chiesa i soli punti concernenti la fede o i costumi, che esso stesso abbia apertamente dichiarato come tali. Le altre cose che il Concilio propone, in quanto dottrina del magistero supremo della Chiesa, tutti e singoli i fedeli devono accettarle e tenerle secondo lo spirito dello stesso Concilio, il quale risulta sia dalla materia trattata, sia dalla maniera in cui si esprime, conforme alle norme d&#8217;interpretazione teologica\u00bb (AAS 77\/1 [1965] 72).<\/p>\n<p style=\"text-align: justify;\">L\u2019infallibilit\u00e0 si rivela solo nel magistero obbligante tutta la Chiesa, che richiede un atto di fede teologale, in ragione appunto della irreformabilit\u00e0 della dottrina. Per le altre dottrine bisogna tener conto dello spirito (della natura e del fine) del Concilio, e vedere in unit\u00e0 la materia trattata e il modo di esprimersi.<\/p>\n<p style=\"text-align: justify;\">Credo sia fuori luogo attribuire sic et simpliciter la definizione di infallibile alle diverse dottrine\/insegnamenti del Concilio. Il magistero ordinario perch\u00e9 autentico per\u00f2 rimane vincolante e richiede l\u2019ossequio dell\u2019intelletto e della volont\u00e0, pur essendo soggetto ad eventuali revisioni con l\u2019ausilio della teologia, in ragione di una comprensione accresciuta dei dati (si veda su questo il documento della Congregazione per la Dottrina della Fede, Donum veritatis, del 24 maggio 1990, nn. 22-24).<\/p>\n<p style=\"text-align: justify;\">Dire comunque che il Vaticano II ha una natura pastorale non \u00e8 squalificare il Concilio e non significa non riconoscere i suoi insegnamenti dogmatici, ma prevenire un abbaglio, oggi diffuso sia tra i progressisti che tra i tradizionalisti, che porta a leggere il Vaticano II alla stregua del Concilio di Trento o del Vaticano I. Non ci si accorge della peculiarit\u00e0 del Vaticano II, ovvero della sua natura, del suo fine e del diverso tenore magisteriale dei suo documenti, e si finisce col dogmatizzare tutti i suoi insegnamenti.<\/p>\n<p style=\"text-align: justify;\">Questo per\u00f2 \u00e8 fatale: cos\u00ec, o si fa iniziare la Chiesa dal Vaticano II o si cestina il Vaticano II per far vivere la Chiesa. Il problema rimane fino a quando non ci si decide a tralasciare questa ermeneutica rigidamente tradizionale di approccio al Vaticano II, iniziando a vedere che il nostro concilio \u00e8 sui generis: inaugura un \u201cnuovo\u201d modo di insegnare e di esser concilio per la Chiesa, modo che dar\u00e0 un\u2019impronta caratteristica al post-concilio: una scelta pi\u00f9 pastorale per dire la dottrina di fede della Chiesa. \u00c8 su questo che ci dobbiamo interrogare.<\/p>\n<p style=\"text-align: justify;\">E vengo cos\u00ec ad un ultimo punto, alle novit\u00e0 dottrinali di cui parla. Non sono d\u2019accordo sul fatto che le novit\u00e0 in quanto tali farebbero avanzare la Tradizione. Semmai la comprensione della fede su un piano teologico, ma per il progresso dogmatico \u00e8 necessaria la definitivit\u00e0 della dottrina. Qui leggo un dato simile all\u2019infallibilit\u00e0: per lei le novit\u00e0 dottrinali sono per s\u00e9 un avanzamento della Tradizione e pertanto bisogna collocarsi ora dopo di esse per riconoscere la Tradizione nel suo stadio avanzato in ragione del Concilio. Sembra allora che la verifica delle innovazioni non serva o che, se occorra, si pregiudichi la bont\u00e0 del Concilio. E questo per il fatto che le innovazioni sarebbero infallibili.<\/p>\n<p style=\"text-align: justify;\">Invece, a mio modesto giudizio, bisogna collocarsi anche qui su un piano diverso. Non sono le innovazioni che, in quanto tali, fanno avanzare la Tradizione. \u00c8 piuttosto la Tradizione, che progredendo in ragione del nuovo, in uno sviluppo omogeneo, d\u00e0 alle cose nuove lo statuto teologico di dottrine o di insegnamenti, in ragione di quanto detto poc\u2019anzi in riferimento al magistero, statuto che pu\u00f2 ascendere fino al grado ultimo di irreformabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">\u00c8 la Tradizione ovvero la Chiesa-mistero, che accoglie le innovazioni ma al contempo le precede nel suo esserci gi\u00e0, a livello ontologico e cronologico. Questo pu\u00f2 apparire un pensiero fissista, ma \u00e8 quanto dire: c\u2019\u00e8 prima la Chiesa e poi la sua comprensione, prima Dio e poi l\u2019uomo. Non \u00e8 per il fatto che siamo di fronte ad un assise conciliare insegnante in modo solenne che avanza necessariamente la Tradizione.<\/p>\n<p style=\"text-align: justify;\">Questo certo lo impariamo col Vaticano II, ma neppur possiamo troppo esulare questo concilio dalla tradizione storica dei concili ecumenici. Infatti, anche il Concilio di Pavia-Siena (1423-1424), non defin\u00ec alcun dogma ma eman\u00f2 solo pochi decreti disciplinari. Non di meno per\u00f2 \u00e8 un concilio ecumenico (difeso dal Card. Brandm\u00fcller), ma non per questo si pu\u00f2 definire infallibile.<\/p>\n<p style=\"text-align: justify;\">\u00c8 proprio sul concetto di infallibilit\u00e0 da lei esposto che non mi ritrovo. Lei dice che per avere l\u2019infallibilit\u00e0 \u00abbasta semplicemente l\u2019enunciato dottrinale in materia di fede del Magistero della Chiesa, specie poi se si tratta del Magistero solenne di un Concilio Ecumenico\u00bb. Allora dovremmo anche dire che, ad esempio, Presbiterorum ordinis insegna in modo infallibile, mentre, in verit\u00e0 al n. 16 c\u2019\u00e8 una svista storica notevole: sembra che non conosca il dato antichissimo \u201ccontinenza-celibato\u201d, e mette sullo stesso piano la tradizione latina e la deroga al celibato per i presbiteri della Chiesa greca, deroga nata dopo il trullano, ma in seguito ad un vero imbroglio.<\/p>\n<p style=\"text-align: justify;\">Ormai la ricerca storico-teologica \u00e8 progredita e si dovrebbe provvedere a perfezionare questo passaggio. Faccio anche un esempio al contrario: se Sacrosanctum concilium fosse infallibile, l\u2019attuazione della riforma liturgica, avvenuta spesso e con facilit\u00e0 in deroga allo ius divinum della liturgia, e andando molto al di l\u00e0 di quanto previsto da detta costituzione, sarebbe un\u2019eresia. Si potrebbe dire questo? No, per il fatto che Sacrosanctum concilium non \u00e8 infallibile ma \u00e8 una costituzione con una natura pastorale, che apre ai possibili adattamenti.<\/p>\n<p style=\"text-align: justify;\">Lei cita poi la Dignitatis humanae sulla libert\u00e0 religiosa, definendolo un testo infallibile, dunque dottrinale. Invece, si tratta di in testo che non \u00e8 n\u00e9 dogmatico n\u00e9 disciplinare, ma contiene norme pratiche di comportamento in materia di libert\u00e0 religiosa. Questa dichiarazione vuole dare delle norme pratiche e non intende affatto allontanarsi dalla dottrina cattolica sulla libert\u00e0 religiosa (cf. AS IV\/1, 433).<\/p>\n<p style=\"text-align: justify;\">Gli abusi, spesso, hanno fatto leva proprio sulla sua infallibilit\u00e0 per accentuare il concetto di libert\u00e0 religiosa soggettiva, fino a scadere in un relativismo religioso, contro il perenne insegnamento della Chiesa circa il dovere morale di riconoscere la verit\u00e0 e di professarla solo nella Persona del Verbo incarnato. Certo, la libert\u00e0 religiosa di cui parla il Vaticano II \u00e8 uno sviluppo del concetto stesso di libert\u00e0, che tiene conto del dato della modernit\u00e0, ma non esaurisce il contenuto della dottrina classica: \u00e8 un di pi\u00f9, che per\u00f2 necessita della Tradizione per essere compreso, dato il suo fine volto al dialogo con gli uomini.<\/p>\n<p style=\"text-align: justify;\">Vedo una certa frizione tra dottrina e prassi in materia di libert\u00e0 religiosa, proprio nella sua esecuzione pastorale di Assisi. Non si pu\u00f2 dire che Assisi cambia la dottrina della Chiesa in materia di libert\u00e0 religiosa. Assolutamente no. Ma \u00e8 una scelta pastorale che deriva dal Vaticano II, da questa dichiarazione e soprattutto da Nostra aetate, per affermare il rispetto e la verit\u00e0 della libert\u00e0 religiosa di ogni uomo.<\/p>\n<p style=\"text-align: justify;\">Al contempo per\u00f2 questa adunanza porta in s\u00e9 un dato dottrinale: qual \u00e8 la vera religione? La pastorale che \u00e8 il fine di Assisi e della Diginitatis humanae, qui, come sempre, incontra la dogmatica: solo Cristo \u00e8 la verit\u00e0. Come coniugarle? Il Vaticano II non ce lo dice, ma lascia spazio ad interventi successivi.<\/p>\n<p style=\"text-align: justify;\">Il Pontefice opta ora di nuovo per Assisi, pur conscio delle notevoli problematiche sincretiste che ad esso furono connesse in ragione dello \u201cspirito d\u2019Assisi\u201d, da lui denunciato perch\u00e9 funesto quanto lo \u201cspirito del Concilio\u201d. Nessun per\u00f2 potrebbe dire che Assisi cambia la fede della Chiesa nella verit\u00e0 di Cristo unico Salvatore. Se Dignitatis humanae fosse infallibile non si avrebbe neanche pi\u00f9 una certa libert\u00e0 nella sua attuazione pastorale, il cui giudizio prudenziale spetta al magistero.<\/p>\n<p style=\"text-align: justify;\">In questa tensione tra dogmatica e pastorale nel Concilio, si nasconde, a mio modo di vedere, tutto il problema ermeneutico del Vaticano II. Io per infallibile intendo non-fallibile, irreformabile: allora ben poche sono le dottrine che si possono dire tali.<\/p>\n<p style=\"text-align: justify;\">Direi allora che bisognerebbe leggere \u201cinfallibile\u201d nel senso pi\u00f9 rigoroso e classico della teologia, mentre il Concilio Vaticano II, quale unicum magisteriale, in modo pi\u00f9 flessibile ed articolato, distinguendo i diversi piani, in ragione del progresso teologico verificatosi grazie allo stesso Vaticano II. Gli atti del nostro convegno, che pubblicheremo, ci aiuteranno sicuramente per un discorso pi\u00f9 accurato.<\/p>\n<p style=\"text-align: justify;\">Le rinnovo i sensi di stima ed amicizia nei nostri Santi Padri Francesco e Domenico<\/p>\n<p style=\"text-align: justify;\">p. Serafino M. Lanzetta, FI<\/p>\n<div align=\"justify\">\n<div>Firenze, 16 gennaio 2011<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza Romana n. 1175 del 22 gennaio 2011 Risposta di p. Serafino M. Lanzetta a P. Giovanni Cavalcoli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34310,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[344],"class_list":["post-4348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-concilio-vaticano-ii","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-25T20:26:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-07T15:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"208\" \/>\n\t<meta property=\"og:image:height\" content=\"242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Quel concilio che ci fa pensare!\",\"datePublished\":\"2011-01-25T20:26:12+00:00\",\"dateModified\":\"2016-06-07T15:24:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/\"},\"wordCount\":2258,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/concilio.jpg\",\"keywords\":[\"Concilio Vaticano II\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/\",\"name\":\"Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/concilio.jpg\",\"datePublished\":\"2011-01-25T20:26:12+00:00\",\"dateModified\":\"2016-06-07T15:24:35+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/concilio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/concilio.jpg\",\"width\":208,\"height\":242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quel-concilio-che-ci-fa-pensare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quel concilio che ci fa pensare!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/","og_locale":"it_IT","og_type":"article","og_title":"Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2011-01-25T20:26:12+00:00","article_modified_time":"2016-06-07T15:24:35+00:00","og_image":[{"width":208,"height":242,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Quel concilio che ci fa pensare!","datePublished":"2011-01-25T20:26:12+00:00","dateModified":"2016-06-07T15:24:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/"},"wordCount":2258,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg","keywords":["Concilio Vaticano II"],"articleSection":["Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/","name":"Quel concilio che ci fa pensare! - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg","datePublished":"2011-01-25T20:26:12+00:00","dateModified":"2016-06-07T15:24:35+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/01\/concilio.jpg","width":208,"height":242},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quel-concilio-che-ci-fa-pensare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Quel concilio che ci fa pensare!"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4348"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4348\/revisions"}],"predecessor-version":[{"id":34311,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4348\/revisions\/34311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34310"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}