{"id":4293,"date":"2010-12-16T00:00:00","date_gmt":"2010-12-15T23:00:00","guid":{"rendered":""},"modified":"2016-05-02T12:14:43","modified_gmt":"2016-05-02T10:14:43","slug":"indagini-sul-suicidio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/","title":{"rendered":"Indagini sul suicidio"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33901\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg\" alt=\"suicidio\" width=\"150\" height=\"200\" \/>Il Foglio,<\/strong>1 dicembre 2010<\/div>\n<p style=\"text-align: justify;\"><em>Annulla tutti i significati, ma non \u00e8 senza significato. La fede, il materialismo, l\u2019oriente estremo<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Francesco Agnoli<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Vi \u00e8 solamente un problema filosofico veramente serio: quello del suicidio. Giudicare se la vita valga o non valga la pena di essere vissuta, \u00e8 rispondere al quesito fondamentale della filosofia\u201d: cos\u00ec scriveva Albert Camus nel \u201cMito di Sisifo\u201d. Questa frase ritorna attuale oggi con il dibattito sull\u2019eutanasia, che andrebbe a mio avviso affrontato, appunto, insieme al problema del suicidio (e a quello della disgregazione familiare e della solitudine, metafisica e quotidiana).<\/div>\n<p style=\"text-align: justify;\">Non \u00e8 infatti un caso che la richiesta di legalizzazione dell\u2019eutanasia cresca con il crescere, nel nostro occidente, del ricorso agli anti depressivi e al suicidio. Recentemente l\u2019Oms ricordava che nel 2000 sono morte per suicidio circa un milione di persone, ben pi\u00f9 che in tante guerre e calamit\u00e0 messe insieme, mentre \u201cnegli ultimi 45 anni il tasso di suicidio \u00e8 cresciuto del 65 per cento in tutto il mondo, in particolare tra i giovani\u201d.<\/p>\n<p style=\"text-align: justify;\">Uno psicoterapeuta come Viktor Frankl, che speriment\u00f2 la durezza del lager, disse che quando c\u2019\u00e8 un perch\u00e9, tutti i come diventano sopportabili. Se so perch\u00e9 vivo, se la preziosit\u00e0 della vita mi \u00e8 chiara, se la vita come dono \u00e8 un\u2019idea radicata, ogni circostanza, bench\u00e9 dura, diventa pi\u00f9 facilmente tollerabile.<\/p>\n<p style=\"text-align: justify;\">Scriveva ancora Frankl, il quale definiva il nostro tempo \u201cl\u2019epoca del vuoto esistenziale\u201d: \u201cSe una persona \u00e8 riuscita a porre le basi del significato che essa cercava, allora \u00e8 pronta a soffrire, a offrire sacrifici, a dare anche, se fosse necessario, la propria vita per amore di quel significato. Al contrario, se non esiste alcun significato del suo vivere, una persona tende a togliersi la vita ed \u00e8 pronta a farlo anche se tutti i suoi bisogni, sotto ogni aspetto, sono stati soddisfatti\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019uomo \u00e8 capace di adeguarsi a tutto, o quasi: solo che lo spirito sostenga il corpo, e se stesso; solo che lo spirito non sia ancora pi\u00f9 debole del corpo. Se c\u2019\u00e8 un perch\u00e9, tutti i come divengono pi\u00f9 o meno sopportabili. E non vi \u00e8 dubbio, a mio parere, che il perch\u00e9 vero sia solo e soltanto Dio, dal momento che tutti gli altri, in un momento o nell\u2019altro, possono cedere. Un Dio personale che ci ha creato, che ci guarda e ci conosce e il cui amore rende preziosa ogni singola esistenza. Un Dio che manca ad esempio ai grandi popoli cinese e giapponese. Che, non a caso, hanno da secoli un triste primato dei suicidi.<\/p>\n<p style=\"text-align: justify;\">In Cina e Giappone infatti il ricorso al suicidio \u00e8 estremamente diffuso, amplissimo, e, quel che pi\u00f9 interessa, accettato culturalmente. Parlando dei cinesi J. J. Matignon scriveva, all\u2019inizio del Novecento, che il suicidio \u201csi riscontra in tutte le classi e a tutte le et\u00e0\u201d, ed \u00e8 spesso dettato anche da motivi che per la nostra cultura sono del tutto \u201cfutili\u201d: per vendetta, per rancore, per collera o gelosia, per questioni di onore\u2026 \u201cCapita che un mendicante attui la sua vendetta tagliandosi la gola davanti alla vostra porta\u201d.<\/p>\n<p style=\"text-align: justify;\">Dall\u2019India alla Cina, ricorda Marzio Barbagli, \u201cdarsi la morte per colpire un nemico, immolandosi con lui o facendogli ricadere addosso la colpa della propria morte, \u00e8 una scelta messa a disposizione per secoli da culture diverse\u201d. In entrambi questi paesi, poi, vi sono dei suicidi, come quello della moglie o della concubina sulla tomba del marito, che sono considerati meritori ed auspicabili.<\/p>\n<p style=\"text-align: justify;\">Un altissimo tasso di suicidi si registra anche in Giappone: 24, 4 ogni 100 mila abitanti, almeno 4 volte di pi\u00f9 che in Italia, visto che il numero reale \u00e8 in verit\u00e0 ben pi\u00f9 alto. Il Giappone ha anche un primato nel numero dei giovani suicidi. Kamikaze e harakiri \u201csono le parole della lingua giapponese pi\u00f9 conosciute nel mondo\u201d. Qualche anno fa la \u201cGuida al suicidio perfetto\u201d dello scrittore Wataru Tsurumi, in cui si spiegava come uccidersi buttandosi dalla finestra o sotto il treno, divenne un bestseller con 550 mila copie in otto mesi.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 questo dramma? A prescindere dalle mille motivazioni che possono stare dietro un suicidio, \u00e8 difficile non notare che anche nel ricco Giappone, come in Cina, l\u2019uomo non \u00e8 creatura unica, irripetibile, di un Dio che la ama fino a morire per lei. \u201cI giapponesi \u2013 ricorda il nunzio apostolico in Giappone, Alberto Bottari de Castello-, non hanno un rapporto personale con Dio. Il concetto dell\u2019individuo, che \u00e8 al centro della cultura occidentale, non fa parte del loro Dna culturale.<\/p>\n<p style=\"text-align: justify;\">Si identificano con il gruppo, la societ\u00e0, l\u2019azienda, la nazione. Quando un cristiano arriva alla decisione di togliersi la vita sa che sta per infrangere una regola sacra: la vita gliel\u2019ha data Dio e solo Dio gliela pu\u00f2 togliere. Il giapponese tentato dal suicidio non ha questo freno. Non ha il concetto del peccato. Non ha nessuno, non ha niente, all\u2019infuori del proprio mondo materiale e culturale, a cui chiedere aiuto. Ma nel suo mondo chiedere aiuto \u00e8 disonorevole, e allora deve risolvere all\u2019interno di se stesso il dramma della propria infelicit\u00e0, divenuta insopportabile.<\/p>\n<p style=\"text-align: justify;\">I cristiani, anche nei momenti pi\u00f9 bui, possono sempre tendere la mano verso Dio. I giapponesi no. Hanno otto milioni di dei, migliaia di meravigliosi templi, santuari, altari, altarini, due religioni ufficiali, il buddismo e lo shintoismo, ma vivono senza il Dio unico onnipotente e misericordioso, senza il concetto di Dio padre di tutta l\u2019umanit\u00e0 e presente in ciascuno di noi, sempre\u201d.<\/p>\n<p style=\"text-align: justify;\">Nello stesso tempo in Giappone il buddismo \u00e8 una religione atea che crede nella reincarnazione, cio\u00e8 che nega, appunto, l\u2019unicit\u00e0 di una vita personale. Il suicidio quindi non \u00e8 considerato eticamente negativo, anzi \u00e8 talora contemplato come possibile \u201csoluzione\u201d ad un determinato problema.<\/p>\n<p style=\"text-align: justify;\">Maurice Pinguet, gi\u00e0 direttore dell\u2019Istituto franco-giapponese di Tokyo, nel suo \u201cLa morte volontaria in Giappone\u201d, nota anzitutto il profondo immanentismo che caratterizza la cultura di questo popolo, e in secondo luogo mette in luce come in Giappone siano sempre esistite forme di suicidio che la cultura cristiana rifiuta: ad esempio il \u201csuicidio di solidariet\u00e0\u201d, in cui i genitori \u201ccoinvolgevano i loro figli nella morte, convincendoli, o a loro insaputa\u201d. Infatti alla madre giapponese che uccide il figlio \u201cnon viene in mente che il bambino possa rappresentare una esistenza distinta, posta sin dalla nascita, o dal concepimento, sotto la sovranit\u00e0 di Dio\u201d.<\/p>\n<p style=\"text-align: justify;\">Vi \u00e8 poi, sempre nella cultura giapponese, il \u201csuicidio di accompagnamento\u201d: alla morte dell\u2019imperatore, del sovrano, del padrone, funzionari, vassalli, servi lo hanno spesso accompagnato nella morte, eliminandosi. Vi \u00e8 infine il suicidio come rituale, svolto con precisione e solennit\u00e0: harakiri \u00e8 l\u2019atto di uccidersi lentamente, aprendosi il ventre, estraendone le viscere, \u201csenza battere ciglio\u201d. Del resto, se tutta la vita dell\u2019uomo \u00e8 qui ed ora, come protestare altrimenti la propria innocenza? Come lavarsi di una colpa, che altrimenti rimarr\u00e0 per sempre? Come cancellare la vergogna? Come salvare l\u2019onore?<\/p>\n<p style=\"text-align: justify;\">Una conferma a questa ipotesi, e che cio\u00e8 l\u2019ateismo contribuisca a togliere alla vita umana quella sacralit\u00e0 religiosa che \u00e8 spesso un utile antidoto alla scelta estrema di eliminarsi, viene dai paesi comunisti, in cui l\u2019ateismo \u00e8 stato imposto e diffuso a tutti i livelli.<\/p>\n<p style=\"text-align: justify;\">In un celebre film intitolato \u201cLe vite degli altri\u201d si ricorda che negli anni 70 e 80, Russia, Ungheria e Germania dell\u2019est, tutti e tre paesi comunisti, avevano il primato mondiale dei suicidi, bench\u00e9 i regimi, che pure catalogavano tutto, nascondessero le cifre relative al disastroso fenomeno. Infatti erano stati proprio molti teorici del socialismo a spiegare che, una volta instaurata l\u2019eguaglianza economica e materiale, alcolismo, prostituzione, furti e suicidi, sarebbero spariti.<\/p>\n<p style=\"text-align: justify;\">In verit\u00e0 con l\u2019avvento del regime bolscevico i suicidi iniziarono a crescere. Il Partito comunista cerc\u00f2 allora di condannarli come \u201cuna forma di individualismo borghese\u201d. Il suicidio, per i comunisti atei, era considerato una appropriazione indebita della vita, che apparteneva non a Dio, come si era detto sino a quel momento, ma al partito, allo stato, alla comunit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Tanto che chi si suicidava subiva l\u2019espulsione postuma dal partito e altre pene, ad esempio riguardo al suo funerale. Ma l\u2019efficacia di queste posizioni fu inesistente. Non uccidersi perch\u00e9 la vita \u00e8 un dono di Dio, \u00e8 un messaggio che pu\u00f2 essere convincente, come dimostrano i bassi tassi di suicidio del medioevo e sino all\u2019esplosione ottocentesca (vedi: Marzio Barbagli, Congedarsi dal mondo, Il Mulino). Non farlo perch\u00e9 Stalin non vuole, \u00e8 un dogma meno credibile.<\/p>\n<p style=\"text-align: justify;\">\u201cNel 1924-25 \u2013 scrive Barbagli \u2013 vi fu un forte aumento dei suicidi\u201d, non solo tra gli avversari del comunismo, ma \u201ctra gli iscritti al partito\u201d, tra coloro che professavano la fede del regime. Stalin condann\u00f2 il fatto spiegando che il suicidio era il mezzo pi\u00f9 semplice per lasciare il mondo, tradendo il partito e sputando \u201cper l\u2019ultima volta sul partito\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cIn ogni caso, continua il Barbagli, il governo smise di pubblicare statistiche e studi sull\u2019argomento\u201d. Possiamo quindi ipotizzare un aumento sempre crescente di suicidi in occasione del terrore, cos\u00ec come c\u2019era stato all\u2019epoca del terrore giacobino e della ghigliottina. Ma con la morte di Stalin la crescita dei suicidi non cal\u00f2 e il numero rimase alto sino alla fine.<\/p>\n<p style=\"text-align: justify;\">Il crollo del regime, la morte definitiva della fede comunista segn\u00f2 un ulteriore incremento. Veniva cio\u00e8 a mancare anche l\u2019ultima forma di \u201csenso\u201d, per quanto labile. Nel 1994 si arriv\u00f2 alla cifra impressionante di 43 suicidi per 100.000 abitanti! \u201cPur essendo diminuito negli anni seguenti, continua Barbagli, nel 2004 il tasso di suicidio in Russia (34 per 100. 000 abitanti) era da due a tre volte superiore a quello degli Stati Uniti e dei paesi dell\u2019Europa occidentale\u201d.<\/p>\n<p style=\"text-align: justify;\">Anche oggi le macerie spirituali lasciate dal materialismo ateo sono ben evidenti, visto che gli ex paesi dell\u2019ateismo di stato hanno contemporaneamente il triste primato dei divorzi, degli aborti e quello, appunto, dei suicidi. L\u2019Oms dunque rivela oggi che al primo posto nella classifica dei paesi con il pi\u00f9 alto numero di suicidi nel 2009 si trovano la Bielorussia, con 35, 1 suicidi ogni 100.000 persone; al secondo posto viene la Lituania, al terzo la Russia, al quarto il Kazakistan, al quinto l\u2019Ungheria, al sesto il Giappone, all\u2019ottavo l\u2019Ucraina\u2026 ben 6 dei primi 8 paesi di questa terribile classifica sono ex paesi comunisti (senza contare che mancano le cifre vere per la Cina).<\/p>\n<p style=\"text-align: justify;\">Eppure non \u00e8 sempre stato cos\u00ec, dal momento che prima della rivoluzione del 1917 \u201cla percentuale dei suicidi in Russia era una delle pi\u00f9 basse al mondo\u201d (Moskovskji Komsomolets). Quanto alla Lituania, seconda nella classifica del 2010, ma prima in quella del 2009, Alvydas Navickas, presidente dell\u2019Associazione lituana di suicidiologia e vicerettore dell\u2019Universit\u00e0 di Vilnius, sintetizza cos\u00ec la storia del suo paese: \u201cPrima della Seconda guerra mondiale, si suicidavano 8 lituani su 100. 000.<\/p>\n<p style=\"text-align: justify;\">La maggior parte della popolazione viveva in campagna, frequentava la chiesa: esisteva una comunit\u00e0 forte con una routine stabile. In seguito scoppi\u00f2 la guerra e venne il regime sovietico: Stalin deport\u00f2 gli agricoltori pi\u00f9 ricchi e install\u00f2 la maggior parte nei Kolchoz (cooperative agricole). Vodka e alcol prodotti in casa iniziarono a scorrere come anestesia, quotidianamente. Nella decade degli anni ottanta l\u2019indice crebbe ogni anno fino a 30 suicidi su 100. 000 persone. Con la caduta dell\u2019Urss il tasso ha subito un forte rialzo, fino a toccare il tetto, tra il 1994 e il 1995, di 46 su 100.000\u201d (<a href=\"http:\/\/www.cafebabel.it\/article\/33596\/stalin-disoccupazione-maltempo-suicidi-lituania.html\" target=\"_blank\">articolo<\/a>)<\/p>\n<p style=\"text-align: justify;\">E\u2019 a questo punto inevitabile ricordare quanto scriveva alla fine dell\u2019Ottocento il grande Dostoevskij, nel suo romanzo \u201cI Demoni\u201d, in cui illuminava la mentalit\u00e0 degli atei rivoluzionari del suo tempo. L\u2019autore russo faceva dire ad uno dei suoi personaggi che a frenare la volont\u00e0 degli uomini di suicidarsi \u00e8 anzitutto l\u2019idea di \u201cun altro mondo\u201d dopo la morte (idea che non toglie, ma al contrario conferisce valore, proprio a questo mondo concreto in cui viviamo ogni giorno).<\/p>\n<p style=\"text-align: justify;\">Ma quando l\u2019ateismo trionfer\u00e0, continuava il rivoluzionario, prefigurazione dei comunisti del 1917, l\u2019uomo, messo da parte Dio, affermer\u00e0 la sua totale libert\u00e0: \u201cLa piena libert\u00e0 ci sar\u00e0 allora, quando sar\u00e0 indifferente vivere o non vivere\u201d. Un giorno \u201cvi sar\u00e0 l\u2019uomo nuovo, felice e superbo. A chi sar\u00e0 indifferente vivere o non vivere, quello sar\u00e0 l\u2019uomo nuovo! Chi vincer\u00e0 il dolore e la paura, quello sar\u00e0 Dio. Mentre l\u2019altro Dio non vi sar\u00e0\u2026 Possibile che nessuno su tutto il pianeta, avendola finita con Dio e avendo posto fede nell\u2019arbitrio, osi proclamar l\u2019arbitrio, nel senso pi\u00f9 completo?\u201d. Conclusione? \u201cIo sono obbligato a uccidermi, perch\u00e9 il mio arbitrio \u00e8 uccidere me stesso\u201d.<\/p>\n<p style=\"text-align: justify;\">Dostoevskij aveva visto giusto: la proclamazione di una libert\u00e0 illimitata da parte dell\u2019uomo, di una sua autonomia morale, di una sua autodeterminazione totale, luciferina, \u00e8 anche l\u2019affermazione della sua drammatica solitudine, con le ovvie conseguenze.<\/p>\n<p style=\"text-align: justify;\">Ecco perch\u00e9 oggi sono proprio certi atei come Maurizio Mori, il consigliere di Beppino Englaro, a proclamare la fine della \u201csacralit\u00e0 della vita\u201d, respingendola come un concetto cristiano che non ci appartiene pi\u00f9, e a collegare il presunto diritto all\u2019aborto, con quello all\u2019eutanasia (o \u201csuicidio assistito\u201d). Riaffermando cos\u00ec il principio dell\u2019autodeterminazione assoluta gi\u00e0 proclamato dal rivoluzionario di Dostoevskij.<\/p>\n<p style=\"text-align: justify;\">Dichiarava qualche anno orsono il socialista francese Jacques Attali, gi\u00e0 consigliere del presidente Mitterrand, e oggi di Sarkozy: \u201cLa logica socialista \u00e8 la libert\u00e0, e la libert\u00e0 fondamentale \u00e8 il suicidio. Di conseguenza il diritto al suicidio diretto o indiretto \u00e8 dunque un valore assoluto di questo tipo di societ\u00e0\u201d. Qualche anno prima, su California Medicine, aveva affermato, coerentemente, che la vita non \u00e8 pi\u00f9 da considerare un valore assoluto, ma \u201crelativo\u201d, e ci\u00f2 significa che accanto al \u201ccontrollo e alla selezione delle nascite\u201d occorrer\u00e0 porre la \u201cselezione delle morti\u201d, cio\u00e8 all\u2019eutanasia, per motivi personali, ma anche economici, politici.<\/p>\n<p style=\"text-align: justify;\">Laddove manca Dio, \u00e8 la vita dell\u2019uomo a perdere valore, e a sfociare pi\u00f9 spesso nel suicidio, individuale o legalizzato e statalizzato che sia. Scriveva a ragione il gi\u00e0 citato Pinguet, parlando per\u00f2, stavolta, del nichilismo occidentale: \u201cIn un mondo che non ha altra vita che quella quaggi\u00f9, altra volont\u00e0 che quella del soggetto, l\u2019uomo diviene il solo giudice della totalit\u00e0 dell\u2019essere che resta in bilico sul filo di rasoio della sua decisione. L\u00e0 dove brillava l\u2019onnipotenza divina, una vertiginosa implosione ha scavato il suicidio nichilista, buco nero nel quale l\u2019assolutezza della libert\u00e0 dovrebbe farsi inghiottire\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3758\" target=\"_blank\">Quel compagno che aiuta a superare le prove pi\u00f9 dure<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=483\" target=\"_blank\">Il mal di vivere \u00e8 sempre pi\u00f9 giovane<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3748\" target=\"_blank\">Perche&#8217; nel benestante Giappone la vita vale cos\u00ec poco<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio,1 dicembre 2010 Annulla tutti i significati, ma non \u00e8 senza significato. La fede, il materialismo, l\u2019oriente estremo di Francesco Agnoli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[606],"class_list":["post-4293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-suicidio","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indagini sul suicidio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indagini sul suicidio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-15T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-02T10:14:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"194\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Indagini sul suicidio\",\"datePublished\":\"2010-12-15T23:00:00+00:00\",\"dateModified\":\"2016-05-02T10:14:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/\"},\"wordCount\":2356,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/suicidio-1.jpg\",\"keywords\":[\"suicidio\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/\",\"name\":\"Indagini sul suicidio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/suicidio-1.jpg\",\"datePublished\":\"2010-12-15T23:00:00+00:00\",\"dateModified\":\"2016-05-02T10:14:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/suicidio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/suicidio-1.jpg\",\"width\":194,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/indagini-sul-suicidio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indagini sul suicidio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indagini sul suicidio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/","og_locale":"it_IT","og_type":"article","og_title":"Indagini sul suicidio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-12-15T23:00:00+00:00","article_modified_time":"2016-05-02T10:14:43+00:00","og_image":[{"width":194,"height":259,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Indagini sul suicidio","datePublished":"2010-12-15T23:00:00+00:00","dateModified":"2016-05-02T10:14:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/"},"wordCount":2356,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg","keywords":["suicidio"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/","name":"Indagini sul suicidio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg","datePublished":"2010-12-15T23:00:00+00:00","dateModified":"2016-05-02T10:14:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/suicidio-1.jpg","width":194,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/indagini-sul-suicidio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Indagini sul suicidio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4293"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4293\/revisions"}],"predecessor-version":[{"id":33902,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4293\/revisions\/33902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33901"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}