{"id":42896,"date":"2017-04-24T00:00:18","date_gmt":"2017-04-23T22:00:18","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=42896"},"modified":"2019-05-02T10:13:02","modified_gmt":"2019-05-02T08:13:02","slug":"limpero-e-sacro","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/","title":{"rendered":"L\u2019Impero \u00e8 sacro"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-42897\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov-300x204.jpg\" alt=\"\" width=\"250\" height=\"170\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov-300x204.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov-768x522.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov-1024x696.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg 1280w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>da <strong>Il Sabato<\/strong> n.49 \u2013<\/p>\n<p style=\"text-align: center;\">9 Dicembre 1989<strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>1989, crolla il comunismo? Augusto Del Noce ha qualche dubbio. Dalle macerie sta nascendo una nuova egemonia sovietica. <\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Augusto del Noce<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Secondo il giudizio abituale, il 1989 sarebbe stato l\u2019anno del \u00abfallimento del comunismo\u00bb. E\u2019 una troppo facile formula su cui conviene intendersi. Le interpretazioni correnti del comunismo sovietico si riducono alle tre seguenti: comparse gi\u00e0 nei primi anni dell\u2019instaurazione di quel regime, si sono certamente molto affinate, in seguito per\u00f2 senza mutare sostanzialmente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/lavoro_Urss.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32432\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/lavoro_Urss.jpg\" alt=\"\" width=\"148\" height=\"230\" \/><\/a>La prima vi vedeva la pi\u00f9 grande, e la definitiva rivoluzione della storia, quella destinata a sostituire il cristianesimo e a farlo perire: lo spirito dell\u2019utopia che si faceva scienza e storia, la filosofia moderna che trovava la sua verifica, eccetera.<\/p>\n<p style=\"text-align: justify;\">N\u00e9 mancavano certamente, e continuano ad esistere anche oggi teologi cattolico-blochiani (da Ernst Bloch, teorico del ponte tra \u00abateismo marxista e cristianesimo\u00bb) che vi vedevano l\u2019avvento del Terzo regno di Gioacchino da Fiore.<\/p>\n<p style=\"text-align: justify;\">La seconda parlava invece di una rivoluzione tradita (titolo della celebre opera di Trotzki). Accanto alla religione nuova, che si era corrotta nel farsi Chiesa, le sette ereticali.<\/p>\n<p style=\"text-align: justify;\">C\u2019era infine chi vi vedeva la trasformazione di un fenomeno inizialmente messianico e profetico, ultimo erede mondanizzato del messianismo ebraico, in un altro di natura esclusivamente politica. Il marxismo si realizzava inserendosi nella storia russa, in una linea che era gi\u00e0 stata di Pietro il Grande e della grande Caterina, il cui obiettivo era l\u2019estensione dell\u2019impero russo verso l\u2019Europa; arrivare al dominio di quella Europa che era il centro della Civilt\u00e0.<\/p>\n<div id=\"attachment_35249\" style=\"width: 153px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/Del_Noce.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35249\" class=\"wp-image-35249\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/Del_Noce.jpg\" alt=\"\" width=\"153\" height=\"200\" \/><\/a><p id=\"caption-attachment-35249\" class=\"wp-caption-text\">Augusto Del Noce<\/p><\/div>\n<p style=\"text-align: justify;\">Si pu\u00f2 anche dire che si tratta di tre momenti di un\u2019interpretazione unica; il primo riguarda le speranze e le intenzioni di Marx e di Engels; l\u2019ultimo, il risultato che le contraddice nel modo pi\u00f9 completo: quello che doveva essere il compimento pieno dell\u2019idea rivoluzionaria si \u00e8 realizzato risolvendosi nella continuazione di ci\u00f2 in cui il marxismo vedeva il massimo degli avversari, l\u2019imperialismo zarista.<\/p>\n<p style=\"text-align: justify;\">Su questa eterogenesi dei fini ci sarebbe molto da riflettere. Inoltre, queste tre interpretazioni riproducono quelle usate per la Chiesa cattolica: dai fedeli, dagli eretici, dai laici. Per quest\u2019ultima mi viene in mente il saggio <em>Controriforma<\/em> che Benedetto Croce scrisse nel \u201924 e che poi premise quale primo paragrafo nella sua introduzione alla <em>Storia d\u2019Italia nell\u2019et\u00e0 barocca<\/em>, pubblicata nel 1929: \u00abLa Controriforma non rappresent\u00f2 una categoria ideale, ma la difesa di una istituzione storicamente data; e perci\u00f2 potrebbe, tutt\u2019al pi\u00f9, valere genericamente come simbolo dell\u2019un\u2019azione conservatrice, dell\u2019abilit\u00e0 politica, della disciplina\u2026\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/Urss_Gorbaciov.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-42898\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/Urss_Gorbaciov-300x168.jpg\" alt=\"\" width=\"250\" height=\"140\" \/><\/a>Falsa rispetto alla Controriforma cattolica, questa definizione si adatta invece a pennello alla presente situazione del comunismo sovietico, ridotto ora alla conservazione e all\u2019estensione del potere, dopo che sono venute meno le idee della liberazione universale e della funzione redentrice della classe proletaria. Il fatto nuovo dell\u201989 \u00e8 l\u2019esplicita rifondazione operata in questo senso.<\/p>\n<p style=\"text-align: justify;\">Se si guarda agli aspetti profetici e messianici, e alla fede rivoluzionaria, e al mito dell\u2019uomo nuovo, questi sono spenti da molto tempo. Lenin poteva pensare alla rivoluzione mondiale, Stalin a mantenere provvisoriamente il socialismo in un solo Paese, confidando \u2013 o contribuendo in maniera decisiva a crearne le condizioni (le eccezionali qualit\u00e0 di Stalin nella politica pura non sono negabili) \u2013 in quella guerra tra i Paesi capitalisti che avrebbe permesso la ripresa della rivoluzione. Ma i suoi successori?<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/06\/pci.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22500 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/06\/pci.jpg\" alt=\"\" width=\"240\" height=\"160\" \/><\/a>Che speranze potevano e possono avere in una rivoluzione mondiale, in una guerra che ne sarebbe l\u2019occasione, in un successo elettorale che per un momento parve possibile, rispetto ai Paesi occidentali, per la sola Italia? E la fede rivoluzionaria in una trasformazione mondana non pu\u00f2 durare troppo a lungo, tanto pi\u00f9 quando i progressi sembrano quelli dell\u2019estensione del potere della <em>nomenklatura<\/em>, e non altri.<\/p>\n<p style=\"text-align: justify;\">Pareva che al comunismo restasse, col breznevismo, la sola possibilit\u00e0 della mummificazione, e corrispondentemente il disagio e l\u2019agitazione delle nazionalit\u00e0. Ma l\u2019occasione per una riunificazione si \u00e8 presentata, nella prossimit\u00e0 dell\u2019unificazione europea, e nella prospettiva della partecipazione a essa, come alla \u00abcasa comune\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/02\/europa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31863\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/02\/europa.jpg\" alt=\"\" width=\"250\" height=\"170\" \/><\/a>Evidentemente il comunismo non poteva presentarsi nelle sembianze totalitarie, che erano pur sempre condizionate dalla fede rivoluzionaria. Doveva parlare della \u00absinistra europea e dell\u2019ispirazione a far parte dell\u2019Internazionale socialista; doveva rimuovere dal potere i dirigenti di vecchia formazione.<\/p>\n<p style=\"text-align: justify;\">La nuova linea comporta esoneri e agitazioni dal basso nei Paesi legati alla vecchia impostazione\u00bb. Ma questo rientrare nella sinistra europea comporta delle obbligazioni che sono diventate particolarmente visibili nell\u2019antico partito comunista forte dell\u2019Europa occidentale, l\u2019italiano.<\/p>\n<p style=\"text-align: justify;\">Parlare dunque di fallimento \u00e8 ambiguo. Se si vuole riferirsi all\u2019istallazione di un mondo affatto nuovo, s\u00ec: se invece ai rapporti di potenza nuovi da istaurare nel mondo vecchio, no; e tutto lascia pensare ad una ricerca di egemonia della Russia nella nuova Europa, sia pure sotto la forma che si suol chiamare di finlandizzazione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/Repubblica_pagina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-42899\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/Repubblica_pagina.jpg\" alt=\"\" width=\"250\" height=\"181\" \/><\/a>Quel che succede ora in Italia \u00e8 estremamente interessante. Cambiamento di nome che \u00e8 anche, e soprattutto, cambiamento di sostanza. Capitolazione, parrebbe, davanti all\u2019occidentalismo del tipo nuovo, al nuovo spirito borghese, quello che si esprime, per ricorrere ai pi\u00f9 noto esempi, in De Benedetti e ne <em>La Repubblica<\/em>; e che, certamente, \u00e8 affatto nuovo, e pienamente, rispetto a quel tipo per cui venne usato il termine cristiano-borghese e che ebbe qui in Italia il suo paradigma pi\u00f9 esemplare sul piano mondiale nella personalit\u00e0 di Benedetto Croce.<\/p>\n<p style=\"text-align: justify;\">Riconosciamo a Occhetto il suo nella coerenza in questa capitolazione; nell\u2019alternativa antidemocristiana la lotta di classe deve sparire; e perci\u00f2 anche il termine comunismo come quello che trae il suo significato dall\u2019antitesi al capitalismo. Ed \u00e8 difficile non provare una qualche simpatia per i suoi oppositori, perch\u00e9 essi una fede, anche se sbagliata, l\u2019hanno conosciuta; non si pu\u00f2 dir lo stesso per i politicizzati comunisti nuovi.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/cattocomunista.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28817\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/cattocomunista.jpg\" alt=\"\" width=\"250\" height=\"191\" \/><\/a>Ma questa della capitolazione del comunismo al neocapitalismo, pur accompagnata dai vantaggi conseguenti alla possibile alternativa \u00e8 la sola via che gli si presenta? Se la prospettiva \u00e8 dolorosa per coloro che avevano votato per la vita al comunismo, non lo \u00e8 nemmeno per coloro che ne sono stati i pi\u00f9 risoluti avversari.<\/p>\n<p style=\"text-align: justify;\">Abbiamo parlato dell\u2019estensione dell\u2019egemonia sovietica che pu\u00f2 avvenire attraverso la sinistra europea. Si chiarirebbe cos\u00ec il significato delle guerre di questo secolo; dall\u2019eredit\u00e0 del Sacro Romano impero nell\u2019impero asburgico si sostituirebbe la desacralizzazione dell\u2019impero sovietico. Inoltre: il conformismo pubblicistico di oggi esalta la fine della guerra fredda; si dimentica che la guerra fredda ha rappresentato la crisi dell\u2019organizzazione del mondo proposta a Yalta. Non si vorrebbe che la distensione presente ne realizzasse la riconferma in una prospettiva di definitivit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Dal punto di vista religioso l\u2019accordo presente significherebbe la compitezza dell\u2019agnosticismo, via pi\u00f9 perfezionata delle persecuzioni per l\u2019estinzione delle religioni.<\/p>\n<div id=\"attachment_34564\" style=\"width: 240px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Achille-Occhetto.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34564\" class=\"wp-image-34564\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Achille-Occhetto.jpg\" alt=\"\" width=\"240\" height=\"143\" \/><\/a><p id=\"caption-attachment-34564\" class=\"wp-caption-text\">Achille Occhetto<\/p><\/div>\n<p style=\"text-align: justify;\">Sarebbe per\u00f2 inesatto dire che questa previsione pessimistica, che corrisponde sostanzialmente alla descrizione di quella che sarebbe la situazione del mondo unificato dopo la vittoria del neocapitalismo e la riconciliazione con esso del comunismo, sia l\u2019unica possibile.<\/p>\n<p style=\"text-align: justify;\">Davanti all\u2019evidenza della sconfitta, pu\u00f2 darsi che una parte autorevole del pensiero comunista sia portata ad una rifondazione della critica dello spirito neoborghese, nella sua evoluzione recente: e in ci\u00f2 al riconoscimento che la sola forza esistente capace di opporvisi sia il pensiero cattolico; e che questo comporti un radicale mutamento di rapporti tra cattolicesimo e comunismo.<\/p>\n<p style=\"text-align: justify;\">Il dire questo non significa proposta di una ripresa del cattocomunismo; esso era un movimento che dal cattolicesimo procedeva verso il comunismo, in cui, per quel che riguarda la maggior parte dei suoi aderenti si risolse; il processo di oggi ne rappresenterebbe l\u2019inverso.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7364\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\" alt=\"\" width=\"175\" height=\"200\" \/><\/a><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=42940\" target=\"_blank\" rel=\"noopener noreferrer\">Nell\u2019eccellente articolo che apparve su queste colonne<\/a> il 21 ottobre Massimo Borghesi ha documentato il passaggio nella pubblicistica laica, dopo una critica dura e aspra, a un idealizzamento della figura di Giovanni Paolo II, separato da tutti i movimenti cattolici e sovrapposto a essi.<\/p>\n<p style=\"text-align: justify;\">Che per la maggior parte dei suoi operatori si tratti di una manovra politica diretta a distaccarlo, nell\u2019opinione corrente, da Cl, dal cardinale Ratzinger, eccetera, \u00e8 ben certo. In linea di principio tuttavia questo riconoscimento dell\u2019universalit\u00e0 dell\u2019insegnamento di Giovanni Paolo II, oltre le parti che oggi prevalgono, potrebbe essere elemento condizionante anche di un\u2019autocritica comunista, e sarei portato a leggere un invito a un serio dialogo in alcuni articoli apparsi in tale direzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Sabato n.49 \u2013 9 Dicembre 1989\u00a0 1989, crolla il comunismo? Augusto Del Noce ha qualche dubbio. Dalle macerie sta nascendo una nuova egemonia sovietica. di Augusto del Noce<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":42897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66,32,82,84],"tags":[1695,139,424,175],"class_list":["post-42896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adel-noce-scritti","category-filosofia-del-comunismo","category-comunismo-in-italia","category-urss","tag-augusto-del-noce","tag-comunismo","tag-comunismo-in-italia-2","tag-urss-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-23T22:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-02T08:13:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L\u2019Impero \u00e8 sacro\",\"datePublished\":\"2017-04-23T22:00:18+00:00\",\"dateModified\":\"2019-05-02T08:13:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/\"},\"wordCount\":1392,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/GiovanniPaoloII_Gorbaciov.jpg\",\"keywords\":[\"Augusto Del Noce\",\"comunismo\",\"comunismo in Italia\",\"Urss\"],\"articleSection\":[\"A.Del Noce - scritti\",\"Comunismo\",\"Comunismo in Italia\",\"URSS\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/\",\"name\":\"L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/GiovanniPaoloII_Gorbaciov.jpg\",\"datePublished\":\"2017-04-23T22:00:18+00:00\",\"dateModified\":\"2019-05-02T08:13:02+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/GiovanniPaoloII_Gorbaciov.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/GiovanniPaoloII_Gorbaciov.jpg\",\"width\":1280,\"height\":870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limpero-e-sacro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Impero \u00e8 sacro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-04-23T22:00:18+00:00","article_modified_time":"2019-05-02T08:13:02+00:00","og_image":[{"width":1280,"height":870,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L\u2019Impero \u00e8 sacro","datePublished":"2017-04-23T22:00:18+00:00","dateModified":"2019-05-02T08:13:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/"},"wordCount":1392,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg","keywords":["Augusto Del Noce","comunismo","comunismo in Italia","Urss"],"articleSection":["A.Del Noce - scritti","Comunismo","Comunismo in Italia","URSS"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/","name":"L\u2019Impero \u00e8 sacro - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg","datePublished":"2017-04-23T22:00:18+00:00","dateModified":"2019-05-02T08:13:02+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/GiovanniPaoloII_Gorbaciov.jpg","width":1280,"height":870},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpero-e-sacro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L\u2019Impero \u00e8 sacro"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=42896"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42896\/revisions"}],"predecessor-version":[{"id":42944,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42896\/revisions\/42944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/42897"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=42896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=42896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=42896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}