{"id":4279,"date":"2010-12-09T00:00:00","date_gmt":"2010-12-08T23:00:00","guid":{"rendered":""},"modified":"2016-06-21T16:39:31","modified_gmt":"2016-06-21T14:39:31","slug":"i-cattolici-e-le-nuove-ideologie","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/","title":{"rendered":"I cattolici e le nuove ideologie"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35228\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg\" alt=\"ideologie\" width=\"250\" height=\"187\" \/>Ag Zenit<\/strong>(ZENIT.org)<\/div>\n<div style=\"text-align: center;\">gioved\u00ec\u00a025 novembre 2010<\/div>\n<p style=\"text-align: center;\">di mons. <strong>Giampaolo Crepaldi<\/strong><\/p>\n<p style=\"text-align: justify;\">(<em>Arcivescovo di Trieste, Presidente della Commissione \u201cCaritas in veritate\u201d del Consiglio delle Conferenze Episcopali d&#8217;Europa [CCEE] e Presidente dell\u2019Osservatorio Internazionale \u201cCardinale Van Thuan\u201d sulla Dottrina Sociale della Chiesa<\/em>)<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">ROMA, La ragione politica oggi tende ad esser debole in quanto viene tallonata dal relativismo, che la rende spesso incapace di esaminare razionalmente i valori morali e i disvalori e di valutare l\u2019utilit\u00e0 delle varie religioni per la costruzione del bene comune. Questa debolezza rende la ragione politica maggiormente disponibile alle sirene delle nuove ideologie.<\/p>\n<p style=\"text-align: justify;\">Dopo il crollo delle grandi ideologie ottocentesche e novecentesche, fatto che si fa simbolicamente risalire al crollo del muro di Berlino nel 1989, le ideologie non sono sparite dalla scena politica. Ne sono infatti nate molte altre ed una soprattutto: il riduzionismo. Il riduzionismo \u00e8 la principale ideologia di oggi. Mentre le ideologie di un tempo erano integrali (e integraliste), ossia proponevano una visione completa ed onnicomprensiva della realt\u00e0, l\u2019ideologia oggi prevalente \u00e8 esattamente l\u2019opposto: spezzetta la realt\u00e0 in ambiti non misurabili reciprocamente. Cos\u00ec, con la scusa di liberarsi dalle ideologie ne crea un\u2019altra, altrettanto omnicomprensiva, se pure per difetto piuttosto che per eccesso.<\/p>\n<p style=\"text-align: justify;\">Il riduzionismo \u00e8 ampiamente diffuso in tutti gli ambiti. La persona viene ridotta ai suoi geni o ai suoi neuroni, l\u2019amore \u00e8 ridotto a chimica, la famiglia viene ridotta ad un accordo, i diritti vengono ridotti a desideri, la democrazia viene ridotta a procedura, la religione viene ridotta a mito, la procreazione viene ridotta a produzione in laboratorio, il sapere viene ridotto a scienza e la scienza viene ridotta ad esperimento, i valori morali vengono ridotti a scelte, le culture vengono ridotte ad opinioni, la verit\u00e0 \u00e8 ridotta a sensazione, la veracit\u00e0 viene ridotta ad autenticit\u00e0, ossia a coerenza con la propria autoaffermazione.<\/p>\n<p style=\"text-align: justify;\">L\u2019insinuarsi dell\u2019ideologia nelle questioni che riguardano l\u2019uomo e il suo vero bene provoca una certa difficolt\u00e0 a cogliere i problemi nella loro globalit\u00e0. L\u2019ideologia, infatti, si nutre di riduzionismo. Essa \u00e8 una posizione particolare che pretende di valere per l\u2019intero. Non ogni riduzione diventa ideologia, ma solo quella che nasconde questa riduzione e pretende di parlare ancora per il tutto. L\u2019ideologia, cos\u00ec, finisce per inquinare il quadro del sapere e per sgretolare \u00abla coesione interiore del cosmo della ragione\u00bb (Benedetto XVI).<\/p>\n<p style=\"text-align: justify;\">Questo vale anche per la ragione politica. Se la scienza neonatale ci dice che un bambino nato prematuro alla 22ma settimana pu\u00f2 essere salvato, risulta difficile motivare perch\u00e9 si possa continuare a permettere l\u2019aborto legale fino alla 24ma settimana.Se la scienza ci dice che non si possono adoperare cellule staminali embrionali per la ricostruzione di tessuti malati perch\u00e9 esprimono alte possibilit\u00e0 cancerogene e se la stessa scienza ci dice che c\u2019\u00e8 la possibilit\u00e0 di adoperare per fini terapeutici le cellule staminali adulte, le quali possono essere fatte regredire allo stadio delle embrionali con tutte le conseguenti potenzialit\u00e0 positive ma senza rischio, diventa molto difficile spiegare perch\u00e9 le legislazioni di molti stati continuino a finanziare la ricerca scientifica tramite le staminali embrionali rifiutando di applicare perfino quel principio di precauzione che in altri contesti \u00e8 proposto come un imperativo categorico.<\/p>\n<p style=\"text-align: justify;\">In questo caso, se la maggioranza degli scienziati si dice favorevole, non pu\u00f2 essere per motivi scientifici, ma semmai per una specie di \u201cfede\u201d in una generica libert\u00e0 di ricerca scientifica che presenta molti sintomi dell\u2019ideologia.<\/p>\n<p style=\"text-align: justify;\">L\u2019allargamento della ragione, per\u00f2, non pu\u00f2 essere frutto della sola ragione, in quanto nessuno si d\u00e0 ci\u00f2 che non ha. La <em>Deus caritas est<\/em> assegna alla fede questo compito e la <em>Spe salvi<\/em> lo attribuisce alla speranza. In quest\u2019ultima enciclica, Benedetto XVI parla infatti dell\u2019allargamento \u201cdel cuore\u201d oltre che della ragione.<\/p>\n<p style=\"text-align: justify;\">Riferendosi a Sant\u2019Agostino, il papa dice che \u00abL\u2019uomo \u00e8 stato creato per una realt\u00e0 grande [\u2026] ma il suo cuore \u00e8 troppo stretto per la grande realt\u00e0 che gli \u00e8 assegnata. deve essere allargato [\u2026], allargato e poi ripulito\u00bb. Per questo la ragione politica ha bisogno anche della fede cristiana, perch\u00e9 per purificarsi essa ha bisogno anche del cuore. E mentre la ragione \u00e8 tutto sommato una caratteristica universale, il cuore \u00e8 una caratteristica personale.<\/p>\n<p style=\"text-align: justify;\">La politica ha bisogno di uomini di fede, di credenti impegnati in essa, affinch\u00e9 la stessa ragione politica possa ampliarsi verso quanto attende l\u2019uomo nella sua totalit\u00e0 e trascendenza. Le ideologie di oggi sono per esempio l\u2019ecologismo, il vitalismo, lo scientismo, il materialismo, lo psicologismo, lo sviluppismo, il terzomondismo, il pauperismo, l\u2019ideologia del gender, l\u2019ideologia della diversit\u00e0, quella della tolleranza, l\u2019economicismo, l\u2019ideologia dell\u2019homo oeconomicus, l\u2019inclusivismo, il narcisismo.<\/p>\n<p style=\"text-align: justify;\">L\u2019<strong>ecologismo<\/strong> \u00e8 l\u2019esaltazione della natura in quanto tale fino a proclamarne la superiorit\u00e0 rispetto alla stessa persona vista come elemento di disturbo per l\u2019ecologia naturale. L\u2019ecologismo spesso insegue una salvezza intesa come benessere ed equilibrio psicofisico con il pericolo di confondere la preghiera con il training autogeno. Il vitalismo tende a considerare tutte le forme di vita come aventi la stessa dignit\u00e0 fino a mettere in dubbio la superiorit\u00e0 dell\u2019uomo rispetto agli altri esseri viventi e parlare, per esempio, di diritti della natura, diritti degli animali o diritti delle piante.<\/p>\n<p style=\"text-align: justify;\">Lo <strong>scientismo<\/strong> \u00e8 l\u2019esaltazione della scienza come unica forma di sapere e perfino di salvezza dell\u2019umanit\u00e0. Esso va di pari passo con il materialismo in quanto la scienza, si dice, constata semplicemente dei fatti e li misura, quindi tutto \u00e8 fattuale e misurabile. Il <strong>materialismo<\/strong> significa che tutto \u00e8 fatto di materia e che lo spirito non esiste, sicch\u00e9 la vita umana, anche nelle sue manifestazioni pi\u00f9 alte come quella religiosa o etica o artistica, sarebbe frutto o dei geni o dei neuroni. C\u2019\u00e8 oggi un forte <strong>riduzionismo<\/strong> antropologico che riduce appunto la persona umana ai suoi geni o ai suoi neuroni e perfino l\u2019amore non sarebbe che chimica.<\/p>\n<p style=\"text-align: justify;\">Una forma sottile di materialismo antropologico \u00e8 lo <strong>psicologismo<\/strong>, cui accenna anche la <em>Caritas in veritate<\/em>: tutti i problemi interiori della persona sono ridotti a problemi psicologici e la prima cosa che si fa \u00e8 andare dallo psicologo. Ma ci sono i problemi morali e spirituali che non possono essere ridotti a quelli psicologici. Il confessore non \u00e8 un analista, un pap\u00e0 e una mamma non possono esimersi dall\u2019educare al bene morale i loro figli delegando la questione agli esperti psicologi.<\/p>\n<p style=\"text-align: justify;\">Il materialismo \u00e8 evidente anche nello <strong>sviluppismo,<\/strong> ossia nel considerare i problemi dello sviluppo solo come problemi materiali senza contare i fattori culturali, religiosi o spirituali. Per contro c\u2019\u00e8 anche l\u2019ideologia della decrescita o del dopo-sviluppo che nega valore allo sviluppo e manifesta una visione pessimistica dell\u2019uomo. Il <strong>pauperismo<\/strong> \u00e8 invece l\u2019ideologia secondo cui per stare tutti meglio e perch\u00e9 ci sia maggiore giustizia bisognerebbe essere tutti pi\u00f9 poveri e dividere in parti uguali la torta della ricchezza. Il pauperismo \u00e8 spesso sposato con il terzomondismo, ossia con il dare tutte le colpe del sottosviluppo ai paesi sviluppati, semplificando il quadro delle responsabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019ideologia del <strong>gender<\/strong> significa pensare che le identit\u00e0 sessuali siano costruzioni culturali e scelte di percorsi di vita, anzich\u00e9 una vocazione contenuta nella nostra natura di persone sessuate. La ripercussione di questa ideologia sull\u2019educazione alla famiglia, alla procreazione e alla filiazione sono molto negative. Tra l\u2019altro comportano la perdita pressoch\u00e9 totale della dimensione sociale della sessualit\u00e0 e l\u2019idea che all\u2019origine della societ\u00e0 non stiano due individui asessuati ma un uomo e una donna nella loro complementariet\u00e0 sessuale.<\/p>\n<p style=\"text-align: justify;\">L\u2019i<strong>deologia della diversit\u00e0<\/strong> consiste nell\u2019assolutizzare la diversit\u00e0 come tale, indipendentemente dalla verit\u00e0 della diversit\u00e0. Le diversit\u00e0 sono una ricchezza, ma quando rimangono dentro un quadro vero di umanit\u00e0 e rappresentano molte strade per esprimere la comune natura umana. Le diversit\u00e0 in quanto tali non sono n\u00e9 vere n\u00e9 false, n\u00e9 buone n\u00e9 cattive e la convivenza non \u00e8 un accostamento indifferente di tutte le diversit\u00e0, nessuna esclusa, ma una loro integrazione a servizio della comune umanit\u00e0, il che richiede il superamento della ideologia della tolleranza, dato che ci sono anche cose che non vanno tollerate.<\/p>\n<p style=\"text-align: justify;\">L\u2019ideologia dell\u2019homo oeconomicus e dell\u2019<strong>economicismo<\/strong> sostiene che tutto quanto l\u2019uomo fa avviene in vista di un interesse materiale e che l\u2019economia, come sistema del perseguimento del proprio self-interest, sia la vera molla della storia. Vengono cos\u00ec negate tutte le relazioni disinteressate e perfino il valore economico della gratuit\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019i<strong>nclusivimo <\/strong>\u00e8 l\u2019ideologia che confonde il legittimo conferimento di diritti al riconoscimento automatico dei desideri come se fossero diritti. Includere \u00e8 molto importante, perch\u00e9 l\u2019esclusione significa non riconoscere a qualcuno dei diritti collegati con la sua dignit\u00e0 di persona. Non pu\u00f2 voler dire per\u00f2 includere ogni desiderio, anche i pi\u00f9 narcisistici, egoistici, eccentrici, individualistici, voluttuari dentro un sistema di cittadinanza. Non ho dato che pochi cenni per ognuna delle ideologie elencate, mentre se ne potrebbero indicare anche delle altre.<\/p>\n<p style=\"text-align: justify;\">Il cattolico impegnato in politica dovrebbe fare attenzione agli agguati di queste ideologie, che sono oggi molto insidiosi. Egli dovrebbe essere guidato da un sano realismo, vorrei dire da un realismo cristiano. La verit\u00e0 \u00e8 la realt\u00e0. Il bene non \u00e8 altro che la realt\u00e0 in quanto \u00e8 desiderabile.Il cattolico si attenga a questa realt\u00e0 e vedr\u00e0 che spesso le cose non sono come le ideologie le presentano. Mantenga una libert\u00e0 di giudizio, promuova approcci alternativi, ed oggi il realismo cattolico \u00e8 l\u2019approccio ai problemi pi\u00f9 alternativo che esista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag Zenit(ZENIT.org) gioved\u00ec\u00a025 novembre 2010 di mons. Giampaolo Crepaldi (Arcivescovo di Trieste, Presidente della Commissione \u201cCaritas in veritate\u201d del Consiglio delle Conferenze Episcopali d&#8217;Europa [CCEE] e Presidente dell\u2019Osservatorio Internazionale \u201cCardinale Van Thuan\u201d sulla Dottrina Sociale della Chiesa)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35228,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,53],"tags":[926,478],"class_list":["post-4279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrina-sociale","category-politica","tag-ideologie","tag-relativismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I cattolici e le nuove ideologie - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I cattolici e le nuove ideologie - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-08T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-21T14:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I cattolici e le nuove ideologie\",\"datePublished\":\"2010-12-08T23:00:00+00:00\",\"dateModified\":\"2016-06-21T14:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/\"},\"wordCount\":1552,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/ideologie.jpg\",\"keywords\":[\"ideologie\",\"relativismo\"],\"articleSection\":[\"Dottrina sociale\",\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/\",\"name\":\"I cattolici e le nuove ideologie - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/ideologie.jpg\",\"datePublished\":\"2010-12-08T23:00:00+00:00\",\"dateModified\":\"2016-06-21T14:39:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/ideologie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/ideologie.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cattolici-e-le-nuove-ideologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I cattolici e le nuove ideologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I cattolici e le nuove ideologie - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/","og_locale":"it_IT","og_type":"article","og_title":"I cattolici e le nuove ideologie - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-12-08T23:00:00+00:00","article_modified_time":"2016-06-21T14:39:31+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I cattolici e le nuove ideologie","datePublished":"2010-12-08T23:00:00+00:00","dateModified":"2016-06-21T14:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/"},"wordCount":1552,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg","keywords":["ideologie","relativismo"],"articleSection":["Dottrina sociale","Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/","name":"I cattolici e le nuove ideologie - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg","datePublished":"2010-12-08T23:00:00+00:00","dateModified":"2016-06-21T14:39:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/ideologie.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cattolici-e-le-nuove-ideologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I cattolici e le nuove ideologie"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4279"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4279\/revisions"}],"predecessor-version":[{"id":35229,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4279\/revisions\/35229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35228"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}