{"id":4275,"date":"2010-12-09T00:00:00","date_gmt":"2010-12-08T23:00:00","guid":{"rendered":""},"modified":"2015-03-19T11:07:52","modified_gmt":"2015-03-19T10:07:52","slug":"comunicare-la-salute","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/","title":{"rendered":"Comunicare la salute"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21751\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg\" alt=\"comunicazione_salute_cover\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg 228w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Il Corriere del Sud<\/strong>, n.13, 30 ottobre 2010<\/div>\n<p style=\"text-align: center;\">di<strong> Andrea Bartelloni<\/strong><\/p>\n<p style=\"text-align: justify;\">Comunicare la salute, ma forse sarebbe stato meglio parlare di comunicazione della malattia, infatti \u00e8 questo il tema conduttore del ponderoso manuale edito da Raffaello Cortina e curato dalla Fondazione Zo\u00e9 (Zambon Open Educational, <a href=\"http:\/\/www.fondazionezoe.it\/\" target=\"_blank\">www.fondazionezoe.it<\/a>) che grazie alla collaborazione di numerosi specialisti e operatori del mondo sanitario affronta i molteplici aspetti di questo delicato problema.<\/p>\n<p style=\"text-align: justify;\"><!--more-->Articolato in nove sezioni, raccoglie i contributi di medici, psicologi, sociologi, esperti di etica e di diritto ed \u00e8 indirizzato a quanti sono coinvolti nella comunicazione tra medico e paziente.<\/p>\n<p style=\"text-align: justify;\">Ottantadue interventi racchiusi tra due importanti parentesi che danno un senso compiuto all\u2019opera: la prima parentesi \u00e8 la sezione che tratta di etica e antropologia, principio e fondamento di ogni corretta impostazione nei rapporti umani, e l\u2019altra, la postfazione, uno sguardo al futuro che parla di un qualche cosa di molto probabile, anzi di quasi attuale.<\/p>\n<p style=\"text-align: justify;\">Partirei proprio da qui perch\u00e9 la prospettiva descritta da Domenico De Masi, docente di sociologia alla Sapienza di Roma, \u00e8 per certi aspetti inquietante. Dopo aver descritto lo sviluppo della societ\u00e0 umana nei suoi molteplici aspetti, arriva a concludere che, nell\u2019odierna societ\u00e0 della comunicazione, quest\u2019ultima \u201cesce dal mondo del pressappoco per entrare nell\u2019universo della precisione scientifica\u201d. Su questo si innesca la medicalizzazione totale dell\u2019uomo di oggi che pretende di curare tutti e tutto da prima della nascita all\u2019ultimo respiro (allontanandolo il pi\u00f9 possibile o interrompendolo). Il mito dell\u2019efficienza e la sempre pi\u00f9 lunga aspettativa di vita rivoluzionano i nostri rapporti col corpo, la salute e la malattia, il tempo libero, la famiglia e cos\u00ec via.<\/p>\n<p style=\"text-align: justify;\">Ma che futuro ci aspetta? Non sar\u00e0 probabilmente <em>Il mondo nuovo<\/em> di Aldous Huxley, anche perch\u00e9 molti degli aspetti descritti sono gi\u00e0 realt\u00e0 anche se non diffusi a livello globale: \u201cMolte donne avranno un figlio senza avere un marito\u201d; valori come l\u2019estetica, la soggettivit\u00e0, l\u2019emotivit\u00e0 e la flessibilit\u00e0 \u201cavranno colonizzato anche gli uomini\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cNegli stili di vita prevarr\u00e0 l\u2019androginia\u201d. Il lavoro sar\u00e0 completamente terziarizzato e si tender\u00e0 a raggiungere una massima affidabilit\u00e0 ed efficienza nelle prestazioni. Dato che le persone saranno sempre pi\u00f9 convinte che, vivendo una sola volta occorra vivere bene, molte professioni si dedicheranno al benessere e alla qualit\u00e0 della vita. \u201cLa comunicazione relativa alla salute e alla malattia, alla bellezza del corpo e all\u2019equilibrio della mente occuper\u00e0 il primo posto nel sistema comunicativo globale\u201d.<\/p>\n<p style=\"text-align: justify;\">Ma questo mondo futuro, che per certi aspetti si \u00e8 gi\u00e0 realizzato, \u00e8 il miglior futuro possibile? Quale uomo \u00e8 destinato a questo futuro, e chi \u00e8 l\u2019uomo?<\/p>\n<p style=\"text-align: justify;\">A questa domanda si dedica la prima sezione di etica e bioetica che in apertura del manuale d\u00e0 le categorie interpretative dalle quali scaturisce tutto il discorso che seguir\u00e0.<\/p>\n<p style=\"text-align: justify;\">E allora viene fuori l\u2019uomo come composto di anima e di corpo, la nozione di persona con la sua componente materiale e spirituale, fondamentale perch\u00e9 il paziente torni ad essere un \u201cchi\u201d e non un \u201cche cosa\u201d. E la diagnosi di una malattia diventa un processo delicato e difficile dal punto di vista etico e \u201cdel rapporto interumano tra medico e paziente\u201d che si amplifica quando la diagnosi ha un impatto sociale o riguarda una persona non ancora nata, come per la diagnosi con i test genetici che, a volte non sono indicatori certi di una malattia, ma indicano solo una predisposizione. In questi casi l\u2019informazione potrebbe essere anche un danno.<\/p>\n<p style=\"text-align: justify;\">E ritorniamo al fondamentale concetto di persona umana che deve tornare al centro della medicina e solo cos\u00ec si potr\u00e0 cercare di risolvere la crisi del rapporto medico-paziente nata, forse, dall\u2019eccessiva attenzione alla malattia dimenticandosi dell\u2019uomo malato nella sua interezza.<\/p>\n<p style=\"text-align: justify;\">In mezzo a queste due parentesi si snodano tutti gli interventi sulla comunicazione della salute: nei media, da parte delle istituzioni e tra medico e paziente. Qui si parla di tecnologia, di aspettative da parte dei pazienti e dei medici, di conflitti, fino ad analizzare le tecniche comunicative con i vari strumenti che le moderne tecnologie ci offrono. Le ultime sezioni sono dedicate ai farmaci e a come l\u2019informazione medico-scientifica viene veicolata dai media, dal teatro e dal cinema.<\/p>\n<p style=\"text-align: justify;\">Un manuale che non dovrebbe mancare nella biblioteca di ogni medico che offre molti spunti di riflessione e di discussione, con un impianto molto ben articolato e molto utile in un mondo dove la salute da \u201cvalore\u201d \u00e8 diventata un \u201cbisogno\u201d, quasi un diritto costituzionale, che genera un\u2019 \u201cipercriticit\u00e0 verso istituzioni, professionisti\u201d che \u201cdevono\u201d garantire salute, benessere, forma, bellezza, acuit\u00e0 mentale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Corriere del Sud, n.13, 30 ottobre 2010 di Andrea Bartelloni Comunicare la salute, ma forse sarebbe stato meglio parlare di comunicazione della malattia, infatti \u00e8 questo il tema conduttore del ponderoso manuale edito da Raffaello Cortina e curato dalla Fondazione Zo\u00e9 (Zambon Open Educational, www.fondazionezoe.it) che grazie alla collaborazione di numerosi specialisti e operatori &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":21751,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[242],"class_list":["post-4275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri","tag-sanita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicare la salute - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicare la salute - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-08T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-19T10:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"228\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Comunicare la salute\",\"datePublished\":\"2010-12-08T23:00:00+00:00\",\"dateModified\":\"2015-03-19T10:07:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/\"},\"wordCount\":754,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/comunicazione_salute_cover.jpg\",\"keywords\":[\"sanit\u00e0\"],\"articleSection\":[\"Libri\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/\",\"name\":\"Comunicare la salute - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/comunicazione_salute_cover.jpg\",\"datePublished\":\"2010-12-08T23:00:00+00:00\",\"dateModified\":\"2015-03-19T10:07:52+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/comunicazione_salute_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/comunicazione_salute_cover.jpg\",\"width\":228,\"height\":228},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/comunicare-la-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicare la salute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicare la salute - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicare la salute - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-12-08T23:00:00+00:00","article_modified_time":"2015-03-19T10:07:52+00:00","og_image":[{"width":228,"height":228,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Comunicare la salute","datePublished":"2010-12-08T23:00:00+00:00","dateModified":"2015-03-19T10:07:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/"},"wordCount":754,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg","keywords":["sanit\u00e0"],"articleSection":["Libri"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/","name":"Comunicare la salute - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg","datePublished":"2010-12-08T23:00:00+00:00","dateModified":"2015-03-19T10:07:52+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/12\/comunicazione_salute_cover.jpg","width":228,"height":228},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/comunicare-la-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Comunicare la salute"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4275"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4275\/revisions"}],"predecessor-version":[{"id":21752,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4275\/revisions\/21752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/21751"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}