{"id":4228,"date":"2010-11-22T09:26:23","date_gmt":"2010-11-22T08:26:23","guid":{"rendered":""},"modified":"2016-01-04T18:25:21","modified_gmt":"2016-01-04T17:25:21","slug":"papa-il-preservativo-e-gli-imbecilli","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/","title":{"rendered":"Papa, il preservativo e gli imbecilli"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29198\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg\" alt=\"condom\" width=\"250\" height=\"161\" \/><\/a>dal sito Facebook di <strong>Alleanza Cattolica<\/strong> 22 novembre 2010<\/div>\n<p style=\"text-align: center;\">di<strong> Massimo Introvigne<\/strong><\/p>\n<p style=\"text-align: justify;\">In settimana, quando esce il libro-intervista del Papa, ne parleremo come merita. Oggi invece parliamo di imbecilli. Dalle associazioni gay a qualche cosiddetto tradizionalista, tutti a dire che il Papa ha cambiato la tradizionale dottrina cattolica sugli anticoncezionali.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Titoli a nove colonne sulle prime pagine. Esultanza dell\u2019ONU. Commentatori che ci spiegano come il Papa abbia ammesso che \u00e8 meglio che le prostitute si proteggano con il preservativo da gravidanze indesiderate: e per\u00f2, se si comincia con le prostitute, come non estendere il principio ad altre donne povere e non in grado di allevare figli, e poi via via a tutti?<\/div>\n<p style=\"text-align: justify;\">Peccato, per\u00f2, che \u2013 come spesso capita \u2013 i commentatori si siano lasciati andare a commentare sulla base di lanci d\u2019agenzia, senza leggere la pagina integrale sul tema dell\u2019intervista di Benedetto XVI, che pure fa parte delle anticipazioni trasmesse ai giornalisti. Il Papa, in tema di lotta all\u2019AIDS, \u00a0afferma che la \u00abfissazione assoluta sul preservativo implica una banalizzazione della sessualit\u00e0\u00bb, e che \u00abla lotta contro la banalizzazione della sessualit\u00e0 \u00e8 anche parte della lotta per garantire che la sessualit\u00e0 sia considerata come un valore positivo\u00bb.<\/p>\n<p style=\"text-align: justify;\">Nel paragrafo successivo \u2013 traducendo correttamente dall\u2019originale tedesco \u2013 Benedetto XVI continua: \u00abCi pu\u00f2 essere un fondamento nel caso di alcuni individui, come quando un prostituto usi il preservativo (wenn etwa ein Prostituierter ein Kondom verwendet), e questo pu\u00f2 essere un primo passo nella direzione di una moralizzazione, una prima assunzione di responsabilit\u00e0, sulla strada del recupero della consapevolezza che non tutto \u00e8 consentito e che non si pu\u00f2 fare ci\u00f2 che si vuole. Ma non \u00e8 davvero il modo di affrontare il male dell&#8217;infezione da HIV. Questo pu\u00f2 basarsi solo su di una umanizzazione della sessualit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Non so se il testo italiano che uscir\u00e0 tradurr\u00e0 correttamente \u00abun prostituto\u00bb, come da originale tedesco, o riporter\u00e0 \u2013 come in alcune anticipazioni giornalistiche italiane &#8211; \u00abuna prostituta\u00bb. \u00abProstituto\u00bb, al maschile, \u00e8 cattivo italiano ma \u00e8 l\u2019unica tradizione di \u00abProstituierter\u00bb, e se si mette la parola al femminile l\u2019intera frase del Papa non ha pi\u00f9 senso. Infatti le prostitute donne ovviamente non \u00abusano\u00bb il preservativo: al massimo lo fanno usare ai loro clienti.<\/p>\n<p style=\"text-align: justify;\">Il Papa ha in mente proprio la prostituzione maschile, dove spesso \u2013 come riporta la letteratura scientifica in materia \u2013 i clienti insistono perch\u00e9 i \u00abprostituti\u00bb non usino il preservativo, e dove molti \u00abprostituti\u00bb &#8211; clamoroso il caso di Haiti, a lungo un paradiso del turismo omosessuale \u2013 soffrono di AIDS e infettano centinaia di clienti, molti dei quali muoiono.\u00a0 Qualcuno potrebbe dire che \u00abprostituto\u00bb si applica anche al gigol\u00f2 eterosessuale che si accompagna a pagamento con donne: ma l\u2019argomento sarebbe capzioso perch\u00e9 \u00e8 tra i \u00abprostituti\u00bb omosessuali che l\u2019AIDS \u00e8 notoriamente epidemico.<\/p>\n<p style=\"text-align: justify;\">Stabilito dunque che le gravidanze non c\u2019entrano, perch\u00e9 dalla prostituzione omosessuale \u00e8 un po\u2019 difficile che nascano bambini, il Papa non dice nulla di rivoluzionario. Un \u00abprostituto\u00bb che ha un rapporto mercenario con un omosessuale \u2013 per la verit\u00e0, chiunque abbia un rapporto sessuale con una persona dello stesso sesso \u2013 commette dal punto di vista cattolico un peccato mortale. Se per\u00f2, consapevole di avere l\u2019AIDS, infetta il suo cliente sapendo d\u2019infettarlo, oltre al peccato mortale contro il sesto comandamento ne commette anche uno contro il quinto, perch\u00e9 si tratta di omicidio, almeno tentato.<\/p>\n<p style=\"text-align: justify;\">Commettere un peccato mortale o due non \u00e8 la stessa cosa, e anche nei peccati mortali. c\u2019\u00e8 una gradazione. L\u2019immoralit\u00e0 \u00e8 un peccato grave, ma l\u2019immoralit\u00e0 unita all\u2019omicidio lo \u00e8 di pi\u00f9.<\/p>\n<p style=\"text-align: justify;\">Un \u00abprostituto\u00bb omosessuale affetto da AIDS che infetta sistematicamente i suoi clienti \u00e8 un peccatore insieme immorale e omicida. Se colto da scrupoli decide di fare quello che \u2013 a torto o a ragione (il problema dell\u2019efficacia del preservativo nel rapporto omosessuale non \u00e8 pi\u00f9 morale ma scientifico) \u2013 gli sembra possa ridurre il rischio di commettere un omicidio non \u00e8 improvvisamente diventato una brava persona, ma ha compiuto \u00abun primo passo\u00bb &#8211; certo insufficiente e parzialissimo \u2013 verso la resipicenza.<\/p>\n<p style=\"text-align: justify;\">Di Barbabl\u00f9 (Gilles de Rais, 1404-1440) si dice che attirasse i bambini, avesse rapporti sessuali con loro e poi li uccidesse. Se a un certo punto avesse deciso di continuare a fare brutte cose con i bambini ma poi, anzich\u00e9 ucciderli, li avesse lasciati andare, questo \u00abprimo passo\u00bb non sarebbe stato assolutamente sufficiente a farlo diventare una persona morale. Ma possiamo dire che sarebbe stato assolutamente irrilevante? Certamente i genitori di quei bambini avrebbero preferito riaverli indietro vivi.<\/p>\n<p style=\"text-align: justify;\">Dunque se un\u00a0 \u00abprostituto\u00bb assassino a un certo punto, restando \u00abprostituto\u00bb, decide di non essere pi\u00f9 assassino, \u00a0questo \u00abpu\u00f2 essere un primo passo\u00bb.\u00a0 \u00abMa \u2013 come dice il Papa &#8211; questo non \u00e8 davvero il modo di affrontare il male dell&#8217;infezione da HIV\u00bb. Bisognerebbe piuttosto smettere di fare i \u00abprostituti\u00bb, e di trovare clienti.<\/p>\n<p style=\"text-align: justify;\">Dove stanno la novit\u00e0 e lo scandalo se non nella malizia di qualche commentatore? Al proposito, vince il premio per il titolo pi\u00f9 imbecille il primo lancio della Associated Press, versione in lingua inglese (poi per fortuna corretto, ma lo trovate ancora indicizzato su Yahoo con questo titolo): \u00abIl Papa: la prostituzione maschile \u00e8 ammissibile, purch\u00e9 si usi il preservativo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>dal sito Facebook di Alleanza Cattolica 22 novembre 2010 di Massimo Introvigne In settimana, quando esce il libro-intervista del Papa, ne parleremo come merita. Oggi invece parliamo di imbecilli. Dalle associazioni gay a qualche cosiddetto tradizionalista, tutti a dire che il Papa ha cambiato la tradizionale dottrina cattolica sugli anticoncezionali.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,5],"tags":[2394,1876],"class_list":["post-4228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benedetto-xvi","category-chiesa","tag-aids","tag-anticoncezionali","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-22T08:26:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-04T17:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Papa, il preservativo e gli imbecilli\",\"datePublished\":\"2010-11-22T08:26:23+00:00\",\"dateModified\":\"2016-01-04T17:25:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/\"},\"wordCount\":850,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/condom.jpg\",\"keywords\":[\"Aids\",\"anticoncezionali\"],\"articleSection\":[\"Benedetto XVI\",\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/\",\"name\":\"Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/condom.jpg\",\"datePublished\":\"2010-11-22T08:26:23+00:00\",\"dateModified\":\"2016-01-04T17:25:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/condom.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/condom.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/papa-il-preservativo-e-gli-imbecilli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa, il preservativo e gli imbecilli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/","og_locale":"it_IT","og_type":"article","og_title":"Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-11-22T08:26:23+00:00","article_modified_time":"2016-01-04T17:25:21+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Papa, il preservativo e gli imbecilli","datePublished":"2010-11-22T08:26:23+00:00","dateModified":"2016-01-04T17:25:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/"},"wordCount":850,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg","keywords":["Aids","anticoncezionali"],"articleSection":["Benedetto XVI","Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/","name":"Papa, il preservativo e gli imbecilli - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg","datePublished":"2010-11-22T08:26:23+00:00","dateModified":"2016-01-04T17:25:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/11\/condom.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/papa-il-preservativo-e-gli-imbecilli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Papa, il preservativo e gli imbecilli"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4228"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4228\/revisions"}],"predecessor-version":[{"id":29199,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4228\/revisions\/29199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29198"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}