{"id":42241,"date":"2019-03-14T00:00:56","date_gmt":"2019-03-13T23:00:56","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=42241"},"modified":"2019-03-15T18:53:55","modified_gmt":"2019-03-15T17:53:55","slug":"il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/","title":{"rendered":"Il nome della rosa, ci risiamo con la leggenda nera"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome_rosa_Eco.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-42242\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome_rosa_Eco.png\" alt=\"\" width=\"143\" height=\"200\"><\/a>Da<strong> <a href=\"http:\/\/lanuovabq.it\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\">La Nuova Bussola quotidiana<\/a> <\/strong>11 Marzo 2019<\/p>\n<p style=\"text-align: justify;\"><em>Gi\u00e0 dalla prima scena si \u00e8 capito che la nuova versione-kolossal de Il nome della rosa,&nbsp;finanziata da RaiCinema, cio\u00e8 dal contribuente&nbsp;era anche peggio della precedente, il film di Jean-Jacques Annaud del 1986, tratto dal \u00abpalinsesto\u00bb di Umberto Eco. La storia della lotta per le investiture ci dice l&#8217;asatto opposto della nuova fiction.&nbsp;<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Rino Cammilleri<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 dalla prima scena si \u00e8 capito che la nuova versione-kolossal de <em>Il nome della rosa<\/em> (finanziata da RaiCinema, cio\u00e8 dal contribuente) era anche peggio della precedente, il film di Jean-Jacques Annaud del 1986, tratto dal \u00abpalinsesto\u00bb di Umberto Eco. Il quale, pretendendo questa aggiunta nei titoli, chiar\u00ec che il film non poteva rappresentare tutta la complessit\u00e0 del romanzo bestseller omonimo. La prima scena di cui dicevamo \u00e8 una scritta che avverte lo spettatore che nel 1327, anno in cui si svolge la vicenda, l\u2019imperatore Ludovico stava cercando di \u00abseparare la politica dalla religione\u00bb. Messa cos\u00ec, \u00e8 chiaro che la simpatia dello spettatore si orienter\u00e0 verso l\u2019imperatore, che la Chiesa vorrebbe sottomettere imponendo ai posteri uno stato teocratico di tipo, per intenderci, khomeinista.<\/p>\n<p style=\"text-align: justify;\"><strong>La storia, vera, dice per\u00f2 il contrario<\/strong>: tutta la lunga Lotta per le Investiture, dal secolo XI al Concordato di Worms del 1122, fu combattuta perch\u00e9 era l\u2019imperatore a voler mettere il cappello sulla Chiesa decidendo lui la nomina dei vescovi. L\u2019imperatore che regnava nel 1327, Ludovico IV il Bavaro, aveva deciso allora di tagliare del tutto i legami con la Chiesa. Infatti, fu il primo imperatore a farsi incoronare non dal papa, ma da un laico, quello Sciarra Colonna che aveva preso a schiaffi il papa Bonifacio VIII ad Anagni. Gesto che simbolicamente chiuse il Medioevo cristianissimo. Gesto la cui portata Bonifacio VIII comprese benissimo, tant\u2019\u00e8 che ne mor\u00ec di crepacuore.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/nome_rosa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7228\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/nome_rosa.jpg\" alt=\"\" width=\"139\" height=\"200\"><\/a>La Chiesa, come previsto, fin\u00ec alla merc\u00e9 del potere politico<\/strong>: nel 1327 il pontificato non era pi\u00f9 a Roma ma ad Avignone, deportato in Francia da Filippo il Bello, il distruttore dei templari. Il potere politico, privo della guida, e del freno, di un\u2019autorit\u00e0 morale, da allora divenne sempre pi\u00f9 assoluto, culminando nei totalitarismi del secolo XX.<\/p>\n<p style=\"text-align: justify;\"><strong>Il kolossal televisivo gi\u00e0 dalla prima puntata<\/strong> ci ha presentato un inquisitore veramente esistito, Bernardo Gui, come la quintessenza del fanatismo pi\u00f9 ottuso e ideologico, quasi che l\u2019Inquisizione fosse stata l\u2019antesignana della Gestapo, delle SS e del Kgb. Ora, poich\u00e9 nessuno storico da decenni si sente di sostenere una fesseria del genere, ecco che una fiction ricavata da un romanzo (fiction a sua volta) ripropone in tutto il suo squallore \u00abgotico\u00bb la leggenda nera sull\u2019Inquisizione e i \u00absecoli bui\u00bb, propalandola per il pianeta alle nuove generazioni (la fiction, infatti, \u00e8 stata acquistata da molti Paesi).<\/p>\n<p style=\"text-align: justify;\"><strong>Trent\u2019anni fa medievisti come Franco Cardini e Marco Tangheroni<\/strong> si spesero per ricordare che a) i monasteri medievali erano fari di cultura, non di ignoranza; b) essi sfamavano i dintorni, tant\u2019\u00e8 che \u00e8 rimasto il detto \u00abcosa passa il convento oggi?; c) le biblioteche monastiche non avevano affatto passaggi segreti o libri inaccessibili; d) il divieto di ridere lo immaginava Eco, laddove i monaci copiarono e tramandarono anche opere pagane licenziose come quelle di Ovidio; e) Bernardo Gui fu un mite inquisitore e un fine intellettuale, stimato come il maggiore storico del suo tempo; f) non si potevano accendere roghi su due piedi, la procedura era complessa e garantista; g) i dolciniani, per realizzare il loro comunismo utopico, saccheggiavano e uccidevano. Ancora: il papa Giovanni XXII mai si sogn\u00f2 di abolire i francescani, ma disputava con gli eretici \u00abfraticelli\u00bb&nbsp;francescani che intendevano instaurare la povert\u00e0 assoluta; e i termini della questione sfociavano nell\u2019eresia dell\u2019abolizione, di principio, della propriet\u00e0 privata. Eccetera.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma la potenza delle immagini<\/strong>, in prima serata e a puntate, \u00e8 praticamente invincibile. La generazione dei Tangheroni, ma anche dei Messori e, ma s\u00ec, dei Cammilleri, ha gi\u00e0 dato. Tocca adesso alle nuove leve, se ci sono, ricominciare, con pazienza, di nuovo tutto da capo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da La Nuova Bussola quotidiana 11 Marzo 2019 Gi\u00e0 dalla prima scena si \u00e8 capito che la nuova versione-kolossal de Il nome della rosa,&nbsp;finanziata da RaiCinema, cio\u00e8 dal contribuente&nbsp;era anche peggio della precedente, il film di Jean-Jacques Annaud del 1986, tratto dal \u00abpalinsesto\u00bb di Umberto Eco. La storia della lotta per le investiture ci dice &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":42344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122,91,24],"tags":[1136],"class_list":["post-42241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al-cinema","category-medioevo","category-storia","tag-storia-della-chiesa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-13T23:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-15T17:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il nome della rosa, ci risiamo con la leggenda nera\",\"datePublished\":\"2019-03-13T23:00:56+00:00\",\"dateModified\":\"2019-03-15T17:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/nome-della-rosa.jpg\",\"keywords\":[\"storia della chiesa\"],\"articleSection\":[\"Al cinema\",\"Medioevo\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/\",\"name\":\"Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/nome-della-rosa.jpg\",\"datePublished\":\"2019-03-13T23:00:56+00:00\",\"dateModified\":\"2019-03-15T17:53:55+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/nome-della-rosa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/nome-della-rosa.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il nome della rosa, ci risiamo con la leggenda nera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/","og_locale":"it_IT","og_type":"article","og_title":"Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2019-03-13T23:00:56+00:00","article_modified_time":"2019-03-15T17:53:55+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il nome della rosa, ci risiamo con la leggenda nera","datePublished":"2019-03-13T23:00:56+00:00","dateModified":"2019-03-15T17:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/"},"wordCount":669,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg","keywords":["storia della chiesa"],"articleSection":["Al cinema","Medioevo","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/","name":"Il nome della rosa, ci risiamo con la leggenda nera - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg","datePublished":"2019-03-13T23:00:56+00:00","dateModified":"2019-03-15T17:53:55+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/nome-della-rosa.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-nome-della-rosa-ci-risiamo-con-la-leggenda-nera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il nome della rosa, ci risiamo con la leggenda nera"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=42241"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42241\/revisions"}],"predecessor-version":[{"id":42345,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/42241\/revisions\/42345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/42344"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=42241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=42241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=42241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}