{"id":4158,"date":"2010-10-28T00:00:00","date_gmt":"2010-10-27T22:00:00","guid":{"rendered":""},"modified":"2015-11-09T11:59:00","modified_gmt":"2015-11-09T10:59:00","slug":"educazione-e-maleducazione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/","title":{"rendered":"Educazione e maleducazione"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27255\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg\" alt=\"maleducazione\" width=\"250\" height=\"183\" \/><\/a>La Civilt\u00e0 Cattolica<\/strong> n.3846<\/div>\n<div style=\"text-align: center;\">\u00a018 settembre 2010<\/div>\n<p style=\"text-align: center;\"><strong>Giandomenico Mucci<\/strong> s.i.<\/p>\n<p style=\"text-align: justify;\">Non sono soltanto i vecchi e gli anziani a lamentare da noi il tramonto delle buone maniere. Un po&#8217; da ogni parte ci sono i segni di un turbamento diffuso per la mancanza di rispetto per se stessi e per gli altri. Non ci riferiamo ai grandi crimini. Parliamo di quella maleducazione spicciola che compromette in qualche modo la convivenza civile.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Citiamo a caso. Il televisore tenuto anche di notte ad alto volume, gli scarabocchi indelebili sui muri tinteggiati di fresco, il <em>chewmg gum<\/em> sputato sulle strade e attaccato perfino ai muri e alle colonne dei palazzi storici, i cellulari che squillano nelle chiese e durante le conferenze e i concerti, lo scarso rispetto per gli anziani, i genitori, i professori, anche da parte dei bambini, il mozzicone ancora acceso gettato dal finestrino dell&#8217;auto, l&#8217;automobilista che ha torto e pretende di avere ragione urlando, e via dicendo (1).<\/div>\n<p style=\"text-align: justify;\">C&#8217;\u00e8 chi dice che tali sono gli effetti del relativismo o del nichilismo o del permissivismo. Altri parlano di emergenza educativa derivante dall&#8217;enfatizzazione senza scrupoli del valore del denaro, del successo e del potere (2). Discutano i competenti. Per quanto riguarda il costume italiano, ci sembrano convincenti le osservazioni storico-fenomenologiche di Sergio Romano. Gli italiani sono cortesi, umani, bonari, fors&#8217;anche pi\u00f9 di altri popoli. In essi queste qualit\u00e0 scattano quando due persone scoprono di avere qualcosa in comune: la citt\u00e0 natale, i passatempi, lo stesso bar, la stessa squadra di calcio, le stesse idee politiche.<\/p>\n<p style=\"text-align: justify;\">Manca per\u00f2 la cortesia formale. Se hanno fretta e devono farsi strada, non usano l&#8217;urbano \u00abpermesso\u00bb e tanto meno chiedono scusa. In luoghi affollati, parlano al cellulare ad alta voce dando fastidio agli altri. Guidano l&#8217;auto o la moto come se gli altri avessero il dovere di dare loro la precedenza in ogni caso. Salvo poi a diventare esageratamente cortesi, cio\u00e8 servili, specialmente con gli stranieri che fanno turismo.<\/p>\n<p style=\"text-align: justify;\">Secondo Romano, sulle cattive maniere degli italiani pesano i due fattori fondamentali, che sono la famiglia e la scuola, senza trascurare l&#8217;analfabetismo che \u00e8 tutt&#8217;altro che vinto. Si aggiungono due altri importanti fattori. Il primo \u00e8 la debolezza della borghesia italiana. Il galateo quotidiano \u00e8 un&#8217;invenzione borghese che \u00e8 sorta, verso la fine del Settecento, in Gran Bretagna, si \u00e8 diffusa in Francia e nei Paesi germanici durante l&#8217;Ottocento ed \u00e8 legata alla rivoluzione industriale e al ruolo crescente della borghesia nella politica e negli affari.<\/p>\n<p style=\"text-align: justify;\">Sennonch\u00e9, in Italia, in altri Paesi del Mediterraneo e nei Paesi slavi, la rivoluzione industriale \u00e8 arrivata tardi e non ha modificato le norme pi\u00f9 elementari della convivenza civile. Fino a non molto tempo fa, gli ufficiali davano del tu ai soldati e i padroni di casa ai domestici: abitudine peraltro non ancora completamente estinta. Il secondo fattore \u00e8 il comportamento di coloro che godono di notoriet\u00e0: uomini politici, cantanti, attori, gente dello sport, artisti, intellettuali.<\/p>\n<p style=\"text-align: justify;\">Costoro sono, di fatto, modello e specchio per una parte rilevante della societ\u00e0. Ebbene, questa <em>\u00e9lite <\/em>(\u00abmai parola \u00e8 stata cos\u00ec male usata\u00bb, nota Romano) \u00e8 formata solitamente da persone che litigano abitualmente, si insultano, usano un linguaggio triviale, raccontano storielle ammiccanti e, soprattutto, ostentano compiaciuti un uso feudale del loro potere (3)<\/p>\n<p style=\"text-align: justify;\"><strong><em>I ragazzi<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Come potrebbero ragazzi <em>e <\/em>giovani sfuggire a questo stato di cose? Non si contano le analisi e le indagini che psicologi e sociologi dedicano da tempo al mondo giovanile. Sono un sintomo certo del malessere della societ\u00e0 gli accoltellamenti, le rapine, le aggressioni, gli stupri di gruppo, gli assassini perpetrati dagli adolescenti. E la cronaca nera registra, accanto a questo malessere, at\u00adteggiamenti giovanili che possono essere ricondotti anche alla loro mancata educazione.<\/p>\n<p style=\"text-align: justify;\">Tutti abbiamo osservato, in molti ragazzi arrestati dopo un crimine, la freddezza e l&#8217;indifferenza non soltanto verso le vittime, ma pure verso i propri familiari e verso se stessi: talvolta, almeno all&#8217;apparenza, si mostrano insensibili finanche alla prospettiva del carcere, come se il superamento della noia fosse valso l&#8217;esperienza del delitto e il dolore di molti. \u00c8 un&#8217;indifferenza riflessa anche nell&#8217;abbigliamento monotono: <em>jeans, <\/em>scarpe sportive, felpa, in qualsiasi occasione, sia la casa o la scuola, il lavoro o il <em>pub, <\/em>lo sport o la discoteca.<\/p>\n<p style=\"text-align: justify;\">La stampa italiana \u00e8 stata spesso sensibile a questo cruciale argomento. Non \u00e8, infatti, fenomeno da poco che tali ragazzi provengano non soltanto dalle zone di degrado, emarginazione e miseria, ma anche da famiglie, case e quartieri bene: e talvolta l&#8217;indigenza, talaltra la crisi di solitudine e di noia, talvolta il gruppo di amici sbagliati formano una miscela esplosiva.<\/p>\n<p style=\"text-align: justify;\">Non un foglio ecclesiastico, ma un foglio laico ha dato risalto recentemente a un dato obiettivo. Oggi la famiglia italiana \u00e8 debole.<\/p>\n<p style=\"text-align: justify;\">I ragazzi sono privi della costante presenza dei genitori. Ma manca ai genitori il sostegno di altre figure di educatori come i parroci, i maestri, i professori. Capita anzi non raramente che i genitori prendano pregiudizialmente le parti dei figli contro l&#8217;opera di questi che dovrebbero essere cercati e accettati come collaboratori dell&#8217;educazione impartita in famiglia. \u00abE rinunciare a qualsiasi forma di istruzione religiosa \u00e8, ovviamente, una scelta rispettabilissima che per\u00f2 priva la famiglia di un supporto non indifferente\u00bb (4). Quelle stesse famiglie, che avanzano critiche pi\u00f9 o meno pretestuose contro quei collaboratori, permettono poi passivamente che i figli subiscano il prolungato \u00abmagistero\u00bb della televisione, \u00abquesto leviatano catodico\u00bb (5).<\/p>\n<p style=\"text-align: justify;\">Le responsabilit\u00e0 etiche e la funzione spesso diseducativa dei <em>media, <\/em>particolarmente della televisione, sono state sottolineate dal Papa. I <em>media, <\/em>essendo gli strumenti attraverso i quali avvengono i processi di mediazione simbolica, inducono una cultura che pu\u00f2 condurre all&#8217;assuefazione all&#8217;egoismo e all&#8217;indifferenza: \u00abOgni giorno, attraverso i giornali, la televisione, la radio, il male viene raccontato, ripetuto, amplificato, abituandoci alle cose pi\u00f9 orribili, facendoci diventare insensibili e, in qualche maniera, intossicandoci, perch\u00e9 il negativo non viene pienamente smaltito e giorno per giorno si accumula. Il cuore si indurisce e i pensieri si incupiscono. Siamo tutti attori e, nel male come nel bene, il nostro comportamento ha un influsso sugli altri\u00bb (6).<\/p>\n<p style=\"text-align: justify;\">Quale sar\u00e0 questo influsso sulla formazione dei ragazzi e dei giovani? Quanta parte della maleducazione \u00e8 dovuta a questo influsso?<\/p>\n<p style=\"text-align: justify;\">Una realistica osservazione di Angelo Panebianco offre un esempio di controeducazione. Le corporazioni o categorie italiane (alti burocrati, magistrati, professori universitari, giornalisti, medici ospedalieri eccetera) comprendono al loro interno professionalit\u00e0 eccellenti, mediocrit\u00e0 e casi di indegnit\u00e0 professionale. L&#8217;opinione pubblica finisce spesso per credere che quei gruppi siano composti soltanto di mediocrit\u00e0 e indegnit\u00e0, perch\u00e9 la presenza in essi delle eccellenze \u00e8 oscurata dal meccanismo mediatico che porta solitamente sotto i riflettori soltanto le indegnit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Succede poi che le rappresentanze dei gruppi si impegnino nella difesa a oltranza di tali indegnit\u00e0 per salvaguardare l&#8217;immagine del gruppo di fronte all&#8217;opinione pubblica e al potere politico. Di fatto, risultano protetti i membri peggiori. Anche qui: come riusciranno i giovani a vedersi riconosciuto \u00abil diritto di essere aiutati a valutare con retta coscienza e ad accettare con adesione personale i valori morali\u00bb (7)?<\/p>\n<p style=\"text-align: justify;\"><strong><em>Il sapere umanistico<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Educazione vuoi dire cultura. E cultura non significa semplice acquisizione di competenze e di civismo. \u00c8 stato detto da qualcuno che la cultura \u00e8 apertura alla consapevolezza del valore moralmente educativo del sapere in quanto tale. E l&#8217;idea cara a tutta la tradizione umanistica occidentale. La cultura \u00e8 rivolta costitutivamente alla verit\u00e0 <em>e <\/em>alla bellezza ed \u00e8 in se stessa fonte decisiva di raffinamento etico e di crescita civile.<\/p>\n<p style=\"text-align: justify;\">Cultura come storia, letteratura, arti, matematica (8). Un breve cenno a tre problemi, tra i tanti, dai quali \u00e8 pi\u00f9 facile evincere lo stretto legame che esiste tra cultura e educazione. L&#8217;insistenza periodica della stampa in proposito sta a dimostrare la dipendenza dell&#8217;emergenza educativa da una rinnovata promozione della cultura umanistica.<\/p>\n<p style=\"text-align: justify;\">Occorre innanzitutto superare la visione ideologica sessantottina della storia nazionale. E tempo che la scuola riprenda a raccontarla con il rispetto dei fatti, spirito critico e piet\u00e0. Senza oscurare le sue pagine nere che, per gli ultimi settanta anni, si chiamano disfatta militare, guerra civile, terrorismo, scandali, criminalit\u00e0 organizzata<em>. <\/em>Senza oscurare le sue pagine luminose che, a tacere delle glorie della passata civilt\u00e0 italiana, si chiamano, per quanto attiene all&#8217;epoca della Repubblica, disfatta del fascismo e Italia diventata potenza occidentale, membro fondatore della Comunit\u00e0 europea e sesta o settima economia mondiale (9).<\/p>\n<p style=\"text-align: justify;\">E&#8217; giusto che i ragazzi italiani, che vivono in un mondo multietnico, conoscano e apprezzino i valori delle civilt\u00e0 dei quali \u00e8 portatore il suo compagno di banco. Ma \u00e8 altres\u00ec giusto osservare il principio del gradiente, come lo definisce Chiara Frugoni. La preminenza va data alla nostra storia nazionale, antica e attuale, perch\u00e9 l\u00e0 sono le nostre radici e non bisogna rinunciare alla propria identit\u00e0 culturale (10).<\/p>\n<p style=\"text-align: justify;\">A proposito di questa identit\u00e0 da conservare, \u00e8 un segnale preoccupante che l&#8217;editoria italiana, probabilmente schiacciata dal mercato, abbia abbandonato ogni disegno organico di proposte, riproposte e riletture dei classici della letteratura antica e moderna, che \u00e8 uno dei vessilli identitari dell&#8217;Italia, quelli che indicano un progetto e una meta (11). Mario Luzi parlava della \u00absostanza nutritiva della letteratura\u00bb e poneva il suo valore formativo in questo, \u00abche non ci disloca in un mondo parallelo ma ci trattiene nel nostro ordinario incrementando la nostra lucidit\u00e0 e la nostra comprensione\u00bb (12).<\/p>\n<p style=\"text-align: justify;\">E qui il discorso cade ancora sulla scuola. Premettiamo che, secondo stime verosimili, in Italia sono circa tre milioni coloro che o non sanno n\u00e9 leggere n\u00e9 scrivere o lo fanno con difficolt\u00e0. Una ricerca curata dall&#8217;associazione dei direttori del personale (Gidp) rileva che i <em>curricula <\/em>presentati da persone in cerca di lavoro, anche da coloro che aspirano a funzioni di responsabilit\u00e0 gestionale, sono scritti senza controllo grammaticale.<\/p>\n<p style=\"text-align: justify;\">Noti linguisti, come Giovanni Gobber, affermano che la scuola italiana d&#8217;oggi non insegna a scrivere ed \u00e8 sottovalutata l&#8217;importanza dell&#8217;ortografia e della pronuncia corretta delle parole (13). E cosa dire della struttura del discorso, dei neologismi strampalati, dell&#8217;impoverimento della sintassi (14)? Con questi presupposti, si pu\u00f2 pensare seriamente alla formazione culturale dei ragazzi e dei giovani, i quali peraltro disertano spesso i libri, che restano il mezzo principale per imparare a scrivere e ad educarsi alla cultura?<\/p>\n<p style=\"text-align: justify;\">Vogliamo infine accennare al fenomeno degli anglicismi. Sergio Romano si \u00e8 domandato perch\u00e9 gli italiani, specialmente i giovani, si lascino sommergere da una valanga di anglicismi non sempre utili e necessari. Fenomeno non del tutto nuovo. Le grandi potenze economiche e imperiali impongono regole commerciali, formule contrattuali, strumenti di credito e di risparmio. Le lingue corrono grazie all&#8217;influenza degli Stati che le parlano.<\/p>\n<p style=\"text-align: justify;\">Nel Settecento, quando l&#8217;influenza della Francia fu grande dall&#8217;Atlantico agli Urali, l&#8217;aristocrazia e i ceti emergenti della societ\u00e0 italiana parlavano francese, leggevano libri francesi, introducevano neologismi francesi: e fu un&#8217;importazione cos\u00ec massiccia da rinnovare l&#8217;italiano. Vengono dal francese, secondo Bruno Migliorini, cotoletta, baionetta, mitraglia, picchetto, manovra, scialuppa, cerniera, ghisa, aggiotaggio, conto corrente, dipartimento, marionetta, minuetto, giardinaggio, interessante, intraprendente, manifattura, materia prima, rapporto (come relazione tra persone), saggio (come articolo), vignetta, papa.<\/p>\n<p style=\"text-align: justify;\">In quel secolo, anche la lingua italiana esercit\u00f2 una sua influenza, per esempio nel campo della musica. Si pensi ai tanti libretti d&#8217;opera di Haydn e Mozart e ai tanti testi poetici musicati dai grandi artisti europei. Oggi l&#8217;influenza linguistica italiana sembra limitarsi alla moda, alla gastronomia e alla criminalit\u00e0: dolce vita, paparazzo, mafia, camorra, pizza, espresso, cappuccino, tiramis\u00f9 (15).<\/p>\n<p style=\"text-align: justify;\">Dunque, pu\u00f2 piacere o no, ma non \u00e8 un dramma la presenza degli anglicismi nell&#8217;italiano. Ma perch\u00e9 usare parole straniere quando l&#8217;italiano ha termini perfettamente equivalenti? Hanno questa abitudine i navigatori di internet e quanti o hanno studiato e lavorato all&#8217;estero o svolgono attivit\u00e0 di carattere internazionale: finanzieri, agenti di borsa, stilisti, esperti di relazioni pubbliche, impresari della moda e della comunicazione, tecnici delle nuove tecnologie, organizzatori di convegni e seminari.<\/p>\n<p style=\"text-align: justify;\">In questi campi, soprattutto in quello economico e finanziario, la parola inglese indica funzioni e strumenti che provengono dagli Stati Uniti e dalla Gran Bretagna. Tutto ci\u00f2 appartiene all&#8217;evoluzione naturale delle lingue e al predominio di una sulle altre per le ragioni segnalate.<\/p>\n<p style=\"text-align: justify;\">La \u00abmaleducazione\u00bb comincia quando gli italiani, adulti e ragazzi, vogliono ostentare o le loro conoscenze linguistiche o le loro frequentazioni internazionali o la loro malintesa modernit\u00e0. E questo \u00e8 snobismo. Incuranti di rendersi poco comprensibili a una larga parte di concittadini, abusano degli esotismi perch\u00e9 pensano che il \u00abparlare difficile\u00bb sia segno di intelligenza e di superiorit\u00e0. E magari storpiano la parola inglese o la usano a sproposito! E l&#8217;italiano \u00e8 inondato da un diluvio di parole inglesi, mal pronunciate, mal comprese e il pi\u00f9 delle volte inutili (16). E questo \u00e8 provincialismo.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> Cfr A. MUNDULA, \u00abContro la maleducazione\u00bb, in <em>Feeria<\/em> 17 (2009) 12-14; L. TRUSS<em>, I<\/em> <em>maleducati<\/em>, Casale Monferrato (Al), Piemme, 2006.<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong> Cfr A. ANDREINI, \u00abII coraggio di educare\u00bb, in <em>Feeria<\/em>, cit., 32-35.<\/p>\n<p style=\"text-align: justify;\"><strong>3)<\/strong> Cfr S. ROMANO, \u00abLa maleducazione italiana. Ragioni e responsabilit\u00e0\u00bb, in <em>Corrie<\/em><em>re della Sera, <\/em>16 novembre 2008, 31.<\/p>\n<p style=\"text-align: justify;\"><strong>4)<\/strong> I. BOSSI FEDRIGOTTI, \u00abI nostri figli senza maestri\u00bb, ivi, 30 aprile 2009, 1 e 36.<\/p>\n<p style=\"text-align: justify;\"><strong>5)<\/strong> R. CHIABERGE, \u00abMa l&#8217;intelletuale non perde il vizio\u00bb, in <em>Il Sole 24 Ore, <\/em>18 gennaio 2004, 28.<\/p>\n<p style=\"text-align: justify;\"><strong>6)<\/strong> Cfr F. GlANSOLDATI, \u00abRatzinger critica i mass media\u00bb, in \/\/ <em>Messaggero, 9 <\/em>dicembre 2009, 13.<\/p>\n<p style=\"text-align: justify;\"><strong>7)<\/strong> <em>Gravissimum educationis, <\/em>n. 1 c.<\/p>\n<p style=\"text-align: justify;\"><strong>8)<\/strong> Cfr E. GALLI DELLA LOGGIA, \u00abScuola. Cos\u00ec la democrazia diventa catechismo\u00bb, in <em>Corriere della Sera, <\/em>8 novembre 2009, 28 s.<\/p>\n<p style=\"text-align: justify;\"><strong>9)<\/strong> Cfr S. ROMANO, \u00abPerch\u00e9 \u00e8 cos\u00ec difficile insegnare l&#8217;amor di patria\u00bb, ivi, 15 febbraio 2010, 31.<\/p>\n<p style=\"text-align: justify;\"><strong>10)<\/strong> Cfr C. FRUGONI, \u00abLa storia del mondo \u00e8 una sciocchezza\u00bb, in <em>la Repubblica, <\/em>13 marzo 2001.<\/p>\n<p style=\"text-align: justify;\"><strong>11)<\/strong> Cfr P. Di STEFANO, \u00abL&#8217;Italia senza identit\u00e0 non crede nei classici\u00bb, in <em>Corriere del<\/em><em>la Sera, <\/em>20 ottobre 2009, 42 <em>s; <\/em>U. MOTTA, \u00abII canone, i classici e i moderni\u00bb, in <em>Vita e Pensiero <\/em>89 (2006) 100-104.<\/p>\n<p style=\"text-align: justify;\"><strong>12)<\/strong> M. LUZI, \u00abInedito\u00bb, in <em>Avvenire, <\/em>27 maggio 2005, 30.<\/p>\n<p style=\"text-align: justify;\"><strong>13)<\/strong> Cfr A. SCAGLIA, \u00abUno su dieci non sa l&#8217;italiano\u00bb, in <em>Libero, <\/em>18 agosto 2009, 1 e 6.<\/p>\n<p style=\"text-align: justify;\"><strong>14)<\/strong> Cfr C. SEGRE, \u00abBoss, plot, trend: l&#8217;onda irresistibile\u00bb, in <em>Corriere della Sera, <\/em>15 febbraio 2010, 29.<\/p>\n<p style=\"text-align: justify;\"><strong>15)<\/strong> Cfr S. ROMANO, \u00abII trionfo dell&#8217;inglese come cambia l&#8217;italiano\u00bb, ivi, 15 gennaio 2010,51.<\/p>\n<p style=\"text-align: justify;\"><strong>16)<\/strong> Cfr Id. \u00abPerch\u00e9 tante parole inglesi in bocca a molti italiani\u00bb, ivi, 17 ottobre 2009, 49<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Civilt\u00e0 Cattolica n.3846 \u00a018 settembre 2010 Giandomenico Mucci s.i. Non sono soltanto i vecchi e gli anziani a lamentare da noi il tramonto delle buone maniere. Un po&#8217; da ogni parte ci sono i segni di un turbamento diffuso per la mancanza di rispetto per se stessi e per gli altri. Non ci riferiamo &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,23],"tags":[1871,234],"class_list":["post-4158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-scuola-ed-educazione","tag-buone-maniere","tag-educazione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Educazione e maleducazione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educazione e maleducazione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-27T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-09T10:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"262\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Educazione e maleducazione\",\"datePublished\":\"2010-10-27T22:00:00+00:00\",\"dateModified\":\"2015-11-09T10:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/\"},\"wordCount\":2297,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/10\\\/maleducazione.jpg\",\"keywords\":[\"buone maniere\",\"educazione\"],\"articleSection\":[\"Costume\",\"Scuola ed educazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/\",\"name\":\"Educazione e maleducazione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/10\\\/maleducazione.jpg\",\"datePublished\":\"2010-10-27T22:00:00+00:00\",\"dateModified\":\"2015-11-09T10:59:00+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/10\\\/maleducazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/10\\\/maleducazione.jpg\",\"width\":262,\"height\":192},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/educazione-e-maleducazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educazione e maleducazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educazione e maleducazione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/","og_locale":"it_IT","og_type":"article","og_title":"Educazione e maleducazione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-10-27T22:00:00+00:00","article_modified_time":"2015-11-09T10:59:00+00:00","og_image":[{"width":262,"height":192,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Educazione e maleducazione","datePublished":"2010-10-27T22:00:00+00:00","dateModified":"2015-11-09T10:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/"},"wordCount":2297,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg","keywords":["buone maniere","educazione"],"articleSection":["Costume","Scuola ed educazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/","name":"Educazione e maleducazione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg","datePublished":"2010-10-27T22:00:00+00:00","dateModified":"2015-11-09T10:59:00+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/10\/maleducazione.jpg","width":262,"height":192},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/educazione-e-maleducazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Educazione e maleducazione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4158"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4158\/revisions"}],"predecessor-version":[{"id":27256,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4158\/revisions\/27256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27255"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}